{"id":66957,"date":"2005-10-26T00:00:00","date_gmt":"2005-10-26T00:00:00","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2005\/10\/26\/incertitudes-et-certitudes-irakiennes-annee-2003\/"},"modified":"2005-10-26T00:00:00","modified_gmt":"2005-10-26T00:00:00","slug":"incertitudes-et-certitudes-irakiennes-annee-2003","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2005\/10\/26\/incertitudes-et-certitudes-irakiennes-annee-2003\/","title":{"rendered":"Incertitudes et certitudes irakiennes, ann\u00e9e 2003"},"content":{"rendered":"<p><p>Nous signalons un passage de l&rsquo;article de <a href=\"http:\/\/www.defensenews.com\/story.php?F=1184605&#038;C=thisweek\" class=\"gen\">Defense News du 24 octobre<\/a> qui nous a servi de support pour notre <a href=\"http:\/\/www.dedefensa.org\/article.php?art_id=2096\" class=\"gen\">Faits &#038; Commentaires du 25 octobre<\/a>. Cet article concernait notamment la question de l&rsquo;autonomie industrielle et strat\u00e9gique de l&rsquo;Europe pour ses \u00e9quipements militaires, face aux intrusions US (l\u00e9gislation ITAR) \u00e0 cause des composants am\u00e9ricains dans certains syst\u00e8mes europ\u00e9ens.<\/p>\n<\/p>\n<p><p>\t\u00ab <em> And retired French Gen. Bernard Molard told a conference audience recently that Europe must develop its space capabilities independent of the United States for strategic reasons. Molard chairs the security and defense working group of Eurospace, a subsidiary of ASD, the lobby in Brussels that represents Europe&rsquo;s aerospace and defense industries.<\/em> <\/p>\n<\/p>\n<p><p>\t\u00bb <em>France didn&rsquo;t follow other allies into the war in Iraq because we had our own satellite means to verify whether WMD [weapons of mass destruction] were actually there. We could see they weren&rsquo;t there, and we didn&rsquo;t go for it, he said.<\/em> \u00bb<\/p>\n<\/p>\n<p><p>\tA notre connaissance, c&rsquo;est la premi\u00e8re fois qu&rsquo;il est affirm\u00e9 publiquement de fa\u00e7on aussi pr\u00e9cise que la raison  plut\u00f4t l&rsquo;une des raisons, \u00e0 notre sens, de l&rsquo;abstention de la France dans la guerre contre l&rsquo;Irak repose sur le constat technique de l&rsquo;absence d&rsquo;ADM en Irak gr\u00e2ce \u00e0 la reconnaissance satellite. Nous parlons ici de la pr\u00e9cision du propos, \u00e9tant entendu par ailleurs que le doute sur l&rsquo;existence des ADM de Saddam \u00e9tait largement r\u00e9pandu dans les milieux dirigeants fran\u00e7ais. (A notre connaissance, c&rsquo;est la premi\u00e8re fois qu&rsquo;il est affirm\u00e9 publiquement de fa\u00e7on aussi pr\u00e9cise : nous ne pr\u00e9tendons certainement pas \u00e0 la certitude dans ce cas et nous prendrions connaissance avec int\u00e9r\u00eat de toute pr\u00e9cision et contestation.)<\/p>\n<\/p>\n<p><p>\tBien entendu, cette affirmation est, dans le contexte de l&rsquo;article, un puissant argument en faveur de l&rsquo;ind\u00e9pendance compl\u00e8te (pas de composants US) des syst\u00e8mes d&rsquo;arme europ\u00e9ens.<\/p>\n<\/p>\n<p><\/p>\n<p><p>\tMis en ligne le 26 octobre 2005 \u00e0 10H05<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nous signalons un passage de l&rsquo;article de Defense News du 24 octobre qui nous a servi de support pour notre Faits &#038; Commentaires du 25 octobre. Cet article concernait notamment la question de l&rsquo;autonomie industrielle et strat\u00e9gique de l&rsquo;Europe pour ses \u00e9quipements militaires, face aux intrusions US (l\u00e9gislation ITAR) \u00e0 cause des composants am\u00e9ricains dans&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[2],"tags":[3860,4797,2687,4793,4798],"class_list":["post-66957","post","type-post","status-publish","format-standard","hentry","category-bloc-notes","tag-adm","tag-export","tag-france","tag-itar","tag-satellite"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/66957","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=66957"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/66957\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=66957"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=66957"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=66957"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}