{"id":66985,"date":"2005-11-05T00:00:00","date_gmt":"2005-11-05T00:00:00","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2005\/11\/05\/ue-cia-et-vertu-europeenne-damage-control\/"},"modified":"2005-11-05T00:00:00","modified_gmt":"2005-11-05T00:00:00","slug":"ue-cia-et-vertu-europeenne-damage-control","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2005\/11\/05\/ue-cia-et-vertu-europeenne-damage-control\/","title":{"rendered":"<strong><em>UE, CIA et vertu europ\u00e9enne: \u201cdamage control\u201d<\/em><\/strong>"},"content":{"rendered":"<p><h2 class=\"common-article\">UE, CIA et vertu europ\u00e9enne: <em>damage control<\/em><\/h2>\n<\/p>\n<p><\/p>\n<p><p>\t5 novembre 2005  Nous avons eu un instant, un tr\u00e8s court instant, la tentation de nuancer notre texte <a href=\"http:\/\/www.dedefensa.org\/article.php?art_id=2125\" class=\"gen\">F&#038;C d&rsquo;hier<\/a> sur les camps de torture de la CIA en Roumanie et en Pologne. Nous avons rapidement \u00e9cart\u00e9 cette tentation. Tr\u00e8s vite, il nous est apparu qu&rsquo;il importait de suivre cette question, de l&rsquo;aborder selon l&rsquo;id\u00e9e du respect de la chronologie et, justement, d&rsquo;ent\u00e9riner les changements de ton <strong>officiels<\/strong>,  pour une fois, l&rsquo;<strong>\u00e9volution<\/strong> des mensonges officiels est une pr\u00e9cieuse indication. Notre conclusion \u00e0 ce point est celle-ci: il s&rsquo;agit d&rsquo;une des tentatives les plus \u00e9chevel\u00e9es de l&rsquo;UE de sauver les meubles de sa pauvre r\u00e9putation, coinc\u00e9e qu&rsquo;elle est entre son alignement inconditionnel sur les USA et la n\u00e9cessit\u00e9 de sauver la bonne r\u00e9putation de l&rsquo;\u00e9largissement \u00e0 25.<\/p>\n<\/p>\n<p><p>\t\u00ab <em>Si cette affaire devenait incontr\u00f4lable, <\/em>dit une source ind\u00e9pendante europ\u00e9enne, <em>c&rsquo;est le principe m\u00eame de l&rsquo;\u00e9largissement vers les pays anciennement communistes qui serait remis en question, et sur le terrain le plus d\u00e9licat, qui est celui de l&rsquo;alignement sur les Am\u00e9ricains. L&rsquo;Europe n&rsquo;a pas besoin de cela.<\/em> \u00bb. En un sens, l&rsquo;id\u00e9e est confirm\u00e9e indirectement par cette d\u00e9claration (<a href=\"http:\/\/www.dedefensa.org\/article.php?art_id=2127\" class=\"gen\">que nous avons d\u00e9j\u00e0 cit\u00e9e<\/a>) de Janusz Onyszkiewicz, ancien ministre polonais de la d\u00e9fense et d\u00e9put\u00e9 au PE: la confirmation de l&rsquo;existence de tels centres de torture \u00ab <em>would do enormous damage to Poland&rsquo;s image. We already suffer from being America&rsquo;s Trojan donkey in Europe.<\/em> \u00bb Curieux, curieux: ces Am\u00e9ricains, qui sont notre lumi\u00e8re en tout, ont l&rsquo;amiti\u00e9 si compromettante qu&rsquo;un Polonais en arrive \u00e0 se sentir ostracis\u00e9.<\/p>\n<\/p>\n<p><p>\tMais le principal, qui est le risque que cette affaire fait courir \u00e0 l&rsquo;Europe, les bureaucrates-diplomates-moralistes des institutions europ\u00e9ennes, soutenus par leurs comp\u00e8res des capitales nationales, l&rsquo;ont compris au bout de 48 heures. D&rsquo;o\u00f9 un exercice p\u00e9rilleux et, r\u00e9p\u00e9tons le mot, \u00e9chevel\u00e9 de ce que les Am\u00e9ricains (il est opportun de les citer) d\u00e9signent comme le <em>damage control<\/em>.<\/p>\n<\/p>\n<p><p>\tIl est int\u00e9ressant de noter que les premiers d\u00e9mentis cat\u00e9goriques sont venus des pays non impliqu\u00e9s, jusqu&rsquo;\u00e0 cette pr\u00e9cision qui est certainement le d\u00e9tail <em>a contrario<\/em> le plus convaincant de la r\u00e9alit\u00e9 de l&rsquo;affaire: la d\u00e9claration du ministre tch\u00e8que de l&rsquo;Int\u00e9rieur Frantiszek Bublan que la demande de l&rsquo;\u00e9tablissement de tels camps lui a \u00e9t\u00e9 faite par les USA, et qu&rsquo;il l&rsquo;a rejet\u00e9e. L&rsquo;important est bien entendu qu&rsquo;il y a affirmation officielle et nullement d\u00e9mentie qu&rsquo;il y a eu demande de la CIA Selon ce qu&rsquo;on sait du statut et de l&rsquo;honorabilit\u00e9 des pays de l&rsquo;Europe ex-communiste (\u00e9limination des anciens cadres communistes beaucoup plus avanc\u00e9e chez les Tch\u00e8ques et les Hongrois que chez les autres, corruption \u00e0 mesure), un ministre de l&rsquo;int\u00e9rieur tch\u00e8que peut refuser \u00e0 la CIA ce qu&rsquo;un ministre de l&rsquo;int\u00e9rieur d&rsquo;un autre pays de l&rsquo;ancien bloc (si certains pensent \u00e0 la Pologne et \u00e0 la Roumanie, tant pis pour eux) aura beaucoup plus de difficult\u00e9s \u00e0 refuser,  s&rsquo;il en a l&rsquo;intention, d&rsquo;ailleurs,  et si l&rsquo;on prend la peine de le lui demander, du reste. Selon la m\u00eame logique des situations connues et archi-classiques, on voit mal la CIA proposer l&rsquo;installation d&rsquo;un <em>black site<\/em> \u00e0 la Tch\u00e9quie et rien du tout \u00e0 la Pologne et \u00e0 la Roumanie. Plus on va vers l&rsquo;Est, plus la CIA se sent chez elle.<\/p>\n<\/p>\n<p><p>\tEnfin, deux jours plus tard (apr\u00e8s l&rsquo;article du <em>Post<\/em>), les d\u00e9mentis cat\u00e9goriques sont venus, essentiellement des deux pays int\u00e9ress\u00e9s. L&rsquo;UE n&rsquo;attendait que cela pour affirmer vertueusement qu&rsquo;avec des d\u00e9mentis d&rsquo;une telle puissance, on ne pouvait que les croire. C&rsquo;est une curieuse logique: plus vous d\u00e9mentissez fort, plus vous avez de chances d&rsquo;\u00eatre crus. On appr\u00e9ciera l&rsquo;\u00e9trange d\u00e9monstration, la preuve de l&rsquo;innocence par le coup de gueule qui nous est <a href=\"http:\/\/euobserver.com\/?aid=20248&#038;rk=1\" class=\"gen\">ainsi offerte<\/a>, caract\u00e9ris\u00e9e par ces remarques : \u00ab <em>They wouldn&rsquo;t have said it in that tone if there was a shred of truth in it. Having this level of denial means it didn&rsquo;t happen, the Institute for Security Studies&rsquo; eastern Europe expert Marcin Zaborowski told EUobserver. If they are lying, they have put themselves in very deep trouble, he added.<\/em> \u00bb Curieux, curieux: on ne voit pas pourquoi le mensonge serait plus condamnable parce qu&rsquo;il a \u00e9t\u00e9 gueul\u00e9, au lieu d&rsquo;\u00eatre susurr\u00e9 ; et l&rsquo;on ne voit pas, <em>a contrario<\/em>, que la v\u00e9rit\u00e9 soit plus convaincante parce qu&rsquo;elle aurait \u00e9t\u00e9 gueul\u00e9e au lieu d&rsquo;\u00eatre dite sur le ton calme, mesur\u00e9 et assur\u00e9 des choses qui vont de soi. L&rsquo;affaire est tout de m\u00eame simple: \u00e0 voix basse ou \u00e0 haute voix, un <em>black site<\/em> (\u00e7a fait plus chic que: centre de torture) reste un <em>black site<\/em>, et s&rsquo;il s&rsquo;av\u00e8re qu&rsquo;il y en a r\u00e9ellement le volume du d\u00e9menti n&rsquo;y changera rien.<\/p>\n<\/p>\n<p><p>\tVient aussit\u00f4t la confirmation qu&rsquo;on attend que cela, du c\u00f4t\u00e9 de Bruxelles:  \u00ab <em>Warsaw and Bucharest has categorically denied the claims however, with policy advisors to EU foreign affairs chief Javier Solana accepting the rebuttals at face value.<\/em> \u00bb Pour une fois, l&rsquo;expression anglaise a tout son sel et tout son sens: \u00ab <em>at face value.<\/em> \u00bb Les Fran\u00e7ais disent plut\u00f4t: \u00e0 la t\u00eate du client, ce qui a un tout autre sens. On est entre gens d&rsquo;honneur et il importe de pouvoir se regarder les yeux dans les yeux et de dire : ce n&rsquo;est pas moi.<\/p>\n<\/p>\n<p><p>\tAu reste, tous ces braves gens ne mentent peut-\u00eatre pas compl\u00e8tement. Comme, du temps du Pacte, les dirigeants communistes des pays satellites ignoraient ce que le KGB faisait sur leur sol, aujourd&rsquo;hui, du temps de l&rsquo;UE (?), les m\u00eames dirigeants recycl\u00e9s ignorent ce que la CIA fait sur leur sol. Les uns (KGB) et les autres (CIA) avaient et ont suffisamment de dossiers sur les uns et les autres pour faire reculer le p\u00e9ch\u00e9 de curiosit\u00e9. Les dirigeants recycl\u00e9s n&rsquo;ont pas \u00e0 s&rsquo;en effrayer parce qu&rsquo;ils ne sont pas les premiers \u00e0 baigner \u00e9ventuellement dans cette ignorance aga\u00e7ante. Dans les ann\u00e9es 1970 et 1980, ni les dirigeants italiens ni les dirigeants belges ne savaient ce que faisaient la CIA, la DIA et tout le toutim sur leurs territoires,  <a href=\"http:\/\/www.dedefensa.org\/article.php?art_id=1370\" class=\"gen\">au temps<\/a> de <em>Gladio<\/em> reconverti, des <em>Brigadi Rossi<\/em> et des tueurs du Brabant.<\/p>\n<\/p>\n<p><p>\tL&rsquo;UE prend donc les dispositions qu&rsquo;il faut. Elle ne fera pas d&rsquo;enqu\u00eate, cette id\u00e9e-l\u00e0 est insultante. Elle interrogera les uns et les autres pour avoir confirmation de son id\u00e9e premi\u00e8re: tout cela n&rsquo;a pas de sens, on est entre gens d&rsquo;honneur.<\/p>\n<\/p>\n<p><p>\tBien, quittons ces zones peu rago\u00fbtantes. Le fait reste, indissoluble, que les pays concern\u00e9s ont subi un vilain choc. La casserole leur restera attach\u00e9e \u00e0 la queue, encore discr\u00e8te mais qui peut devenir tintamarresque si un dissident quelconque, ou un officier de la CIA qui a des bleus \u00e0 l&rsquo;\u00e2me, sortait sur <em>Internet<\/em> des photos in\u00e9dites d&rsquo;un ou l&rsquo;autre de ces <em>black site<\/em> mal situ\u00e9s. Les Fran\u00e7ais geignent continuellement \u00e0 propos de l&rsquo;isolement de la France en Europe. Qu&rsquo;ils consid\u00e8rent le cas polonais \u00e0 l&rsquo;aune du g\u00e9missement de Janusz Onyszkiewicz: l&rsquo;existence de tels centres de torture \u00ab <em>would do enormous damage to Poland&rsquo;s image<\/em> \u00bb. En fait, l&rsquo;universelle pr\u00e9somption de culpabilit\u00e9, qui est malheureusement la ran\u00e7on du maniement universel du mensonge (il faut s&rsquo;en plaindre \u00e0 qui de droit), fait penser que, d&rsquo;ores et d\u00e9j\u00e0, l&rsquo;\u00ab <em>enormous damage to Poland&rsquo;s image<\/em> \u00bb est d\u00e9j\u00e0 fait et que la plainte solitaire de Onyszkiewicz (\u00ab <em>We already suffer from being America&rsquo;s Trojan donkey in Europe<\/em> \u00bb) n&rsquo;en sera que plus fun\u00e8bre.<\/p>\n<\/p>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>UE, CIA et vertu europ\u00e9enne: damage control 5 novembre 2005 Nous avons eu un instant, un tr\u00e8s court instant, la tentation de nuancer notre texte F&#038;C d&rsquo;hier sur les camps de torture de la CIA en Roumanie et en Pologne. Nous avons rapidement \u00e9cart\u00e9 cette tentation. Tr\u00e8s vite, il nous est apparu qu&rsquo;il importait de&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[3126,2827,2720,4812],"class_list":["post-66985","post","type-post","status-publish","format-standard","hentry","category-faits-et-commentaires","tag-black","tag-pologne","tag-roumanie","tag-sites"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/66985","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=66985"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/66985\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=66985"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=66985"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=66985"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}