{"id":66989,"date":"2005-11-06T00:00:00","date_gmt":"2005-11-06T00:00:00","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2005\/11\/06\/le-jsf-des-britts-cloisonnements-et-trahison\/"},"modified":"2005-11-06T00:00:00","modified_gmt":"2005-11-06T00:00:00","slug":"le-jsf-des-britts-cloisonnements-et-trahison","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2005\/11\/06\/le-jsf-des-britts-cloisonnements-et-trahison\/","title":{"rendered":"Le JSF des <em>Britts<\/em>, \u2014 cloisonnements et trahison"},"content":{"rendered":"<p><p>Le mois dernier, la Chambre des Communes entendait diverses personnalit\u00e9s am\u00e9ricaines \u00e0 propos du programme JSF. Tom Burbage, VP de Lockheed Martin et General Manager du programme pr\u00e9cisait notamment ceci, selon <a href=\"http:\/\/www.aviationnow.com\/\" class=\"gen\">Aviation Week &#038; Space Technology<\/a> du 31 octobre : \u00ab <em>The possibility that the UK would not only provide maintenance support for its own F-35B, but also those of the U.S. Marine Corps, was confirmed by Tom Burbage<\/em> \u00bb<\/p>\n<\/p>\n<p><p>\tLe cas est essentiel. Les Britanniques cherchent d\u00e9sesp\u00e9r\u00e9ment \u00e0 s&rsquo;assurer du contr\u00f4le de leurs propres JSF, notamment en obtenant les capacit\u00e9s de contr\u00f4le \u00e9lectronique (code-source) pour la maintenance et l&rsquo;entretien de leurs appareils durant leur vie op\u00e9rationnelle. C&rsquo;est ce qu&rsquo;ils nomment <em>Operational Sovereignty<\/em>\u00bb (OS). (On peut voir une critique pessimiste de cette possibilit\u00e9 du contr\u00f4le de l&rsquo;OS dans le rapport North, auquel il est fait r\u00e9f\u00e9rence dans notre texte <a href=\"http:\/\/www.dedefensa.org\/article.php?art_id=2080\" class=\"gen\">Analyse du 20 octobre<\/a>)<\/p>\n<\/p>\n<p><p>\tLa possibilit\u00e9 \u00e9voqu\u00e9e par Burbage concerne effectivement le F-35B, la version \u00e0 atterrissage et d\u00e9collage verticaux (STOVL). Cette version avait r\u00e9cemment \u00e9t\u00e9 renforc\u00e9e par l&rsquo;int\u00e9r\u00eat de l&rsquo;USAF d&rsquo;en acqu\u00e9rir un certain nombre, dans la commande g\u00e9n\u00e9rale de JSF qu&rsquo;elle envisage. Les Britanniques jouent donc sur l&rsquo;hypoth\u00e8se que le F-35B est pratiquement verrouill\u00e9 avec l&rsquo;engagement de l&rsquo;USAF en plus du Marine Corps. Le point est vital. Les Britanniques savent (et s&rsquo;ils ne le savent pas, on le leur dit) qu&rsquo;ils n&rsquo;ont aucune chance d&rsquo;obtenir les codes-source n\u00e9cessaires pour le contr\u00f4le OS de leurs JSF s&rsquo;ils \u00e9taient oblig\u00e9s d&rsquo;acqu\u00e9rir une version conventionnelle\/CTOL (Navy F-35C pour la version embarqu\u00e9e, USAF F-35A \u00e9ventuellement pour la RAF),  en cas d&rsquo;abandon du F-35B.<\/p>\n<\/p>\n<p><p>\tAbandon du F-35B? Hmm hmm Dans le m\u00eame num\u00e9ro d&rsquo;<em>Aviation Week<\/em>, dans la rubrique <em>Washington Ouylook<\/em>, il nous est dit ceci: \u00ab <em>Under then-Chief of Staff Gen. John Jumper&rsquo;s watch, the Air Force was courting the idea of buying the STOVL variant and diminushing its buy of conventional (CTOL) F-35s. Only weeks after succeeding Jumper however, Gen. T. Michael (Buzz) Moseley is mulling an all-CTOL buy. In the meantime, observers say acting Deputy Defense Secretary Gordon England may be looking to kill one JSF variant as a way to curb the increasing cost of procurement effort.<\/em> \u00bb<\/p>\n<\/p>\n<p><p>\tR\u00e9fl\u00e9chissez: L&rsquo;USAF laisse tomber le STOVL pour une commande uniquement de la version CTOL (F-35A). England envisage d&rsquo;abandonner une version du JSF. Difficile de ne pas \u00e9tablir un rapport de cause \u00e0 effet. Si le Pentagone abandonne le F-35B (STOVL), finis les code-sources pour les <em>Britts<\/em>,  s&rsquo;il en fut jamais question, d&rsquo;ailleurs. Merci, Mr. Burbage, pour l&rsquo;int\u00e9ressant t\u00e9moignage devant les Communes,  et Robert North,  <a href=\"http:\/\/www.dedefensa.org\/article.php?art_id=2080\" class=\"gen\">pas si b\u00eate<\/a>.<\/p>\n<\/p>\n<p><p>\tTout cela, en attendant la prochaine rumeur et la prochaine trahison.    <\/p>\n<\/p>\n<p><\/p>\n<p><p>\tMis en ligne le 6 novembre \u00e0 08H20<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le mois dernier, la Chambre des Communes entendait diverses personnalit\u00e9s am\u00e9ricaines \u00e0 propos du programme JSF. Tom Burbage, VP de Lockheed Martin et General Manager du programme pr\u00e9cisait notamment ceci, selon Aviation Week &#038; Space Technology du 31 octobre : \u00ab The possibility that the UK would not only provide maintenance support for its own&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[2],"tags":[4817,4818],"class_list":["post-66989","post","type-post","status-publish","format-standard","hentry","category-bloc-notes","tag-burbage","tag-f35"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/66989","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=66989"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/66989\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=66989"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=66989"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=66989"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}