{"id":66994,"date":"2005-11-07T00:00:00","date_gmt":"2005-11-07T00:00:00","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2005\/11\/07\/quelques-verite-nucleaires-et-britanniques\/"},"modified":"2005-11-07T00:00:00","modified_gmt":"2005-11-07T00:00:00","slug":"quelques-verite-nucleaires-et-britanniques","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2005\/11\/07\/quelques-verite-nucleaires-et-britanniques\/","title":{"rendered":"Quelques v\u00e9rit\u00e9 nucl\u00e9aires et britanniques"},"content":{"rendered":"<p><p>Il y a une longue analyse de la situation de la puissance nucl\u00e9aire britannique dans la perspective du d\u00e9bat pol\u00e9mique du remplacement des missiles strat\u00e9giques (SLBM) <em>Trident<\/em>, dans <a href=\"http:\/\/news.independent.co.uk\/uk\/politics\/article325156.ece\" class=\"gen\">The Independent d&rsquo;hier<\/a>.<\/p>\n<\/p>\n<p><p>\tLong d\u00e9bat, r\u00e9flexions int\u00e9ressantes, avec les arguments pour et contre. Que vaut le nucl\u00e9aire aujourd&rsquo;hui? Est-il encore dissuasif, et de quoi? Ne faut-il pas changer sa structure ? Ne faut-il pas l&rsquo;abandonner? Et ainsi de suite: rien de bouleversant mais une bonne mise en perspective. Encore notera-t-on l&rsquo;absence des arguments essentiels, sur la souverainet\u00e9 nationale, sur l&rsquo;influence, sur le poids diplomatique, etc  Cette faiblesse, dont la cause nous est bien expliqu\u00e9e par la derni\u00e8re phrase, aussi abrupte que cela, qui cl\u00f4t m\u00e9chamment le d\u00e9bat sur le remplacement du <em>Trident<\/em>, sur le mode cessons donc de jouer: \u00ab <em>we will wait and see what America does. Then copy it.<\/em> \u00bb<\/p>\n<\/p>\n<p><p>\tEn effet, le d\u00e9bat se r\u00e9sume \u00e0 cette conclusion, qui vaut qu&rsquo;on publie les quatre derniers paragraphes de l&rsquo;article. Ils donnent une bonne mesure de la mis\u00e8re britannique, de la mis\u00e8re de la dignit\u00e9 nationale de cette grande nation qu&rsquo;est l&rsquo;Angleterre.<\/p>\n<\/p>\n<p><p>\t\u00ab <em>At least decisions will be made relatively publicly this time: Trident was commissioned in secret, as a replacement for Polaris. Two other factors have also changed since 1980. The British government, influenced by America, has dropped its long-held policy of never striking first. And the myth of Britain having an independent nuclear deterrent has been exposed.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb <em>The myth was built on memories of Britain standing alone against the enemy in 1940. But that could only be repeated if the UK fell out with the USA  and if such a thing happened, America could shut down the British Trident force within 18 months, simply by refusing to co-operate.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb <em>The blueprints, engines, fuel and guidance systems are American. Lockheed-Martin, a US corporation, is one of the three companies managing Aldermaston. Washington knows where that elusive British submarine on patrol today is hiding, and where it&rsquo;s going. The missiles can&rsquo;t be fired without information from American satellites.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb <em>So MPs can rage all they like about not getting a vote, and the Prime Minister can warm his hands on Britain&rsquo;s apparent status as a nuclear power, but when it comes to replacing Trident, whatever the cost, one outcome is more likely than anything else: we will wait and see what America does. Then copy it.<\/em> \u00bb<\/p>\n<\/p>\n<p><\/p>\n<p><p>\tMis en ligne le 7 novembre 2005 \u00e0 09H41<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il y a une longue analyse de la situation de la puissance nucl\u00e9aire britannique dans la perspective du d\u00e9bat pol\u00e9mique du remplacement des missiles strat\u00e9giques (SLBM) Trident, dans The Independent d&rsquo;hier. Long d\u00e9bat, r\u00e9flexions int\u00e9ressantes, avec les arguments pour et contre. Que vaut le nucl\u00e9aire aujourd&rsquo;hui? Est-il encore dissuasif, et de quoi? Ne faut-il pas&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[2],"tags":[3004,3345,3344,4775],"class_list":["post-66994","post","type-post","status-publish","format-standard","hentry","category-bloc-notes","tag-nucleaire","tag-relationships","tag-special","tag-trident"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/66994","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=66994"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/66994\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=66994"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=66994"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=66994"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}