{"id":67041,"date":"2005-11-24T00:00:00","date_gmt":"2005-11-24T00:00:00","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2005\/11\/24\/et-la-pologne-sinquiete-elle-meme\/"},"modified":"2005-11-24T00:00:00","modified_gmt":"2005-11-24T00:00:00","slug":"et-la-pologne-sinquiete-elle-meme","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2005\/11\/24\/et-la-pologne-sinquiete-elle-meme\/","title":{"rendered":"\u2026 Et la Pologne s&rsquo;inqui\u00e8te elle-m\u00eame"},"content":{"rendered":"<p><p>Pour compl\u00e9ter <a href=\"http:\/\/www.dedefensa.org\/article.php?art_id=2185\" class=\"gen\">les pr\u00e9c\u00e9dentes remarques<\/a>, en s\u00e9parant bien les deux questions pour mieux mettre en \u00e9vidence la contradiction, il y a la question des rapports de la Pologne avec les USA. Ce soutien appara\u00eet \u00e9galement paradoxal, cette fois dans le chef des Polonais eux-m\u00eames tels qu&rsquo;ils nous apparaissent d\u00e9sormais. Traditionalistes, nationalistes et souverains, c&rsquo;est-\u00e0-dire appuy\u00e9s sur des structures tr\u00e8s fortes, les Polonais soutiennent une politique dont l&rsquo;orientation g\u00e9n\u00e9rale est celle d&rsquo;une attaque des souverainet\u00e9s et d&rsquo;une d\u00e9structuration des traditions. A plus ou moins longue \u00e9ch\u00e9ance, les Polonais vont se trouver confront\u00e9s \u00e0 cette contradiction.<\/p>\n<\/p>\n<p><p>\tEn attendant, autre paradoxe, la premi\u00e8re critique des milieux europ\u00e9ens contre les Polonais (leur traditionalisme) am\u00e8ne naturellement une autre critique contre leur alignement sur les USA. C&rsquo;est un paradoxe puisque les milieux europ\u00e9ens qui \u00e9mettent cette critique sont eux-m\u00eames pro-US et align\u00e9s sur les USA.<\/p>\n<\/p>\n<p><p>\tD&rsquo;o\u00f9 cette remarque, extraite <a href=\"http:\/\/www.iht.com\/articles\/2005\/11\/23\/news\/poland.php\" class=\"gen\">du m\u00eame article<\/a>, o\u00f9 l&rsquo;on voit les Polonais critiqu\u00e9s pour leur pro-am\u00e9ricanisme par une d\u00e9put\u00e9e britannique \u00ab <em>Concerns about American influence on Warsaw grew this month when Human Rights Watch charged that Poland was a host country in a network of secret CIA prisons for suspected terrorists. EU foreign ministers agreed Monday to write to the United States to seek clarification.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb <em>We need to put a protective wing around some of our new countries that are quite unused to U.S. bullying, said Sara Ludford, a Liberal member of the European Parliament from Britain, referring to the alleged covert prisons.<\/em> \u00bb<\/p>\n<\/p>\n<p><\/p>\n<p><p>\tMis en ligne le 24 novembre 2005 \u00e0 08H50<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Pour compl\u00e9ter les pr\u00e9c\u00e9dentes remarques, en s\u00e9parant bien les deux questions pour mieux mettre en \u00e9vidence la contradiction, il y a la question des rapports de la Pologne avec les USA. Ce soutien appara\u00eet \u00e9galement paradoxal, cette fois dans le chef des Polonais eux-m\u00eames tels qu&rsquo;ils nous apparaissent d\u00e9sormais. Traditionalistes, nationalistes et souverains, c&rsquo;est-\u00e0-dire appuy\u00e9s&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[2],"tags":[],"class_list":["post-67041","post","type-post","status-publish","format-standard","hentry","category-bloc-notes"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/67041","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=67041"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/67041\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=67041"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=67041"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=67041"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}