{"id":67055,"date":"2005-11-28T00:00:00","date_gmt":"2005-11-28T00:00:00","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2005\/11\/28\/recriture-de-lhistoire-style-neocon\/"},"modified":"2005-11-28T00:00:00","modified_gmt":"2005-11-28T00:00:00","slug":"recriture-de-lhistoire-style-neocon","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2005\/11\/28\/recriture-de-lhistoire-style-neocon\/","title":{"rendered":"R\u00e9criture de l&rsquo;Histoire, style \u201c<em>neocon<\/em>\u201d"},"content":{"rendered":"<p><p>Dans le <a href=\"http:\/\/www.dedefensa.org\/article.php?art_id=2199\" class=\"gen\">F&#038;C du jour<\/a> o\u00f9 nous traitons de la p\u00e9n\u00e9tration des n\u00e9o-conservateurs en Europe, les interventions du ministre de la d\u00e9fense polonais Sikorski m\u00e9ritent quelques commentaires sur le fond de l&rsquo;intervention qui est d\u00e9crite. Dans <a href=\"http:\/\/www.iht.com\/articles\/2005\/11\/25\/opinion\/poland.php\" class=\"gen\">le texte du Herald Tribune cit\u00e9<\/a>, Sikorski cite l&rsquo;exemple d&rsquo;un exercice planifi\u00e9 par les Russes en 1979, qui sacrifie la Pologne. Il explicite son intervention par ce jugement : \u00ab <em>It is important for people to know who was the hero and who was the villain.<\/em> \u00bb<\/p>\n<\/p>\n<p><p>\tVoici le passage sur cet exercice :  \u00ab <em>At a press conference Friday, Sikorski unveiled a map showing hypothetical plans in the event of a NATO attack on Warsaw Pact nations which called for a Soviet counterattack that would have included the nuclear bombing of Munich, Brussels, Dutch ports and other targets. This in turn, according to Soviet military thinking, would precipitate NATO nuclear attacks on forces concentrated on the Vistula River, attacks that the Polish government now estimates would have killed two million Poles.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb <em>The map showed the widespread destruction of Western Europe, including mushroom clouds over key areas of Germany, Belgium, the Netherlands and Denmark. Cities such as Brussels would have been destroyed as Soviet troops advanced to the Western shores of the Continent, although Britain and France would have been left unscathed.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb <em>Poland was being asked to participate in an operation that may have resulted in the destruction of Poland, said Sikorski, who came into the government from the American Enterprise Institute, a conservative research group in Washington.<\/em> \u00bb<\/p>\n<\/p>\n<p><p>\tUn commentaire en forme de deux questions a sa place ici:<\/p>\n<\/p>\n<p><p>\t&bull; Pourquoi Sikorski ne signale-t-il pas, en plus des vilains qu&rsquo;il d\u00e9nonce (les Sovi\u00e9tiques, qui contr\u00f4l\u00e8rent la Pologne durant la guerre froide), Churchill et Roosevelt qui c\u00e9d\u00e8rent le contr\u00f4le de la Pologne \u00e0 Staline \u00e0 Yalta, en f\u00e9vrier 1945, et s&rsquo;av\u00e8rent ainsi les vilains originels?<\/p>\n<\/p>\n<p><p>\t&bull; Au vu de la description de la manuvre qui sacrifie la Pologne (\u00e0 cause d&rsquo;une contre-attaque de l&rsquo;OTAN, suite \u00e0 une contre-attaque du Pacte, suite \u00e0 une attaque de l&rsquo;OTAN,  c&rsquo;\u00e9tait l\u00e0 le sc\u00e9nario), pourquoi ne note-t-il pas \u00e9galement que l&rsquo;OTAN, c&rsquo;est-\u00e0-dire les Am\u00e9ricains comme le Pacte c&rsquo;\u00e9taient les Sovi\u00e9tiques, sacrifie de son c\u00f4t\u00e9 la Belgique, les Pays-Bas, l&rsquo;Allemagne et le Danemark, attaqu\u00e9s nucl\u00e9airement par le Pacte (l&rsquo;URSS) suite \u00e0 une attaque de l&rsquo;OTAN?<\/p>\n<\/p>\n<p><\/p>\n<p><p>\tMis en ligne le 28 novembre 2005 \u00e0 15H50<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dans le F&#038;C du jour o\u00f9 nous traitons de la p\u00e9n\u00e9tration des n\u00e9o-conservateurs en Europe, les interventions du ministre de la d\u00e9fense polonais Sikorski m\u00e9ritent quelques commentaires sur le fond de l&rsquo;intervention qui est d\u00e9crite. Dans le texte du Herald Tribune cit\u00e9, Sikorski cite l&rsquo;exemple d&rsquo;un exercice planifi\u00e9 par les Russes en 1979, qui sacrifie&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[2],"tags":[2631,584,3209,2827,4862,3210],"class_list":["post-67055","post","type-post","status-publish","format-standard","hentry","category-bloc-notes","tag-de","tag-otan","tag-pacte","tag-pologne","tag-sikorski","tag-varsovie"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/67055","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=67055"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/67055\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=67055"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=67055"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=67055"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}