{"id":67057,"date":"2005-11-28T00:00:00","date_gmt":"2005-11-28T00:00:00","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2005\/11\/28\/journal-de-bord-de-dedefensaorg-051128-campagne-de-soutien-en-vitesse-de-croisiere\/"},"modified":"2005-11-28T00:00:00","modified_gmt":"2005-11-28T00:00:00","slug":"journal-de-bord-de-dedefensaorg-051128-campagne-de-soutien-en-vitesse-de-croisiere","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2005\/11\/28\/journal-de-bord-de-dedefensaorg-051128-campagne-de-soutien-en-vitesse-de-croisiere\/","title":{"rendered":"Journal de bord de dedefensa.org \u2014 051128, campagne de soutien en vitesse de croisi\u00e8re"},"content":{"rendered":"<p><p>28 novembre 2005 <\/p>\n<\/p>\n<p><p>\tUn court message pour signaler\/rappeler \u00e0 nos lecteurs que la campagne d&rsquo;appel \u00e0 donation\/de soutien \u00e0 notre site <em>dedefensa.org<\/em>, si elle a cess\u00e9 dans sa phase active, avec le grand bandeau de t\u00eate de page, continue disons en r\u00e9gime de croisi\u00e8re.<\/p>\n<\/p>\n<p><p>\tVous avez deux acc\u00e8s \u00e0 la page de souscription, soit en t\u00eate de page sur le petit cadre <em>dedefensa.org  campagne de soutien<\/em> situ\u00e9 \u00e0 droite en face de notre manchette <em>dedefensa.org<\/em> ; soit dans le sommaire g\u00e9n\u00e9ral, dans la colonne de gauche indicative des rubriques, \u00e0 la rubrique Donation. Ces deux liens vous m\u00e8nent donc <a href=\"http:\/\/www.dedefensa.org\/donation.php\" class=\"gen\">\u00e0 la page donation<\/a>, avec les formules de paiement disponibles.<\/p>\n<\/p>\n<p><p>\tIl y a aussi le lien <a href=\"https:\/\/www.paypal.com\/cgi-bin\/webscr\" class=\"gen\">Paypal<\/a>, qui m\u00e8ne au seul mode de paiement Paypal. Avec tout cela, il vous est difficile de dire que vous ne saviez pas comment faire!<\/p>\n<\/p>\n<p><p>\tNous vous rappelons <a href=\"http:\/\/www.dedefensa.org\/article.php?art_id=2190\" class=\"gen\">notre pr\u00e9c\u00e9dent message<\/a>, o\u00f9 nous vous donnions les r\u00e9sultats de notre campagne de promotion active. Nous allons r\u00e9fl\u00e9chir un certain temps \u00e0 ce premier essai qui n&rsquo;est pas vraiment le coup de ma\u00eetre esp\u00e9r\u00e9, pour mieux pr\u00e9parer d&rsquo;autres campagnes et vous convaincre de participer plus activement.<\/p>\n<\/p>\n<p><p>\t&bull; <em>Nota Bene<\/em>: nous avons eu quelques difficult\u00e9s r\u00e9cemment dans l&rsquo;alimentation de notre rubrique Forum. Certains messages qui devraient y figurer ne s&rsquo;y trouvent pas. Nous sommes en train de venir \u00e0 bout de ces difficult\u00e9s. Un rappel \u00e0 nos lecteurs: quand vous donnez le commentaire d&rsquo;un texte pr\u00e9cis, veillez \u00e0 utiliser le message de r\u00e9action directement li\u00e9 \u00e0 ce texte (en-dessus du texte, dans le bandeau rappellant le titre et la date du texte).<\/p>\n<\/p>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>28 novembre 2005 Un court message pour signaler\/rappeler \u00e0 nos lecteurs que la campagne d&rsquo;appel \u00e0 donation\/de soutien \u00e0 notre site dedefensa.org, si elle a cess\u00e9 dans sa phase active, avec le grand bandeau de t\u00eate de page, continue disons en r\u00e9gime de croisi\u00e8re. Vous avez deux acc\u00e8s \u00e0 la page de souscription, soit en&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[9],"tags":[],"class_list":["post-67057","post","type-post","status-publish","format-standard","hentry","category-messagerie"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/67057","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=67057"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/67057\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=67057"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=67057"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=67057"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}