{"id":67067,"date":"2005-12-02T00:00:00","date_gmt":"2005-12-02T00:00:00","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2005\/12\/02\/tony-blair-et-les-necessites-de-la-geographie\/"},"modified":"2005-12-02T00:00:00","modified_gmt":"2005-12-02T00:00:00","slug":"tony-blair-et-les-necessites-de-la-geographie","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2005\/12\/02\/tony-blair-et-les-necessites-de-la-geographie\/","title":{"rendered":"<strong><em>Tony Blair et les n\u00e9cessit\u00e9s de la g\u00e9ographie<\/em><\/strong>"},"content":{"rendered":"<p><h2 class=\"common-article\">Tony Blair et les n\u00e9cessit\u00e9s de la g\u00e9ographie<\/h2>\n<\/p>\n<p><\/p>\n<p><p>\t2 d\u00e9cembre 2005  Avec des tonalit\u00e9s diff\u00e9rentes pour arranger la pr\u00e9sentation de l&rsquo;\u00e9v\u00e9nement, la presse britannique pr\u00e9sente la derni\u00e8re d\u00e9cision du gouvernement Blair, cette nuit, pour ce qu&rsquo;elle est : une capitulation diplomatique pour tenter d&rsquo;arracher un accord sur le budget de l&rsquo;UE qui sauve la pr\u00e9sidence britannique du d\u00e9sastre,  mieux vaut la d\u00e9faite que le d\u00e9sastre Le <a href=\"http:\/\/www.timesonline.co.uk\/article\/0,,17129-1900614,00.html\" class=\"gen\">Times de Londres<\/a> d\u00e9crit de cette fa\u00e7on la d\u00e9cision britannique d&rsquo;une concession unilat\u00e9rale sur le ch\u00e8que britannique (<em>dixit<\/em> les <em>Frenchs<\/em>, pour l&rsquo;expression):  \u00ab <em>The admission that the current budget system is too favourable to Britain is a dramatic U-turn for the Government, which had previously maintained that the rebate remains fully justified because the UK gets so little from farm subsidies.<\/em> \u00bb<\/p>\n<\/p>\n<p><p>\tCette d\u00e9cision marque aussi (pour ceux qui y ont cru) l&rsquo;abandon officiel des grands espoirs proclam\u00e9s par Blair au d\u00e9but de sa pr\u00e9sidence. Selon le <a href=\"http:\/\/politics.guardian.co.uk\/eu\/story\/0,9061,1655990,00.html\" class=\"gen\">Guardian<\/a>, \u00ab <em>Tony Blair last night abandoned hopes of major reform of the EU budget when he admitted he will unilaterally cut Britain&rsquo;s historic \u00a33bn-a-year budget rebate if it proves necessary to clinch a compromise deal at next month&rsquo;s Brussels summit.<\/em> \u00bb Mais disons la chose de fa\u00e7on un peu plus abrupte et n\u00e9cessairement plus juste, en empruntant son commentaire \u00e0 un diplomate europ\u00e9en cit\u00e9 par le quotidien: \u00ab<D> Mr Blair <D>[is] paying the price for raising expectations then failing to deliver. His speech in Brussels in June about Europe&rsquo;s future was a hopeful moment. He has become a victim of his own spin. This looks like being the worst British presidency in history.<D> \u00bb<\/p>\n<\/p>\n<p><p>\tL&rsquo;int\u00e9r\u00eat suppl\u00e9mentaire de cette derni\u00e8re remarque est qu&rsquo;elle date <a href=\"http:\/\/politics.guardian.co.uk\/eu\/comment\/0,9236,1654725,00.html\" class=\"gen\">d&rsquo;hier<\/a>, avant la d\u00e9cision britannique de cette nuit qui est l&rsquo;aveu complet de la description que fait ce diplomate. Elle r\u00e9sume le drame de Tony Blair, avec le contraste entre les mots,  entre <em>a hopeful moment<\/em>, pour d\u00e9signer son discours, et <em>a victim of his own spin<\/em> pour d\u00e9signer le sort de Blair apr\u00e8s cette entame de la pr\u00e9sidence britannique. Nous y sommes : aujourd&rsquo;hui, l&rsquo;espoir n&rsquo;est plus que du vulgaire <em>spin<\/em> et l&rsquo;effet grandiose du mois de juin conduit \u00e0 la mis\u00e8re de la d\u00e9cision de d\u00e9cembre. A qui la faute (qui s&rsquo;est fait roi en instituant le <em>spin<\/em> comme substance de l&rsquo;espoir?).<\/p>\n<\/p>\n<p><p>\tLe reste est \u00e0 l&rsquo;avenant dans les divers commentaires.<\/p>\n<\/p>\n<p><p>\t&bull; De cette \u00e9trange pr\u00e9sidence britannique, d\u00e9marr\u00e9e dans le grandiose et termin\u00e9e dans la capitulation, il faut d&rsquo;abord accepter l&rsquo;explication du Premier ministre britannique qui s&rsquo;est mis lui-m\u00eame dans une position si difficile. La faiblesse int\u00e9rieure qui suscite les rodomontades \u00e0 l&rsquo;ext\u00e9rieur et conduisent \u00e0 la capitulation ext\u00e9rieure pour ne pas finalement succomber chez soi,  tentative d\u00e9sesp\u00e9r\u00e9e d&rsquo;ailleurs, et certains ne donneront vite plus cher de la peau d&rsquo;un Blair qui eut, la nuit derni\u00e8re, \u00e0 choisir entre Charybde et Scylla: \u00ab <em>He has just suffered his first defeat in the Commons since he became prime minister. This has given rise to a flurry of speculation that he may leave office sooner rather than later  and there are people, including those in his own party, who actually want him to leave early. There are even some MPs who would not be averse to engineering further defeats in the Commons in order to make his position untenable. So Blair knows that the outcome of a budget deal could therefore be crucial for his survival as prime minister&#8230;<\/em> \u00bb<\/p>\n<\/p>\n<p><p>\t&bull; L&rsquo;\u00e9vidence \u00e9clate aujourd&rsquo;hui que le Royaume-Uni qui emportait l&rsquo;Europe dans sa besace en juin alors que tous les commentateurs (tiens, surtout fran\u00e7ais) trempaient leur plume dans l&rsquo;extase pour acclamer Blair est dans une position tr\u00e8s difficile en Europe. Ce commentaire de Simon Tisdall hier, avant la d\u00e9cision de cette nuit, le dit assez bien, avec l&#8217;emploi du mot <em>isolated<\/em> qu&rsquo;on r\u00e9serve d&rsquo;habitude \u00e0 la France : \u00ab <em>But even this might not be enough. Despite the attractions of backbench cheers in December, there is no doubt that Blair genuinely wants a deal to be made. He is conscious of his European responsibilities and only too aware of how isolated Britain would seem if it were regarded as the main cause of a breakdown in a second European summit.<\/em> \u00bb<\/p>\n<\/p>\n<p><p>\t&bull; Les Fran\u00e7ais, <a href=\"http:\/\/politics.guardian.co.uk\/eu\/story\/0,9061,1656056,00.html\" class=\"gen\">Chirac surtout<\/a>, sont d\u00e9crits comme vainqueurs dans cette bataille: \u00ab <em>Jacques Chirac&rsquo;s annus horribilis, which has seen the most severe riots in France for a generation, could be about to end on a positive note. <\/em>[&#8230;] <em>Mr Chirac, who has struggled to assert his authority since French voters rejected the EU constitution in May, is likely to congratulate himself for trapping Britain over the past three years.<\/em> \u00bb<\/p>\n<\/p>\n<p><p>\t&#8230; Mais non, ce n&rsquo;est pas Chirac qui a pi\u00e9g\u00e9 Blair. Le Britannique s&rsquo;est arrang\u00e9 tout seul pour se tirer dans le pied, cette manuvre si maladroite compl\u00e8tement indigne d&rsquo;un homme politique britannique. Il faut \u00e9largir le d\u00e9bat, le sortir de l&rsquo;agriculture et du ch\u00e8que britannique pour le mettre \u00e0 sa vraie dimension : le climat, les grands courants qui conditionnent les jugements et les perceptions.<\/p>\n<\/p>\n<p><p>\tL&rsquo;\u00e9pouvantable position o\u00f9 se trouve aujourd&rsquo;hui le Royaume-Uni a sa source dans l&rsquo;absurde politique du Premier ministre, son alignement inconditionnel sur les Etats-Unis dont il ne tire aucun avantage sinon celui de pouvoir faire un peu plus de <em>spin<\/em>,  d\u00e9cid\u00e9ment son activit\u00e9 favorite. L&rsquo;isolement britannique actuel et la faiblesse de la position de Tony Blair, rendus encore plus dramatiques aujourd&rsquo;hui par les rodomontades d&rsquo;hier (le discours de juin), elles-m\u00eames n\u00e9cessaires alors pour dissimuler ces faiblesses,  tout cela s&rsquo;est form\u00e9 et n&rsquo;a cess\u00e9 de s&rsquo;aggraver ces quatre derni\u00e8res ann\u00e9es \u00e0 cause de la politique d&rsquo;alignement britannique sur Washington. C&rsquo;est la cr\u00e9ation du seul Blair ; c&rsquo;est son illumination, sa lubie, sa certitude fausse De 1998 (accord de Saint-Malo) \u00e0 2001, les Britanniques s&rsquo;\u00e9taient forg\u00e9s une situation int\u00e9ressante en Europe, en mettant en place <em>de facto<\/em> une alliance privil\u00e9gi\u00e9e avec la principale puissance (la France) dans le principal domaine (la d\u00e9fense). Cet acquis politique a \u00e9t\u00e9 scandaleusement cochonn\u00e9, pulv\u00e9ris\u00e9, par la politique aveugl\u00e9ment pro-am\u00e9ricaine de Blair jusqu&rsquo;\u00e0 l&rsquo;enlisement dans l&rsquo;infamie irakienne. Blair le grand Europ\u00e9en a succomb\u00e9 \u00e0 l&rsquo;<em>hubris<\/em> anglo-saxon, au <a href=\"http:\/\/www.dedefensa.org\/article.php?art_id=2141\" class=\"gen\">glamour<\/a> de la soi-disant puissance US repr\u00e9sent\u00e9e par l&rsquo;ineffable GW. Ce temps historique est une farce.<\/p>\n<\/p>\n<p><p>\tLa g\u00e9ographie, elle, reste ce qu&rsquo;elle est. Si l&rsquo;Angleterre est une \u00eele, elle est vraiment tr\u00e8s proche de l&rsquo;Europe. C&rsquo;est un enseignement de cette terrible fin d&rsquo;une pr\u00e9sidence britannique de l&rsquo;UE qui ajoute (du point de vue britannique) l&rsquo;ignominie \u00e0 l&rsquo;impuissance sur fond d&rsquo;ignorance de la g\u00e9ographie.<\/p>\n<\/p>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tony Blair et les n\u00e9cessit\u00e9s de la g\u00e9ographie 2 d\u00e9cembre 2005 Avec des tonalit\u00e9s diff\u00e9rentes pour arranger la pr\u00e9sentation de l&rsquo;\u00e9v\u00e9nement, la presse britannique pr\u00e9sente la derni\u00e8re d\u00e9cision du gouvernement Blair, cette nuit, pour ce qu&rsquo;elle est : une capitulation diplomatique pour tenter d&rsquo;arracher un accord sur le budget de l&rsquo;UE qui sauve la pr\u00e9sidence&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[705,4875,4874,779,4820,3045,2609,2804],"class_list":["post-67067","post","type-post","status-publish","format-standard","hentry","category-faits-et-commentaires","tag-blair","tag-britannique","tag-cheque","tag-chirac","tag-glamour","tag-sommet","tag-ue","tag-usa"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/67067","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=67067"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/67067\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=67067"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=67067"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=67067"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}