{"id":67077,"date":"2005-12-06T00:00:00","date_gmt":"2005-12-06T00:00:00","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2005\/12\/06\/panicus-britannicus\/"},"modified":"2005-12-06T00:00:00","modified_gmt":"2005-12-06T00:00:00","slug":"panicus-britannicus","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2005\/12\/06\/panicus-britannicus\/","title":{"rendered":"<strong><em>\u201cPanicus Britannicus\u201d<\/em><\/strong>"},"content":{"rendered":"<p><h2 class=\"common-article\"><em>Panicus Britannicus<\/em><\/h2>\n<\/p>\n<p><\/p>\n<p><p>\t6 novembre 2005  Les Britanniques sont, sur les sujets sensibles, lorsqu&rsquo;il s&rsquo;agit des Etats-Unis, assez lents et surtout tr\u00e8s prudents et tr\u00e8s discrets. A un moment, pourtant, cette prudence et cette discr\u00e9tion ne sont plus de mise. Quant \u00e0 la lenteur, on doit s&rsquo;en passer lorsque le temps commence \u00e0 presser. Avec tout cela, on d\u00e9finit le cas du JSF et ce moment o\u00f9 l&rsquo;attitude britannique commence \u00e0 ressembler \u00e0 une panique convenable.<\/p>\n<\/p>\n<p><p>\tAvec ce qu&rsquo;il faut de doigt\u00e9 britannique, les r\u00e9centes (30 novembre) d\u00e9clarations du chef des acquisitions au MoD, Lord Drayson, signalent qu&rsquo;on entre dans la zone des temp\u00eates au bout de laquelle une d\u00e9cision devra \u00eatre prise. (Ces d\u00e9clarations sont \u00e9galement signal\u00e9es et comment\u00e9es dans un article de <a href=\"http:\/\/www.defensenews.com\/story.php?F=1389602&#038;C=thisweek\" class=\"gen\">Defense News<\/a> du 5 d\u00e9cembre.) Cette d\u00e9cision se r\u00e9duit \u00e0 une alternative :<\/p>\n<\/p>\n<p><p>\t&bull; Les Am\u00e9ricains doivent transf\u00e9rer aux Britanniques les codes-source et certaines technologies fondamentales pour leur permettre de disposer de leurs propres JSF en toute souverainet\u00e9.<\/p>\n<\/p>\n<p><p>\t&bull; Ou bien, les Britanniques devront chercher autre chose<\/p>\n<\/p>\n<p><p>\tLe premier cas est largement expos\u00e9 par Richard North dans un r\u00e9cent document, dont nous parlons abondamment aussi bien d&rsquo;une fa\u00e7on g\u00e9n\u00e9rale, <a href=\"http:\/\/www.dedefensa.org\/article.php?art_id=2115\" class=\"gen\">dans un r\u00e9cent F&#038;C<\/a> que d&rsquo;une fa\u00e7on plus pr\u00e9cise sur cette question des codes-source du JSF, <a href=\"http:\/\/www.dedefensa.org\/article.php?art_id=2080\" class=\"gen\">dans une r\u00e9cente Analyse<\/a>. North est tr\u00e8s pessimiste sur la possibilit\u00e9 que les Am\u00e9ricains acceptent les exigences des Britanniques.<\/p>\n<\/p>\n<p><p>\tLe deuxi\u00e8me terme de l&rsquo;alternative est l&rsquo;abandon. Impossible dit-on partout. Voire: le mot n&rsquo;a pas cours, ni chez les Fran\u00e7ais, ni chez les Britanniques. En attendant, les Britanniques commencent \u00e0 prendre leurs pr\u00e9cautions, avec toutes les pr\u00e9cautions d&rsquo;usage oserait-on dire,  mais le fait est bien l\u00e0. (Curieusement, comme on verra plus loin, les deux pr\u00e9cautions s&rsquo;annulent. A force d&rsquo;\u00eatre habiles avec les Am\u00e9ricains, les Britanniques ne le sont plus du tout avec eux-m\u00eames)<\/p>\n<\/p>\n<p><p>\tIl s&rsquo;agit des d\u00e9clarations de Lord Drayson. Le haut fonctionnaire britannique fait son annonce avec une pr\u00e9caution ironique et dans des termes qui marquent toujours prudence et discr\u00e9tion. Il n&#8217;emp\u00eache : ce qui est dit est dit car nous approchons du moment que nous nommerions le chas de l&rsquo;aiguille ; lorsque, dans le cas si complexe qu&rsquo;on a jusqu&rsquo;ici d\u00e9battu, tout se r\u00e9duit \u00e0 l&rsquo;alternative finale et au cas le plus simple : oui ou non. Les grandes choses sont ainsi faites, malgr\u00e9 la prudence et la discr\u00e9tion : au bout du terme, l&rsquo;alternative est r\u00e9duite \u00e0 sa plus simple expression. C&rsquo;est le cas de la souverainet\u00e9 nationale, qui ne se satisfait ni des un peu, ni des en partie, ni des compromis. On en dispose ou on n&rsquo;en dispose pas. Pour les Britanniques, le JSF est devenu compl\u00e8tement un cas de souverainet\u00e9 nationale.<\/p>\n<\/p>\n<p><p>\tLord Drayson annonce donc un plan B. Officiellement, cela signifie que les Britanniques vont envisager une alternative avec le JSF, au cas o\u00f9. (Soyons s\u00e9rieux : ils l&rsquo;ont d\u00e9j\u00e0 fait en secret car la chose est toujours faite, par pr\u00e9caution. L&rsquo;important ici est que cela soit dit.)<\/p>\n<\/p>\n<p><p>\tDrayson : \u00ab <em>I am not getting into details about a Plan B, but I am saying there has to be a Plan B. I have no sense we need an alternative plan today, and I am not saying we need to pull any levers on Plan B today, absolutely not. But we need to make sure we have done the work needed to ensure we have an option&#8230;<\/em><\/p>\n<\/p>\n<p><p>\t\u00ab <em>I spent many years working in America. I like them and respect them, but one of the things they really respect are people who have worked out what their alternative is to a negotiated agreement.  It&rsquo;s very important for us not to travel in hope on things. Be businesslike, realistic and ensure we have thought through our plan B.<\/em> \u00bb<\/p>\n<\/p>\n<p><p>\tLes d\u00e9clarations de Drayson sont renforc\u00e9es par celles qui ont \u00e9t\u00e9 faites r\u00e9cemment, devant une commission des Communes, par le Commodore Simon Henley, qui dirige les programmes \u00e0 la Defence Procurement Agency. Pour Henley, \u00ab <em>nous devons disposer des technologies n\u00e9cessaires pour permettre un usage autonome des JSF. Nous devons avoir un contr\u00f4le souverain, ne serait-ce que pour des raisons op\u00e9rationnelles.<\/em> \u00bb<\/p>\n<\/p>\n<p><p>\tQuel est ce plan B de Lord Drayson? On en conna\u00eet les termes depuis longtemps, et ils ont \u00e9t\u00e9 r\u00e9p\u00e9t\u00e9s.<\/p>\n<\/p>\n<p><p>\t&bull; Une version navalis\u00e9e du <em>Typhoon<\/em>, dont BAE laisse dire, encore aujourd&rsquo;hui, qu&rsquo;il est pr\u00eat \u00e0 la d\u00e9velopper. Imaginer une version embarqu\u00e9e de ce monstre qui a de la peine \u00e0 exister en version terrestre conventionnelle normale rel\u00e8ve pour l&rsquo;instant de la plus haute fantaisie. Au mieux, cela nous m\u00e8nerait autour de 2015-2020 pour un prototype monstrueux, au prix de sommes pharaoniques, pour quelque chose qui ne marcherait pas. Pendant ce temps, les porte-avions britanniques vogueraient avec des cocottes en papier embarqu\u00e9es.<\/p>\n<\/p>\n<p><p>\t&bull; Un autre avion US. Il n&rsquo;y en a qu&rsquo;un, le F\/A-18E\/F, qui est une poussive am\u00e9lioration d&rsquo;un YF-17\/F-18 con\u00e7u dans les ann\u00e9es 1973-78. Les Britanniques auraient ainsi compl\u00e9t\u00e9 le <em>remake<\/em> de la minable aventure du F-111 qui repr\u00e9sente la plus honteuse d\u00e9cision d&rsquo;abdication de sa propre souverainet\u00e9, consid\u00e9r\u00e9e d&rsquo;un point de vue g\u00e9n\u00e9ral, qu&rsquo;ait connue le Royaume-Uni. (Abandon en 1964 du brillant projet britannique TSR-2 quasiment achev\u00e9 en faveur du TFX\/F-111 am\u00e9ricain. Celui-ci marche mal, co\u00fbte plus cher que pr\u00e9vu, conna\u00eet d&rsquo;innombrables probl\u00e8mes, dans un cadre o\u00f9 les Britanniques sont trait\u00e9s comme quantit\u00e9 n\u00e9gligeable. [Cela ne nous rappelle-t-il rien?] Finalement, les Britanniques se reportent sur le F-4 <em>Phantom<\/em> am\u00e9ricain, avion d\u00e9j\u00e0 vieux, beaucoup plus conventionnel et aux qualit\u00e9s assez moyennes par rapport au brillant TSR2.) Pire encore : avec le F\/A-18E\/F, les Britanniques retrouveraient les probl\u00e8mes de souverainet\u00e9 rencontr\u00e9s avec le JSF, un co\u00fbt tr\u00e8s \u00e9lev\u00e9, avec l&rsquo;animosit\u00e9 des Am\u00e9ricains en plus Une alternative pire que le choix initial.<\/p>\n<\/p>\n<p><p>\t&bull; Reste l&rsquo;option du diable (selon nombre de Britanniques): le <em>Rafale<\/em> fran\u00e7ais, qui est op\u00e9rationnel en version embarqu\u00e9e. Option du diable pour toutes les raisons qu&rsquo;on conna\u00eet, tr\u00e8s pol\u00e9miques et politiques, tr\u00e8s passionnelles, qui marquent les relations franco-britanniques ; tout cela, encore plus sensible dans ce domaine de tr\u00e8s haute importance des avions de combat. Un choix <em>Rafale<\/em> signerait, par son c\u00f4t\u00e9 symbolique tr\u00e8s puissant, l&rsquo;acte de d\u00e9c\u00e8s des <em>special relationships<\/em> dans le domaine technologique et militaire, qui est l&rsquo;essentiel de ces relations. Signalons que, pour North, c&rsquo;est la seule alternative r\u00e9elle dans le cas de l&rsquo;abandon du JSF: \u00ab <em>Having already retired her ship-borne Harriers, there is no ready replacement. The only possible alternative is the Rafale, which has been selected to equip the new French carrier.<\/em> \u00bb<\/p>\n<\/p>\n<p><p>\tVoil\u00e0 les termes de ce terrible imbroglio britannique qui est en train de parvenir \u00e0 son terme, \u00e0 son moment de d\u00e9cision. Certes, Drayson nous dit bien de quoi il s&rsquo;agit : le plan B est un moyen de pression sur les Am\u00e9ricains pour les conduire \u00e0 c\u00e9der, pour l&rsquo;instant rien de s\u00e9rieux&#8230; De pr\u00e9caution en pr\u00e9caution, l&rsquo;une annulant l&rsquo;autre, Drayson qui se dit fin tacticien montre une \u00e9tonnante faiblesse tactique (mais, on le comprend, les Britanniques ont tellement peur de d\u00e9plaire aux Am\u00e9ricains). Annoncer la chose de cette fa\u00e7on, c&rsquo;est \u00f4ter, aux yeux des Am\u00e9ricains, tout cr\u00e9dit \u00e0 ce moyen de pression puisque c&rsquo;est dire que ce plan B n&rsquo;en est pas un en v\u00e9rit\u00e9 mais un simple moyen de pression Dr\u00f4le de sens tactique de la part de Drayson qui dit bien conna\u00eetre les Am\u00e9ricains. Dans tous les cas, il ne conna\u00eet rien \u00e0 la dissuasion : pour \u00eatre cr\u00e9dible, comme pour la dissuasion, le plan B doit \u00eatre absolument s\u00e9rieux d\u00e8s le d\u00e9part.<\/p>\n<\/p>\n<p><p>\tNous, nous pensons ceci : dans leur grande finesse et leur incomparable vanit\u00e9 (qui peut d\u00e9sirer autre chose que cette unique septi\u00e8me merveille du monde qu&rsquo;est le JSF?), les Am\u00e9ricains ne croient pas et ne croiront pas jusqu&rsquo;au bout une seule seconde que les Britanniques peuvent abandonner le JSF. Ils ne feront donc aucune concession majeure. Ils alimenteront l&rsquo;\u00e9volution de la situation vers le moment ultime, le chas de l&rsquo;aiguille o\u00f9, pour les Britanniques, un oui aux Am\u00e9ricains signifiera l&rsquo;abandon complet de la souverainet\u00e9 nationale, et o\u00f9, pour <strong>la premi\u00e8re fois<\/strong> en v\u00e9rit\u00e9, ces m\u00eames Britanniques devront consid\u00e9rer s\u00e9rieusement le plan B ou abdiquer. Le moment du chas de l&rsquo;aiguille se rapproche vite, d\u00e9sormais.<\/p>\n<\/p>\n<p><p>\tComme nous l&rsquo;\u00e9crivons par ailleurs, 2006 sera <a href=\"http:\/\/www.dedefensa.org\/article.php?art_id=2219\" class=\"gen\">l&rsquo;ann\u00e9e du JSF<\/a>.<\/p>\n<\/p>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Panicus Britannicus 6 novembre 2005 Les Britanniques sont, sur les sujets sensibles, lorsqu&rsquo;il s&rsquo;agit des Etats-Unis, assez lents et surtout tr\u00e8s prudents et tr\u00e8s discrets. A un moment, pourtant, cette prudence et cette discr\u00e9tion ne sont plus de mise. Quant \u00e0 la lenteur, on doit s&rsquo;en passer lorsque le temps commence \u00e0 presser. Avec tout&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[4878,250,3825,3219,4879,3129],"class_list":["post-67077","post","type-post","status-publish","format-standard","hentry","category-faits-et-commentaires","tag-drayon","tag-jsf","tag-north","tag-rafale","tag-tsr-2","tag-typhoon"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/67077","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=67077"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/67077\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=67077"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=67077"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=67077"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}