{"id":67113,"date":"2005-12-18T00:00:00","date_gmt":"2005-12-18T00:00:00","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2005\/12\/18\/pour-leurope-un-sobre-retour-a-la-realite\/"},"modified":"2005-12-18T00:00:00","modified_gmt":"2005-12-18T00:00:00","slug":"pour-leurope-un-sobre-retour-a-la-realite","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2005\/12\/18\/pour-leurope-un-sobre-retour-a-la-realite\/","title":{"rendered":"<strong><em>Pour l&rsquo;Europe, un sobre retour \u00e0 la r\u00e9alit\u00e9<\/em><\/strong>"},"content":{"rendered":"<p><h2 class=\"common-article\">Pour l&rsquo;Europe, un sobre retour \u00e0 la r\u00e9alit\u00e9<\/h2>\n<\/p>\n<p><\/p>\n<p><p>\t18 d\u00e9cembre 2005  Maintenant que tout le monde est rentr\u00e9 chez soi, voyons les choses s\u00e9rieusement. Le sommet de Bruxelles a bien mis la situation au clair, notamment par rapport \u00e0 l&rsquo;extraordinaire d\u00e9cha\u00eenement pro-anglo-saxon que nous entend\u00eemes en juin-juillet. Bien que cruel, le titre du <em>Sunday Times<\/em> <a href=\"http:\/\/www.timesonline.co.uk\/article\/0,,2087-1938210,00.html\" class=\"gen\">de ce matin<\/a> nous r\u00e9sume cette situation : \u00ab <em>French overjoyed at the taming of Tony<\/em> \u00bb,  ce qui pourrait se traduire par le constat que les Fran\u00e7ais prirent grand plaisir \u00e0 observer le domptage de Tony Blair. On pourrait ajouter que le dompteur fut Angela Merkel, ce qui ne manque pas de sel.<\/p>\n<\/p>\n<p><p>\tBref, la r\u00e9alit\u00e9 est de retour. Elle renvoie au magasin des accessoires les sornettes diverses, fabriqu\u00e9es par les Anglo-Saxons et que les commentateurs fran\u00e7ais relay\u00e8rent fid\u00e8lement cet \u00e9t\u00e9. La r\u00e9alit\u00e9, ce sont ces quatre points principalement:<\/p>\n<\/p>\n<p><p>\t&bull; Plus que jamais, l&rsquo;Europe c&rsquo;est trois grands acteurs: Allemagne, France et UK. Qu&rsquo;on soit \u00e0 16 ou \u00e0 25.<\/p>\n<\/p>\n<p><p>\t&bull; S&rsquo;il y a un acteur plus isol\u00e9 que les autres dans ce trio, c&rsquo;est l&rsquo;anglais et non le fran\u00e7ais. <\/p>\n<\/p>\n<p><p>\t&bull; Tony Blair garde une ambition europ\u00e9enne qui le met en position de faiblesse,  dans le concert europ\u00e9en et chez lui  parce que, malgr\u00e9 tout, il est pr\u00eat \u00e0 faire des concessions pour garder cette dimension europ\u00e9enne.<\/p>\n<\/p>\n<p><p>\t&bull; Dans sa position de faiblesse, Merkel ne peut briller que si elle joue les faiseuses de compromis (<em>honest brocker<\/em>). Elle l&rsquo;a fait et cela profite \u00e0 la France.<\/p>\n<\/p>\n<p><p>\tObservons d&rsquo;abord, comme ligne de r\u00e9flexion g\u00e9n\u00e9rale, qu&rsquo;il y a une logique europ\u00e9enne. Ce n&rsquo;est pas une logique communautaire ni une logique de l&rsquo;int\u00e9gration, ni une logique de la r\u00e9forme (anglo-saxonne), ni une logique de la p\u00e9rennisation de la PAC, etc. C&rsquo;est une logique des int\u00e9r\u00eats europ\u00e9ens, qui passe par le maintien en place des sources de sa puissance. Celle-ci s&rsquo;exprime par un axe de nations puissantes (les trois cit\u00e9es), dont la France est plus que jamais le pivot. C&rsquo;est une r\u00e9alit\u00e9 g\u00e9opolitique (la position de la France, la puissance de ses structures, notamment militaires) et une r\u00e9alit\u00e9 psychologique (la France est le seul pays \u00e0 poss\u00e9der une perception tr\u00e8s forte de la souverainet\u00e9 nationale et de l&rsquo;ind\u00e9pendance). Voil\u00e0 les facteurs europ\u00e9ens. Le reste, c&rsquo;est-\u00e0-dire le mauvais \u00e9tat de la France,  sa crise budg\u00e9taire, sa crise de soci\u00e9t\u00e9, l&rsquo;ahurissante m\u00e9diocrit\u00e9 de son personnel politique,  constitue une crise fran\u00e7aise qui est le reflet de la crise g\u00e9n\u00e9rale, on dirait la crise de civilisation qui affecte l&rsquo;Occident en priorit\u00e9, et le reste derri\u00e8re ; bref, la crise de civilisation qui s&rsquo;exprime dans le cadre de la globalisation. La France est singuli\u00e8rement touch\u00e9e, ou touch\u00e9e d&rsquo;une fa\u00e7on voyante, parce que c&rsquo;est un pays aux structures traditionnelles fortes, qui oppose le plus de r\u00e9sistance \u00e0 la pouss\u00e9e d\u00e9structurante qui est la cause de la crise ; mais tous les autres, notamment tous les autres pays europ\u00e9ens, sont touch\u00e9s et \u00e9galement plus ou moins \u00e0 la d\u00e9rive, et au bout du compte impuissants.<\/p>\n<\/p>\n<p><p>\t(On a trop souvent l&rsquo;impression qu&rsquo;en disant ce que nous jugeons \u00eatre des r\u00e9alit\u00e9s historiques puissantes, nous faisons le pan\u00e9gyrique de la France actuelle, de sa grandeur politique et de son bonheur courant, de son influence heureuse, de la qualit\u00e9 de ses dirigeants, etc. Rien de tout cela. La France est en crise parce qu&rsquo;il est <strong>normal<\/strong> aujourd&rsquo;hui d&rsquo;\u00eatre en crise; le pays qui ne le serait pas nous inqui\u00e9terait beaucoup; le pays qui l&rsquo;est beaucoup (la France) ne fait que manifester sa puissante sensibilit\u00e9 historique \u00e0 une situation au caract\u00e8re subversif sans pr\u00e9c\u00e9dent. Certaines puissantes r\u00e9alit\u00e9s historiques persistent, et tant qu&rsquo;elles le feront il y aura crise; le jour o\u00f9 elles dispara\u00eetront, si cela arrive (notre conviction est que cela n&rsquo;arrivera pas) il n&rsquo;y aura plus de crise. Nous serons r\u00e9duits \u00e0 un magma g\u00e9n\u00e9ral o\u00f9 se seront ab\u00eem\u00e9s notre civilisation et l&rsquo;\u00e9quilibre du monde. Ce sera la fin de l&rsquo;Histoire,  merci, Fukuyama,  et la fin de la civilisation telle que nous la connaissons.)<\/p>\n<\/p>\n<p><p>\tLes enseignements de ce sommet pour les trois grands pays (et pour l&rsquo;Europe par cons\u00e9quent) sont les suivants:<\/p>\n<\/p>\n<p><p>\t&bull; La France n&rsquo;a pas besoin d&rsquo;une direction inspir\u00e9e pour peser le poids qu&rsquo;elle p\u00e8se en Europe, qui est consid\u00e9rable. On dirait m\u00eame que, vu l&rsquo;\u00e9tat calamiteux de la classe politique fran\u00e7aise, sa bassesse et son manque d&rsquo;inspiration, il vaut mieux que les Fran\u00e7ais laissent faire les autres dans les sommets europ\u00e9ens et qu&rsquo;ils en disent le moins possible. Il faut observer cela comme un paradoxe logique: dans le d\u00e9sordre actuel, la France n&rsquo;a pas besoin, au niveau europ\u00e9en, d&rsquo;une direction affirm\u00e9e qui ne pourrait \u00eatre, \u00e0 cause de la m\u00e9diocrit\u00e9 g\u00e9n\u00e9rale, qu&rsquo;un \u00e9talage de vanit\u00e9s futiles et de victoires m\u00e9diatiques sans substance. Son poids et sa psychologie font de la France, aujourd&rsquo;hui, dans la crise g\u00e9n\u00e9rale, le pivot central \u00e9vident de l&rsquo;Europe. (Nous parlerons diff\u00e9remment si surgit un nouveau de Gaulle. On verra. Il faut toujours \u00eatre pr\u00eat au miracle.) L&rsquo;isolement fran\u00e7ais que le troupeau des journalistes asserment\u00e9s d\u00e9noncent en ricanant de plaisir tous les six mois revient au constat de l&rsquo;unicit\u00e9 de la position fran\u00e7aise: la France est n\u00e9cessairement la seule nation \u00e0 \u00eatre, dans la crise d\u00e9structurante que nous subissons aujourd&rsquo;hui avec une force incroyable, compl\u00e8tement europ\u00e9enne. Par cons\u00e9quent, elle para\u00eet parfois isol\u00e9e, et elle l&rsquo;est d&rsquo;ailleurs,  mais isol\u00e9e parce que la plus europ\u00e9enne. Comme nous sommes en Europe, l&rsquo;isolement cesse r\u00e9guli\u00e8rement, quand nous revenons \u00e0 la r\u00e9alit\u00e9 historique.<\/p>\n<\/p>\n<p><p>\t&bull; L&rsquo;Allemagne manuvre dans ses vraies limites, qui sont r\u00e9gionales. Une Merkel limit\u00e9e par sa victoire-d\u00e9faite est peut-\u00eatre une excellente chose : une chanceli\u00e8re \u00e0 l&rsquo;ambition r\u00e9gionalis\u00e9e. Cette ambition la porte n\u00e9cessairement \u00e0 renforcer l&rsquo;axe de sa r\u00e9gion, ce qui passe par un soutien de la France mais un soutien critique de la direction fran\u00e7aise. Le <a href=\"http:\/\/www.timesonline.co.uk\/article\/0,,2087-1938214,00.html\" class=\"gen\">Sunday Times<\/a> dit que Merkel a retenu Chirac dans sa charge beno\u00eetement anti-anglaise (inutile de frapper un Tony Blair d\u00e9j\u00e0 \u00e0 terre), ce qui n&rsquo;est peut-\u00eatre pas plus mal : \u00ab <em>Diplomats said Mrs Merkel had restrained President Jacques Chirac of France, rather than giving him the free hand he enjoyed under Germany&rsquo;s previous leader, Gerhard Schr\u00f6der, whose relations with Mr Blair had become poisonous.<\/em> \u00bb Puisqu&rsquo;on ne peut saluer un Tony Blair pulv\u00e9ris\u00e9 et qu&rsquo;il n&rsquo;est pas question de saluer la France, la presse proclame Merkel vainqueur (\u00ab <em> Angela Merkel, the new German Chancellor, emerged as the key deal-maker at her debut EU summit<\/em> \u00bb, \u00e9crit <a href=\"http:\/\/news.independent.co.uk\/europe\/article333842.ece\" class=\"gen\">The Independent<\/a>). Pourquoi pas? On a les victoires qu&rsquo;on peut et celle-ci lui va comme un gant.<\/p>\n<\/p>\n<p><p>\t&bull; La situation britannique est de loin la plus int\u00e9ressante. Le parti conservateur a retrouv\u00e9 des ailes avec son nouveau pr\u00e9sident David Cameron, sorte de Sarkozy d&rsquo;outre-Manche, c&rsquo;est-\u00e0-dire \u00e0 front renvers\u00e9 (conservateur dans un parti bloqu\u00e9 dans une droite dure, s&rsquo;affichant audacieusement <a href=\"http:\/\/observer.guardian.co.uk\/politics\/story\/0,6903,1670004,00.html\" class=\"gen\">vers la gauche<\/a>). Il faut se m\u00e9fier de ces emportements faciles,  l\u00e0 aussi, on verra. Plus int\u00e9ressante est la position nouvelle de Tony Blair. Tout le monde lui tire dessus parce qu&rsquo;il a capitul\u00e9, y compris, \u00e0 peine <em>mezzo voce<\/em>, son <a href=\"http:\/\/www.timesonline.co.uk\/article\/0,,2087-1938214,00.html\" class=\"gen\">Iago personnel<\/a>, le chancelier de l&rsquo;\u00c9chiquier Gordon Brown. Blair battu \u00e0 cause de l&rsquo;Angleterre anti-europ\u00e9enne, \u00e0 la d\u00e9rive chez lui \u00e0 cause de ses engagements pro-am\u00e9ricains (Irak), redevient peut-\u00eatre int\u00e9ressant. Sa seule possibilit\u00e9 de r\u00e9sistance acharn\u00e9e (il s&rsquo;y conna\u00eet), c&rsquo;est peut-\u00eatre, justement, l&rsquo;option europ\u00e9enne; c&rsquo;est sa diff\u00e9rence, le domaine o\u00f9 il peut encore s&rsquo;affirmer, tous les autres devenant anti-europ\u00e9ens en d\u00e9non\u00e7ant sa capitulation. A Bruxelles, Blair a mang\u00e9 son pain noir europ\u00e9en, avec une capitulation humiliante sur le ch\u00e8que sans rien avoir de solide en \u00e9change. Il ne lui reste plus qu&rsquo;une solution : jouer l&rsquo;Europe \u00e0 fond, et esp\u00e9rer qu&rsquo;il y reste pour lui quelques miettes de pain blanc. Il pourrait alors \u00e0 nouveau chercher \u00e0 incurver la politique britannique dans un sens franchement europ\u00e9en. Par exemple, avec une initiative comme il en eut d\u00e9j\u00e0 (le trait\u00e9 de Saint-Malo en d\u00e9cembre 1998)?<\/p>\n<\/p>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Pour l&rsquo;Europe, un sobre retour \u00e0 la r\u00e9alit\u00e9 18 d\u00e9cembre 2005 Maintenant que tout le monde est rentr\u00e9 chez soi, voyons les choses s\u00e9rieusement. Le sommet de Bruxelles a bien mis la situation au clair, notamment par rapport \u00e0 l&rsquo;extraordinaire d\u00e9cha\u00eenement pro-anglo-saxon que nous entend\u00eemes en juin-juillet. Bien que cruel, le titre du Sunday Times&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[705,779,4633,4824],"class_list":["post-67113","post","type-post","status-publish","format-standard","hentry","category-faits-et-commentaires","tag-blair","tag-chirac","tag-merkel","tag-pac"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/67113","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=67113"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/67113\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=67113"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=67113"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=67113"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}