{"id":67136,"date":"2005-12-28T00:00:00","date_gmt":"2005-12-28T00:00:00","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2005\/12\/28\/le-temps-des-complots\/"},"modified":"2005-12-28T00:00:00","modified_gmt":"2005-12-28T00:00:00","slug":"le-temps-des-complots","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2005\/12\/28\/le-temps-des-complots\/","title":{"rendered":"\u201cLe temps des complots\u201d\u2026"},"content":{"rendered":"<p><p>Ce n&rsquo;est pas un hasard,  m\u00eame s&rsquo;il y a le hasard de nos recherches et de nos consultations,  si plusieurs textes qui ont trait de pr\u00e8s ou de loin aux th\u00e9ories de complot paraissent simultan\u00e9ment sur notre site. Pour rappel, et peut-\u00eatre pour inciter nos lecteurs \u00e0 faire un lien entre tout cela :<\/p>\n<\/p>\n<p><p>\t\u00a0Notre <em>F&#038;C<\/em> sur <a href=\"http:\/\/www.dedefensa.org\/article.php?art_id=2276\" class=\"gen\">Iran-Irak : le temps des complots<\/a>.<\/p>\n<\/p>\n<p><p>\t\u00a0Ce texte d&rsquo;origine pakistanaise, publi\u00e9 le 25 d\u00e9cembre, qui rappelle <a href=\"http:\/\/www.dedefensa.org\/choix.php?link_id=6188&#038;comm=1\" class=\"gen\">le r\u00f4le d&rsquo;April Graspie<\/a> dans la premi\u00e8re guerre du Golfe.<\/p>\n<\/p>\n<p><p>\t\u00a0Nos textes sur les r\u00e9flexions du <a href=\"http:\/\/www.dedefensa.org\/article.php?art_id=2278\" class=\"gen\">Dr. Ganser<\/a>, sur d&rsquo;\u00e9ventuels liens entre <a href=\"http:\/\/www.dedefensa.org\/article.php?art_id=2277\" class=\"gen\">Gladio et 9\/11<\/a>.<\/p>\n<\/p>\n<p><p>\tIl y a sans aucun doute une histoire secr\u00e8te des crises dans les relations internationales ces derni\u00e8res ann\u00e9es, nous dirions par d\u00e9finition, parce que la question du terrorisme se traite pour une part consid\u00e9rable en secret. Mais le plus important, \u00e0 notre sens, est le lien secret entre les \u00e9v\u00e9nements actuels (ces derni\u00e8res ann\u00e9es) et ceux de la Guerre froide.<\/p>\n<\/p>\n<p><p>\tLa recherche doit \u00eatre conduite en ayant \u00e0 l&rsquo;esprit une hypoth\u00e8se fondamentale : l&rsquo;id\u00e9e selon laquelle la Guerre froide est elle-m\u00eame une p\u00e9riode o\u00f9 la guerre secr\u00e8te a jou\u00e9 un r\u00f4le consid\u00e9rable. Nous ne parlons pas seulement de la guerre secr\u00e8te USA-URSS, ou Occident-URSS, qui est largement document\u00e9e, parfois m\u00eame d&rsquo;une fa\u00e7on \u00e9trangement outranci\u00e8re. Nous parlons surtout de la guerre secr\u00e8te dans les autres zones et pour d&rsquo;autres objectifs que la classique strat\u00e9gie de la Guerre froide ; une guerre secr\u00e8te qui se serait faite aussi bien \u00e0 l&rsquo;int\u00e9rieur de l&rsquo;Occident qu&rsquo;en rapport avec des zones p\u00e9riph\u00e9riques au conflit Est-Ouest.  <\/p>\n<\/p>\n<p><\/p>\n<p><p>\tMis en ligne le 28 d\u00e9cembre 2005 \u00e0 11H42<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ce n&rsquo;est pas un hasard, m\u00eame s&rsquo;il y a le hasard de nos recherches et de nos consultations, si plusieurs textes qui ont trait de pr\u00e8s ou de loin aux th\u00e9ories de complot paraissent simultan\u00e9ment sur notre site. Pour rappel, et peut-\u00eatre pour inciter nos lecteurs \u00e0 faire un lien entre tout cela : \u00a0Notre&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[2],"tags":[4941,4926,4413,4942],"class_list":["post-67136","post","type-post","status-publish","format-standard","hentry","category-bloc-notes","tag-april","tag-complot","tag-gladio","tag-graspie"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/67136","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=67136"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/67136\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=67136"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=67136"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=67136"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}