{"id":67143,"date":"2006-01-01T00:00:00","date_gmt":"2006-01-01T00:00:00","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2006\/01\/01\/le-monde-black-de-gw\/"},"modified":"2006-01-01T00:00:00","modified_gmt":"2006-01-01T00:00:00","slug":"le-monde-black-de-gw","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2006\/01\/01\/le-monde-black-de-gw\/","title":{"rendered":"<strong><em>Le monde \u201cblack\u201d de GW<\/em><\/strong>"},"content":{"rendered":"<p><h2 class=\"common-article\">Le monde <em>black<\/em> de GW<\/h2>\n<\/p>\n<p><\/p>\n<p><p>\t1er janvier 2006  Le long article du Washington <em>Post<\/em> <a href=\"http:\/\/www.washingtonpost.com\/wp-dyn\/content\/article\/2005\/12\/29\/AR2005122901585_pf.html\" class=\"gen\">du 30 d\u00e9cembre<\/a> sur la position et l&rsquo;activit\u00e9 de la CIA aux Etats-Unis est plein de signification. L&rsquo;article a des prolongements d&rsquo;analyse sugg\u00e9rant une \u00e9volution structurelle radicale. Il nous d\u00e9crit une machinerie de s\u00e9curit\u00e9 nationale (la CIA, mais en fait plus que la CIA) qui continue de s&rsquo;\u00e9tendre dans ses structures et ses activit\u00e9s depuis 2001. En m\u00eame temps, cette situation dynamique mise de plus en plus \u00e0 d\u00e9couvert provoque de plus en plus de r\u00e9actions hostiles (\u00ab <em>Covert CIA Program Withstands New Furor  Anti-Terror Effort Continues to Grow<\/em> \u00bb).<\/p>\n<\/p>\n<p><p>\tL&rsquo;int\u00e9r\u00eat de l&rsquo;article est qu&rsquo;il constitue une somme tr\u00e8s r\u00e9v\u00e9latrice de l&rsquo;\u00e9tat de l&rsquo;\u00e9volution du renseignement am\u00e9ricain, et plus g\u00e9n\u00e9ralement du monde <em>black<\/em> (secret) du syst\u00e8me de l&rsquo;am\u00e9ricanisme depuis le 11 septembre 2001. Il met en \u00e9vidence, \u00e0 notre sens, quelques points essentiels d&rsquo;une situation tout \u00e0 fait nouvelle mais point surprenante,  tout \u00e0 fait nouvelle parce qu&rsquo;expos\u00e9e de plus en plus en pleine lumi\u00e8re, pas \u00e9tonnante parce que de nombreux signes alimentaient des hypoth\u00e8ses dans le sens d&rsquo;une situation qui nous est d\u00e9crite,  et dont l&rsquo;origine est \u00e0 chercher dans la Guerre froide, voire dans les origines de la Guerre froide (Dans ce cas, la correspondance entre <a href=\"http:\/\/www.dedefensa.org\/article.php?art_id=2278\" class=\"gen\">Gladio et 9\/11<\/a> prend tout son sens.) L&rsquo;article fait ce travail de mise en \u00e9vidence de fa\u00e7on plus ou moins volontaire, de fa\u00e7on plus ou moins consciente, en mesurant plus ou moins les implications de ce qu&rsquo;il met \u00e0 d\u00e9couvert.<\/p>\n<\/p>\n<p><p>\tNous tentons de mentionner les points qui nous apparaissent importants. Ils d\u00e9passent largement le seul cadre politique et de s\u00e9curit\u00e9 de l&rsquo;actuelle situation aux Etats-Unis. Mis bout \u00e0 bout ou confront\u00e9s les uns aux autres, ces divers points doivent conduire \u00e0 des interrogations fondamentales sur la forme m\u00eame du syst\u00e8me am\u00e9ricaniste et, par cons\u00e9quent, sur les rapports de ce syst\u00e8me avec le reste de l&rsquo;Occident.<\/p>\n<\/p>\n<p><p>\t&bull; Il existe d\u00e9sormais, au sein de la CIA, un programme d\u00e9sign\u00e9 par les initiales GST. Il recouvre un nombre semble-t-il non limit\u00e9 de sous-programmes repr\u00e9sentant tous les volets de la lutte anti-terroriste (interpr\u00e9tation restrictive), et en fait tous les volets d&rsquo;une nouvelle fa\u00e7on de traiter les affaires du monde (interpr\u00e9tation g\u00e9n\u00e9rale).<\/p>\n<\/p>\n<p><p>\t\u00ab <em>The effort President Bush authorized shortly after Sept. 11, 2001, to fight al Qaeda has grown into the largest CIA covert action program since the height of the Cold War, expanding in size and ambition despite a growing outcry at home and abroad over its clandestine tactics, according to former and current intelligence officials and congressional and administration sources.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb <em>The broad-based effort, known within the agency by the initials GST, is compartmentalized into dozens of highly classified individual programs, details of which are known mainly to those directly involved.<\/em> \u00bb<\/p>\n<\/p>\n<p><p>\t&bull; D\u00e9sormais, le pouvoir ne dissimule plus, ni l&rsquo;importance, ni la forme des activit\u00e9s de la CIA et du renseignement en g\u00e9n\u00e9ral, et de l&rsquo;action dite <em>covert<\/em>. En un sens, on dirait que le <em>black<\/em> (d\u00e9signe toutes les activit\u00e9s secr\u00e8tes) n&rsquo;est plus <em>black<\/em> dans son principe m\u00eame s&rsquo;il le reste dans ses modalit\u00e9s. Finie, l&rsquo;\u00e9poque du diplomate, du ministre ou du Pr\u00e9sident disant \u00e0 un agent secret : Vous accomplirez votre mission mais sachez que si vous \u00eates pris, nous nierons vous avoir donn\u00e9 des instructions, nous nierons m\u00eame que nous vous connaissons. L&rsquo;attitude de GW et des autres est compl\u00e8tement diff\u00e9rente : \u00ab <em>In the past, presidents set up buffers to distance themselves from covert action, said A. John Radsan, assistant general counsel at the CIA from 2002 to 2004. But this president, who is breaking down the boundaries between covert action and conventional war, seems to relish the secret findings and the dirty details of operations.<\/em> \u00bb<\/p>\n<\/p>\n<p><p>\t&bull; Les conditions de la guerre contre la terreur telle que l&rsquo;envisagent les autorit\u00e9s et l&rsquo;<em>establishment<\/em> de Washington sont telles que les op\u00e9rations secr\u00e8tes sont devenues universelles, affectent tous les domaines et ne sont contraintes par rien. Le ma\u00eetre-mot, qui autorise tout : l\u00e9gitime d\u00e9fense. \u00ab <em>Everything is done in the name of self-defense, so they can do anything because nothing is forbidden in the war powers act, said one official who was briefed on the CIA&rsquo;s original cover program and who is skeptical of its legal underpinnings. It&rsquo;s an amazing legal justification that allows them to do anything, said the official.<\/em> \u00bb (Par exemple, nous ne pensons pas du tout, comme l&rsquo;exprime <a href=\"http:\/\/news.independent.co.uk\/world\/politics\/article335859.ece\" class=\"gen\">The Independent aujourd&rsquo;hui<\/a> que la guerre contre la terreur aux USA va \u00e9voluer vers une normalisation, une banalisation: \u00ab <em>Americans, in all probability, will develop a more European, more fatalistic attitude to terrorism: that it is a scourge to be contained, rather than eliminated once and for all.<\/em> \u00bb Nous pensons au contraire que la situation va continuer \u00e0 s&rsquo;exacerber \u00e0 Washington, car c&rsquo;est bien l\u00e0 qu&rsquo;est le principal th\u00e9\u00e2tre d&rsquo;op\u00e9ration, \u00e0 l&rsquo;int\u00e9rieur du syst\u00e8me.)<\/p>\n<\/p>\n<p><p>\t&bull; Tout cela fonctionne selon des modes de pens\u00e9e compl\u00e8tement maximalistes, notamment dans l&rsquo;interpr\u00e9tation des lois, dans l&rsquo;interpr\u00e9tation de la situation (les services de s\u00e9curit\u00e9 vivent selon l&rsquo;id\u00e9e qu&rsquo;une nouvelle attaque type-9\/11 est une probabilit\u00e9 permanente, voire une quasi-certitude), dans l&rsquo;interpr\u00e9tation des perspectives (les pratiques actuelles sont justifi\u00e9es par le fait que, si elles n&rsquo;\u00e9taient pas r\u00e9alis\u00e9es, des pratiques encore plus extr\u00eames seraient n\u00e9cessaires).<\/p>\n<\/p>\n<p><p>\t\u00ab <em>Gen. Michael V. Hayden, deputy director of national intelligence, has described the administration&rsquo;s philosophy in public and private meetings, including a session with human rights groups.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb <em>We&rsquo;re going to live on the edge, Hayden told the groups, according to notes taken by Human Rights Watch and confirmed by Hayden&rsquo;s office. My spikes will have chalk on them. . . . We&rsquo;re pretty aggressive within the law. As a professional, I&rsquo;m troubled if I&rsquo;m not using the full authority allowed by law. Not stopping another attack not only will be a professional failure, he argued, but also will move the line again on acceptable legal limits to counterterrorism.<\/em> \u00bb<\/p>\n<\/p>\n<p><p>\t&bull; Certains, surtout parmi ceux qui ont eu et n&rsquo;ont plus de responsabilit\u00e9s dans le syst\u00e8me de s\u00e9curit\u00e9 nationale, d\u00e9plorent cette \u00e9volution en mettant en \u00e9vidence la perte de contr\u00f4le du syst\u00e8me que cela implique. \u00ab <em> But a former CIA officer said the agency lost its way after Sept. 11, rarely refusing or questioning an administration request. The unorthodox measures have got to be flushed out of the system, the former officer said. That&rsquo;s how it works in this country.<\/em> \u00bb<\/p>\n<\/p>\n<p><p>\tCes divers constats et remarques font prendre conscience d&rsquo;une \u00e9volution d\u00e9cisive aux USA, depuis le 11 septembre 2001. Il y a eu des aspects spectaculaires, des pol\u00e9miques, des scandales, etc. Mais cette enqu\u00eate nous dit bien plus encore : c&rsquo;est un v\u00e9ritable changement de culture qui s&rsquo;est install\u00e9, fond\u00e9 sur une modification radicale de la perception du monde. Nous serions tent\u00e9s d&rsquo;aller plus loin encore en proposant l&rsquo;id\u00e9e qu&rsquo;il s&rsquo;agit d&rsquo;un changement de la psychologie m\u00eame, affectant les dirigeants am\u00e9ricains en g\u00e9n\u00e9ral.<\/p>\n<\/p>\n<p><p>\tD\u00e9sormais, ce qui \u00e9tait l&rsquo;exception et l&rsquo;accident dissimul\u00e9 devient la r\u00e8gle d&rsquo;action au grand jour. Le monde secret (<em>black<\/em>) n&rsquo;est plus le monde secret, il est devenu la norme. Ce qui est tr\u00e8s frappant, \u00e9ventuellement choquant, ce n&rsquo;est pas tant les pratiques de la CIA (et du reste) que le fait que ces pratiques soient de plus en plus mises \u00e0 jour, accept\u00e9es, voire pr\u00f4n\u00e9es comme une fa\u00e7on normale de faire.<\/p>\n<\/p>\n<p><p>\tL&rsquo;Am\u00e9rique ne se transforme nullement en \u00c9tat policier. Les innombrables querelles juridiques en cours, suivies d&rsquo;effets, de pol\u00e9miques l\u00e9galistes, de plaidoiries juridiques, etc., montrent que l&rsquo;architecture juridique du pays reste extr\u00eamement puissante, active et efficace, et qu&rsquo;elle est utilis\u00e9e par des oppositions-dissidences tr\u00e8s d\u00e9termin\u00e9es. (Ces pratiques subsisteront parce qu&rsquo;elle sont n\u00e9cessaires au fonctionnement du syst\u00e8me \u00e9conomique.) Mais le syst\u00e8me, lui, acquiert une psychologie d&rsquo;\u00c9tat policier, o\u00f9 l&rsquo;activit\u00e9 polici\u00e8re sous toutes ses formes constitue la principale activit\u00e9, et la principale activit\u00e9 consid\u00e9r\u00e9e.<\/p>\n<\/p>\n<p><p>\tLa perspective am\u00e9ricaine est beaucoup moins vers une d\u00e9rive fasciste et\/ou polici\u00e8re que dans une contradiction qui va aller jusqu&rsquo;\u00e0 l&rsquo;exacerbation et le d\u00e9sordre entre cette nouvelle psychologie et un <em>corpus<\/em> l\u00e9gal de plus en plus puissant et de plus en plus efficace \u00e0 mesure qu&rsquo;il gagne en exp\u00e9rience dans l&rsquo;usage qui en est fait contre le syst\u00e8me. (Autant l&rsquo;administration GW s&rsquo;attribue des pouvoirs extraordinaires dans l&rsquo;interpr\u00e9tation qu&rsquo;elle fait de la loi, autant les actions qui sont men\u00e9es contre elle et les mesures pr\u00e9ventives qu&rsquo;elle est conduite \u00e0 prendre pour \u00e9viter les effets extr\u00eames de ces mesures contribuent \u00e0 freiner, voire \u00e0 paralyser sa politique dans nombre de cas importants.) C&rsquo;est une application surprenante de la situation illustr\u00e9e par <a href=\"http:\/\/www.dedefensa.org\/article.php?art_id=2270\" class=\"gen\">le mot de William M. Arkin<\/a> (\u00ab <em>D\u00e9truire notre pays pour pouvoir mieux le sauver<\/em> \u00bb) ; c&rsquo;est une application pouss\u00e9e \u00e0 l&rsquo;extr\u00eame du paradoxe puisque la m\u00eame formule \u00e0 peine modifi\u00e9e pourrait \u00eatre reprise par les adversaires de GW qui mobilisent l&rsquo;appareil juridique ; eux laissent croire qu&rsquo;ils iront jusqu&rsquo;\u00e0 d\u00e9truire notre syst\u00e8me pour pouvoir mieux le sauver<\/p>\n<\/p>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le monde black de GW 1er janvier 2006 Le long article du Washington Post du 30 d\u00e9cembre sur la position et l&rsquo;activit\u00e9 de la CIA aux Etats-Unis est plein de signification. L&rsquo;article a des prolongements d&rsquo;analyse sugg\u00e9rant une \u00e9volution structurelle radicale. Il nous d\u00e9crit une machinerie de s\u00e9curit\u00e9 nationale (la CIA, mais en fait plus&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[3126,3104],"class_list":["post-67143","post","type-post","status-publish","format-standard","hentry","category-faits-et-commentaires","tag-black","tag-cia"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/67143","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=67143"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/67143\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=67143"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=67143"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=67143"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}