{"id":67147,"date":"2006-01-02T00:00:00","date_gmt":"2006-01-02T00:00:00","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2006\/01\/02\/la-crise-climatique-devient-notre-crise\/"},"modified":"2006-01-02T00:00:00","modified_gmt":"2006-01-02T00:00:00","slug":"la-crise-climatique-devient-notre-crise","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2006\/01\/02\/la-crise-climatique-devient-notre-crise\/","title":{"rendered":"<strong><em>La crise climatique devient notre crise<\/em><\/strong>"},"content":{"rendered":"<p><h2 class=\"common-article\">La crise climatique devient notre crise<\/h2>\n<\/p>\n<p><\/p>\n<p><p>\t2 janvier 2006   Comme nous le signalons par ailleurs, le texte de Mark Lynas dans <a href=\"http:\/\/news.independent.co.uk\/environment\/article335860.ece\" class=\"gen\">The Independent du jour<\/a> nous fait prendre conscience, peut-\u00eatre sans que lui-m\u00eame l&rsquo;ait cherch\u00e9 et peut-\u00eatre sans l&rsquo;avoir cherch\u00e9 nous-m\u00eames, que nous sommes entr\u00e9s dans l&rsquo;\u00e9poque o\u00f9 la crise climatique est, si l&rsquo;on veut, descendue dans la rue. Elle est devenue, en 2005, une crise comme une autre, \u00e0 part bien entendu qu&rsquo;elle est bien plus grave qu&rsquo;aucune autre. Nous voulons dire que la crise climatique a d\u00e9finitivement quitt\u00e9 son image \u00e9cologiste, son image de crise \u00e0 la fois exotique et orient\u00e9e, pour devenir une crise tout court qui affecte notre vie et, surtout, notre avenir. Elle s&rsquo;est banalis\u00e9e, au vrai sens du terme mais avec l&rsquo;effet contraire de l&rsquo;habituel processus, puisqu&rsquo;elle est ainsi devenue plus sensible \u00e0 tous, et par cons\u00e9quent plus pressante et urgente. La crise climatique n&rsquo;appartient plus aux \u00e9cologistes, elle est d\u00e9sormais le fardeau de tous.<\/p>\n<\/p>\n<p><p>\tC&rsquo;est ce que Lynas traduit de la sorte, en se concentrant sur la sc\u00e8ne britannique, en bon Britannique et parce que, effectivement et objectivement, il est vrai que les Britanniques sont \u00e0 la pointe de la bataille pour faire entrer la crise climatique dans nos pr\u00e9occupations g\u00e9n\u00e9rales et fondamentales.<\/p>\n<\/p>\n<p><p>\t\u00ab <em>The past 12 months have seen big changes in the political  as well as the actual  climate. Perhaps the Rubicon was crossed when David Cameron was seen with Zac Goldsmith, editor of The Ecologist, discussing the ins and outs of global warming. Once the party of big business and anti-regulation, the Tories seem set to outflank a struggling Labour on the issue.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb <em>What is so surprising is not just the shifting of the ideological landscape that this implies, but the fact that everyone agrees that it matters. Even as recently as the May general election, climate change barely made a headline. Now Cameron&rsquo;s re-invigorated Tories clearly see it as a vote-winner. Tony Blair, who did so much to put climate on the agenda, but then failed to deliver serious policies to address it, could lose out as a result.<\/em> \u00bb<\/p>\n<\/p>\n<p><p>\tCette transformation d&rsquo;une crise exotique fondamentale en une crise g\u00e9n\u00e9rale fondamentale est un \u00e9v\u00e9nement important, m\u00eame s&rsquo;il est difficile de le distinguer comme tel au premier coup d&rsquo;il. Il est du plus grand int\u00e9r\u00eat d&rsquo;examiner les causes et les cons\u00e9quences de cette transformation.<\/p>\n<\/p>\n<p><p>\t&bull; La premi\u00e8re de ces causes est l&rsquo;\u00e9vidence. Il y a des signes violents de la d\u00e9gradation des conditions directes ou indirectes du climat (la fonte acc\u00e9l\u00e9r\u00e9e de la calotte glaciaire arctique, beaucoup plus rapide de ce qui \u00e9tait envisag\u00e9 par les alarmistes). Il y a des manifestations climatiques violentes de la d\u00e9gradation du climat. Il ne fait aucun doute que, dans l&rsquo;esprit des gens, et cela \u00e0 partir de nombre de commentaires scientifiques, la puissance monstrueuse de l&rsquo;ouragan Katrina qui a d\u00e9truit La Nouvelle Orl\u00e9ans est due au r\u00e9chauffement climatique.  <\/p>\n<\/p>\n<p><p>\t&bull; La seconde de ces causes est la politisation implicite de la crise, et une politisation violente au travers de tel ou tel \u00e9v\u00e9nement. Le cas le plus \u00e9vident est Katrina : jamais un \u00e9v\u00e9nement naturel n&rsquo;aura \u00e9t\u00e9 aussi rapidement politis\u00e9 que Katrina, cela en rapport avec la consternante m\u00e9diocrit\u00e9 de l&rsquo;administration GW et ses effets. Par cons\u00e9quence indirecte (assez peu consciemment r\u00e9alis\u00e9e), c&rsquo;est l&rsquo;une des causes de Katrina (le r\u00e9chauffement climatique) qui est elle-m\u00eame politis\u00e9e, c&rsquo;est-\u00e0-dire introduite sur la sc\u00e8ne politique g\u00e9n\u00e9rale. Le fait n&rsquo;a pas \u00e9t\u00e9 directement mis en \u00e9vidence mais il nous semble qu&rsquo;il s&rsquo;inscrira indirectement dans les consciences. Apr\u00e8s Katrina, rien n&rsquo;est plus pareil : tout grand d\u00e9sastre naturel, surtout li\u00e9 \u00e0 l&rsquo;Am\u00e9rique, sera soup\u00e7onn\u00e9 d&rsquo;\u00eatre le produit de la crise climatique et sera consid\u00e9r\u00e9 d&rsquo;un point de vue politique. <\/p>\n<\/p>\n<p><p>\t&bull; Une troisi\u00e8me cause, inattendue et encourageante : l&rsquo;Am\u00e9rique, certes, c&rsquo;est-\u00e0-dire la politique am\u00e9ricaniste de GW Bush, joue un r\u00f4le paradoxal dans cette politisation et cette g\u00e9n\u00e9ralisation de la crise climatique. En s&rsquo;opposant effectivement \u00e0 cette \u00e9volution, par le biais d&rsquo;une opposition radicale \u00e0 l&rsquo;existence elle-m\u00eame de la crise, GW a fait \u00e0 ses adversaires dans ce domaine un cadeau somptueux : le formidable courant anti-am\u00e9ricain actuel devient <em>de facto<\/em> un courant qui soutient \u00e9videmment l&rsquo;acceptation de l&rsquo;existence de la crise, et l&rsquo;interpr\u00e9tation politique et g\u00e9n\u00e9rale de cette crise. C&rsquo;est l&rsquo;application du nouveau pr\u00e9cepte : tout ce que GW et Washington condamnent a toutes les chances d&rsquo;acqu\u00e9rir respect, prestige et puissance dans le reste du monde. (Un point annexe \u00e0 consid\u00e9rer est la fa\u00e7on dont les caract\u00e9ristiques fondamentales du syst\u00e8me am\u00e9ricanistes pourraient \u00eatre utilis\u00e9es contre lui. C&rsquo;est le cas des capacit\u00e9s de nuisance du syst\u00e8me juridique, qui pourraientt \u00eatre retourn\u00e9es contre le syst\u00e8me si certains <a href=\"http:\/\/www.dedefensa.org\/article.php?art_id=2290\" class=\"gen\">l&rsquo;utilisent habilement<\/a>.)<\/p>\n<\/p>\n<p><p>\t&bull; Autre cause et autre point paradoxal, l&rsquo;activisme du Royaume-Uni et de Blair. Point paradoxal parce que, dans ce cas : (1) Blair est tr\u00e8s populaire aupr\u00e8s de ses \u00e9lecteurs, des Britanniques en g\u00e9n\u00e9ral et de la classe politique britannique ; (2) Blair est sur une ligne nettement d\u00e9marqu\u00e9e et antagoniste de l&rsquo;administration GW. Cette rubrique est un point important parce qu&rsquo;elle implique que la puissante capacit\u00e9 de communications des Britanniques,  influence, <em>spin<\/em> et  tout l&rsquo;attirail m\u00e9diatico-virtualiste,  est plut\u00f4t au service de l&rsquo;excellente cause de l&rsquo;alerte et de la g\u00e9n\u00e9ralisation de la crise climatique. <\/p>\n<\/p>\n<p><p>\t&bull; Enfin, il y a un contexte de crise naturelle plus g\u00e9n\u00e9ral, notamment la crise des ressources p\u00e9troli\u00e8res, qui modifie les psychologies dans le sens de faire \u00e9voluer le jugement. Qui s&rsquo;int\u00e9resse aux crises naturelles, et, par cons\u00e9quent, \u00e0 la crise climatique, n&rsquo;est plus consid\u00e9r\u00e9 comme un <em>zozo<\/em> barbu, \u00e9cologiste gauchisant et subversif, en <MI>jeans<D< crasseux, etc. D'ailleurs les <em>gentlemen<\/em> de la <em>City<\/em> se baladent en chemises \u00e0 col ouvert et s&rsquo;inqui\u00e8tent fortement de la crise climatique. C&rsquo;est par de tels ph\u00e9nom\u00e8nes de communications que les grandes choses se r\u00e9alisent aujourd&rsquo;hui. Seul le r\u00e9sultat compte mais,  en passant,  cela nous en dit long sur notre \u00e9poque<\/p>\n<\/p>\n<p><p>\tQuelles vont \u00eatre les cons\u00e9quences de cette prise de conscience, de cette banalisation au bon sens de la crise climatique ? Elles sont tr\u00e8s nombreuses, directement et potentiellement, et les explorer toutes n&rsquo;a aucun sens. Nous nous arr\u00eaterons pourtant \u00e0 deux d&rsquo;entre elles, parce qu&rsquo;elles sont g\u00e9n\u00e9rales, fondamentales, politiques et qu&rsquo;elles participent de domaines qui nos importent.<\/p>\n<\/p>\n<p><p>\t&bull; L&rsquo;effet sur la position de Washington va \u00eatre important. L&rsquo;isolement de Washington sur cette question s&rsquo;est confirm\u00e9 en 2005, dans des conditions peu favorables \u00e0 l&rsquo;administration GW dans la mesure o\u00f9 le fondement de sa position (d&rsquo;ailleurs en train d&rsquo;\u00e9voluer sous la pression des faits) est une position scientifique hyper-extr\u00e9miste et de moins en moins s\u00e9rieuse. Washington va devoir \u00e9voluer, mais contraint et forc\u00e9, c&rsquo;est-\u00e0-dire sans jamais retrouver la pr\u00e9pond\u00e9rance qui lui est habituelle dans les rassemblements internationaux. Un autre aspect de l&rsquo;isolement de Washington est son isolement \u00e0 l&rsquo;int\u00e9rieur. De plus en plus d&rsquo;\u00c9tats et de ville des USA <a href=\"http:\/\/www.dedefensa.org\/article.php?art_id=1882\" class=\"gen\">r\u00e9pudient, sinon rejettent<\/a> la position officielle de Washington et adoptent les normes de Kyoto. C&rsquo;est un cas int\u00e9ressant de d\u00e9volution du pouvoir, qui joue son r\u00f4le dans une crise am\u00e9ricaniste \u00e0 multiples facettes (Irak, s\u00e9curit\u00e9 int\u00e9rieure, protection des libert\u00e9s civiles, etc.) o\u00f9 la mise en cause du pouvoir central est d\u00e9sormais implicitement faite.<\/p>\n<\/p>\n<p><p>\t&bull; L&rsquo;effet sur la mise en cause de notre syst\u00e8me g\u00e9n\u00e9ral est un autre aspect essentiel des cons\u00e9quences de la banalisation de la crise climatique,  un autre mais, certes, le principal de ce qui est \u00e0 venir. \u00c9videmment, cette crise est directement li\u00e9e aux activit\u00e9s humaines, sp\u00e9cifiquement au mode de d\u00e9veloppement que nous avons choisi. L\u00e0 aussi, elle se combine puissamment \u00e0 la crise de production du p\u00e9trole, qui refl\u00e8te \u00e9galement le choix de notre type de d\u00e9veloppement. Ce qui nous attend, au plus nous p\u00e9n\u00e9trerons dans la crise climatique, c&rsquo;est le d\u00e9veloppement de critiques radicales contre ce syst\u00e8me d&rsquo;\u00ab <em>\u00e9conomie de force<\/em> \u00bb comme le d\u00e9signaient en 1931 Robert Aron et Arnaud Dandieu. R\u00e9cemment (d\u00e9but novembre), Blair a sembl\u00e9 amorcer un tournant, dans une d\u00e9claration faite au sommet du G8 (selon <a href=\"http:\/\/www.guardian.co.uk\/climatechange\/story\/0,,1606602,00.html\" class=\"gen\">The Guardian<\/a> du 2 novembre 2005) : \u00ab <em>He said when the Kyoto protocol expires in 2012, the world would need a more sensitive framework for tackling global warming. \u00a0\u00bbPeople fear some external force is going to impose some internal target on you &#8230; to restrict your economic growth,\u00a0\u00bb he said. \u00a0\u00bbI think in the world after 2012 we need to find a better, more sensitive set of mechanisms to deal with this problem.\u00a0\u00bb His words come in the build-up to UN talks in Montreal this month on how to combat global warming after Kyoto. \u00a0\u00bbThe blunt truth about the politics of climate change is that no country will want to sacrifice its economy in order to meet this challenge,\u00a0\u00bb he said.<\/em> \u00bb<\/p>\n<\/p>\n<p><p>\t Eh bien, cette affirmation selon laquelle rien de notre syst\u00e8me \u00e9conomique ne pourra \u00eatre modifi\u00e9e, nous semble, \u00e0 nous, au regard de la crise climatique qui gronde d\u00e9j\u00e0, rien de moins qu&rsquo;une incantation extr\u00eamement inqui\u00e8te. Dire que rien ne sera chang\u00e9 \u00e0 notre syst\u00e8me \u00e9conomique comme le fait le Premier ministre britannique alors que personne n&rsquo;a rien exig\u00e9 de pr\u00e9cis \u00e0 cet \u00e9gard (sinon les Am\u00e9ricains, mais m\u00eame Blair ne se pr\u00e9occupent pas de leurs d\u00e9clarations dans ce domaine), c&rsquo;est presque reconna\u00eetre que c&rsquo;est effectivement sur ce terrain que se mesureront, ces prochaines ann\u00e9es, les grands enjeux de notre destin\u00e9e. Et reconna\u00eetre cela, d\u00e9j\u00e0, c&rsquo;est amorcer une retraite qui sera rythm\u00e9e au gr\u00e9 des futurs Katrina. <\/p>\n<\/p>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La crise climatique devient notre crise 2 janvier 2006 Comme nous le signalons par ailleurs, le texte de Mark Lynas dans The Independent du jour nous fait prendre conscience, peut-\u00eatre sans que lui-m\u00eame l&rsquo;ait cherch\u00e9 et peut-\u00eatre sans l&rsquo;avoir cherch\u00e9 nous-m\u00eames, que nous sommes entr\u00e9s dans l&rsquo;\u00e9poque o\u00f9 la crise climatique est, si l&rsquo;on veut,&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[705,4631,4955],"class_list":["post-67147","post","type-post","status-publish","format-standard","hentry","category-faits-et-commentaires","tag-blair","tag-kyoto","tag-lynas"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/67147","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=67147"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/67147\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=67147"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=67147"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=67147"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}