{"id":67168,"date":"2006-01-11T00:00:00","date_gmt":"2006-01-11T00:00:00","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2006\/01\/11\/la-nsa-pourrait-espionner-des-millions-damericains\/"},"modified":"2006-01-11T00:00:00","modified_gmt":"2006-01-11T00:00:00","slug":"la-nsa-pourrait-espionner-des-millions-damericains","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2006\/01\/11\/la-nsa-pourrait-espionner-des-millions-damericains\/","title":{"rendered":"La NSA pourrait espionner des millions d&rsquo;Am\u00e9ricains"},"content":{"rendered":"<p><p>Russell Tice est la source qui a permis au New York <em>Times<\/em> de composer son article du 16 d\u00e9cembre 2005 impliquant l&rsquo;administration GW Bush dans une affaire d&rsquo;espionnage \u00e9lectronique des Am\u00e9ricains par la NSA. Tice a \u00e9t\u00e9 un employ\u00e9 de la NSA pendant 20 ann\u00e9es. Il a expliqu\u00e9 \u00e0 <a href=\"http:\/\/abcnews.go.com\/WNT\/print?id=1491889\" class=\"gen\">ABCNews<\/a> qu&rsquo;il \u00e9tait sp\u00e9cialis\u00e9 dans les programmes d&rsquo;\u00e9coute ill\u00e9gale \u00e0 l&rsquo;\u00e9tranger, \u00ab <em>in what&rsquo;s called special access programs. We called them black world programs and operations.<\/em> \u00bb Il selmble qu&rsquo;on puisse identifier ce travail comme r\u00e9alis\u00e9 dans le cadre de l&rsquo;op\u00e9ration <em>Echelon<\/em>.<\/p>\n<\/p>\n<p><p>\t\u00ab <em>But now, Tice tells ABC News that some of those secret black world operations run by the NSA were operated in ways that he believes violated the law. He is prepared to tell Congress all he knows about the alleged wrongdoing in these programs run by the Defense Department and the National Security Agency in the post-9\/11 efforts to go after terrorists. The mentality was we need to get these guys, and we&rsquo;re going to do whatever it takes to get them, he said.<\/em> \u00bb<\/p>\n<\/p>\n<p><p>\tGW Bush a affirm\u00e9, en reconnaissant l&rsquo;existence de ce programme d&rsquo;\u00e9coute de citoyens am\u00e9ricains, qu&rsquo;il ne concernait que quelques centaines de personnes dans le cadre de ce qui, selon lui, ne n\u00e9cessite pas d&rsquo;autorisation sp\u00e9ciale, et que ce chiffre ne serait pas d\u00e9pass\u00e9. Tice est en complet d\u00e9saccord. Pour lui, les proc\u00e9dures secr\u00e8tes d&rsquo;\u00e9coute de la NSA font que les param\u00e8tres choisis pour les \u00e9coutes des quelques centaines d&rsquo;Am\u00e9ricains, dans ce cadre hors-l\u00e9galit\u00e9 d\u00e9cr\u00e9t\u00e9 par le gouvernement, pourraient conduire si n\u00e9cessaire \u00e0 l&rsquo;\u00e9coute sans autorisation de millions d&rsquo;Am\u00e9ricains.<\/p>\n<\/p>\n<p><p>\tTice est pr\u00eat \u00e0 t\u00e9moigner devant le Congr\u00e8s.<\/p>\n<\/p>\n<p><\/p>\n<p><p>\tMis en ligne le 11 janvier 2006 \u00e0 14H07<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Russell Tice est la source qui a permis au New York Times de composer son article du 16 d\u00e9cembre 2005 impliquant l&rsquo;administration GW Bush dans une affaire d&rsquo;espionnage \u00e9lectronique des Am\u00e9ricains par la NSA. Tice a \u00e9t\u00e9 un employ\u00e9 de la NSA pendant 20 ann\u00e9es. Il a expliqu\u00e9 \u00e0 ABCNews qu&rsquo;il \u00e9tait sp\u00e9cialis\u00e9 dans les&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[2],"tags":[4915,4916,3871,4974],"class_list":["post-67168","post","type-post","status-publish","format-standard","hentry","category-bloc-notes","tag-ecoutes","tag-illegales","tag-nsa","tag-tice"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/67168","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=67168"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/67168\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=67168"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=67168"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=67168"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}