{"id":67198,"date":"2006-01-20T00:00:00","date_gmt":"2006-01-20T00:00:00","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2006\/01\/20\/a-la-recherche-dune-verite-qui-colle\/"},"modified":"2006-01-20T00:00:00","modified_gmt":"2006-01-20T00:00:00","slug":"a-la-recherche-dune-verite-qui-colle","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2006\/01\/20\/a-la-recherche-dune-verite-qui-colle\/","title":{"rendered":"<strong><em>A la recherche d&rsquo;une v\u00e9rit\u00e9 qui colle<\/em><\/strong>"},"content":{"rendered":"<p><h2 class=\"common-article\">A la recherche d&rsquo;une v\u00e9rit\u00e9 qui colle<\/h2>\n<\/p>\n<p><\/p>\n<p><p>\t20 janvier 2006  La grande bataille du village de Damadola n&rsquo;a pas eu lieu le 13 janvier mais est en cours actuellement, entre Am\u00e9ricains et Pakistanais essentiellement. C&rsquo;est la bataille men\u00e9e par les Am\u00e9ricains pour obtenir une version officielle-officieuse qui les agr\u00e9e, notamment pour leurs int\u00e9r\u00eats int\u00e9rieurs. C&rsquo;est une bataille pour un habillage virtualiste et pour les int\u00e9r\u00eats de groupes de pression,  ou sous les pressions des groupes d&rsquo;int\u00e9r\u00eat, si l&rsquo;on veut. Cette description de la bataille en cours est un expos\u00e9 succinct de ce qu&rsquo;est r\u00e9ellement la guerre contre la terreur au nom de laquelle diplomates et militaires sont tent\u00e9s de vous dire, pour justifier leur utilit\u00e9, qu&rsquo;une mobilisation maximale est n\u00e9cessaire, au nom de laquelle on envisage les conflits les plus extr\u00eames et les d\u00e9cisions les plus folles.<\/p>\n<\/p>\n<p><p>\tTout est rassembl\u00e9 dans la cha\u00eene habituelle du syst\u00e8me pour cette bataille de la mise au point (peut-on dire : l&rsquo;invention?) d&rsquo;une version qui tienne, avec, cette fois, une g\u00e2terie : les copains pakistanais servant de base ou de fournisseurs de d\u00e9sinformation, mais avec leurs propres exigences. Cela nous rappelle ce mot du Premier ministre pakistanais Aziz, au lendemain <a href=\"http:\/\/www.dedefensa.org\/article.php?art_id=2331\" class=\"gen\">de l&rsquo;attaque de Damadola<\/a> : \u00ab [Aziz] <em>called Friday&rsquo;s airstrike on a village near the Afghan border very regrettable but said, I don&rsquo;t think that takes away from the fact that Pakistan needs investment.<\/em> \u00bb On comprend de quels investissements il est question.<\/p>\n<\/p>\n<p><p>\tLa cha\u00eene du syst\u00e8me enfile successivement les officiels pakistanais, \u00e9ventuellement des sources proches du renseignement pakistanais (ISI), le commentaire professionnel US, avec l&rsquo;habituel New York <em>Times<\/em> comme relais.<\/p>\n<\/p>\n<p><p>\tUne pi\u00e8ce rarissime venue en surcro\u00eet pour \u00e9clairer cette affaire d&rsquo;une dimension plus large, c&rsquo;est <a href=\"http:\/\/www.nytimes.com\/2006\/01\/19\/international\/asia\/19aziz.html?pagewanted=print\" class=\"gen\">la le\u00e7on<\/a> que le Premier ministre pakistanais inflige \u00e0 ses amis am\u00e9ricains, sans espoir d&rsquo;ailleurs de changer quoi que ce soit dans leur comportement. On la signalera d&rsquo;abord, avant de revenir \u00e0 la fabrique d&rsquo;information. Il faut avoir \u00e0 l&rsquo;esprit que Aziz parle de la coop\u00e9ration et de la coordination de deux pays qui sont extr\u00eamement proches dans la lutte contre le terrorisme dans cette r\u00e9gion depuis le 11 septembre 2001, et donc ont coop\u00e9r\u00e9 et se sont coordonn\u00e9s activement pendant plus de quatre ans d\u00e9j\u00e0.<\/p>\n<\/p>\n<p><p>\t\u00ab <em> The prime minister of Pakistan said yesterday that the deaths of 18 civilians in American airstrikes on a Pakistani village last week pointed out a need for stricter coordination between his country and the United States but would not set back their joint effort to fight terrorism.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb <em>Our war against terror is based on principles, so if our objectives are similar, I think we can work together, Prime Minister Shaukat Aziz said in an interview at a Midtown Manhattan hotel. However, the modus operandi and the code of conduct need to be discussed, and while I&rsquo;m in Washington, we will certainly talk about it.<\/em><\/p>\n<\/p>\n<p><p>\t(&#8230;)<\/p>\n<\/p>\n<p><p>\t\u00bb <em>Speaking of the C.I.A. and the counterpart Pakistani services, he said, The liaison is there between the two agencies but as the exact way of tackling the intelligence, I believe there was a bit of a communications gap.<\/em> \u00bb<\/p>\n<\/p>\n<p><p>\tCette absence de coop\u00e9ration et de coordination des Am\u00e9ricains et des Pakistanais, du fait essentiellement des premiers qui effectuent toutes leurs actions sans en aviser les Pakistanais, est une des causes du d\u00e9sordre qui entoure l&rsquo;attaque de Damadola. Les Am\u00e9ricains continuent leur effort pour faire accr\u00e9diter la th\u00e8se que l&rsquo;attaque \u00e0 donn\u00e9 des r\u00e9sultats. En attendant, cette offensive virtualiste a donn\u00e9 des r\u00e9sultats, au niveau m\u00e9diatique, avec des articles, dont celui du New York <em>Times<\/em> du <a href=\"http:\/\/www.nytimes.com\/2006\/01\/19\/international\/asia\/19pakistan.html?th=&#038;emc=th&#038;pagewanted=print\" class=\"gen\">19 janvier<\/a> qui nous gratifie d&rsquo;une nouvelle version, plus travaill\u00e9e, plus subtile que la liquidation du n\u00b02 d&rsquo;Al Qa\u00efda.<\/p>\n<\/p>\n<p><p>\t\u00ab <em>Two senior members of Al Qaeda and the son-in-law of its No. 2 leader, Ayman al-Zawahiri, were among those killed in the American airstrikes in remote northeastern Pakistan last week, two Pakistani officials said here on Wednesday.<\/em> <\/p>\n<\/p>\n<p><p>\t\u00bb <em>The bodies of the men have not been recovered, but the two officials said the Pakistani authorities had been able to establish through intelligence sources the names of three of those killed in the strikes, and maybe a fourth. Both of the officials have provided reliable information in the past, but neither would be identified because they were not authorized to speak to the news media.<\/em> <\/p>\n<\/p>\n<p><p>\t\u00bb <em>American counterterrorism officials declined to say whether the four Qaeda members were in fact killed in the raid, or whether the men were among those who were the targets of it. But one American official said, These are the kinds of people we would have expected to have been there.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb <em>If any or all were indeed killed, it would be a stinging blow to Al Qaeda&rsquo;s operations, said the American officials, who were granted anonymity because they were not authorized by their agencies to speak for attribution. They said all four men named by the Pakistani officials were among the top level of Al Qaeda&rsquo;s inner circle of leadership.<\/em> \u00bb<\/p>\n<\/p>\n<p><p>\tLa v\u00e9ritable op\u00e9ration de Damadola a donc consist\u00e9, \u00e0 partir du 13 janvier, \u00e0 rassembler les officiels pakistanais pour les convaincre de diffuser une version plus favorable aux actions am\u00e9ricaines. Les Am\u00e9ricains, de leur c\u00f4t\u00e9 (\u00ab <em>American counterterrorism officials<\/em> \u00bb), se tiennent sur la r\u00e9serve, maniant la d\u00e9sinformation selon les normes du milieu : suggestion de confirmation \u00e9ventuelle, dans certaines conditions, prudence extr\u00eame, etc.,  mais affirmation discr\u00e8te qu&rsquo;il s&rsquo;agit d&rsquo;une formidable victoire (\u00ab <em>a stinging blow to Al Qaeda&rsquo;s op\u00e9rations <\/em> \u00bb) en cas de confirmation,  laquelle, si elle vient, viendra \u00e0 nouveau d&rsquo;une manipulation ext\u00e9rieures (\u00ab <em>Pakistani officials<\/em> \u00bb ou proches).<\/p>\n<\/p>\n<p><p>\tL&rsquo;arrangement manipulatoire de l&rsquo;information est meilleur que l&rsquo;op\u00e9ration de Damadola elle-m\u00eame, et meilleur bien s\u00fbr que les pi\u00e8tres interventions d&rsquo;une Rice pendant l&rsquo;affaire des vols de la CIA, o\u00f9 les montages ne sont m\u00eame pas crus par ceux qui les \u00e9noncent. Les \u00ab <em>American counterterrorism officials<\/em> \u00bb ont pour eux de pouvoir jouer de l&rsquo;aura de myst\u00e8re et de professionnalisme qui entoure leurs activit\u00e9s, et de l&rsquo;impossibilit\u00e9 absolue de r\u00e9gler une affaire comme celle de Damadola d&rsquo;une fa\u00e7on claire et indubitable ; ils ont m\u00eame pour eux, pour certains d&rsquo;entre eux dans tous les cas, de croire que ce qu&rsquo;ils disent refl\u00e8te une certaine v\u00e9rit\u00e9.<\/p>\n<\/p>\n<p><p>\tLe montage est tellement actif que des opposants peuvent m\u00eame avancer l&rsquo;hypoth\u00e8se que l&rsquo;op\u00e9ration elle-m\u00eame est un montage complet \u00e0 destination politique, pour renforcer par la terreur la main-mise du gouvernement pakistanais et des Am\u00e9ricains sur la population (\u00ab <em> Some officials and opposition politicians have accused the government of inventing the presence of foreign militants in the area to mitigate the political fallout<\/em> \u00bb). Parfois aussi, des v\u00e9rit\u00e9s tra\u00eenent ici ou l\u00e0, par inadvertance, maladresse ou lassitude, comme la d\u00e9claration du Premier ministre pakistanais Aziz sur les dirigeants d&rsquo;Al Qa\u00efda, s&rsquo;ils existent : \u00ab [Aziz] <em>expressed little hope of the imminent capture or killing of the top two leaders of Al Qaeda, Osama bin Laden and Ayman al-Zawahiri, saying they had the resources to move about the tribal areas and beyond without being detected. \u00ab Frankly, nobody knows where they are, he said. The simple answer is that nobody has a clue.<\/em> \u00bb<\/p>\n<\/p>\n<p><p>\tIl est assez probable que cette activit\u00e9 inusit\u00e9e du milieu du renseignement et du contre-terrorisme US, pour les suites d&rsquo;une op\u00e9ration de cette sorte, a aussi des causes internes (\u00e0 Washington, s&rsquo;entend) tr\u00e8s importantes,  ce sont m\u00eame, le plus souvent, les plus importantes. Il semble que ces milieux veulent renouveler et relancer le soutien parlementaire \u00e0 leurs activit\u00e9s, notamment du point de vue des budgets, en tentant de d\u00e9montrer l&rsquo;efficacit\u00e9 de cette sorte d&rsquo;op\u00e9ration et de la technologie. L&rsquo;accent mis sur l&#8217;emploi d&rsquo;engins <em>Predator<\/em> durant l&rsquo;op\u00e9ration va dans ce sens. L&rsquo;affaire Cunningham est pour beaucoup dans cette situation et dans cette d\u00e9marche des milieux du renseignement US. On sait que cette affaire implique des irr\u00e9gularit\u00e9s dans certains contrats secrets <a href=\"http:\/\/www.dedefensa.org\/article.php?art_id=2223\" class=\"gen\">avec la CIA<\/a> et l&rsquo;on craint que ses retomb\u00e9es, avec <a href=\"http:\/\/www.dedefensa.org\/article.php?art_id=2250\" class=\"gen\">des implications diverses<\/a> dont certaines peuvent \u00eatre incontr\u00f4lables, conduisent \u00e0 des restrictions dommageables (pour les contractants et pour les services de renseignement). Toute publicit\u00e9 favorable sur le professionnalisme des SR, toute bonne relation publique est essentiel. On a vu d&rsquo;ailleurs que l&rsquo;op\u00e9ration de Damadola a d\u00e9j\u00e0 forc\u00e9 \u00e0 des <a href=\"http:\/\/www.dedefensa.org\/article.php?art_id=2331\" class=\"gen\">regroupements de parlementaires<\/a> au nom du patriotisme, fort favorables \u00e0 ces milieux.<\/p>\n<\/p>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A la recherche d&rsquo;une v\u00e9rit\u00e9 qui colle 20 janvier 2006 La grande bataille du village de Damadola n&rsquo;a pas eu lieu le 13 janvier mais est en cours actuellement, entre Am\u00e9ricains et Pakistanais essentiellement. C&rsquo;est la bataille men\u00e9e par les Am\u00e9ricains pour obtenir une version officielle-officieuse qui les agr\u00e9e, notamment pour leurs int\u00e9r\u00eats int\u00e9rieurs. C&rsquo;est&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[5001,3379],"class_list":["post-67198","post","type-post","status-publish","format-standard","hentry","category-faits-et-commentaires","tag-damadola","tag-pakistan"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/67198","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=67198"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/67198\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=67198"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=67198"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=67198"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}