{"id":67200,"date":"2006-01-22T00:00:00","date_gmt":"2006-01-22T00:00:00","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2006\/01\/22\/rupert-smith-solana-et-la-futilite-de-la-force\/"},"modified":"2006-01-22T00:00:00","modified_gmt":"2006-01-22T00:00:00","slug":"rupert-smith-solana-et-la-futilite-de-la-force","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2006\/01\/22\/rupert-smith-solana-et-la-futilite-de-la-force\/","title":{"rendered":"<strong><em>Rupert Smith, Solana et la futilit\u00e9 de la force<\/em><\/strong>"},"content":{"rendered":"<p><h2 class=\"common-article\">Rupert Smith, Solana et la futilit\u00e9 de la force<\/h2>\n<\/p>\n<p><\/p>\n<p><p>\t22 janvier 2006   Jeudi 19 janvier 2006, \u00e0 Bruxelles, le g\u00e9n\u00e9ral britannique Sir Rupert Smith pr\u00e9sentait son livre <em>The Utility of Force: The Art of War in the Modern World<\/em>. C&rsquo;\u00e9tait l&rsquo;organisation NDA (New Defense Agenda) qui organisait cette manifestation, o\u00f9 \u00e9tait pr\u00e9sent Javier Solana, le Haut Repr\u00e9sentant europ\u00e9en.<\/p>\n<\/p>\n<p><p>\tRupert Smith est un g\u00e9n\u00e9ral britannique c\u00e9l\u00e8bre, notamment pour trois de ses principaux commandements avant son d\u00e9part \u00e0 la retraite : commandant la division britannique durant la premi\u00e8re guerre du Golfe (1991), commandant la United Nations Protection Force (UNPROFOR) en Bosnie en 1995 (il succ\u00e9dait \u00e0 Michael Rose), adjoint au SACEUR (NATO DSACEUR), le commandant en chef supr\u00eame en Europe en 1996.<\/p>\n<\/p>\n<p><p>\tLa th\u00e8se de Rupert Smith est que la guerre industrielle (<em>the industrial war<\/em>) est finie, remplac\u00e9e par la  guerre entre les gens (<em>the war amongst the people<\/em>). La force pure est devenue inutile, d\u00e9plac\u00e9e, contre-productive. A propos de la guerre contre l&rsquo;Irak, Rupert Smith parle m\u00eame, non sans une certaine ironie d\u00e9daigneuse, de \u00ab <em>la futilit\u00e9 de la force<\/em> \u00bb.<\/p>\n<\/p>\n<p><p>\tLa pr\u00e9sentation du livre dit ceci : \u00ab <em>Why do we use military force to solve the world&rsquo;s political problems? And why do our forces win military battles but still fail to solve those problems? It is because the force used lacks utility. From Iraq to the Balkans, and from Afghanistan to Chechnya, over the past fifteen years there has been a steady stream of military interventions that have not delivered on their promise for peace, or even a political resolution. Nonetheless, we still go to war  yet war as cognitively known to most non-combatants, war as a battle in the field between men and machinery, war as a massive deciding event in a dispute in international affairs: such war no longer exists.<\/em> \u00bb<\/p>\n<\/p>\n<p><p>\tCette vision est, \u00e0 premi\u00e8re vue, \u00e9tonnante pour un militaire. Elle correspond \u00e0 une exp\u00e9rience acquise par une g\u00e9n\u00e9ration de militaires europ\u00e9ens, et notamment britanniques, durant les op\u00e9rations humanitaires des ann\u00e9es quatre-vingt-dix (particuli\u00e8rement en ex-Yougoslavie). Rupert Smith est de la m\u00eame \u00e9poque et du m\u00eame esprit que <a href=\"http:\/\/www.dedefensa.org\/article.php?art_id=2315\" class=\"gen\">Sir Michael Rose<\/a>.<\/p>\n<\/p>\n<p><p>\tDans ses consid\u00e9rations, Rupert Smith observe que nombre de structures militaires s&rsquo;av\u00e8rent compl\u00e8tement d\u00e9pass\u00e9es, notamment l&rsquo;OTAN. Par contre, l&rsquo;UE, dans son \u00e9volution actuelle de mise en place d&rsquo;une structure militaire, est particuli\u00e8rement pr\u00eate \u00e0 s&rsquo;imposer comme le mod\u00e8le le mieux adapt\u00e9e aux nouvelles conditions, notamment gr\u00e2ce au mariage naturel des capacit\u00e9s militaires qui sont mises en place avec les capacit\u00e9s civiles d\u00e9j\u00e0 en place. C&rsquo;est une page blanche sur laquelle peut \u00eatre trac\u00e9e la nouvelle structure militaire (militaro-civile) ad\u00e9quate.<\/p>\n<\/p>\n<p><p>\tCertains pourraient voir dans le sch\u00e9ma qu&rsquo;esquisse Rupert-Smith, lorsqu&rsquo;on lui ajoute une dimension politique de prospective strat\u00e9gique, une vision qui se rapproche de celle du diplomate britannique <a href=\"http:\/\/www.dedefensa.org\/article.php?art_id=188\" class=\"gen\">Robert Cooper<\/a> (qui travaille au secr\u00e9tariat g\u00e9n\u00e9ral de l&rsquo;UE, avec Janvier Solana). La parent\u00e9 est incontestable ; elle n&rsquo;est d&rsquo;ailleurs pas surprenante et, \u00e9ventuellement, pas illogique. Lorsque Rupert Smith d\u00e9crit la situation militaire \u00e0 venir, sinon d&rsquo;ores et d\u00e9j\u00e0 existante, et qu&rsquo;il d\u00e9signe l&rsquo;UE comme meilleur instrument potentiel d&rsquo;intervention, il implique la possibilit\u00e9 que cet instrument soit effectivement utilis\u00e9 comme Cooper le sugg\u00e8re. L&rsquo;usage \u00e0 venir sugg\u00e9rera le jugement politique qu&rsquo;on doit en faire. Par ailleurs, tout cela ne fait que prendre en compte une situation bien r\u00e9elle, qui est la fin de la guerre conventionnelle telle que la connaissions, et l&rsquo;affirmation de la guerre de quatri\u00e8me g\u00e9n\u00e9ration (ou asym\u00e9trique). <\/p>\n<\/p>\n<p><p>\tSolana, qui assistait activement \u00e0 cette pr\u00e9sentation, s&rsquo;est montr\u00e9 compl\u00e8tement d&rsquo;accord avec Rupert Smith. (Tout au plus estime-t-il qu&rsquo;il faudrait envisager une plus grande visibilit\u00e9 militaire, d&rsquo;un point de vue classique.)<\/p>\n<\/p>\n<p><p>\tPuis il y eut les questions, apr\u00e8s cette pr\u00e9sentation. L&rsquo;une d&rsquo;entre elles br\u00fblait les l\u00e8vres, et elle fut pos\u00e9e, \u00e0 peu pr\u00e8s sous cette forme : mais si nous sommes effectivement dans le monde que vous d\u00e9crivez, alors nous sommes dans un autre monde que celui des Am\u00e9ricains? Question br\u00fblante et question in\u00e9vitable, qui tient en r\u00e9alit\u00e9 l&rsquo;essentiel de l&rsquo;argument politico-militaire europ\u00e9en en faveur du domaine transatlantique et de la coop\u00e9ration serr\u00e9e avec les Am\u00e9ricains. Coop\u00e9rer avec les Am\u00e9ricains? Autrement dit, faire coop\u00e9rer <em>the industrial war<\/em> avec <em>the war amongst the people<\/em>? Aucun sens, puisque c&rsquo;est justement le fond du propos, que ces deux situations se distinguent parce qu&rsquo;elles n&rsquo;ont rien de commun. Alors, une alliance strat\u00e9gique entre deux conceptions si oppos\u00e9es? Aucun sens non plus.<\/p>\n<\/p>\n<p><p>\tL\u00e0 se situe un incident comique. On aurait pu croire que la question s&rsquo;adressait \u00e0 Rupert Smith. Mais Solana,  sans doute (c&rsquo;est nous qui supposons..) r\u00e9alisant soudain les implications de la question, des conceptions de Rupert Smith et, par cons\u00e9quent, de son propre soutien aux conceptions de Rupert Smith,  Solana s&#8217;empara prestement du micro. Il s&#8217;employa \u00e0 noyer sous un flot de rh\u00e9torique verbeuse (valeurs commune, d\u00e9mocratie et le reste des sornettes connues) la redoutable implication que l&rsquo;intervenant avait mise \u00e0 jour.<\/p>\n<\/p>\n<p><p>\tC&rsquo;est une bonne fa\u00e7on de clore le d\u00e9bat. Les remarques et les constats de Rupert Smith, les conclusions qu&rsquo;il en tire, sont \u00e9videmment \u00e0 mettre \u00e0 l&rsquo;actif de son ouverture d&rsquo;esprit et de la fra\u00eecheur de sa r\u00e9flexion. Par ailleurs, ils ne font que rendre compte d&rsquo;une r\u00e9alit\u00e9 chaque jour plus \u00e9vidente, qui est le changement de nature de ce qu&rsquo;on a coutume de d\u00e9signer sous le nom de la guerre,  mais sans doute est-il n\u00e9cessaire de disposer d&rsquo;ouverture d&rsquo;esprit et de fra\u00eecheur de r\u00e9flexion, aujourd&rsquo;hui, pour rendre compte de la r\u00e9alit\u00e9, tant celle-ci est obscurcie par l&rsquo;intervention virtualiste. Sur le plan politique et sur le plan strat\u00e9gique, les implications sont consid\u00e9rables.<\/p>\n<\/p>\n<p><p>\tIl est vrai que le constat de la fin de <em>the industrial war<\/em> nous \u00e9loigne radicalement des conceptions am\u00e9ricaines. Les Am\u00e9ricains sont totalement verrouill\u00e9s dans ce concept, qui implique le d\u00e9veloppement g\u00e9om\u00e9trique des technologies, du contr\u00f4le centralis\u00e9 (gr\u00e2ce aux technologies), de l&rsquo;utilisation massive de la puissance de feu contr\u00f4l\u00e9e par les technologies, etc. Lorsque Rupert Smith \u00e9voque la \u00ab <em>futilit\u00e9 de la force<\/em> \u00bb \u00e0 propos de la guerre en Irak, on comprend que cela s&rsquo;adresse aux Am\u00e9ricains.<\/p>\n<\/p>\n<p><p>\tCombien de temps ce divorce de fait durera-t-il sans se concr\u00e9tiser au niveau politique ? Autrement dit : 1) pendant combien de temps encore Solana arrivera-t-il \u00e0 s&#8217;emparer du micro avant que Rupert Smith puisse r\u00e9pondre ; 2) pendant combien de temps encore Solana aura-t-il envie de s&#8217;emparer du micro avant que Rupert Smith puisse r\u00e9pondre ; et 3) pendant combien de temps encore Solana s&#8217;emparera-t-il du micro sans avoir envie de dire que, finalement, apr\u00e8s tout, oui, nous vivons d\u00e9sormais dans un autre monde que celui des Am\u00e9ricains.<\/p>\n<\/p>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Rupert Smith, Solana et la futilit\u00e9 de la force 22 janvier 2006 Jeudi 19 janvier 2006, \u00e0 Bruxelles, le g\u00e9n\u00e9ral britannique Sir Rupert Smith pr\u00e9sentait son livre The Utility of Force: The Art of War in the Modern World. C&rsquo;\u00e9tait l&rsquo;organisation NDA (New Defense Agenda) qui organisait cette manifestation, o\u00f9 \u00e9tait pr\u00e9sent Javier Solana, le&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[3745,2645,5004,5005,5003,4457,3777,4128],"class_list":["post-67200","post","type-post","status-publish","format-standard","hentry","category-faits-et-commentaires","tag-asymetrique","tag-guerre","tag-industrial","tag-nda","tag-rupert","tag-smith","tag-solana","tag-war"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/67200","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=67200"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/67200\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=67200"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=67200"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=67200"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}