{"id":67207,"date":"2006-01-24T00:00:00","date_gmt":"2006-01-24T00:00:00","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2006\/01\/24\/pour-memoire-happy-birthday-lempire\/"},"modified":"2006-01-24T00:00:00","modified_gmt":"2006-01-24T00:00:00","slug":"pour-memoire-happy-birthday-lempire","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2006\/01\/24\/pour-memoire-happy-birthday-lempire\/","title":{"rendered":"Pour m\u00e9moire: <em>happy birthday<\/em>, l&#8217;empire"},"content":{"rendered":"<p><p>Robert Parry est un sp\u00e9cialiste de l&rsquo;histoire secr\u00e8te des USA dans la p\u00e9riode 1976 jusqu&rsquo;\u00e0 nos jours; sp\u00e9cialiste, notamment, de la p\u00e9riode Reagan, du scnadale Iran-Contra de la p\u00e9riode, de la pr\u00e9sident Bush-p\u00e8re et de la dynastie des Bush. Dans cet article du 20 janvier sur son site  <a href=\"http:\/\/www.consortiumnews.com\/2006\/011906.html\" class=\"gen\">Consortium News<\/a>, Parry nous invite \u00e0 f\u00eater l&rsquo;anniversaire du quart de si\u00e8cle de l&rsquo;Empire, version postmoderne. (C&rsquo;est le 20 janvier 1981 que Reagan pr\u00eata serment comme pr\u00e9sident des \u00c9tats-Unis.)<\/p>\n<\/p>\n<p><p>\tDans cet article, Parry tente de d\u00e9brouiller la fameuse <em>October Surprise<\/em> de 1980-81 qui liquida Carter et aboutit \u00e0 la lib\u00e9ration des otages am\u00e9ricains de T\u00e9h\u00e9ran le jour de l&rsquo;inauguration de Reagan. Son hypoth\u00e8se, \u00e9tay\u00e9e par de nombreux faits, est que cette lib\u00e9ration fut le r\u00e9sultat d&rsquo;un march\u00e9 entre les Iraniens et le parti r\u00e9publicain, march\u00e9 conclu en octobre 1980 \u00e0 Paris, dans une n\u00e9gociation secr\u00e8te dirig\u00e9e par le candidat vice-pr\u00e9sident Bush-p\u00e8re. (L&rsquo;hypoth\u00e8se avait \u00e9t\u00e9 largement \u00e9voqu\u00e9e \u00e0 l&rsquo;\u00e9poque.) En \u00e9change s&rsquo;\u00e9tablit un courant r\u00e9gulier de livraisons ill\u00e9gales d&rsquo;armes US \u00e0 l&rsquo;Iran, avec la complicit\u00e9 d&rsquo;Isra\u00ebl et de divers groupes priv\u00e9s de droite, affili\u00e9s au parti r\u00e9publicain. L&rsquo;affaire devait \u00e9galement bifurquer sur le scandale Iran-Contras de 1985-87.<\/p>\n<\/p>\n<p><p>\tDerri\u00e8re cette affaire, il y a une th\u00e8se : une v\u00e9ritable prise de pouvoir aux USA par les extr\u00e9mistes de toutes tendances, sous l&rsquo;\u00e9gide du parti r\u00e9publicain et du <em>Big Business<\/em> rassembl\u00e9 pour une contre-attaque majeure (apr\u00e8s les d\u00e9sordres des ann\u00e9es 1960) par le <a href=\"http:\/\/www.dedefensa.org\/article.php?art_id=353\" class=\"gen\">Manifeste Powell<\/a> de 1971. En m\u00eame temps, on assiste \u00e0 une privatisation massive de toutes les activit\u00e9s lucratives et bellicistes de s\u00e9curit\u00e9 nationale aux USA, \u00e0 commencer par nombre des activit\u00e9s de la CIA sous la direction de Bill Casey (directeur de 1981 \u00e0 1986). Dans ce sch\u00e9ma d&rsquo;un quart de si\u00e8cle, l&rsquo;\u00e8re Clinton est r\u00e9duit \u00e0 un incident o\u00f9 le pr\u00e9sident soi disant d\u00e9mocrate joue le r\u00f4le du compagnon de route des ambitions r\u00e9publicaines,  que sa femme semble aujourd&rsquo;hui \u00e0 m\u00eame de p\u00e9renniser.<\/p>\n<\/p>\n<p><p>\tC&rsquo;est une th\u00e8se de type complotiste lorsqu&rsquo;elle est ainsi r\u00e9sum\u00e9e, mais qui s&rsquo;applique justement \u00e0 un nombre important d&rsquo;\u00e9v\u00e9nements majeurs qui secouent les USA depuis un quart de si\u00e8cle, et fournit une explication coh\u00e9rente sur le long terme. Elle fait d&rsquo;autant mieux comprendre la singularit\u00e9 radicale et extr\u00e9miste de l&rsquo;administration GW. Bref, elle a quelque chose de la r\u00e9alit\u00e9 fondamentale d&rsquo;un fait indubitable : la transformation des USA en cette force belliciste, pr\u00e9datrice, corrompue et totalement incontr\u00f4lable qu&rsquo;ils sont devenus.<\/p>\n<\/p>\n<p><\/p>\n<p><p>\tMis en ligne le 24 janvier 2006 \u00e0 12H57<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Robert Parry est un sp\u00e9cialiste de l&rsquo;histoire secr\u00e8te des USA dans la p\u00e9riode 1976 jusqu&rsquo;\u00e0 nos jours; sp\u00e9cialiste, notamment, de la p\u00e9riode Reagan, du scnadale Iran-Contra de la p\u00e9riode, de la pr\u00e9sident Bush-p\u00e8re et de la dynastie des Bush. Dans cet article du 20 janvier sur son site Consortium News, Parry nous invite \u00e0 f\u00eater&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[2],"tags":[4431,2773,5012,4464,1391,3215,5013],"class_list":["post-67207","post","type-post","status-publish","format-standard","hentry","category-bloc-notes","tag-contras","tag-iran","tag-october","tag-parry","tag-powell","tag-reagan","tag-surprise"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/67207","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=67207"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/67207\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=67207"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=67207"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=67207"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}