{"id":67265,"date":"2006-02-10T00:00:00","date_gmt":"2006-02-10T00:00:00","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2006\/02\/10\/une-initiative-revelatrice\/"},"modified":"2006-02-10T00:00:00","modified_gmt":"2006-02-10T00:00:00","slug":"une-initiative-revelatrice","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2006\/02\/10\/une-initiative-revelatrice\/","title":{"rendered":"Une initiative r\u00e9v\u00e9latrice"},"content":{"rendered":"<p><h2 class=\"titleset_a.deepblue\" style=\"color:#0f3955; font-size:2em\">Une initiative r\u00e9v\u00e9latrice<\/h2>\n<\/p>\n<p><p>10 f\u00e9vrier 2006 &mdash; Le 3 f\u00e9vrier, <em>dedefensa.org<\/em> recevait dans sa bo&icirc;te \u00e0 lettre, en courrier de presse, un exemplaire de <em>Air &#038; Space Power Journal<\/em> (ASPJ), hiver 2005, avec la mention approximative (ASPJ est une revue trimestrielle) mais sensationnelle : \u00ab\u00a0<em>Journal en fran\u00e7ais<\/em>\u00ab\u00a0. (On a acc\u00e8s \u00e0 cette \u00e9dition sur le site de <a class=\"gen\" href=\"http:\/\/www.airpower.maxwell.af.mil\/apjinternational\/aspj-f\/2005\/hiver\/hiver05.html\">ASPJ en fran\u00e7ais<\/a>.)<\/p>\n<\/p>\n<p><p>&#8230; \u00ab\u00a0Sensationnelle\u00a0\u00bb, sans aucun doute. ASPJ (en anglais) est une des revues doctrinales de l&rsquo;USAF, d\u00e9pendant de l&rsquo;Air University de l&rsquo;USAF. Elle v\u00e9hicule les concepts, conceptions et doctrines de l&rsquo;USAF. Elle poss\u00e8de une \u00e9dition en espagnol et en portugais depuis la fin des ann\u00e9es quarante, &mdash; indiquant par l\u00e0 que l&rsquo;USAF consid\u00e8re \u00e9galement ASPJ comme un v\u00e9hicule de support des exportations de syst\u00e8mes d&rsquo;arme vers les pays usagers de ces deux langues, notamment et principalement l&rsquo;Am\u00e9rique latine. Une version en arabe a \u00e9t\u00e9 lanc\u00e9e d\u00e9but 2005, dont on peut dire qu&rsquo;elle peut se justifier par l&rsquo;aspect de l&rsquo;exportation mais aussi, si l&rsquo;on consid\u00e8re les \u00e9v\u00e9nements en cours (tensions avec le monde musulman), pour d&rsquo;autres raisons plus politiques. Une version en fran\u00e7ais n&rsquo;a \u00e9videmment aucune raison d&rsquo;\u00eatre pour la raison de l&rsquo;exportation, ni dans le pass\u00e9 ni aujourd&rsquo;hui (la France et les pays francophones sont en g\u00e9n\u00e9ral consid\u00e9r\u00e9s comme des \u00ab\u00a0territoires hostiles\u00a0\u00bb par l&rsquo;Am\u00e9rique pour l&rsquo;exportation des armements ; si des efforts d&rsquo;investissements sont faits ponctuellement, cette situation g\u00e9n\u00e9rale justifie de consid\u00e9rer comme inutiles des liens conjoncturels comme l&rsquo;est une version fran\u00e7aise de ASPJ).<\/p>\n<\/p>\n<p><p>Notre exp\u00e9rience des publications am\u00e9ricaines sur l&rsquo;aviation militaire, et encore plus des publications de l&rsquo;USAF, nous sugg\u00e8re de penser qu&rsquo;il s&rsquo;agit d&rsquo;une initiative sans pr\u00e9c\u00e9dent. Plus encore : c&rsquo;est une initiative sans pr\u00e9c\u00e9dent qui \u00e9tait compl\u00e8tement improbable si l&rsquo;on se r\u00e9f\u00e8re \u00e0 l&rsquo;esprit de la chose. Dans les milieux de l&rsquo;a\u00e9ronautique militaire am\u00e9ricaine, il existe, au niveau de l&rsquo;appr\u00e9ciation promotionnelle et concurrentielle, de l&rsquo;appr\u00e9ciation des relations publiques, de l&rsquo;appr\u00e9ciation du symbole, une volont\u00e9 syst\u00e9matique, du c\u00f4t\u00e9 anglo-saxon, de minimiser, de r\u00e9duire l&rsquo;importance du fait a\u00e9ronautique fran\u00e7ais, voire de le rejeter et de le d\u00e9nier bel et bien. L&rsquo;aspect concurrentiel des langues fran\u00e7aise et anglais entre \u00e9galement et compl\u00e9mentairement en ligne de compte, avec le facteur suppl\u00e9mentaire de la situation qui fait de l&rsquo;anglais la langue techniquement universelle de l&rsquo;aviation. Nous dirions d&rsquo;une fa\u00e7on abrupte qu&rsquo;il y a, du c\u00f4t\u00e9 anglo-saxon et am\u00e9ricaniste une volont\u00e9 constante de nier l&rsquo;existence du \u00ab\u00a0fait a\u00e9ronautique fran\u00e7ais\u00a0\u00bb, avec sa puissante tradition remontant aux sources de la cr\u00e9ation de l&rsquo;aviation, avec son ambition constante de figurer au premier plan de cette activit\u00e9.<\/p>\n<\/p>\n<p><p>(On observera que ce cas est assez similaire \u00e0 celui du cin\u00e9ma, chronologiquement, historiquement et substantiellement : il y a une concurrence naturelle entre les USA et la France, vue du c\u00f4t\u00e9 am\u00e9ricain de fa\u00e7on tr\u00e8s ambivalente, dans le cin\u00e9ma comme dans l&rsquo;aviation &mdash; la France per\u00e7ue, \u00e0 cause de ses conceptions dans le domaine, comme une ennemie mortelle par les tenants du \u00ab\u00a0cin\u00e9ma-industrie\u00a0\u00bb, au contraire comme une sorte de mod\u00e8le par les Am\u00e9ricains qui voudraient que le cin\u00e9ma soit consid\u00e9r\u00e9 d&rsquo;abord comme un art. Cette similitude nous ram\u00e8ne au d\u00e9but du XX\u00e8me si\u00e8cle, \u00e0 l&rsquo;aube de la cr\u00e9ation de ces deux activit\u00e9s, qui tiennent elles-m\u00eames les cl\u00e9s des deux grands domaines de d\u00e9veloppement de la modernit\u00e9: les technologies avanc\u00e9es pour l&rsquo;aviation, l&rsquo;image et la communication pour le cin\u00e9ma.)<\/p>\n<\/p>\n<p><p>On comprend que, pour toutes ces raisons, une initiative am\u00e9ricaine dans le sens de la promotion en langue fran\u00e7aise d&rsquo;un ouvrage doctrinal de l&rsquo;USAF est r\u00e9ellement un \u00e9v\u00e9nement remarquable.<\/p>\n<\/p>\n<p><p>L&rsquo;autre \u00e9l\u00e9ment remarquable de cet \u00ab\u00a0ASPJ en fran\u00e7ais\u00a0\u00bb, c&rsquo;est le choix du r\u00e9dacteur en chef de l&rsquo;\u00e9dition fran\u00e7aise. Voici comment il est pr\u00e9sent\u00e9 dans la pr\u00e9sentation officielle de l&rsquo;\u00e9dition en fran\u00e7ais (pour une fois, certains de nos lecteurs seront satisfaits puisque, par le fait m\u00eame, il s&rsquo;agit de textes en fran\u00e7ais): &laquo; <em>L&rsquo;\u00e9diteur-r\u00e9dacteur de ASPJ en fran\u00e7ais, Monsieur R\u00e9my Mauduit, poss\u00e8de des qualifications impressionnantes. Originaire d&rsquo;Alg\u00e9rie, il a une exp\u00e9rience consid\u00e9rable de l&rsquo;insurrection et de la contre-insurrection acquise lors de la guerre d&rsquo;Alg\u00e9rie de 1954 \u00e0 1962. En tant qu&rsquo;insurg\u00e9 du Front de Lib\u00e9ration National (FLN), il s&rsquo;est battu contre l&rsquo;arm\u00e9e fran\u00e7aise pendant cinq ann\u00e9es jusqu&rsquo;\u00e0 ce que ses camarades de combat, le suspectant de complicit\u00e9 avec l&rsquo;ennemi l&#8217;emprisonnent et le torturent. &Eacute;chappant \u00e0 ses tortionnaires, R\u00e9my Mauduit rejoint l&rsquo;arm\u00e9e fran\u00e7aise et devient lieutenant, au service d&rsquo;un commando qui pourchassait son ancienne cohorte FLN. Plus tard, quand le Pr\u00e9sident de la R\u00e9publique Fran\u00e7aise, le g\u00e9n\u00e9ral Charles de Gaulle conc\u00e8de l&rsquo;ind\u00e9pendance de l&rsquo;Alg\u00e9rie, R. Mauduit abandonne l&rsquo;arm\u00e9e fran\u00e7aise pour rejoindre l&rsquo;Organisation de l&rsquo;Arm\u00e9e secr\u00e8te (OAS), un groupe de dissidents dirig\u00e9 par des officiers sup\u00e9rieurs fran\u00e7ais qui s&rsquo;\u00e9taient violemment oppos\u00e9s \u00e0 la politique alg\u00e9rienne du g\u00e9n\u00e9ral de Gaulle. R. Mauduit ne passe que quelques jours avec l&rsquo;OAS; il est rapidement arr\u00eat\u00e9 et emprisonn\u00e9 par l&rsquo;arm\u00e9e fran\u00e7aise. Il \u00e9migre aux &Eacute;tas-Unis apr\u00e8s sa lib\u00e9ration et fait une longue carri\u00e8re dans le monde des affaires qui le m\u00e8ne \u00e0 effectuer de multiples voyages dans toute l&rsquo;Afrique.<\/em> &raquo;<\/p>\n<\/p>\n<p><p>Ren\u00e9 M. Mauduit est un cas int\u00e9ressant. C&rsquo;est l&rsquo;auteur de ce livre mentionn\u00e9, effectivement tr\u00e8s int\u00e9ressant, &mdash; <em>J&rsquo;ai \u00e9t\u00e9 fellagha, officier fran\u00e7ais et d\u00e9serteur, &mdash; du FLN \u00e0 l&rsquo;OAS<\/em> (Le Seuil, avril 2004).<\/p>\n<\/p>\n<p><p>(C&rsquo;est alors le nom de R\u00e9my Madoui qui appara&icirc;t comme sur la jaquette du livre, nom d\u00e9j\u00e0 francis\u00e9 par rapport \u00e0 la naissance de l&rsquo;auteur \u00e0 T\u00e9niet el-H\u00e2ad, petit-fils de l&rsquo;<em>agha<\/em> Tayeb, chef de la tribu des Ouled Sidi M&rsquo;Hamed, d&rsquo;une vieille famille de notables arabes. Les transformations du nom de Madoui\/Maudouit, &mdash; nom arabe francis\u00e9, nom arabe francis\u00e9 puis am\u00e9ricanis\u00e9, &mdash; marquent une prodigieuse aventure et une aventure paradoxale au travers des contradictions du drame alg\u00e9rien. A lire le livre de Madoui, on se demande comment l&rsquo;historiographie fran\u00e7aise et militante parvient aujourd&rsquo;hui, sinon par devoir de morale dont on mesure ainsi le conformisme et la vanit\u00e9 id\u00e9ologique, \u00e0 traiter du drame alg\u00e9rien en noir et blanc, m\u00e9chants d&rsquo;un c\u00f4t\u00e9, gentils de l&rsquo;autre. De quel c\u00f4t\u00e9 est Madoui? De quel c\u00f4t\u00e9 est ce cadre sup\u00e9rieur de l&rsquo;arm\u00e9e [ALN] du FLN dans la seule grande unit\u00e9 d\u00e9mocratique qu&rsquo;elle d\u00e9ploya [la <em>Willaya<\/em> IV de l&rsquo;Alg\u00e9rois], ensuite purg\u00e9 par les staliniens du FLN, ceux qui prendront le pouvoir \u00e0 Alger en 1962, ensuite tortur\u00e9 pendant un mois dans un camp de torture du FLN en 1960 [cet aspect de la torture en Alg\u00e9rie int\u00e9resse peu les historiens-militants], ensuite pass\u00e9 \u00e0 l&rsquo;arm\u00e9e fran\u00e7aise dans les commandos de chasse du 6\u00e8me r\u00e9giment d&rsquo;infanterie, ensuite pass\u00e9 \u00e0 l&rsquo;OAS avant de passer tout simplement en justice en France?)<\/p>\n<\/p>\n<p><p>Il faudra revenir sur l&rsquo;exp\u00e9rience r\u00e9volutionnaire et d\u00e9mocratique de Madoui, sur son t\u00e9moignage sur la guerre d&rsquo;Alg\u00e9rie. En attendant, c&rsquo;est sa position \u00e0 la t\u00eate d'\u00a0\u00bbASPJ fran\u00e7ais\u00a0\u00bb qui nous int\u00e9resse ici. Manifestement, c&rsquo;est le livre de Madoui, dont une recension est accessible sur <a class=\"gen\" href=\"http:\/\/www.airpower.maxwell.af.mil\/airchronicles\/bookrev\/berg1.html\">le site d&rsquo;ASPJ<\/a>, qui a attir\u00e9 l&rsquo;attention de l&rsquo;USAF. C&rsquo;est \u00e9videmment l&rsquo;exp\u00e9rience dans la question du terrorisme de l&rsquo;auteur qui justifie essentiellement sa nouvelle position. La pr\u00e9face de pr\u00e9sentation de Madoui insiste sur cette question, par rapport \u00e0 l&rsquo;USAF : &laquo; <em>D&rsquo;une mani\u00e8re g\u00e9n\u00e9rale, les forces a\u00e9rienne et spatiale des &Eacute;tats-Unis doivent \u00eatre \u00e9quip\u00e9es, organis\u00e9es et entra&icirc;n\u00e9es afin d&rsquo;\u00e9tablir leur sup\u00e9riorit\u00e9 op\u00e9rationnelle face \u00e0 tout type de menace, notamment une menace asym\u00e9trique. Une nouvelle grille d&rsquo;analyse de la violence et de la s\u00e9curit\u00e9 s&rsquo;av\u00e8re donc n\u00e9cessaire. Le r\u00f4le de l&rsquo;USAF dans la guerre contre le terrorisme et la gu\u00e9rilla sera le th\u00e8me de la Revue a\u00e9rienne et spatiale, en fran\u00e7ais, du printemps 2006.<\/em> &raquo; Le premier num\u00e9ro de \u00ab\u00a0ASPJ fran\u00e7ais\u00a0\u00bb comprend \u00e9videmment un article sur la question : &laquo; <em>Rendre la puissance a\u00e9rienne efficace contre la gu\u00e9rilla<\/em> &raquo;, par le Dr. Thomas R. Searle.<\/p>\n<\/p>\n<p><p>Le cas de \u00ab\u00a0ASPJ fran\u00e7ais\u00a0\u00bb tel qu&rsquo;il est expos\u00e9 permet de proposer deux remarques :<\/p>\n<\/p>\n<p><p>&bull; Les militaires am\u00e9ricains sont particuli\u00e8rement int\u00e9ress\u00e9s, voire fascin\u00e9s par l&rsquo;exp\u00e9rience fran\u00e7aise en Alg\u00e9rie et, plus g\u00e9n\u00e9ralement, par la guerre d&rsquo;Alg\u00e9rie. On le constate au travers des diverses lectures favorites dans les forces arm\u00e9es, notamment celles de <a class=\"gen\" href=\"http:\/\/www.dedefensa.org\/article.php?art_id=2358\">David Galuda et du colonel Trinquier<\/a>, dont l&rsquo;enseignement sur la contre-gu\u00e9rilla est fond\u00e9 surtout sa la guerre d&rsquo;Alg\u00e9rie, ou encore, plus anecdotiquement, par l&rsquo;int\u00e9r\u00eat qu&rsquo;ils port\u00e8rent au film <a class=\"gen\" href=\"http:\/\/www.dedefensa.org\/article.php?art_id=1373\">\u00ab\u00a0la bataille d&rsquo;Alger\u00a0\u00bb<\/a>. La parution de \u00ab\u00a0ASPJ fran\u00e7ais\u00a0\u00bb autant que la nomination de Madoui\/Mauduit, qui rassemble tous les enseignements de la guerre (gu\u00e9rilla, contre-gu\u00e9rilla, s\u00e9dition, etc.), sont une confirmation de ces tendances, d&rsquo;autant plus remarquable qu&rsquo;elle concerne l&rsquo;USAF qui est traditionnellement une arme peu int\u00e9ress\u00e9e par ces questions.<\/p>\n<\/p>\n<p><p>&bull; Justement&hellip; Il semble que les inqui\u00e9tudes de l&rsquo;USAF quant \u00e0 ses capacit\u00e9s d&rsquo;adaptation \u00e0 la \u00ab\u00a0nouvelle\u00a0\u00bb forme de la guerre, guerre asym\u00e9trique ou de la quatri\u00e8me g\u00e9n\u00e9ration, apparaissent particuli\u00e8rement fortes pour qu&rsquo;une telle initiative ait \u00e9t\u00e9 suscit\u00e9e et men\u00e9e \u00e0 bien. Il s&rsquo;agit sans aucun doute d&rsquo;une reconnaissance de r\u00e9elles faiblesses, dans tous les cas dans certains milieux de l&rsquo;USAF (essentiellement les milieux des universitaires et des doctrinaux) ; c&rsquo;est une d\u00e9marche assez rare dans les cercles am\u00e9ricanistes pour qu&rsquo;elle soit signal\u00e9e avec insistance.<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Une initiative r\u00e9v\u00e9latrice 10 f\u00e9vrier 2006 &mdash; Le 3 f\u00e9vrier, dedefensa.org recevait dans sa bo&icirc;te \u00e0 lettre, en courrier de presse, un exemplaire de Air &#038; Space Power Journal (ASPJ), hiver 2005, avec la mention approximative (ASPJ est une revue trimestrielle) mais sensationnelle : \u00ab\u00a0Journal en fran\u00e7ais\u00ab\u00a0. (On a acc\u00e8s \u00e0 cette \u00e9dition sur le&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[2735,5078,5081,4450,5079,5080,4281,41],"class_list":["post-67265","post","type-post","status-publish","format-standard","hentry","category-faits-et-commentaires","tag-algerie","tag-aspj","tag-fellagha","tag-fln","tag-madoui","tag-oas","tag-torture","tag-usaf"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/67265","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=67265"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/67265\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=67265"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=67265"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=67265"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}