{"id":67268,"date":"2006-02-11T00:00:00","date_gmt":"2006-02-11T00:00:00","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2006\/02\/11\/la-verite-des-prix-style-jsf-britannique\/"},"modified":"2006-02-11T00:00:00","modified_gmt":"2006-02-11T00:00:00","slug":"la-verite-des-prix-style-jsf-britannique","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2006\/02\/11\/la-verite-des-prix-style-jsf-britannique\/","title":{"rendered":"La v\u00e9rit\u00e9 des prix, \u2014 style JSF britannique"},"content":{"rendered":"<p><p>R\u00e9cemment, deux sources britanniques ont annonc\u00e9 implicitement,  on veut dire de fa\u00e7on discr\u00e8te et sans trop insister,  le prix du JSF britannique. Il appara\u00eet tr\u00e8s probable qu&rsquo;il s&rsquo;agisse d&rsquo;\u00e9valuations officielles (MoD) que font les Britanniques pour leur version (le F-35B \u00e0 d\u00e9collage vertical), en fonction des plus r\u00e9centes donn\u00e9es dont ils disposent.<\/p>\n<\/p>\n<p><p>\tBien entendu, ces estimations, d\u00e9j\u00e0 pharamineuses puisqu&rsquo;au del\u00e0 de $100 millions l&rsquo;exemplaire, ne sont que temporaires. Nous sommes \u00e0 6-8 ans de la fin du d\u00e9veloppement du JSF, si tout se passe bien. L&rsquo;on sait que la tendance absolue d&rsquo;un tel d\u00e9lai est celle d&rsquo;augmentations suppl\u00e9mentaires du co\u00fbt. Les conditions budg\u00e9taires actuelles au Pentagone, autant que les conditions sp\u00e9cifiques du programme JSF, aggravent encore les perspectives de cette tendance.<\/p>\n<\/p>\n<p><p>\t&bull; Dans <em>Jane&rsquo;s Defence Weekly<\/em> du 1er f\u00e9vrier, le prix global des JSF britanniques permet de d\u00e9duire un co\u00fbt unitaire de $118,6 millions : \u00ab <em>The UK plans to sign the PSFD MoU with the US late in 2006, which will commit the country to procuring a certain number of aircraft, currently estimated at up to 150 units at a cost of GBP10 billion (USD17.8 billion). Subsequent costs, however, will be determined by whatever through life support strategy is adopted.<\/em> \u00bb<\/p>\n<\/p>\n<p><p>\t&bull;  Dans <a href=\"http:\/\/www.timesonline.co.uk\/article\/0,,2-2028178,00.html\" class=\"gen\">The Times<\/a> du 7 f\u00e9vrier, on lit ceci, o\u00f9 le prix est indiqu\u00e9 en passant, sans trop insister, et en fonction d&rsquo;une date de mise en service (2012) qui semble notablement optimiste: \u00ab <em>The F-35 JSF, which will cost $104 million each, is being developed jointly for the US Armed Forces and for the Royal Navy&rsquo;s two large aircraft carriers, the first of which is due to come into service in 2012.<\/em> \u00bb<\/p>\n<\/p>\n<p><\/p>\n<p><p>\tMis en ligne le 11 f\u00e9vrier 2006 \u00e0 15H51<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>R\u00e9cemment, deux sources britanniques ont annonc\u00e9 implicitement, on veut dire de fa\u00e7on discr\u00e8te et sans trop insister, le prix du JSF britannique. Il appara\u00eet tr\u00e8s probable qu&rsquo;il s&rsquo;agisse d&rsquo;\u00e9valuations officielles (MoD) que font les Britanniques pour leur version (le F-35B \u00e0 d\u00e9collage vertical), en fonction des plus r\u00e9centes donn\u00e9es dont ils disposent. Bien entendu, ces&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[2],"tags":[250,3477,2758],"class_list":["post-67268","post","type-post","status-publish","format-standard","hentry","category-bloc-notes","tag-jsf","tag-prix","tag-uk"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/67268","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=67268"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/67268\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=67268"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=67268"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=67268"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}