{"id":67269,"date":"2006-02-12T00:00:00","date_gmt":"2006-02-12T00:00:00","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2006\/02\/12\/la-crise-politique-britannique-et-le-faustian-bargain-du-jsf\/"},"modified":"2006-02-12T00:00:00","modified_gmt":"2006-02-12T00:00:00","slug":"la-crise-politique-britannique-et-le-faustian-bargain-du-jsf","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2006\/02\/12\/la-crise-politique-britannique-et-le-faustian-bargain-du-jsf\/","title":{"rendered":"<strong><em>La crise politique britannique et le \u201cFaustian bargain\u201d du JSF<\/em><\/strong>"},"content":{"rendered":"<p><h2 class=\"common-article\">La crise politique britannique et le <em>Faustian bargain<\/em> du JSF<\/h2>\n<\/p>\n<p><\/p>\n<p><p>\t12 f\u00e9vrier 2006  Le Royaume-Uni est entr\u00e9 dans une p\u00e9riode d&rsquo;instabilit\u00e9 gouvernementale \u00e0 la suite de la d\u00e9t\u00e9rioration continuelle de la position de Tony Blair suite \u00e0 la guerre d&rsquo;Irak. Le parti travailliste a connu jeudi une d\u00e9faite retentissante (contre un lib\u00e9ral) dans une \u00e9lection partielle \u00e0 Dunfermline, dans la circonscription de Brown, o\u00f9 le succ\u00e8s travailliste ne faisait gu\u00e8re de doute. La position du gouvernement au Parlement, malgr\u00e9 sa majorit\u00e9 parlementaire, est tr\u00e8s fragile avec une minorit\u00e9 significative de d\u00e9put\u00e9s travaillistes votant d\u00e9sormais \u00e9pisodiquement aux c\u00f4t\u00e9s des conservateurs et des lib\u00e9raux (Blair a connu la semaine derni\u00e8re sa deuxi\u00e8me d\u00e9faite parlementaire depuis les \u00e9lections de l&rsquo;ann\u00e9e derni\u00e8re). D&rsquo;ores et d\u00e9j\u00e0, des proches de Tony Blair estiment que Gordon Brown est install\u00e9 dans le r\u00f4le effectif de <a href=\"http:\/\/observer.guardian.co.uk\/politics\/story\/0,,1708045,00.html\" class=\"gen\">co-Premier ministre<\/a>.<\/p>\n<\/p>\n<p><p>\t\u00ab <em>Gordon Brown and Tony Blair are now in effect running Britain as a dual premiership, according to one of the cabinet&rsquo;s most senior figures and close ally of the Prime Minister. Charles Clarke, the Home Secretary, admitted in a remarkably frank interview with The Observer that &lsquo;profound&rsquo; events were unfolding, with Brown given unprecedented licence to set out his stall for the leadership while the Prime Minister was still in office. But he disclosed that he had warned Brown against appearing &lsquo;just to cavil&rsquo; with his colleagues, saying that it was crucial now to show he was a team player.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb <em>Asked if Brown and Blair were now effectively running a dual premiership, Clarke said: That&rsquo;s what Tony would always want, what Gordon should do. To be a great, great leader, that requires [Gordon] to lead &#8211; he has to come out and make the speeches, make the arguments.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb <em>Brown&rsquo;s new status as joint Prime Minister will be displayed tomorrow when he uses a major speech on national security to disclose that three serious terrorist attacks in Britain have been averted since 21 July &#8211; using the evidence of continued threats to justify controversial plans to outlaw the glorification of terrorism and introduce ID cards. The government faces knife-edge votes on both issues this week.<\/em> \u00bb<\/p>\n<\/p>\n<p><p>\tDans ce contexte, la question de JSF prend elle-m\u00eame une tournure dramatique, avec la perspective d&rsquo;un engagement \u00e0 prendre (commande) en novembre prochain. La question du co\u00fbt s&rsquo;est impos\u00e9e comme un deuxi\u00e8me facteur crucial \u00e0 c\u00f4t\u00e9 de la question du transfert des technologies et du contr\u00f4le de l&rsquo;avion. Les Britanniques ne cachent plus leur \u00e9valuation d&rsquo;un prix tr\u00e8s \u00e9lev\u00e9 du JSF, <a href=\"http:\/\/www.dedefensa.org\/article.php?art_id=2414\" class=\"gen\">plus de $100 millions<\/a> l&rsquo;exemplaire. Cet aspect est d&rsquo;autant plus sensible que Gordon Brown est chancelier de l&rsquo;Echiquier et juge l&rsquo;avenir budg\u00e9taire du Royaume-Uni tr\u00e8s difficile.<\/p>\n<\/p>\n<p><p>\tD&rsquo;une fa\u00e7on g\u00e9n\u00e9rale la situation britannique, notamment au regard du programme JSF, a \u00e9t\u00e9 \u00e9tonnamment illustr\u00e9e par un discours r\u00e9cent de Keith Hayward, chef de recherche \u00e0 la Royal Aeronautical Society. (Le discours a eu lieu le 24 janvier \u00e0 Londres. <em>Jane&rsquo;s Defence Industry<\/em> en a fait rapport le lendemain [<a href=\"http:\/\/www.janes.com\/business\/news\/jdi\/jdi060125_1_n.shtml\" class=\"gen\">acc\u00e8s payant<\/a>].)<\/p>\n<\/p>\n<p><p>\tHayward fait un tableau tr\u00e8s sombre de la coop\u00e9ration europ\u00e9enne, des perspectives (tr\u00e8s insuffisantes, selon lui) ouvertes par les initiatives prises au niveau du march\u00e9 europ\u00e9en et de l&rsquo;European Defence Agency. Il avertit que cette situation va pousser le Royaume-Uni vers les Etats-Unis. C&rsquo;est un avertissement pour le moins \u00e9trange pour nombre d&rsquo;observateurs, concernant une situation  o\u00f9 les Britanniques semblent d&rsquo;ores et d\u00e9j\u00e0 si compl\u00e8tement engag\u00e9s avec les Am\u00e9ricains. (Mais peut-\u00eatre Howard adh\u00e8re-t-il en partie au constat de <a href=\"http:\/\/www.dedefensa.org\/article.php?art_id=2115\" class=\"gen\">Robert North<\/a> ?)<\/p>\n<\/p>\n<p><p>\tCe qui est encore plus \u00e9trange est que cette perspective (de se tourner vers les USA) est pr\u00e9sent\u00e9e, cette fois \u00e0 la diff\u00e9rence de North et de nombreuses analyses courantes au Royaume-Uni dans les milieux industriels et financiers, comme un v\u00e9ritable calvaire pour le Royaume-Uni,  et le JSF en est la croix la plus lourde : \u00ab <em>While criticising the EU for failing to tackle the defence market problems, leaving it at least 10 years too late, <\/em>[Howard] <em>said the UK move towards the US was not necessarily of benefit to the country. One only need to look as far as the Joint Strike Fighter [JSF] project to see why, Hayward said. We [the UK] have lost control of JSF and lost access to key capabilities. This is due to US refusals to allow the UK full access to mission systems computers, he added.<\/em> <\/p>\n<\/p>\n<p><p>\t\u00bb <em>He argued that while the US can control this kind of access, under European equal access agreements built into co-operative defence projects this issue would not arise.<\/em> \u00bb<\/p>\n<\/p>\n<p><p>\tD&rsquo;une fa\u00e7on tr\u00e8s significative du degr\u00e9 d&rsquo;inqui\u00e9tude, voire de parano\u00efa, que suscite aujourd&rsquo;hui le programme JSF au Royaume-Uni, le rapport du discours de Hayward sur le site de <em>Jane&rsquo;s<\/em> a \u00e9t\u00e9 l&rsquo;objet de certains am\u00e9nagements significatifs. Entre sa premi\u00e8re mise en ligne et l&rsquo;acc\u00e8s qu&rsquo;on en pouvait avoir d\u00e9but f\u00e9vrier, le texte a \u00e9t\u00e9 modifi\u00e9. De fa\u00e7on plus anodine le titre a \u00e9t\u00e9 chang\u00e9 : de \u00ab <em>EU defense market reforms may be too little, too late, claims RAeS head<\/em> \u00bb, en  \u00ab <em>EDA reform too little, too late<\/em> \u00bb. C&rsquo;est surtout l&rsquo;intervention sur le passage sur le JSF qui est significative. La derni\u00e8re phrase de l&rsquo;article a \u00e9t\u00e9 supprim\u00e9e, o\u00f9 Hayward qualifiait l&rsquo;accord USA-UK sur le JSF de fa\u00e7on particuli\u00e8rement expressive et dramatique, peut-\u00eatre un peu trop risqu\u00e9e \u00e0 \u00eatre rapport\u00e9e par le magazine par les implications qu&rsquo;elle suscite \u00e0 l&rsquo;esprit :<\/p>\n<\/p>\n<p><p>\t\u00ab <em>This is the nature of entering into a Faustian bargain with the US, Hayward said.<\/em> \u00bb La participation au JSF contre l&rsquo;\u00e2me de la nation anglaise?<\/p>\n<\/p>\n<p><p>\tDu c\u00f4t\u00e9 du JSF, les nouvelles sont toujours aussi mauvaises concernant le transfert de technologies, qu&rsquo;on devrait nommer transfert de souverainet\u00e9 des USA vers les Britanniques. Le budget du DoD a confirm\u00e9 l&rsquo;abandon du <a href=\"http:\/\/www.dedefensa.org\/article.php?art_id=2298\" class=\"gen\">moteur Rolls Royce<\/a> dans le programme JSF. (Les Britanniques esp\u00e8rent encore voir le Congr\u00e8s r\u00e9tablir les fonds d&rsquo;un programme qui concerne aussi General Electric et des emplois aux USA.)<\/p>\n<\/p>\n<p><p>\tIl y a aujourd&rsquo;hui la possibilit\u00e9 que l&rsquo;\u00e9volution de la situation politique au Royaume-Uni rencontre le statut et le destin de la participation britannique au programme JSF. Le poids grandissant de Brown, l&rsquo;effacement progressif de Blair constituent, quelles que soient les dispositions prises, une situation de crise,  ne serait-ce que parce que la cause de cette \u00e9volution est une crise s\u00e9rieuse de popularit\u00e9 et d&rsquo;autorit\u00e9 de l&rsquo;actuel gouvernement. Brown n&rsquo;est pas moins atlantiste que Blair mais il est sans doute plus r\u00e9aliste. Et, surtout, il sait compter les sous du Tr\u00e9sor. Pour lui, <a href=\"http:\/\/www.dedefensa.org\/article.php?art_id=2381\" class=\"gen\">comme on l&rsquo;a d\u00e9j\u00e0 vu<\/a>, la facture annonc\u00e9e (et sans doute promise \u00e0 grossir encore) du JSF est extr\u00eamement lourde. Si, par ailleurs, l&rsquo;enthousiasme pour l&rsquo;avion du c\u00f4t\u00e9 des industriels et des militaires ne cesse de se r\u00e9duire \u00e0 mesure des coups port\u00e9s (abandon du moteur Rolls, question fondamentale de la souverainet\u00e9), on comprendra que le JSF soit en train de devenir une affaire JSF et pourrait devenir une crise JSF au niveau du gouvernement lui-m\u00eame.<\/p>\n<\/p>\n<p><p>\tIl s&rsquo;agit d&rsquo;un tournant. C&rsquo;est la premi\u00e8re fois qu&rsquo;on peut raisonnablement placer la question du JSF dans une perspective politique majeure au Royaume-Uni. Encore un effort et l&rsquo;une ou l&rsquo;autre rebuffade de plus de la part des Am\u00e9ricains, et l&rsquo;on pourra consid\u00e9rer que tout peut arriver d&rsquo;ici novembre (d\u00e9cision sur l&rsquo;engagement des commandes) dans un programme JSF devenue affaire d&rsquo;\u00c9tat,  voire, affaire d&rsquo;\u00e2me de la nation anglaise.<\/p>\n<\/p>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La crise politique britannique et le Faustian bargain du JSF 12 f\u00e9vrier 2006 Le Royaume-Uni est entr\u00e9 dans une p\u00e9riode d&rsquo;instabilit\u00e9 gouvernementale \u00e0 la suite de la d\u00e9t\u00e9rioration continuelle de la position de Tony Blair suite \u00e0 la guerre d&rsquo;Irak. Le parti travailliste a connu jeudi une d\u00e9faite retentissante (contre un lib\u00e9ral) dans une \u00e9lection&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[705,4038,4341,4529,250],"class_list":["post-67269","post","type-post","status-publish","format-standard","hentry","category-faits-et-commentaires","tag-blair","tag-brown","tag-howard","tag-janes","tag-jsf"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/67269","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=67269"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/67269\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=67269"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=67269"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=67269"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}