{"id":67333,"date":"2006-03-07T00:00:00","date_gmt":"2006-03-07T00:00:00","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2006\/03\/07\/contorsions-indiennes\/"},"modified":"2006-03-07T00:00:00","modified_gmt":"2006-03-07T00:00:00","slug":"contorsions-indiennes","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2006\/03\/07\/contorsions-indiennes\/","title":{"rendered":"Contorsions indiennes"},"content":{"rendered":"<p><p>On appr\u00e9ciera le caract\u00e8re inhabituel et extr\u00eamement empress\u00e9 de cette r\u00e9action indienne \u00e0 l&rsquo;intervention de la Russie dans la crise iranienne. Hier, les milieux officiels indiens ont beaucoup insist\u00e9 sur l&rsquo;attitude du premier ministre Manmohan Singh soutenant \u00e0 fond les efforts de la Russie pour dissiper la tension dans la crise iranienne. Sanjaya Baru, porte-parole du PM, a pr\u00e9cis\u00e9 que Singh avait personnellement t\u00e9l\u00e9phon\u00e9 samedi dernier (4 mars) \u00e0 Vladimir Poutine. \u00ab <em> The prime minister welcomed Russia&rsquo;s efforts to address the issue related to Iran&rsquo;s nuclear program through dialogue and consultations.<\/em> \u00bb<\/p>\n<\/p>\n<p><p>\tLe geste ainsi que la pr\u00e9sentation appuy\u00e9e qui en est faites sont significatifs. C&rsquo;est la politique indienne de rapprochement avec les USA qui est la cause de cette agitation. Le Premier ministre doit surtout se faire pardonner sa volte-face \u00e0 l&rsquo;IAEA, en f\u00e9vrier, lorsque l&rsquo;Inde soutint la r\u00e9solution pouvant conduire le cas iranien au Conseil de S\u00e9curit\u00e9 \u00e0 la suite de fortes pressions US. Singh voulait ainsi verrouiller ses relations,  temporaires ou pas, on verra,  avec les USA pour signer l&rsquo;accord de coop\u00e9ration nucl\u00e9aire. L&rsquo;accord est sign\u00e9. Singh se trouve aujourd&rsquo;hui dans l&rsquo;obligation de nuancer par tous les moyens possibles la d\u00e9sagr\u00e9able impression laiss\u00e9e par son alignement sur les Etats-Unis.<\/p>\n<\/p>\n<p><p>\tComme toujours, voil\u00e0 le paradoxe de la politique brutale des Etats-Unis. Elle force les pays concern\u00e9s \u00e0 des actes spectaculaires, mais pas n\u00e9cessairement fondateurs, d&rsquo;alignement sur les USA. En g\u00e9n\u00e9ral, cela est suivi, pour ces m\u00eames pays, et selon leurs capacit\u00e9s et leur force, \u00e0 des r\u00e9alignements dans l&rsquo;autre sens \u00e9galement spectaculaires. L&rsquo;intervention de Singh montre que l&rsquo;Inde est entr\u00e9e dans cette phase, apr\u00e8s un an de rapprochement avec les USA ; Pour poursuivre le paradoxe, si le Congr\u00e8s et l&rsquo;<em>establishment<\/em> washingtonien tra\u00eenent des pieds pour ratifier le trait\u00e9, comme c&rsquo;est probable, les r\u00e9actions indiennes de d\u00e9fiance des USA ont toutes les chances d&rsquo;\u00eatre encore plus vives : au besoin de r\u00e9alignement qu&rsquo;on voit actuellement s&rsquo;ajoutera le sentiment de promesses (de l&rsquo;administration Bush) non tenues.<\/p>\n<\/p>\n<p><\/p>\n<p><p>\tMis en ligne le 7 mars 2006 \u00e0 09H39<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>On appr\u00e9ciera le caract\u00e8re inhabituel et extr\u00eamement empress\u00e9 de cette r\u00e9action indienne \u00e0 l&rsquo;intervention de la Russie dans la crise iranienne. Hier, les milieux officiels indiens ont beaucoup insist\u00e9 sur l&rsquo;attitude du premier ministre Manmohan Singh soutenant \u00e0 fond les efforts de la Russie pour dissiper la tension dans la crise iranienne. Sanjaya Baru, porte-parole&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[2],"tags":[3378,2773,3004,916,5162],"class_list":["post-67333","post","type-post","status-publish","format-standard","hentry","category-bloc-notes","tag-inde","tag-iran","tag-nucleaire","tag-poutine","tag-singh"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/67333","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=67333"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/67333\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=67333"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=67333"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=67333"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}