{"id":67374,"date":"2006-03-22T00:00:00","date_gmt":"2006-03-22T00:00:00","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2006\/03\/22\/fukuyama-ou-the-end-of-the-logic\/"},"modified":"2006-03-22T00:00:00","modified_gmt":"2006-03-22T00:00:00","slug":"fukuyama-ou-the-end-of-the-logic","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2006\/03\/22\/fukuyama-ou-the-end-of-the-logic\/","title":{"rendered":"Fukuyama, ou <em>The End of the Logic<\/em>"},"content":{"rendered":"<p><h2 class=\"common-article\">Fukuyama, ou <em>The End of the Logic<\/em><\/h2>\n<\/p>\n<p><p>\t22 mars 2006  Francis Fukuyama fut c\u00e9l\u00e8bre en 1989-90 avec la grande publicit\u00e9 faite \u00e0 sa th\u00e8se The End of History. Depuis, nous en sommes revenus (de la th\u00e8se). Entre-temps, Fukuyama, devenu un incontournable de l&rsquo;<em>establishment<\/em> washingtonien et de l&rsquo;expertise philosophique du syst\u00e8me, s&rsquo;\u00e9tait reclass\u00e9 l\u00e0 o\u00f9 il fallait, notamment et pr\u00e9cis\u00e9ment \u00e0 partir du 11 septembre 2001 : du c\u00f4t\u00e9 des n\u00e9o-conservateurs. R\u00e9cemment, il s&rsquo;en est \u00e9loign\u00e9 avec pertes et fracas jusqu&rsquo;\u00e0 <a href=\"http:\/\/www.dedefensa.org\/article.php?art_id=2446\" class=\"gen\">la rupture finale<\/a>. Disons que la forme de cette rupture fut spectaculaire mais la d\u00e9marche est en elle-m\u00eame assez prudente. Les <em>neocons<\/em>, quoi qu&rsquo;il en soit de leur influence qui perdure presque comme un automatisme, sont d\u00e9sormais identifi\u00e9s avec l&rsquo;extr\u00e9misme d&rsquo;une politique catastrophique dont, pourtant, personne n&rsquo;arrive \u00e0 se d\u00e9barrasser.<\/p>\n<\/p>\n<p><p>\tFukuyama, qui n&rsquo;a jamais cess\u00e9 par ailleurs de proclamer sa conviction lib\u00e9rale (politique de libre \u00e9change, internationaliste, etc.) a d\u00e9sormais choisi une voie baptis\u00e9e n\u00e9o-r\u00e9aliste. M\u00eame si l&rsquo;expression sonne aimable et mod\u00e9r\u00e9e, elle n&rsquo;interdit nullement les emportements (par les temps qui courent, l&#8217;emportement est presque la norme). Fukuyama retrouve au sein de cette nouvelle \u00e9cole des gens comme Zbigniew Brzezinski, regroup\u00e9s autour de la nouvelle publication <em>The American Interest<\/em> ; et l&rsquo;on sait que Brzezinski, dans sa r\u00e9cente intervention, dans <em>The American Interest<\/em> justement, n&rsquo;est <a href=\"http:\/\/www.dedefensa.org\/article.php?art_id=2487\" class=\"gen\">pas tendre<\/a> pour la politique bushiste qu&rsquo;il accuse de provoquer une sorte de r\u00e9volte mondiale anti-US. On est en pays de connaissance,  ce qui nous conduit \u00e0 <a href=\"http:\/\/www.guardian.co.uk\/Iraq\/Story\/0,,1735643,00.html\" class=\"gen\">l&rsquo;article<\/a> de Fukuyama que publie le <em>Guardian<\/em>, ce 21 mars, et qui est l&rsquo;objet de notre analyse.<\/p>\n<\/p>\n<p><p>\tL&rsquo;article n&rsquo;est pas mod\u00e9r\u00e9 non plus. Le sous-titre suffit \u00e0 nous fixer l\u00e0-dessus :  \u00ab <em>The chaotic outcome of Bush&rsquo;s war is feeding US economic nationalism and isolationism, which are a threat to Europe.<\/em> \u00bb L&rsquo;analyse identifie bien les composants d&rsquo;une situation qui pourrait conduire l&rsquo;Am\u00e9rique vers une position \u00e0 la fois protectionniste et isolationniste. Fukuyama cite deux cas r\u00e9cents indiquant cette orientation de l&rsquo;Am\u00e9rique, dont l&rsquo;affaire DPW (Duba\u00ef) et la gestion des ports US. (L&rsquo;autre cas est celui des r\u00e9actions am\u00e9ricaines \u00e0 l&rsquo;affaire des caricatures. La logique est moins convaincante en raison de l&rsquo;ambigu\u00eft\u00e9 du cas.)<\/p>\n<\/p>\n<p><p>\tFukuyama d\u00e9finit ainsi l&rsquo;initiative prise par le Congr\u00e8s de contrecarrer la reprise de la gestion des ports US par DPW, et le retrait cons\u00e9cutif (le 9 Mars) de DPW de cette gestion : \u00ab <em> this shameless pandering to public fears of terrorism undermined every principle of openness and globalisation that the US has been preaching in recent years.<\/em> \u00bb Il s&rsquo;attache \u00e0 certains parlementaires qui ont appuy\u00e9 l&rsquo;initiative du Congr\u00e8s, et particuli\u00e8rement aux lib\u00e9raux parmi eux,  c&rsquo;est-\u00e0-dire essentiellement les d\u00e9mocrates modernistes, pr\u00e9tendument internationalistes, etc.,  notamment et pr\u00e9cis\u00e9ment Hillary Clinton. Le ton est acerbe (derni\u00e8re remarque <a href=\"http:\/\/www.dedefensa.org\/article.php?art_id=2520\" class=\"gen\">tr\u00e8s int\u00e9ressante<\/a> quant \u00e0 la substance m\u00eame de la globalisation) : \u00ab <em>Clinton, who has positioned herself to the right on security issues, saw an opening to attack the president and argued that the Dubai takeover would constitute a violation of US sovereignty. It seems not to have occurred to her that by this logic American multinationals are violating the sovereignty of virtually every country on the planet.<\/em> \u00bb<\/p>\n<\/p>\n<p><p>\tPuis il \u00e9largit son propos. Fukuyama tire les conclusions de cette passe d&rsquo;armes qui a vu toutes les \u00e9tiquettes boulevers\u00e9es, avec le soutien et la pression active de l&rsquo;opinion publique, pour aboutir \u00e0 une action si sp\u00e9cifiquement non-am\u00e9ricaine \u00e0 ses yeux. Il s&rsquo;agit l\u00e0 d&rsquo;une pr\u00e9vision pour l&rsquo;\u00e9volution am\u00e9ricaine,  paradoxalement de moins en moins am\u00e9ricaniste (l&rsquo;isolationnisme et le protectionnisme, dont le texte ci-apr\u00e8s est la description \u00e9volutive, font partie des choses maudites et mises \u00e0 l&rsquo;index par le Parti en g\u00e9n\u00e9ral) : <\/p>\n<\/p>\n<p><p>\t\u00ab <em>We have, then, the makings of a perfect storm. Bush&rsquo;s red-state conservative base tends towards a pugnacious nationalism that opposed humanitarian intervention during the Clinton years. These voters were mobilised by September 11 to support two wars in short order; while they remain loyal to the president, perceived failure in Iraq will turn them in a more openly isolationist direction. Democratic voters, meanwhile, have been moving in an economically nationalist direction and are gearing up for a big fight with America&rsquo;s leading trading partners in Asia. Voters in both parties have become more sympathetic to calls for closing America&rsquo;s borders and reducing immigration.<\/em> \u00bb<\/p>\n<\/p>\n<p><p>\tVoil\u00e0 donc le diagnostic du Dr. Fukuyama, d&rsquo;ailleurs assez dans la logique de celui du Dr. Brzezinski. Sa crainte est bien celle d&rsquo;une \u00e9volution isolationniste et protectionniste. C&rsquo;est une crainte fond\u00e9e, et qui est puissamment aliment\u00e9e par les effets pervers de la catastrophique politique bushiste. <em>Perfect storm<\/em> il pourrait bien y avoir, et plus vite qu&rsquo;on ne croit ou qu&rsquo;on ne craint.<\/p>\n<\/p>\n<p><p>\tQuelle m\u00e9decine contre ce mal terrifiant? C&rsquo;est \u00e0 ce point que la logique de Fukuyama, jusqu&rsquo;alors impeccable, devient \u00e9trange.<\/p>\n<\/p>\n<p><p>\tOn compte sur les Europ\u00e9ens Fukuyama les avertit ou les implore, c&rsquo;est selon. D&rsquo;abord, ils ne doivent pas c\u00e9der \u00e0 l&rsquo;exercice douteux qualifi\u00e9 de <em>schadenfreude<\/em> (cette r\u00e9jouissance d\u00e9plac\u00e9e du malheur d&rsquo;un autre) : \u00ab <em>Many opponents of the Iraq war both in the US and Europe have felt a not-so-secret sense of schadenfreude at the developing chaos in Iraq. While many might intellectually support the emergence of a stable, democratic, pro-western government in Baghdad, success&rsquo; in this matter would be seen as a vindication of all of the baggage that the Bush administration loaded on to this project, including its unilateralism, use of force and incompetent execution of the war&rsquo;s aftermath. Many would therefore be happy seeing Washington suffer a setback, to deter such interventions in the future.<\/em> <\/p>\n<\/p>\n<p><p>\t\u00bb <em>But people should be careful what they wish for&#8230;<\/em> \u00bb<\/p>\n<\/p>\n<p><p>\tPourquoi? Parce que&#8230; \u00ab <em>Like it or not, American power and involvement are necessary to the proper functioning of world order, and the kind of role that a post-Iraq United States may play is very much up for grabs.<\/em> \u00bb (Curieuse logique dont on cherche en vain la sagesse: pourquoi \u00ab <em>American power and involvement are necessary to the proper functioning of world order&#8230;<\/em> \u00bb, s&rsquo;il s&rsquo;av\u00e8re que cette puissance et cette implication ext\u00e9rieure sont porteuses de d\u00e9sordre, de vilenie et de d\u00e9stabilisation, donc de destruction de ce qui tient lieu d&rsquo;ordre du monde? Enfin, passons outre pour l&rsquo;instant.)<\/p>\n<\/p>\n<p><p>\tIci, l&rsquo;appel aux Europ\u00e9ens est plus direct, plus pr\u00e9cis: \u00ab <em>By invading Iraq, the Bush administration allowed what should have been characterised as a fight with a narrow extremist ideology to escalate into something the Islamists could claim was a clash of civilisations. But that clash will play itself out in large measure in Europe, the breeding ground for Mohammed Atta, Mohammed Bouyeri and the July 7 bombers. The controversy over the cartoons underlines the fact that the US and Europe have more in common in the struggle with radical Islamism than either side would like to admit. Cooperation to prevent this escalating into a broader civilisational struggle, and to maintain a generally open, integrated international order, will require solidarity.<\/em> \u00bb<\/p>\n<\/p>\n<p><p>\tComprenons bien. C&rsquo;est bien aux Europ\u00e9ens essentiellement que l&rsquo;appel \u00e0 la coop\u00e9ration et \u00e0 la solidarit\u00e9 s&rsquo;adresse, puisque, par ailleurs,  vraiment comme s&rsquo;il n&rsquo;y avait ni interf\u00e9rences, ni de dynamique de cause \u00e0 effet,  l&rsquo;Am\u00e9rique nous est d\u00e9crite comme sombrant dans le nationalisme politique et \u00e9conomique, c&rsquo;est-\u00e0-dire l&rsquo;isolationnisme et le protectionnisme. (\u00ab <em>A domestic nationalist backlash against the policies that led to the war is brewing, with implications for how the US will deal with Europe and the rest of the world down the road.<\/em> \u00bb) Plus encore, c&rsquo;est-\u00e0-dire pire,  et on le comprend \u00e0 voir le fonctionnement de la quasi-candidate pour 2008 Hillary Clinton,  les Europ\u00e9ens auraient bien tort d&rsquo;attendre un changement positif en 2008, puisque les d\u00e9mocrates semblent n&rsquo;\u00eatre pas tr\u00e8s loin d&rsquo;\u00eatre faits du m\u00eame bois que celui dont on fait les r\u00e9publicains bushistes : \u00ab <em>Many in Europe are eagerly awaiting the end of the Bush years, but it is not clear that a Democratic administration will be more broadmindedly internationalist.<\/em> \u00bb<\/p>\n<\/p>\n<p><p>\tL&rsquo;\u00e9trange march\u00e9 en v\u00e9rit\u00e9, et l&rsquo;\u00e9trange logique pour le justifier : vous autres Europ\u00e9ens, vous continuez \u00e0 vous conduire comme les Am\u00e9ricains et la s\u00e9mantique virtualiste en cours souhaitent que vous le fassiez, portes grandes ouvertes, sacrifiant avec sagesse et lucidit\u00e9 vos int\u00e9r\u00eats \u00e0 ceux d&rsquo;une communaut\u00e9 internationale dont vous faites partie. En \u00e9change, vous aurez en face de vous une Am\u00e9rique cadenass\u00e9e, veillant jalousement \u00e0 ses seuls int\u00e9r\u00eats, hostile \u00e0 la doctrine internationaliste. Ainsi, semblerait conclure <em>in fine<\/em> notre Fukuyama, le terrain est-il pr\u00e9par\u00e9 pour que fleurissent \u00e0 nouveau les cent fleurs de la solidarit\u00e9, de la coop\u00e9ration et de l&rsquo;ouverture du monde plus que jamais post-moderne et lib\u00e9ral.<\/p>\n<\/p>\n<p><p>\tOutre son propos sur la fin de l&rsquo;Histoire, Fukuyama a \u00e9crit \u00e0 propos du dernier homme. L&rsquo;un et l&rsquo;autre vont ensemble. Il est logique, si l&rsquo;on ose dire, que tout cela aille avec la fin de la logique, parce que la logique ne semble plus avoir ni sa place ni son utilit\u00e9 de lien entre l&rsquo;homme et sa pens\u00e9e d&rsquo;une part, et l&rsquo;Histoire \u00e0 laquelle l&rsquo;homme est cens\u00e9 donner son impulsion d&rsquo;autre part. Washington, aujourd&rsquo;hui, dans ses quartiers qui se veulent les plus raisonnables au milieu du d\u00e9cha\u00eenement g\u00e9n\u00e9ral qui balaie l&rsquo;architecture am\u00e9ricaniste, en est r\u00e9duit \u00e0 tenter de nous faire prendre l&rsquo;incantation pour la logique,  mais, d&rsquo;abord, pour continuer \u00e0 croire lui-m\u00eame dans les vestiges du r\u00eave d&rsquo;un monde organis\u00e9 selon les canons de la doctrine. La chose est plus path\u00e9tique que pr\u00e9occupante m\u00eame si elle nourrit \u00e9videment la pr\u00e9occupation que nous devons avoir pour l&rsquo;\u00e9tat du monde et l&rsquo;\u00e9tat de cette pens\u00e9e qui voudrait encore donner un sens au monde, selon les strictes conditions du lib\u00e9ralisme post-moderne.<\/p>\n<\/p>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Fukuyama, ou The End of the Logic 22 mars 2006 Francis Fukuyama fut c\u00e9l\u00e8bre en 1989-90 avec la grande publicit\u00e9 faite \u00e0 sa th\u00e8se The End of History. Depuis, nous en sommes revenus (de la th\u00e8se). Entre-temps, Fukuyama, devenu un incontournable de l&rsquo;establishment washingtonien et de l&rsquo;expertise philosophique du syst\u00e8me, s&rsquo;\u00e9tait reclass\u00e9 l\u00e0 o\u00f9 il&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[3082,1242,4035,1104,1097],"class_list":["post-67374","post","type-post","status-publish","format-standard","hentry","category-faits-et-commentaires","tag-fukuyama","tag-isolationnisme","tag-liberalisme","tag-neocons","tag-protectionnisme"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/67374","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=67374"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/67374\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=67374"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=67374"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=67374"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}