{"id":67385,"date":"2006-03-26T00:00:00","date_gmt":"2006-03-26T00:00:00","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2006\/03\/26\/la-france-modele-as-usual\/"},"modified":"2006-03-26T00:00:00","modified_gmt":"2006-03-26T00:00:00","slug":"la-france-modele-as-usual","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2006\/03\/26\/la-france-modele-as-usual\/","title":{"rendered":"La France, mod\u00e8le <em>as usual<\/em>&#8230;"},"content":{"rendered":"<p><h2 class=\"common-article\">La France, mod\u00e8le <em>as usual<\/em><\/h2>\n<\/p>\n<p><p>\t26 mars 2006  Ces mots nous paraissent significatif de la crise fran\u00e7aise (la crise du CPE \u00e9largie \u00e0 d&rsquo;autres \u00e9v\u00e9nements),  \u00e0 la fois pour l&rsquo;incompr\u00e9hension de la crise et pour la compr\u00e9hension du probl\u00e8me que la crise fran\u00e7aise pose \u00e0 l&rsquo;Europe et au syst\u00e8me en g\u00e9n\u00e9ral : \u00ab <em>This really was a signal that the French have chosen to be isolationists in Europe, Koopmann said. You need to cooperate with France, and, at the moment, I just don&rsquo;t see how.<\/em> \u00bb<\/p>\n<\/p>\n<p><p>\tLa citation est extraite d&rsquo;un texte de Richard Bernstein, dans <a href=\"http:\/\/www.iht.com\/articles\/2006\/03\/23\/news\/europa.php\" class=\"gen\">l&rsquo;International Herald Tribune<\/a> du 24 mars, sur la crise fran\u00e7aise vue d&rsquo;Allemagne. Elle est de Martin Koopmann, directeur du Franco-German Institute of the German Council on Foreign Relations. L&rsquo;\u00e9v\u00e9nement cit\u00e9 par Koopman (le <em>This<\/em> de <em>This really was a signal<\/em>) concerne un vote n\u00e9gatif des socialistes fran\u00e7ais au Parlement europ\u00e9en : \u00ab <em>In the vote at the European Parliament on the compromise formula for liberalizing services, like insurance or consulting or plumbing, across the EU, it was only the French socialist group that voted no.<\/em> \u00bb<\/p>\n<\/p>\n<p><p>\tTout cela nous en dit \u00e9norm\u00e9ment sur la crise en cours en France, sur la France, sur l&rsquo;Europe. Prenons les sujets \u00e0 l&rsquo;inverse de l&rsquo;ordre dans lequel nous les avons \u00e9nonc\u00e9s.<\/p>\n<h3>Sur l&rsquo;Europe<\/h3>\n<\/p>\n<p><p>\tSauf certains cas notables qui m\u00e9ritent souvent mention (le point de vue britannique <a href=\"http:\/\/www.dedefensa.org\/article.php?art_id=2505\" class=\"gen\">d\u00e9j\u00e0 signal\u00e9<\/a> en est un, on en voit deux autres plus loin dans ce texte), l&rsquo;attitude europ\u00e9enne g\u00e9n\u00e9rale devant les \u00e9v\u00e9nements fran\u00e7ais est celle du complet d\u00e9sarroi et de l&rsquo;incompr\u00e9hension, en passant par les attitudes secondaires (col\u00e8re, d\u00e9rision, ironie, rationalisation du jugement n\u00e9gatif, etc.). On n&rsquo;entend pas aborder les questions de fond. L&rsquo;analyse rapport\u00e9e par Bernstein se contente de constater qu&rsquo;en France le syst\u00e8me est bloqu\u00e9 alors qu&rsquo;il ne l&rsquo;est pas en Allemagne : \u00ab <em>To be sure, over the past several years, as the previous German government pressed ahead with a modest reform program, there was plenty of discontent, especially over the phase of the program known as Hartz IV, which cut back on unemployment benefits and other social entitlements. The protest even led, at least in part, to the creation of the new Left Party, which now has some real power in Parliament. And that in a way is the point: the discontent was channeled into a new political party, not into street protests.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb <em>Meanwhile, the Germans by and large seem to have grudgingly accepted the reforms already enacted, including, for example, a health care reform that requires a 10, or $12, payment for each visit to the doctor. In France, as Koopmann pointed out, an attempt to institute a measly 1 payment failed in the face of public opposition.<\/em> \u00bb<\/p>\n<\/p>\n<p><p>\tA aucun moment, dans cette analyse, n&rsquo;est mise en cause la finalit\u00e9 du syst\u00e8me. La seule question,  mais on admettra qu&rsquo;elle est de taille,  est de savoir comment l&rsquo;on s&rsquo;adaptera \u00e0 la situation fran\u00e7aise et que va devenir l&rsquo;Europe \u00e0 cause de cette situation : \u00ab <em>some anxiety that the French turmoil, not just of today but of the past year or two, augurs badly for the prospects of progress on unifying Europe.<\/em> \u00bb<\/p>\n<\/p>\n<p><p>\tCela revient \u00e0 placer en parall\u00e8le ironique et contradictoire, face au constat qu&rsquo;en France le syst\u00e8me est bloqu\u00e9 et qu&rsquo;ailleurs il marche, le constat que la situation fran\u00e7aise peut bloquer le syst\u00e8me europ\u00e9en. C&rsquo;est aussi un constat sur la situation de la globalisation, dont, \u00e9videmment, le syst\u00e8me europ\u00e9en tel qu&rsquo;\u00e0 pr\u00e9sent fait partie : le syst\u00e8me de la globalisation fonctionne effectivement lorsque toutes ses parties fonctionnent, et il est en g\u00e9n\u00e9ral assez puissant pour soumettre les parties r\u00e9tives ; il semble que ce ne soit pas le cas avec la France, qui reste r\u00e9tive, et qui reste trop importante pour que le syst\u00e8me passe outre.<\/p>\n<\/p>\n<p><p>\tCette sorte d&rsquo;analyse ne s&rsquo;arr\u00eate pas \u00e0 la crise actuelle mais embrasse le comportement fran\u00e7ais depuis nombre d&rsquo;\u00e9v\u00e9nements. On parle d&rsquo;une ou de deux ann\u00e9es (\u00ab <em>the past year or two<\/em> \u00bb) mais nous sugg\u00e9rons qu&rsquo;on pourrait remonter plus loin dans l&rsquo;histoire r\u00e9cente, et m\u00eame plus loin dans l&rsquo;Histoire toute grande si n\u00e9cessaire.<\/p>\n<h3>Sur la France<\/h3>\n<\/p>\n<p><p>\tUne fois de plus, voici le constat qu&rsquo;en France les \u00e9lites sont compl\u00e8tement d\u00e9sorient\u00e9es. Cette d\u00e9sorientation est assez logique, si l&rsquo;on consid\u00e8re que rien ne se passe qui puisse rapprocher ces \u00e9lites du sentiment public g\u00e9n\u00e9ral puisque rien ne peut se passer dans ce sens, dans le syst\u00e8me g\u00e9n\u00e9ral auquel adh\u00e8rent en g\u00e9n\u00e9ral ces \u00e9lites fran\u00e7aises. Que ce sentiment g\u00e9n\u00e9ral s&rsquo;exprime \u00e0 l&rsquo;occasion de telle ou telle affaire et \u00e0 l&rsquo;occasion d&rsquo;affaires tr\u00e8s diff\u00e9rentes, impliquant des revendications et des publics diff\u00e9rents, n&rsquo;importe gu\u00e8re dans cette fa\u00e7on d&rsquo;analyser la chose. C&rsquo;est \u00e9videmment l&rsquo;expression du sentiment qui importe.<\/p>\n<\/p>\n<p><p>\tL&rsquo;affaire du CPE est encore plus troublante que d&rsquo;autres qui peuvent lui \u00eatre assimil\u00e9es si l&rsquo;on embrasse les causes fondamentales (notamment, mais non exclusivement : le vote sur le trait\u00e9 de Maastricht en 1992, les gr\u00e8ves de fin 1995, les pr\u00e9sidentielles d&rsquo;avril 2002, le r\u00e9f\u00e9rendum europ\u00e9en de mai 2005). Elle place tous les repr\u00e9sentants politiques en porte-\u00e0-faux, \u00e0 plus ou moins long terme. La gauche, lorsqu&rsquo;elle tend \u00e0 soutenir le mouvement parce que cela est dans la nature des choses politicienne et id\u00e9ologiques, repr\u00e9sente le cas le plus extr\u00eame de cette situation ; si elle recueillait les fruits de cette politique au niveau \u00e9lectoral, elle se trouverait, au pouvoir, dans une position qui s&rsquo;av\u00e9rerait vite intenable. La position de la gauche fran\u00e7aise, aujourd&rsquo;hui, dans le chef du parti socialiste dans la majorit\u00e9 de son appareil, est dans la m\u00eame logique qui, il y a un ans, invitait \u00e0 voter oui \u00e0 la constitution europ\u00e9enne,  qui, aujourd&rsquo;hui, invite \u00e0 soutenir le CPE : logique lib\u00e9rale et logique de privatisation. Monsieur Barroso soutient le CPE ; la gauche institutionnelle du PS, en recommandant le oui, a soutenu les options de monsieur Barroso. C&rsquo;est une question d&rsquo;\u00e9tat d&rsquo;esprit dans le cadre d&rsquo;une in\u00e9luctable logique m\u00e9caniste, et nullement d&rsquo;un quelconque choix id\u00e9ologique dont la logique nous ram\u00e8ne aux batailles sociales du si\u00e8cle dernier dans le fil direct de leur inspiration dans le bouillonnement de l&rsquo;id\u00e9e sociale au XIX\u00e8me si\u00e8cle.<\/p>\n<\/p>\n<p><p>\tCorset\u00e9e dans cette logique de fer qui anime le syst\u00e8me lib\u00e9ral et globalisant, les \u00e9lites de droite ne sont pas tellement plus confortables. Des deux soi-disant faux-fr\u00e8res et fr\u00e8res ennemis qui s&rsquo;affrontent,  Villepin et Sarkozy,  c&rsquo;est celui qui para\u00eetrait pour l&rsquo;instant le plus favoris\u00e9 par les \u00e9v\u00e9nements (Sarko) qui se retrouverait dans les plus grandes difficult\u00e9s en cas de victoire 2007, dans tous les cas par rapport \u00e0 son programme \u00e9lectoral qui est la condition du soutien dont il dispose.<\/p>\n<\/p>\n<p><p>\t(Signe des temps et signe ironique : la d\u00e9magogie des candidats cherchant l&rsquo;\u00e9lection s&rsquo;adresserait d\u00e9sormais plus au syst\u00e8me qu&rsquo;aux votants ; les engagement lib\u00e9raux, r\u00e9formistes, globalisants, voire pro-am\u00e9ricains de Sarkozy, qui sont d&rsquo;abord de la rh\u00e9torique \u00e9lectoraliste, c&rsquo;est-\u00e0-dire de la d\u00e9magogie, sont destin\u00e9s comme tels au syst\u00e8me et \u00e0 ses repr\u00e9sentants m\u00e9diatiques, et non plus au public qui vote. C&rsquo;est un probl\u00e8me d\u00e9licat dont on reparlera d&rsquo;ici l&rsquo;\u00e9lection et qui fa\u00e7onnera le Sarkozy-pr\u00e9sident si la chose devait arriver,  Sarkozy pr\u00e9sident qui nous r\u00e9serverait des surprises par rapport au candidat ou bien qui dispara\u00eetrait corps et bien dans la ni\u00e8me r\u00e9volte fran\u00e7aise.) <\/p>\n<\/p>\n<p><p>\tLe probl\u00e8me des futurs candidats pr\u00e9sidentiels est que la France, d\u00e9sormais, entend \u00eatre gouvern\u00e9e conform\u00e9ment \u00e0 ses conceptions et \u00e0 ses int\u00e9r\u00eats. Dans cette partie, Villepin serait le mieux plac\u00e9 parce qu&rsquo;il a quelques atouts (le nationalisme \u00e9conomique est le plus \u00e9vident d&rsquo;entre eux) ; mais ces atouts demandent \u00e0 \u00eatre identifi\u00e9s comme tels, ce qui n&rsquo;est pas chose ais\u00e9e si l&rsquo;on tient compte des contraintes du syst\u00e8me et des exigences de ses repr\u00e9sentants m\u00e9diatiques. Le paradoxe de la situation actuelle est que le dirigeant qui court le plus grand risque d&rsquo;\u00eatre d\u00e9moli serait le candidat qui r\u00e9pondrait le plus \u00e0 l&rsquo;exigence politique des Fran\u00e7ais, et que ses arguments les plus propres \u00e0 le faire \u00e9lire auraient le plus de difficult\u00e9s \u00e0 \u00eatre pr\u00e9sent\u00e9s comme tels.<\/p>\n<h3>Sur la crise fran\u00e7aise<\/h3>\n<\/p>\n<p><p>\tA c\u00f4t\u00e9 du politique et du social quotidiens, ce que nous nommerions l&rsquo;\u00e9cume des jours,  ce que sont en r\u00e9alit\u00e9 les questions du CPE et du ch\u00f4mage, dont la r\u00e9solution sp\u00e9cifique ne r\u00e9soudrait rien,  l&rsquo;essentiel est que la France exprime une fois de plus, qu&rsquo;elle <strong>r\u00e9p\u00e8te<\/strong> un refus global du syst\u00e8me nihiliste de la globalisation. Pour en bien saisir la substance, il faut moins voir dans cette crise l&rsquo;affirmation de la recherche d&rsquo;une solution \u00e0 un probl\u00e8me sp\u00e9cifique que, d&rsquo;abord, l&rsquo;expression renouvel\u00e9e d&rsquo;un refus. Si l&rsquo;on veut et pour aller au plus simple, il s&rsquo;agit de la raison fran\u00e7aise refusant l&rsquo;absurdit\u00e9 du suicide collectif impliqu\u00e9 <strong>\u00e9videmment<\/strong> par ce syst\u00e8me dont l&rsquo;absurdit\u00e9 propre est d\u00e9montr\u00e9e jusqu&rsquo;\u00e0 la naus\u00e9e. A c\u00f4t\u00e9 de cela, ce que disent les Fran\u00e7ais, ceux qui se r\u00e9voltent et ceux qui commentent la r\u00e9volte (ce sont finalement les m\u00eames puisqu&rsquo;il est entendu qu&rsquo;il faut qu&rsquo;un Fran\u00e7ais se r\u00e9volte une fois dans sa vie et qu&rsquo;il est impossible \u00e0 un Fran\u00e7ais de ne pas commenter les actes des Fran\u00e7ais),  leurs revendications et leurs commentaires expriment en g\u00e9n\u00e9ral tous les travers fran\u00e7ais : la confusion utopique, le go\u00fbt de l&rsquo;abstraction, la suffisance dialectique, l&rsquo;ang\u00e9lisme universaliste, etc.<\/p>\n<\/p>\n<p><p>\tLa France est ingouvernable parce que sa population, pour des raisons bonnes ou moins bonnes qu&rsquo;importe, a divorc\u00e9 d&rsquo;avec son \u00e9poque. Elle refuse le syst\u00e8me qui repr\u00e9sente cette \u00e9poque. Il est important d&rsquo;admettre le fait brut sans trop s&rsquo;attarder aux manifestations diverses qui expriment ce refus, sous peine de se laisser enfermer dans des d\u00e9bats de chapelle n\u00e9cessairement st\u00e9riles.<\/p>\n<\/p>\n<p><p>\tDe ce fait, la France est <em>de facto<\/em> le pays qui, au cur du syst\u00e8me, repr\u00e9sente la plus vigoureuse et la plus significative opposition au syst\u00e8me. La France n&rsquo;est pas un pays exclu du syst\u00e8me ou opprim\u00e9 par le syst\u00e8me, et qui riposte par l&rsquo;ext\u00e9rieur ; elle n&rsquo;est ni un Venezuela, ni une Russie. Elle est, en quelque sorte, \u00e0 la fois le fils prodigue et l&rsquo; enfant terrible du syst\u00e8me ; quoiqu&rsquo;elle en dise et quoiqu&rsquo;elle en donne comme explication (ch\u00f4mage, CPE, etc.), ce qu&rsquo;elle exprime est cette opposition fondamentale, \u00e0 la fois visc\u00e9rale et parfaitement haute jusqu&rsquo;\u00e0 \u00eatre spirituelle, \u00e0 un syst\u00e8me qu&rsquo;elle per\u00e7oit justement comme nihiliste, pr\u00e9dateur et suicidaire. Lorsque le reste du monde (le syst\u00e8me par la voix de ses courroies de transmission) s&rsquo;interroge avec fureur sur ce refus fran\u00e7ais de s&rsquo;adapter au monde moderne, la r\u00e9ponse est que la France refuse de s&rsquo;adapter \u00e0 la course effr\u00e9n\u00e9e vers un suicide globalis\u00e9e. La lucidit\u00e9 n&rsquo;est pas du c\u00f4t\u00e9 qu&rsquo;on croit.<\/p>\n<h2 class=\"common-article2\">Compr\u00e9hension de la crise<\/h2>\n<\/p>\n<p><p>\tDeux exemples, venus de deux perspectives politiques bien diff\u00e9rentes, identifient justement cette tendance fran\u00e7aise. L&rsquo;important, ici, est l&rsquo;identification ; sur l&rsquo;interpr\u00e9tation de la chose identifi\u00e9e, il y a bien des diff\u00e9rences et le champ est ouvert \u00e0 la critique. Le site <em>WSWS.org<\/em> identifie la port\u00e9e globale du mouvement fran\u00e7ais pour argumenter en faveur de la th\u00e8se trotskiste. William Pfaff a une approche plus fondamentale justement r\u00e9sum\u00e9e par le contraste entre deux mots, dans son dernier paragraphe : ce qu&rsquo;on prend pour une \u00ab <em>sterile defense of an<\/em> <strong><em>obsolete<\/em><\/strong> <em>social and economic order<\/em> \u00bb de la part des Fran\u00e7ais doit \u00eatre vu en r\u00e9alit\u00e9 comme  \u00ab <MI>a <strong><em>premonitory<\/em><\/strong> <em>appeal for a new but humane model to replace it<\/em> \u00bb.<\/p>\n<\/p>\n<p><p>\t\u00a0L&rsquo;extrait du texte de <em>WSWS.org<\/em> ne m\u00e2che pas ses mots, en fait de dialectique trotskiste. Dirions-nous que cela dessert la cause en n&rsquo;\u00e9vitant pas l&rsquo;ennui dispens\u00e9 par une phrase ou l&rsquo;autre? Peu importe. Seule compte ici l&rsquo;identification d&rsquo;une analyse qui donne au mouvement fran\u00e7ais son caract\u00e8re global,  avec le d\u00e9tail ironique de voir Pfaff, qu&rsquo;on lit plus loin, cit\u00e9 dans cet extrait : \u00ab <em>Speaking with reporters in Brussels, Chirac was asked how his European Union colleagues had responded to the unrest. The president replied that they had given their support.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb <em>The entire European ruling elite has lined up behind Chirac and Villepin over the CPE struggle. European governments, both conservative and social-democratic, are fully aware of the international significance of what is developing in France and fear similar mass movements developing in opposition to their own right-wing reforms.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb <em>France is the coal miner&rsquo;s canary of modern European society, William Pfaff commented in the International Herald Tribune on March 22. [T]he current unrest in France signals wider popular resistance in Europe to the most important element in the new model of market economics, its undermining of the place of the employee in the corporate order, deliberately rendering the life of the employee precarious.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb <em>The nervousness of Chirac&rsquo;s European colleagues in the face of the anti-CPE movement demonstrates the international character of the student and worker protests. The French ruling elite, like its equivalents internationally, has been driven by the processes of capitalist globalisation to impose ruthless free-market reforms, including privatisations, cuts to social services and welfare spending, and attacks on workers&rsquo; wages and conditions.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb <em>These measures have been advanced by successive social-democratic and Gaullist governments in the face of determined and often militant opposition from within the working class. The struggle over the First Job Contract legislation marks the continuation and deepening of a series of struggles seen in France in the past decade against the political establishment&rsquo;s efforts to dismantle the social gains conceded to the working class in the postwar period.<\/em><\/p>\n<\/p>\n<p><p>\t\u00a0Excellent connaisseur de la psychologie fran\u00e7aise, avec nombre de ses analyses politiques qui le rapprocheraient de la cat\u00e9gorie que nous nommerions gaullistes am\u00e9ricains, William Pfaff \u00e9crit, <a href=\"http:\/\/www.williampfaff.com\/modules\/news\/article.php?storyid=111\" class=\"gen\">le 22 mars<\/a> : \u00ab <em>A larger explanation occurs to me, that France is the coalminer&rsquo;s canary of modern European society. France&rsquo;s rejection of the European Union constitutional treaty [one year] ago caused an international shock because the French rejected the view, all but universally held among European elites, that continuing expansion and market-liberalization are essential to the EU, indeed inevitable. This proved to be untrue, to the general relief of the European public.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb <em>Similarly, it seems to me that the current unrest in France signals wider popular resistance in Europe to the most important element in the new model of market economics, its undermining of the place of the employee in the corporate order, deliberately rendering the life of the employee precarious.<\/em> <\/p>\n<\/p>\n<p><p>\t\u00bb <em>The model&rsquo;s principal characteristic in the U.S. has been to transfer wealth to stockholders and managers, and away from public interests (by tax cuts) and employees (through wage-depression and elimination of employee benefits).<\/em> <\/p>\n<\/p>\n<p><p>\t\u00bb <em>In this perspective, what in France seems sterile defense of an obsolete social and economic order might be interpreted as a premonitory appeal for a new but humane model to replace it. It could be Europe&rsquo;s opportunity.<\/em> \u00bb<\/p>\n<\/p>\n<p><p>\tPour terminer, nous insistons sur l&rsquo;ironie de la situation en citant \u00e0 nouveau l&rsquo;Allemand Koopman: \u00ab <em>This really was a signal that the French have chosen to be isolationists in Europe, Koopmann said. You need to cooperate with France, and, at the moment, I just don&rsquo;t see how.<\/em> \u00bb<\/p>\n<\/p>\n<p><p>\tL&rsquo;isolationnisme fran\u00e7ais en Europe, tel qu&rsquo;il est dit ici, est une sornette sans int\u00e9r\u00eat; la r\u00e9alit\u00e9 est celle de l&rsquo;isolationnisme d&rsquo;un mouvement qui tue les nations, les peuples et le reste. La remarque sonnerait moins comme un reproche, dans ce cas Pour le reste, c&rsquo;est oui : la France \u00e9tant l\u00e0 o\u00f9 elle est, avec la puissance et l&rsquo;influence qu&rsquo;elle a, la France est, comme ils disent, incontournable. Message au syst\u00e8me : il faudra faire avec.<\/p>\n<\/p>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La France, mod\u00e8le as usual 26 mars 2006 Ces mots nous paraissent significatif de la crise fran\u00e7aise (la crise du CPE \u00e9largie \u00e0 d&rsquo;autres \u00e9v\u00e9nements), \u00e0 la fois pour l&rsquo;incompr\u00e9hension de la crise et pour la compr\u00e9hension du probl\u00e8me que la crise fran\u00e7aise pose \u00e0 l&rsquo;Europe et au syst\u00e8me en g\u00e9n\u00e9ral : \u00ab This really&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[5211,4751,2687,2632,4663,1131],"class_list":["post-67385","post","type-post","status-publish","format-standard","hentry","category-faits-et-commentaires","tag-cpe","tag-economique","tag-france","tag-globalisation","tag-patriotisme","tag-pfaff"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/67385","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=67385"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/67385\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=67385"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=67385"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=67385"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}