{"id":67422,"date":"2006-04-04T00:00:00","date_gmt":"2006-04-04T00:00:00","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2006\/04\/04\/voici-the-new-mccarthysm\/"},"modified":"2006-04-04T00:00:00","modified_gmt":"2006-04-04T00:00:00","slug":"voici-the-new-mccarthysm","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2006\/04\/04\/voici-the-new-mccarthysm\/","title":{"rendered":"Voici \u201c<em>the New McCarthysm<\/em>\u201d"},"content":{"rendered":"<p><p>Excellente enqu\u00eate dans <em>Guardian<\/em> d&rsquo;<a href=\"http:\/\/www.guardian.co.uk\/usa\/story\/0,,1746227,00.html\" class=\"gen\">aujourd&rsquo;hui<\/a> sur ce qui nous est pr\u00e9sent\u00e9 comme <em>the new McCarthysm<\/em>. Objectif av\u00e9r\u00e9 et parfaitement identifi\u00e9 : l&rsquo;universit\u00e9 et le monde de l&rsquo;\u00e9ducation, bastion suppos\u00e9 de ce qui reste de pens\u00e9e lib\u00e9rale (au sens am\u00e9ricain et intellectuel du terme) aux USA. Processus connu, bas\u00e9 sur l&rsquo;extraordinaire conformisme du comportement am\u00e9ricain quand il devient am\u00e9ricaniste.<\/p>\n<\/p>\n<p><p>\tTout se d\u00e9roule selon un sch\u00e9ma connu. <em>The new McCarthysm<\/em> a ses McCarthys postmodernes et au petit pied, dont l&rsquo;un des plus actifs est David Horowitz, ancien trotskiste \u00e9lev\u00e9 dans une famille de militants marxistes, et qui a suivi le parcours de ses amis n\u00e9o-conservateurs.<\/p>\n<\/p>\n<p><p>\tL&rsquo;article est pourtant mod\u00e9r\u00e9ment pessimiste, estimant que le <em>New McCarthysm<\/em> n&rsquo;a pas encore infect\u00e9 toute l&rsquo;universit\u00e9 US. Mais le probl\u00e8me tel qu&rsquo;il est pr\u00e9sent\u00e9, qui est celui d&rsquo;un affrontement entre des forces manipulant le terrorisme intellectuel et la d\u00e9nonciation, et d&rsquo;autres, repr\u00e9sentant la libert\u00e9 d&rsquo;esprit et de parole, l&rsquo;est peut-\u00eatre de fa\u00e7on trop incompl\u00e8te. Le v\u00e9ritable probl\u00e8me du maccarthysme, d\u00e9j\u00e0 rencontr\u00e9 lors du maccarthysme originel, est celui du comportement de ces lib\u00e9raux progressistes am\u00e9ricains et de leur \u00e9volution intellectuelle. Ce qui fut impressionnant dans la p\u00e9riode maccarthyste fut moins les effets directs que l&rsquo;influence indirecte par conformisme et par crainte exerc\u00e9e sur les esprits. Nombre de lib\u00e9raux progressistes am\u00e9ricains adopt\u00e8rent \u00e0 cette \u00e9poque un jugement et un comportement conformes aux exigences du maccarthysme.<\/p>\n<\/p>\n<p><\/p>\n<p><p>\tMis en ligne le 4 avril 2006 \u00e0 09H41<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Excellente enqu\u00eate dans Guardian d&rsquo;aujourd&rsquo;hui sur ce qui nous est pr\u00e9sent\u00e9 comme the new McCarthysm. Objectif av\u00e9r\u00e9 et parfaitement identifi\u00e9 : l&rsquo;universit\u00e9 et le monde de l&rsquo;\u00e9ducation, bastion suppos\u00e9 de ce qui reste de pens\u00e9e lib\u00e9rale (au sens am\u00e9ricain et intellectuel du terme) aux USA. Processus connu, bas\u00e9 sur l&rsquo;extraordinaire conformisme du comportement am\u00e9ricain quand&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[2],"tags":[3506,5255,3256],"class_list":["post-67422","post","type-post","status-publish","format-standard","hentry","category-bloc-notes","tag-maccarthysme","tag-mccarthysm","tag-new"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/67422","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=67422"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/67422\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=67422"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=67422"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=67422"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}