{"id":67425,"date":"2006-04-05T00:00:00","date_gmt":"2006-04-05T00:00:00","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2006\/04\/05\/tous-en-scene-pour-2008\/"},"modified":"2006-04-05T00:00:00","modified_gmt":"2006-04-05T00:00:00","slug":"tous-en-scene-pour-2008","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2006\/04\/05\/tous-en-scene-pour-2008\/","title":{"rendered":"<strong><em>Tous en sc\u00e8ne pour 2008\u2026<\/em><\/strong>"},"content":{"rendered":"<p><h2 class=\"common-article\">Tous en sc\u00e8ne pour 2008<\/h2>\n<\/p>\n<p><\/p>\n<p><p>\t5 avril 2006  Hier, le commentateur am\u00e9ricain Jim Lobe faisait para\u00eetre une chronique d&rsquo;analyse sur l&rsquo;\u00e9volution des forces politiques \u00e0 Washington. L&rsquo;essentiel de <a href=\"http:\/\/www.antiwar.com\/lobe\/?articleid=8803\" class=\"gen\">l&rsquo;analyse<\/a> porte sur l&rsquo;effacement, que Lobe semble juger d\u00e9sormais in\u00e9luctable et en partie d&rsquo;ores et d\u00e9j\u00e0 accompli, de l&rsquo;influence extr\u00e9miste du mouvement n\u00e9o-conservateur. En un sens, il rejoint l&rsquo;analyse de base de Francis Fukuyama lorsque celui-ci annonce que la fin des <em>neocons<\/em> est d\u00e9j\u00e0 l\u00e0 (<em>After the neocons<\/em>, titre de son dernier livre) ; mais on a vu (notre <a href=\"http:\/\/www.dedefensa.org\/article.php?art_id=2521\" class=\"gen\">F&#038;C<\/a> du 22 mars) que Fukuyama pousse l&rsquo;analyse plus loin en mettant en \u00e9vidence le risque d&rsquo;une Am\u00e9rique devenant isolationniste, avec des tendances radicalistes nouvelles (au niveau de l&rsquo;\u00e9tiquette), avec notamment le nationalisme populiste d&rsquo;Hillary Clinton, qui vaudrait largement celui des <em>neocons<\/em>.<\/p>\n<\/p>\n<p><p>\tPr\u00e9cision de Fukuyama, dans <a href=\"http:\/\/news.independent.co.uk\/people\/profiles\/article353600.ece\" class=\"gen\">The Independent<\/a> du 26 mars: \u00ab <em>He <\/em>[Fukuyama] <em>despairs of American politicians. As Iraq becomes seen as more and more of a failure, it will push the Republican base back towards isolationism, while Hillary Clinton&rsquo;s populist nationalism in opposing the takeover of US ports by an Arab company, he winces, is terrible.<\/em> \u00bb <\/p>\n<\/p>\n<p><p>\tNous allons tenter de r\u00e9unir les deux analyses,  celle de Lobe et celle de Fukuyama,  pour proposer une perspective am\u00e9ricaine.<\/p>\n<\/p>\n<p><p>\tLobe fait justement remarquer que le d\u00e9clin de l&rsquo;influence des <em>neocons<\/em> a commenc\u00e9 imm\u00e9diatement apr\u00e8s la victoire \u00e0 Bagdad, en avril 2003.<\/p>\n<\/p>\n<p><p>\t\u00ab <em>In fact, the hawks&rsquo; decline dates back to late 2003, when it became clear that Cheney and Rumsfeld and their neoconservative subordinates, then-Deputy Defense Secretary Paul Wolfowitz, Undersecretary for Policy Douglas Feith, had totally failed to anticipate, let alone prepare for, a Sunni-based insurgency that has gone from strength to strength.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb <em>Except for a brief period from Bush&rsquo;s November 2004 reelection and very early in 2005  a period in which they had hoped that Powell&rsquo;s departure and the president&rsquo;s soaring pro-democracy Inaugural Address signaled a resurgence of their power  the hawks have steadily lost power to the realists led by Rice, whose neoconservative rhetoric, like the president&rsquo;s, has masked the shift back to the more cautious approach of Bush&rsquo;s father.<\/em> \u00bb<\/p>\n<\/p>\n<p><p>\tC&rsquo;est le dernier point qui nous arr\u00eate dans l&rsquo;analyse de Lobe. Le radicalisme <em>neocon<\/em> aurait laiss\u00e9 place \u00e0 une sorte de n\u00e9o-r\u00e9alisme repr\u00e9sent\u00e9 par Rice et ses adjoints Zoellick (ex-repr\u00e9sentant US aux n\u00e9gociations commerciales) et Nicholas Burns (ex-ambassadeur des USA \u00e0 l&rsquo;OTAN). Lobe affirme que leur rh\u00e9torique n\u00e9o-conservatrice dissimule un v\u00e9ritable r\u00e9alisme. Nous ne pensons pas que le point essentiel soit l\u00e0 (encore que des rencontres r\u00e9centes avec Zoellick et Burns, et aussi avec Rice, n&rsquo;ont pas laiss\u00e9 \u00e0 certains diplomates europ\u00e9ens l&rsquo;impression d&rsquo;une diplomatie US devenue mod\u00e9r\u00e9e). Il nous semble que cette pr\u00e9sentation d&rsquo;une \u00e9volution raisonn\u00e9e (et raisonnable) est infond\u00e9e. Nous croyons fermement que la r\u00e9alit\u00e9 est plut\u00f4t qu&rsquo;entre-temps s&rsquo;est impos\u00e9 ce fait fondamental : avec le d\u00e9sastre irakien, la mise en \u00e9vidence des limites path\u00e9tiques de la puissance militaire US sur laquelle s&rsquo;appuyait toute la politique (?) n\u00e9oconservatrice. <\/p>\n<\/p>\n<p><p>\tAutrement dit, le n\u00e9o-r\u00e9alisme de Rice &#038; compagnie n&rsquo;est qu&rsquo;une adaptation piteuse et acc\u00e9l\u00e9r\u00e9e \u00e0 une situation d\u00e9sastreuse par rapport au statut et aux pr\u00e9tentions am\u00e9ricanistes. L&rsquo;esprit n&rsquo;a nullement chang\u00e9, et nous ne voyons nullement cela comme un retour \u00e0 la mod\u00e9ration (d&rsquo;ailleurs toute relative) de la p\u00e9riode 1989-1993 de Bush p\u00e8re. On colmate les br\u00e8ches, on fait bonne figure, mais rien, ni de l&rsquo;obsession guerri\u00e8re, ni de la vaniteuse suffisance am\u00e9ricaniste, ni de la brutalit\u00e9 des exigences, n&rsquo;a disparu.<\/p>\n<\/p>\n<p><p>\tAu contraire,  et c&rsquo;est l\u00e0 que l&rsquo;analyse de Fukuyama a son poids,  on constate un durcissement et une radicalisation g\u00e9n\u00e9rale chez ceux qu&rsquo;on pouvait consid\u00e9rer comme r\u00e9serv\u00e9s du temps des <em>neocons<\/em> : du r\u00e9publicain John McCaine aux d\u00e9mocrates de Hillary Clinton \u00e0 Joseph Biden, sans parler des d\u00e9mocrates super-faucons type Lieberman. Cela se traduit en pratique par une parano\u00efa s\u00e9curitaire, une surench\u00e8re dans le protectionnisme agressif et, comme le voit Fukuyama, une \u00e9volution bien possible vers une position d&rsquo;isolationnisme belliciste.<\/p>\n<\/p>\n<p><p>\tOn pourrait dire que les <em>neocons<\/em>, idiots utiles dont on se d\u00e9barrasse comme d&rsquo;un <em>kleenex<\/em>, ont fait leur temps. L&rsquo;extr\u00e9misme <em>neocon<\/em>, bruyamment maquill\u00e9 et fard\u00e9 derri\u00e8re d&rsquo;autres \u00e9tiquettes plus avantageuses, est, lui, devenu le courant de la pens\u00e9e <em>mainstream<\/em>.<\/p>\n<\/p>\n<p><p>\tVoil\u00e0 la route vers 2008<\/p>\n<\/p>\n<p><p>\tCe qui nous para\u00eet r\u00e9sumer la situation se retrouve en quatre (cinq) points g\u00e9n\u00e9raux:<\/p>\n<\/p>\n<p><p>\t&bull; GW Bush est discr\u00e9dit\u00e9, non pour avoir lanc\u00e9 l&rsquo;aventure irakienne mais pour l&rsquo;avoir rat\u00e9e. D&rsquo;ailleurs, de McCaine \u00e0 Hillary, et d&rsquo;ailleurs \u00e9galement, du candidat d\u00e9mocrate de 2004 John Kerry, on n&rsquo;entend qu&rsquo;un seul cri : il faut plus d&rsquo;hommes en Irak pour \u00e9craser la vermine insurrectionnelle.<\/p>\n<\/p>\n<p><p>\t &bull; Actuellement, la politique ext\u00e9rieure US est en roues libres, avec toujours la m\u00eame rh\u00e9torique agressive, la m\u00eame pompe et la m\u00eame vanit\u00e9, mais une position de compl\u00e8te paralysie quant aux moyens disponibles. Pour que la pens\u00e9e strat\u00e9gique en soit \u00e0 vaticiner sur <a href=\"http:\/\/www.dedefensa.org\/article.php?art_id=2551\" class=\"gen\">la possibilit\u00e9<\/a> de premi\u00e8res frappes strat\u00e9giques nucl\u00e9aires contre la Russie et la Chine, comme au bon vieux temps, il faut que cette pens\u00e9e soit \u00e0 la fois d\u00e9sesp\u00e9r\u00e9e de l&rsquo;absence de moyens militaires interm\u00e9diaires et toujours aussi d\u00e9connect\u00e9e de la r\u00e9alit\u00e9 par une <em>hubris<\/em> absolument pathologique, et par son virtualisme suffisamment r\u00f4d\u00e9 pour mettre tout cela en musique. (Autre parole judicieuse de Fukuyama : \u00ab <em>I think that the United States needs to reconnect to the world. One of my biggest concerns is what&rsquo;s going to happen in terms of the backlash that the war is going to generate. That&rsquo;s what people ought to focus on.<\/em> \u00bb)<\/p>\n<\/p>\n<p><p>\t&bull; Le Congr\u00e8s a retrouv\u00e9 toute sa verdeur irresponsable d&rsquo;antan pour en rajouter par louches enti\u00e8res, sur <a href=\"http:\/\/www.dedefensa.org\/article.php?art_id=2569\" class=\"gen\">l&rsquo;hyper-s\u00e9curit\u00e9<\/a>, la protection de tous les secrets amass\u00e9s aux USA, le <em>micromanagement<\/em> des sommes colossales du g\u00e2chis pentagonesque, les appels \u00e0 la mobilisation de forces suppl\u00e9mentaires et de dizaines de $milliards en plus pour le Pentagone, et ainsi de suite. Irresponsabilit\u00e9 totale, avec l&rsquo;agressivit\u00e9 rempla\u00e7ant la trouille initiale <em>post<\/em>-9\/11, qui profite du champ laiss\u00e9 libre par l&rsquo;effondrement du syst\u00e8me belliciste de GW &#038; compagnie.<\/p>\n<\/p>\n<p><p>\t&bull; En avant pour 2008, avec l&rsquo;escale interm\u00e9diaire de novembre 2006 qui, si elle donne une majorit\u00e9 aux d\u00e9mocrates au Congr\u00e8s, d\u00e9bouchera sur deux ann\u00e9es de torture g\u00e9n\u00e9ralis\u00e9e de l&rsquo;administration GW, avec GW lui-m\u00eame mis sur le grill de diverses proc\u00e9dures (censure, voire menaces d&rsquo;<em>impeachment<\/em>, etc.). L&rsquo;Am\u00e9rique est enferm\u00e9e dans une d\u00e9magogie extr\u00e9miste sans frein, dans une paralysie politique qui se donne l&rsquo;illusion d&rsquo;exister gr\u00e2ce au th\u00e9\u00e2tre virtualiste. On voit mal ce qui pourrait seulement la mod\u00e9rer et freiner la pose g\u00e9n\u00e9ralis\u00e9e de verrous indestructibles sur les rares portes encore entr&rsquo;ouvertes de la Forteresse Am\u00e9rique.<\/p>\n<\/p>\n<p><p>\t&bull; En commentaire final : que la plupart des gens chic d&rsquo;Occident, particuli\u00e8rement en Europe, suivent cela avec fascination n&#8217;emp\u00eache pas le n\u00e9ant d&rsquo;\u00eatre d\u00e9sesp\u00e9r\u00e9ment vide. Voil\u00e0 un bon proc\u00e8s-verbal de notre temps historique.<\/p>\n<\/p>\n<p><p>\tPendant ce temps-l\u00e0, Rice continuera \u00e0 voyager (Elle se d\u00e9place beaucoup.) Peut-\u00eatre trouvera-t-elle un mari. Cela ferait un <em>happy end<\/em> de circonstance.<\/p>\n<\/p>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tous en sc\u00e8ne pour 2008 5 avril 2006 Hier, le commentateur am\u00e9ricain Jim Lobe faisait para\u00eetre une chronique d&rsquo;analyse sur l&rsquo;\u00e9volution des forces politiques \u00e0 Washington. L&rsquo;essentiel de l&rsquo;analyse porte sur l&rsquo;effacement, que Lobe semble juger d\u00e9sormais in\u00e9luctable et en partie d&rsquo;ores et d\u00e9j\u00e0 accompli, de l&rsquo;influence extr\u00e9miste du mouvement n\u00e9o-conservateur. En un sens, il&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[4906,3278,1094,1104,3306],"class_list":["post-67425","post","type-post","status-publish","format-standard","hentry","category-faits-et-commentaires","tag-4906","tag-hillary","tag-lobe","tag-neocons","tag-rice"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/67425","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=67425"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/67425\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=67425"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=67425"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=67425"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}