{"id":67440,"date":"2006-04-09T00:00:00","date_gmt":"2006-04-09T00:00:00","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2006\/04\/09\/qui-na-pas-son-plan-dattaque\/"},"modified":"2006-04-09T00:00:00","modified_gmt":"2006-04-09T00:00:00","slug":"qui-na-pas-son-plan-dattaque","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2006\/04\/09\/qui-na-pas-son-plan-dattaque\/","title":{"rendered":"Qui n&rsquo;a pas son plan d&rsquo;attaque?"},"content":{"rendered":"<p><h2 class=\"common-article\">Qui n&rsquo;a pas son plan d&rsquo;attaque?<\/h2>\n<\/p>\n<p><p>\t9 avril 2006  Le temps des attaques-surprises par surprise est d\u00e9cid\u00e9ment pass\u00e9. La surprise, aujourd&rsquo;hui, serait qu&rsquo;une attaque-surprise ou n&rsquo;importe quoi d&rsquo;autre de ce genre ne soit pas pr\u00e9c\u00e9d\u00e9 d&rsquo;une avalanche de sp\u00e9culations sur la forme de l&rsquo;attaque, la date de l&rsquo;attaque, les moyens de l&rsquo;attaque, les causes de l&rsquo;attaque, les humeurs et la psychologie de ceux qui fomentent l&rsquo;attaque, etc. Depuis quelques jours, l&rsquo;Iran b\u00e9n\u00e9ficie de ce traitement. C&rsquo;est une avalanche d&rsquo;articles, d&rsquo;analyses et de r\u00e9v\u00e9lations.<\/p>\n<\/p>\n<p><p>\tL&rsquo;hypoth\u00e8se centrale sur les causes possibles de cette pouss\u00e9e de r\u00e9v\u00e9lations (toutes de sources officielles informelles) d&rsquo;intentions guerri\u00e8res est celle d&rsquo;une volont\u00e9 d\u00e9lib\u00e9r\u00e9e de l&rsquo;administration de mettre sur la place publique cette possibilit\u00e9\/probabilit\u00e9 d&rsquo;attaque. Il y a toutes les raisons du monde pour cela, \u00e0 commencer par l&rsquo;extr\u00eame faiblesse de la position politique de GW Bush confront\u00e9 \u00e0 des \u00e9v\u00e9nements irakiens hors de tout contr\u00f4le. La th\u00e8se d&rsquo;une attaque ext\u00e9rieure pour faire diversion d&rsquo;une position politique int\u00e9rieure affaiblie (ici, path\u00e9tique conviendrait mieux) est tellement rab\u00e2ch\u00e9e, apr\u00e8s avoir \u00e9t\u00e9 plus d&rsquo;une fois confirm\u00e9e par les \u00e9v\u00e9nements, qu&rsquo;elle en est devenue un classique du genre ; pour autant, elle doit \u00eatre tenue pour toujours aussi vigoureuse car il n&rsquo;y a rien de plus solide que le classique. Dans ce cas, on le comprend, la publicit\u00e9 pr\u00e9alable des intentions d&rsquo;attaque fait aussi bien partie de la manuvre que l&rsquo;\u00e9ventuelle attaque elle-m\u00eame ; de m\u00eame si l&rsquo;administration entend faire pression sur les Iraniens.<\/p>\n<\/p>\n<p><p>\tD&rsquo;autres hypoth\u00e8ses sur les causes de ces intentions guerri\u00e8res tiennent aux analyses de l&rsquo;\u00e9quipe GW Bush, \u00e0 la psychologie manich\u00e9enne du pr\u00e9sident, aux manigances de ce qu&rsquo;il reste des n\u00e9o-conservateurs et ainsi de suite. Ces cas ne n\u00e9cessitent pas de publicit\u00e9 pr\u00e9alable mais ils ne l&rsquo;interdisent pas non plus. D&rsquo;ailleurs, toutes ces causes peuvent s&rsquo;ajouter et se compl\u00e9ter. <\/p>\n<\/p>\n<p><p>\tDifficile de se faire une religion. La seule conclusion ferme que nous proposerons, avant de proposer une revue de d\u00e9tails non exhaustive est qu&rsquo;il s&rsquo;agit, par-dessus tout, d&rsquo;un signe de plus de l&rsquo;immense d\u00e9sordre qui caract\u00e9rise ce qu&rsquo;on a encore coutume de d\u00e9signer comme la politique \u00e9trang\u00e8re de Washington ; cela quand on consid\u00e8re ces bruits divers d&rsquo;attaque dans le cadre qui importe, qui est le cadre g\u00e9n\u00e9ral de cette politique \u00e9trang\u00e8re, Irak compris. Qu&rsquo;on d\u00e9ploie des plans d&rsquo;attaque grandioses contre l&rsquo;Iran au moment o\u00f9 le courant anti-guerre de Washington s&rsquo;estime proche de <a href=\"http:\/\/www.dedefensa.org\/article.php?art_id=2587\" class=\"gen\">sa victoire<\/a> qui pourrait concr\u00e9tiser une humiliante d\u00e9faite US en conduisant \u00e0 un retrait des troupes d&rsquo;Irak, est un signe convaincant \u00e0 cet \u00e9gard.<\/p>\n<\/p>\n<p><p>\tEnfin, n&rsquo;oublions pas le plan psychologique, si important. On sent souvent dans toutes ces analyses soi-disant rationnelles, y compris chez les sources officielles concern\u00e9es, un certain vertige de puissance dont les planificateurs et les commentateurs am\u00e9ricains sont singuli\u00e8rement priv\u00e9s avec l&rsquo;Irak. Ces bruits d\u00e9taill\u00e9s d&rsquo;attaque contre l&rsquo;Iran constituent effectivement une r\u00e9affirmation virtualiste de la puissance am\u00e9ricaine \u00e0 l&rsquo;heure o\u00f9 celle-ci est gravement mise en cause par les catastrophiques \u00e9v\u00e9nements irakiens. Ce que l&rsquo;on pourrait tenir comme compl\u00e8tement surprenant, irr\u00e9aliste et d\u00e9raisonnable,  fomenter un plan d&rsquo;attaque et en faire la publicit\u00e9 au moment o\u00f9 l&rsquo;on subit une d\u00e9faite de la dimension de l&rsquo;irakienne,  devient presque logique : riposte virtualiste puissante \u00e0 la d\u00e9faite irakienne.<\/p>\n<h3>Revue de d\u00e9tails<\/h3>\n<\/p>\n<p><p>\tMaintenant, la revue de d\u00e9tails de quelques articles pr\u00e9sentant des plans de guerre. Elle ne pr\u00e9tend en aucun cas \u00eatre exhaustive.<\/p>\n<\/p>\n<p><p>\t\u00a0Selon notre estimation, c&rsquo;est le 3 avril que commence l&rsquo;actuelle vague de sp\u00e9culation d&rsquo;une attaque contre l&rsquo;Iran, avec <LIEN=http:\/\/www.wpherald.com\/print.php?StoryID=20060403-101347-4356r>l&rsquo;article d&rsquo;Arnaud de Borchgrave, <em>Editor at large<\/em> de UPI. Borchgrave rapporte des confidences selon lesquelles on pr\u00e9parerait une attaque tr\u00e8s rapide, tr\u00e8s efficace et tr\u00e8s puissante, gr\u00e2ce au bombardier B-2. \u00ab <em>A prominent neocon, still in good odor at the White House and OSD (Office of the Secretary of Defense), speaking privately, assured us that by the time president Bush leaves office in January 2009, Iran&rsquo;s nuclear weapons ambitions would be history. <\/em>[&#8230;] B-2s, this prominent armchair strategist <D>[told us]. <em> Two of them could do the job in a single strike against multiple targets. With a crew of two per bomber, only four American lives would be at risk, an all-time record in the history of warfare.<\/em> \u00bb Borchgrave montre un certain scepticisme sur la sagesse de cette option, sur son efficacit\u00e9 et sur son opportunit\u00e9; par contre, il d\u00e9taille les cons\u00e9quences malheureuses et dangereuses sans nombre qui suivraient son application.<\/p>\n<\/p>\n<p><p>\t\u00a0L&rsquo;analyse de Borchgrave est reprise ici ou l\u00e0, notamment par certains sites et journaux non-US, comme le <a href=\"http:\/\/www.dailytimes.com.pk\/default.asp?page=2006%5C04%5C05%5Cstory_5-4-2006_pg7_62\" class=\"gen\">Daily Times<\/a> pakistanais, avec, le 5 avril, un article de Khalid Hasan : \u00ab <em>Two B-2s could take out Iran&rsquo;s nuclear assets.<\/em> \u00bb<\/p>\n<\/p>\n<p><p>\t&bull; Il semblerait que l&rsquo;informateur de Borchgrave soit Edward Luttwak, si l&rsquo;on se reporte \u00e0 la longue <a href=\"http:\/\/www.timesonline.co.uk\/article\/0,,2089-2125207,00.html\" class=\"gen\">analyse<\/a> de Sarah Baxter, dans le <em>Sunday Times<\/em> d&rsquo;aujourd&rsquo;hui : \u00ab <em>Edward Luttwak, a Pentagon adviser and expert on military strategy at the Center for Strategic and International Studies in Washington, is a leading advocate of the theory that Iran&rsquo;s nuclear installations could be bombed in a single night. Inside the Pentagon, top officials have been citing Luttwak&rsquo;s views. Air strikes by a handful of B2 bombers, flying out of the British dependency of Diego Garcia in the Indian Ocean, would be enough to demolish the most critical Iranian nuclear sites such as Natanz, Arak and Isfahan.<\/em> \u00bb Baxter nous sort \u00e9galement de son chapeau Richard Perle, qui se faisait rare, et qui, lui, rejette l&rsquo;option Luttwak d&rsquo;attaque courte et rapide pour une v\u00e9ritable guerre a\u00e9rienne, bien massive, bien destructrice, pour parvenir \u00e0 la chute du r\u00e9gime des <em>mollahs<\/em>. Pr\u00e9cieuse Baxter qui nous offre plusieurs options en une (analyse).<\/p>\n<\/p>\n<p><p>\t\u00a0Signalons aussi une tr\u00e8s bonne analyse-sp\u00e9culation du 7 avril, sur le site <a href=\"http:\/\/www.forward.com\/main\/printer-friendly.php?id=7616\" class=\"gen\">Forward<\/a>. On a le bonheur de voir un autre revenant <em>neocon<\/em>, fran\u00e7ais celui-l\u00e0 (\u00e0 moins qu&rsquo;il ne se soit naturalis\u00e9?). Laurent Murawiec eut son <a href=\"http:\/\/www.dedefensa.org\/article.php?art_id=337\" class=\"gen\">heure de gloire<\/a> en juillet-ao\u00fbt 2002. Aujourd&rsquo;hui, il pantoufle \u00e0 Heritage Foundation. Il nous annonce qu&rsquo;il est rassur\u00e9, que les USA sont pr\u00eats \u00e0 attaquer eux-m\u00eames et non \u00e0 se d\u00e9charger sur les Isra\u00e9liens de cette t\u00e2che h\u00e9ro\u00efque, et que les Europ\u00e9ens embo\u00eeteront le pas : \u00ab <em>According to Laurent Murawiec, a senior fellow at the conservative Hudson Institute, the Bush administration&rsquo;s contingency plans were being upgraded because the diplomatic solution has lost credibility. Murawiec said that while he feared several years ago that some officials in Washington seemed to be relying on Israel to take out Iran&rsquo;s nuclear facilities, I don&rsquo;t fear this anymore. He added that two European defense ministries were also working on military contingency plans, but declined to identify them.<\/em> \u00bb<\/p>\n<\/p>\n<p><p>\t Bien entendu, les journaux de r\u00e9f\u00e9rence s&rsquo;y sont mis. Par exemple, le Washington <em>Post<\/em> y va de son <a href=\"http:\/\/www.washingtonpost.com\/wp-dyn\/content\/article\/2006\/04\/08\/AR2006040801082_pf.html\" class=\"gen\">analyse-enqu\u00eate<\/a>. Sans r\u00e9elle surprise : on pr\u00e9pare l&rsquo;attaque, voici comment, etc. Le ton y est tout de m\u00eame sceptique : \u00ab <em> No attack appears likely in the short term, and many specialists inside and outside the U.S. government harbor serious doubts about whether an armed response would be effective.<\/em> \u00bb<\/p>\n<\/p>\n<p><p>\t\u00a0L&rsquo;article de Patrick J. Buchanan dans <a href=\"http:\/\/www.amconmag.com\/2006\/2006_04_10\/buchanan.html\" class=\"gen\">The American Conservative Magazine<\/a> du 10 avril est int\u00e9ressant, parce que compl\u00e9mentaire sur le plan politique de toutes les hypoth\u00e8ses d\u00e9taill\u00e9es ces derniers jours. Buchanan parle d&rsquo;une <em>October&rsquo;s Surprise<\/em>\u00bb,  une attaque de l&rsquo;Iran \u00e0 l&rsquo;automne, avec les effets suivants, selon les calculs suppos\u00e9s de l&rsquo;administration GW : \u00ab <em> Rather than appearing a retreat, Bush&rsquo;s pullout from Iraq would look like that of a defiant gunfighter backing through the swinging doors of a Tombstone saloon with both guns blazing. Bush&rsquo;s rating could soar 20 points. Republicans would rally at the return of the 9\/11 president. Democrats would be loath to attack a president who acted forcefully to remove what they themselves say is an intolerable threat. The neocons and Christian Right would hail Bush as the new Churchill. Bush would hold onto both houses in November, costing Democrats their best chance in a decade of recouping power.<\/em> \u00bb (L\u00e8-dessus, Buchanan encha\u00eene sur toutes les cons\u00e9quences probables d&rsquo;une telle attaque, qu&rsquo;il juge consid\u00e9rablement d\u00e9stabilisantes: \u00ab <em>Thus a pre-emptive war on Iran, while a political triumph for the president this fall, could, like the invasion of Iraq, prove a long-term disaster.<\/em> \u00bb<\/p>\n<\/p>\n<p><p>\t\u00a0L&rsquo;article le plus int\u00e9ressant et qui a d&rsquo;ores et d\u00e9j\u00e0 le plus de r\u00e9sonance est celui de Seymour Hersh, qui doit para\u00eetre le 10 avril dans le <a href=\"http:\/\/www.newyorker.com\/printables\/fact\/060417fa_fact\" class=\"gen\">New Yorker<\/a>. Une fois de plus, Hersh nous am\u00e8ne des tonnes de t\u00e9moignages et de citations qu&rsquo;on peut prendre pour r\u00e9els (l&rsquo;homme a assez de cr\u00e9dit et de contacts pour cela). Il nous donne une bonne vision int\u00e9rieure des d\u00e9lib\u00e9rations de l&rsquo;administration, avec les civils toujours aussi allum\u00e9s et GW toujours aussi habit\u00e9, tout cela \u00e0 la grande frayeur des militaires. Surtout, Hersh d\u00e9veloppe l&rsquo;option nucl\u00e9aire, dont il assure qu&rsquo;elle est s\u00e9rieusement envisag\u00e9e. L\u00e0 encore, frayeur extr\u00eame des militaires, certains ayant envisag\u00e9 de d\u00e9missionner. Quelques extraits en vrac de l&rsquo;article de Hersh.<\/p>\n<\/p>\n<p><p>\t\u00ab <em>Iran&rsquo;s President, Mahmoud Ahmadinejad, has challenged the reality of the Holocaust and said that Israel must be wiped off the map. Bush and others in the White House view him as a potential Adolf Hitler, a former senior intelligence official said. That&rsquo;s the name they&rsquo;re using.<\/em> (&#8230;)<\/p>\n<\/p>\n<p><p>\t\u00bb <em>One former defense official, who still deals with sensitive issues for the Bush Administration, told me that the military planning was premised on a belief that a sustained bombing campaign in Iran will humiliate the religious leadership and lead the public to rise up and overthrow the government. He added, I was shocked when I heard it, and asked myself, What are they smoking?&rsquo;<\/em> (&#8230;)<\/p>\n<\/p>\n<p><p>\t\u00bb <em>There&rsquo;s no pressure from Congress not to take military action, the House member added. The only political pressure is from the guys who want to do it. Speaking of President Bush, the House member said, The most worrisome thing is that this guy has a messianic vision.<\/em>  (&#8230;)<\/p>\n<\/p>\n<p><p>\t\u00bb <em>The attention given to the nuclear option has created serious misgivings inside the offices of the Joint Chiefs of Staff, <\/em>[the former senior intelligence official] <em>added, and some officers have talked about resigning. Late this winter, the Joint Chiefs of Staff sought to remove the nuclear option from the evolving war plans for Iranwithout success, the former intelligence official said. The White House said, Why are you challenging this? The option came from you.&rsquo; <\/em> (&#8230;) <\/p>\n<\/p>\n<p><p>\t\u00bb <em>There are very strong sentiments within the military against brandishing nuclear weapons against other countries, <\/em>[the Pentagon adviser on the war on terror] <em>told me. This goes to high levels. The matter may soon reach a decisive point, he said, because the Joint Chiefs had agreed to give President Bush a formal recommendation stating that they are strongly opposed to considering the nuclear option for Iran. The internal debate on this has hardened in recent weeks, the adviser said. And, if senior Pentagon officers express their opposition to the use of offensive nuclear weapons, then it will never happen.<\/em> \u00bb<\/p>\n<\/p>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Qui n&rsquo;a pas son plan d&rsquo;attaque? 9 avril 2006 Le temps des attaques-surprises par surprise est d\u00e9cid\u00e9ment pass\u00e9. La surprise, aujourd&rsquo;hui, serait qu&rsquo;une attaque-surprise ou n&rsquo;importe quoi d&rsquo;autre de ce genre ne soit pas pr\u00e9c\u00e9d\u00e9 d&rsquo;une avalanche de sp\u00e9culations sur la forme de l&rsquo;attaque, la date de l&rsquo;attaque, les moyens de l&rsquo;attaque, les causes de&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[1257,3335,5160,4180,2773,3004,3856],"class_list":["post-67440","post","type-post","status-publish","format-standard","hentry","category-faits-et-commentaires","tag-borchgrave","tag-buchanan","tag-generaux","tag-hersh","tag-iran","tag-nucleaire","tag-revolte"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/67440","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=67440"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/67440\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=67440"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=67440"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=67440"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}