{"id":67505,"date":"2006-04-28T00:00:00","date_gmt":"2006-04-28T00:00:00","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2006\/04\/28\/les-modeles-de-la-democratie-anglo-saxonne-en-lambeaux\/"},"modified":"2006-04-28T00:00:00","modified_gmt":"2006-04-28T00:00:00","slug":"les-modeles-de-la-democratie-anglo-saxonne-en-lambeaux","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2006\/04\/28\/les-modeles-de-la-democratie-anglo-saxonne-en-lambeaux\/","title":{"rendered":"Les mod\u00e8les de la d\u00e9mocratie anglo-saxonne en lambeaux"},"content":{"rendered":"<p><p>Ces deux sondages (surtout l&rsquo;am\u00e9ricain) auraient d\u00fb susciter bien des exclamations inqui\u00e8tes chez les z\u00e9lateurs des vertus anglo-saxonnes. Voyez dans quel \u00e9tat sont les deux principales d\u00e9mocraties anglo-saxonnes, celles qui s&rsquo;affirment comme les phares de l&rsquo;humanit\u00e9 et font la le\u00e7on \u00e0 tous les autres. L&rsquo;exercice est d&rsquo;autant plus int\u00e9ressant que ces deux d\u00e9mocraties sont tr\u00e8s diff\u00e9rentes et qu&rsquo;on ne peut parler de grippage d&rsquo;un m\u00e9canisme sp\u00e9cifique. Ce sont la pratique et l&rsquo;esprit qui sont en cause, ce qui indique que ces d\u00e9mocraties suscitent, \u00e0 l&rsquo;usage, chez ceux qui la conduisent, le contraire de la vertu civique capable de s\u00e9duire l&rsquo;\u00e9lectorat.<\/p>\n<\/p>\n<p><p>\t&bull; Le sondage effectu\u00e9 par <em>Rasmussen Report<\/em> les 25 et 26 avril (r\u00e9sultats publi\u00e9s <a href=\"http:\/\/www.rasmussenreports.com\/2006\/April%20Dailies\/Election%202008.htm\" class=\"gen\">le 27 avril<\/a>) porte sur les questions : pour quel parti, puis pour quel candidat (non identifi\u00e9) de quel parti voteriez-vous en 2008 ? A la premi\u00e8re question (partis) : 44% pour les d\u00e9mocrates, 32% pour les r\u00e9publicains, 7% pour d&rsquo;autres. La seconde question suppose des candidats des deux partis traditionnels et un candidat ind\u00e9pendant (comme c&rsquo;est souvent le cas). R\u00e9sultat <strong>extraordinaire<\/strong> : 31% pour le candidat d\u00e9mocrate, 30% pour le candidat autre (candidat ind\u00e9pendant), 21% pour le candidat r\u00e9publicain. C&rsquo;est une situation compl\u00e8tement th\u00e9orique (pas de personnalit\u00e9 cit\u00e9e, avec l&rsquo;impact de la chose sur le choix des votes) mais c&rsquo;est une situation th\u00e9orique proche d&rsquo;\u00eatre r\u00e9volutionnaire, o\u00f9 l&rsquo;on est devant la tr\u00e8s grande proximit\u00e9 d&rsquo;une situation o\u00f9 les deux partis constituant le parti unique du syst\u00e8me sont proches d&rsquo;\u00eatre battus par un hypoth\u00e9tique ind\u00e9pendant. L&rsquo;\u00e9crasement du parti au pouvoir (les r\u00e9publicains) est stup\u00e9fiant. En tenant compte du cadre conformiste habituel aux USA, ces r\u00e9sultats mesurent l&rsquo;ill\u00e9gitimit\u00e9 totale actuelle du syst\u00e8me.<\/p>\n<\/p>\n<p><p>\t&bull; En compl\u00e9ment, l&rsquo;\u00e9tat de la d\u00e9mocratie de Tony Blair. Les deux grands partis sont dans une position catastrophique. Au dernier sondage de <a href=\"http:\/\/news.independent.co.uk\/uk\/politics\/article360660.ece\" class=\"gen\">The Independent<\/a>, le parti de Tony Blair est \u00e0 33% (recul de 4%) et les conservateurs aussi \u00e0 33% (recul de 2%), tandis que les Lib\u00e9raux-D\u00e9mocrates sont \u00e0 22% (en hausse de 3%). Commentaire de John Curtice, professeur de politique \u00e0 l&rsquo;Universit\u00e9 de Strathclyde: \u00ab <em>Labour is apparently at its lowest ebb in this parliament, while at the same time the Tories are more or less back to where they were before David Cameron became leader. It is as if <\/em>[the] <em>two largest parties are still slugging it out for who is king of the castle, without realising that around them an incoming tide is gradually eroding the castle&rsquo;s foundations.<\/em> \u00bb<\/p>\n<\/p>\n<p><\/p>\n<p><p>\tMis en ligne le 28 avril 2006 \u00e0 11H58<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ces deux sondages (surtout l&rsquo;am\u00e9ricain) auraient d\u00fb susciter bien des exclamations inqui\u00e8tes chez les z\u00e9lateurs des vertus anglo-saxonnes. Voyez dans quel \u00e9tat sont les deux principales d\u00e9mocraties anglo-saxonnes, celles qui s&rsquo;affirment comme les phares de l&rsquo;humanit\u00e9 et font la le\u00e7on \u00e0 tous les autres. L&rsquo;exercice est d&rsquo;autant plus int\u00e9ressant que ces deux d\u00e9mocraties sont tr\u00e8s&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[2],"tags":[3426,705,3009,5333,5310,5190,3014],"class_list":["post-67505","post","type-post","status-publish","format-standard","hentry","category-bloc-notes","tag-anglo-saxon","tag-blair","tag-democrates","tag-independants","tag-republicains","tag-sondage","tag-systeme"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/67505","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=67505"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/67505\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=67505"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=67505"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=67505"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}