{"id":67514,"date":"2006-05-01T00:00:00","date_gmt":"2006-05-01T00:00:00","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2006\/05\/01\/le-jsf-entre-dans-la-guerre-des-tranchees-du-congres\/"},"modified":"2006-05-01T00:00:00","modified_gmt":"2006-05-01T00:00:00","slug":"le-jsf-entre-dans-la-guerre-des-tranchees-du-congres","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2006\/05\/01\/le-jsf-entre-dans-la-guerre-des-tranchees-du-congres\/","title":{"rendered":"Le JSF entre dans la guerre des tranch\u00e9es du Congr\u00e8s"},"content":{"rendered":"<p><p>Le 26 avril, le bureau pour l&rsquo;aviation tactique de la commission des forces arm\u00e9es de la Chambre des Repr\u00e9sentants a donn\u00e9 <a href=\"http:\/\/armedservices.house.gov\/schedules\/4-26-06WeldonOpeningStatementMark.pdf\" class=\"gen\">ses avis<\/a> sur le budget FY2007 du d\u00e9partement de la d\u00e9fense. Deux points concernent notre sujet favori (le JSF). Nous les extrayons du rapport.<\/p>\n<\/p>\n<p><p>\t&bull; La question du <a href=\"http:\/\/www.dedefensa.org\/article.php?art_id=2503\" class=\"gen\">second<\/a> moteur : \u00ab <em>$408 million has been added for the alternate engine for the Joint Strike Fighter, F-35 aircraft program. Because of the problems with the F100 engine for the F-15 and F-16 in the late 1970s and early 1980s, and the resulting evolution of the competitive F110 alternative fighter engine, Congress has for the last 10 years supported an alternate engine program for the F-35. The annual engine competition that resulted from the alternative fighter engine program for the F-15 and 16 resulted in an estimated savings of approximately $4 billion in life cycle costs  a 21 percent savings  as well as improved reliability and maintainability for both competing engines. Fighter engines cost around $10 million each. With the current planned purchase of up to nearly 3,100 F-35s and the likelihood of as many as 4500-6,000 engines being required to support the F-35 over its lifetime, it does not take significant savings through a competitive program to recoup the initial R&#038;D investment. These savings would be in addition to improved performance, reliability, maintainability, and technical innovation expected through competitive versus sole source contracts.<\/em> \u00bb<\/p>\n<\/p>\n<p><p>\t&bull; La question de la structure m\u00eame du programme, avec des cons\u00e9quences chronologiques s\u00e9rieuses: \u00ab <em>Our concern with the F-35 is one of excess R&#038;D and procurement concurrency. DOD is committing to the procurement of aircraft before any testing has been accomplished. The first test aircraft, now scheduled to fly in October or November of this year, is not a production representative aircraft and first-flight has just slipped 2-3 months. Because of R&#038;D and procurement concurrency, the Committee cut the Fiscal Year 2006 request last year for long lead funding for 5 production aircraft, but overall, Congress supported the long lead funding request. This year, we are recommending that we not increase Fiscal Year 2008 production above the 5 aircraft planned in Fiscal Year 2007 because of the lack of testing. Consequently, we recommend cutting the long lead funding by $241 million for 11 aircraft of the 16 aircraft intended for procurement in Fiscal Year 2008.<\/em> \u00bb<\/p>\n<\/p>\n<p><p>\tLes deux recommandations (qui restent \u00e0 \u00eatre ent\u00e9rin\u00e9es par des structures sup\u00e9rieures et par un accord Chambre-S\u00e9nat) impliquent essentiellement que le Congr\u00e8s a d\u00e9cid\u00e9 de s&rsquo;impliquer directement dans le programme JSF. Il y aura donc une guerre des moteurs pour la r\u00e9installation d&rsquo;un programme de moteur alternatif. M\u00eame si <a href=\"http:\/\/www.dedefensa.org\/article.php?art_id=2298\" class=\"gen\">les Britanniques<\/a> (Rolls Royce) peuvent se satisfaire de cette orientation, ils devraient savoir que cela ne signifie rien d&rsquo;autre qu&rsquo;un accroissement de la bataille bureaucratique autour de cette question, avec le caract\u00e8re incontr\u00f4lable qui s&rsquo;y rattache. La seconde recommandation, qui suit <a href=\"http:\/\/www.dedefensa.org\/article.php?art_id=2555\" class=\"gen\">les recommandations<\/a> du GAO, revient \u00e0 proposer une mesure qui, m\u00eame si elle est grandement justifi\u00e9e, aura pour cons\u00e9quence un retard suppl\u00e9mentaire de un \u00e0 deux ans du programme.<\/p>\n<\/p>\n<p><p>\tMais le principal enseignement est celui-ci : le Congr\u00e8s entre directement dans la gestion du programme JSF. Cela implique des complications suppl\u00e9mentaires, un <em>micromanagement<\/em> (gestion tatillonne) du programme, c&rsquo;est-\u00e0-dire un d\u00e9sordre suppl\u00e9mentaire. Le programme JSF \u00e9tait d\u00e9j\u00e0 incontr\u00f4l\u00e9, il va devenir en substance compl\u00e8tement incontr\u00f4lable \u00e0 cause de la dilution du pouvoir de d\u00e9cision et les guerres de tranch\u00e9es bureaucratiques.<\/p>\n<\/p>\n<p><\/p>\n<p><p>\tMis en ligne le 1er mai 2006 \u00e0 11H51<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le 26 avril, le bureau pour l&rsquo;aviation tactique de la commission des forces arm\u00e9es de la Chambre des Repr\u00e9sentants a donn\u00e9 ses avis sur le budget FY2007 du d\u00e9partement de la d\u00e9fense. Deux points concernent notre sujet favori (le JSF). Nous les extrayons du rapport. &bull; La question du second moteur : \u00ab $408 million&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[2],"tags":[3359,3285,4248,250,5339,5340,4962],"class_list":["post-67514","post","type-post","status-publish","format-standard","hentry","category-bloc-notes","tag-chambre","tag-congres","tag-gao","tag-jsf","tag-moteur","tag-programme","tag-rolls"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/67514","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=67514"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/67514\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=67514"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=67514"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=67514"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}