{"id":67531,"date":"2006-05-06T00:00:00","date_gmt":"2006-05-06T00:00:00","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2006\/05\/06\/linculpabilite-et-la-psychologie-americaniste-1\/"},"modified":"2006-05-06T00:00:00","modified_gmt":"2006-05-06T00:00:00","slug":"linculpabilite-et-la-psychologie-americaniste-1","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2006\/05\/06\/linculpabilite-et-la-psychologie-americaniste-1\/","title":{"rendered":"L&rsquo;\u201cinculpabilit\u00e9\u201d et la psychologie am\u00e9ricaniste"},"content":{"rendered":"<p><h2 class=\"titleset_a.deepblue\" style=\"color:#0f3955; font-size:2em\">L'\u00a0\u00bbinculpabilit\u00e9\u00a0\u00bb et la psychologie am\u00e9ricaniste<\/h2>\n<\/p>\n<p><p>6 mai 2006 &mdash; A premi\u00e8re lecture, ce devrait \u00eatre un d\u00e9luge d&rsquo;\u00e9pith\u00e8tes d&rsquo;une ironie lasse ou furieuse, d&rsquo;\u00e9coeurements divers, de moqueries et ainsi de suite&hellip; Nous pensons qu&rsquo;il faut tenter d&rsquo;aller au-del\u00e0 avec l&rsquo;effort de penser la psychologie am\u00e9ricaniste comme quelque chose de <strong>diff\u00e9rent<\/strong>.<\/p>\n<\/p>\n<p><p>D&rsquo;abord la nouvelle. La r\u00e9f\u00e9rence est classique: un article (publi\u00e9 le 1er mai) bien document\u00e9 et sans l&rsquo;ombre d&rsquo;un commentaire de surprise, d&rsquo;incompr\u00e9hension, d&rsquo;indignation, etc., du New York <em>Times<\/em>, repris par l&rsquo;International <em>Herald Tribune<\/em> <a class=\"gen\" href=\"http:\/\/www.iht.com\/articles\/2006\/04\/30\/america\/web.0430gitmo.php&lt;D\">le 30 avril<\/a>. Laissons parler ces gens :<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em;\">\n<p><p>&laquo; <em>A long-running effort by the Bush administration to send home many of the terror suspects held at Guant&aacute;namo Bay, Cuba, has been stymied in part because of concern among United States officials that the prisoners may not be treated humanely by their own governments, officials said.<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>Administration officials have said they hope eventually to transfer or release many of the roughly 490 suspects now held at Guant&aacute;namo. As of February, military officials said, the Pentagon was ready to repatriate more than 150 of the detainees once arrangements could be made with their home countries.<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>But those arrangements have been more difficult to broker than officials in Washington anticipated or have previously acknowledged, raising questions about how quickly the administration can meet its goal of scaling back detention operations at Guant&aacute;namo.<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em> \u00ab\u00a0The Pentagon has no plans to release any detainees in the immediate future,\u00a0\u00bb said a Defense Department spokesman, Lt. Cmdr. Jeffrey Gordon of the Navy. He said the negotiations with foreign governments \u00ab\u00a0have proven to be a complex, time-consuming and difficult process.\u00a0\u00bb<\/em> &raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>Tout de m\u00eame&#8230; Un peu plus loin dans le texte, le journaliste, Tim Golden, se juge fond\u00e9, au nom de l&rsquo;observation objective du monde ext\u00e9rieur, \u00e0 citer un commentaire l\u00e9g\u00e8rement surpris venu effectivement de la partie non-US du monde:<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em;\">\n<p><p>&laquo; <em>\u00ab\u00a0It is kind of ironic that the U.S. government is placing conditions on other countries that it would not follow itself in Guant&aacute;namo or Abu Ghraib,\u00a0\u00bb said a Middle Eastern diplomat from one of the countries involved in the talks. He asked not to be named to avoid criticizing the United States in the name of his government.<\/em> &raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>(La derni\u00e8re phrase de la citation est apr\u00e8s tout aussi importante que la d\u00e9claration de la source anonyme. Elle signifie qu&rsquo;une remarque de bon sens sera prise n\u00e9cessairement comme une attaque critique des Etats-Unis. Elle nous indique l&rsquo;\u00e9tat d&rsquo;inflexibilit\u00e9 o&ugrave; doivent se trouver les n\u00e9gociateurs US, qui implique pour leurs interlocuteurs de s&rsquo;abstenir de tout commentaire d\u00e9sobligeant.)<\/p>\n<\/p>\n<p><p>R\u00e9sumons le propos avant de proposer un commentaire. Les Etats-Unis veulent bien rendre \u00e0 leurs pays d&rsquo;origine un certain nombre de d\u00e9tenus qu&rsquo;ils d\u00e9tiennent ill\u00e9galement depuis des ann\u00e9es, \u00e0 Guantanamo et ailleurs, qu&rsquo;ils soumettent \u00e0 des traitements inhumains, \u00e0 des conditions de torture physique et psychologique, d&rsquo;humiliation, etc. Leurs fermes exigences rendent ces n\u00e9gociations de restitution des nationaux tr\u00e8s difficiles. Ils entendent que ces d\u00e9tenus soient trait\u00e9s d\u00e9cemment par leurs pays d&rsquo;origine et d&rsquo;accueil, c&rsquo;est-\u00e0-dire qu&rsquo;ils ne soient en aucune fa\u00e7on soumis \u00ab\u00a0\u00e0 des traitements inhumains, \u00e0 des conditions de torture physique et psychologique, d&rsquo;humiliation, etc.\u00a0\u00bb<\/p>\n<\/p>\n<p><p>Nous avons le choix entre les habituelles exclamations, les \u00e9pith\u00e8tes, etc., comme nous le signalons en t\u00eate de ce titre, &mdash; et, d&rsquo;autre part, une tentative d&rsquo;analyse et d&rsquo;explication plus structur\u00e9e. Elle ne portera ni sur les prisonniers, ni sur la torture, mais sur la psychologie am\u00e9ricaniste. Elle s&rsquo;articulera sur une notion que nous proposons \u00e0 nos lecteurs sous la forme d&rsquo;un n\u00e9ologisme convenable, qui pourrait faire un mot acceptable par la langue fran\u00e7aise : l&rsquo;id\u00e9e d&rsquo;<strong>inculpabilit\u00e9<\/strong>, &mdash; ou, plus pr\u00e9cis\u00e9ment dit : la notion de <strong>sentiment d&rsquo;inculpabilit\u00e9<\/strong> post\u00e9 au c&oelig;ur de la psychologie am\u00e9ricaniste.<\/p>\n<\/p>\n<p><h2 class=\"titleset_b.deepblue\" style=\"color:#0f3955; font-size:1.65em; font-variant:small-caps\">Au coeur de la psychologie am\u00e9ricaniste<\/h2>\n<\/p>\n<p><p>Nous partons de plusieurs propositions qui peuvent \u00eatre prises comme autant d&rsquo;hypoth\u00e8ses, mais qui sont \u00e0 notre sens largement d\u00e9montr\u00e9es par le constat de la pratique et de l&rsquo;exp\u00e9rience. Cela rend notre exercice de r\u00e9flexion plus vivant qu&rsquo;une simple approche th\u00e9orique. Nous avons la conviction d&rsquo;aborder une mati\u00e8re <strong>vivante<\/strong>.<\/p>\n<\/p>\n<p><p>&bull; Il n&rsquo;y a pas de machiav\u00e9lisme, ou d&rsquo;autres sentiments aussi \u00e9labor\u00e9s o&ugrave; la contradiction est instrument\u00e9e, &mdash; go&ucirc;t de la provocation, go&ucirc;t du paradoxe absurde, etc., &mdash; chez les Am\u00e9ricains lorsqu&rsquo;ils proc\u00e8dent dans leurs actes de politique ext\u00e9rieure, et, particuli\u00e8rement, dans le cas d\u00e9crit ici. Les contradictions ou les absurdit\u00e9s, les soi-disant hypocrisies, trop \u00e9normes pour \u00eatre de l&rsquo;hypocrisie qui par d\u00e9finition se dissimule, ne sont pas le fruit d&rsquo;un calcul ; elles ne sont qu&rsquo;en apparence, pour nous, des \u00ab\u00a0contradictions ou [des] absurdit\u00e9s, [des] soi-disant hypocrisies, trop \u00e9normes pour \u00eatre de l&rsquo;hypocrisie&hellip;\u00a0\u00bb.<\/p>\n<\/p>\n<p><p>&bull; La puissance d&rsquo;influence consid\u00e9rable de l&rsquo;am\u00e9ricanisme est fond\u00e9e sur sa sinc\u00e9rit\u00e9, souvent d\u00e9crite et\/ou expliqu\u00e9e, \u00e0 tort nous semble-t-il, comme \u00ab\u00a0na\u00efvet\u00e9\u00a0\u00bb, comme \u00ab\u00a0infantilisme\u00a0\u00bb, etc. Il n&rsquo;y a aucune raison de revenir sur ce constat de la \u00ab\u00a0sinc\u00e9rit\u00e9\u00a0\u00bb. Il vaut \u00e9galement pour le cas pr\u00e9sent\u00e9 ici. Notre hypoth\u00e8se est que les n\u00e9gociateurs am\u00e9ricains, comme ceux qui leur donnent des consignes, sont pour la plupart, disons pour le \u00ab\u00a0mod\u00e8le standard\u00a0\u00bb, compl\u00e8tement sinc\u00e8res. (Cela ne signifie pas qu&rsquo;ils disent la v\u00e9rit\u00e9 mais qu&rsquo;ils parlent sans dissimuler. La sinc\u00e9rit\u00e9 est &laquo; <em>l&rsquo;absence de trucage<\/em> &raquo; [Robert], qui signifie qu&rsquo;on parle sans dissimuler et qu&rsquo;on dit ce qu&rsquo;on pense et ce qu&rsquo;on croit. Cela ne signifie nullement que ce qu&rsquo;on pense et ce qu&rsquo;on croit soient la v\u00e9rit\u00e9 et la vertu.)<\/p>\n<\/p>\n<p><p>&bull; Pour renforcer ces constats, il y a l&rsquo;\u00e9vidence contraire que les attitudes am\u00e9ricanistes auxquelles nous faisons r\u00e9f\u00e9rence n&rsquo;ont aucun int\u00e9r\u00eat r\u00e9el du point de vue du d\u00e9tail et de l&rsquo;\u00e2pret\u00e9 des n\u00e9gociations. Elles n&rsquo;apportent rien \u00e0 la partie am\u00e9ricaniste, m\u00eame elles contribuent \u00e0 la discr\u00e9diter d&rsquo;une certaine fa\u00e7on, &mdash; par la grossi\u00e8ret\u00e9 du proc\u00e9d\u00e9 si l&rsquo;on accepte l&rsquo;argument de la duplicit\u00e9, comme le montre la r\u00e9action du &laquo; <em>Middle Eastern diplomat from one of the countries involved in the talks<\/em> &raquo;. S&rsquo;il y avait hypocrisie, les Am\u00e9ricains auraient d\u00e9j\u00e0 rendu les d\u00e9tenus en grande pompe, avec une d\u00e9claration d&rsquo;intention des deux parties, aussi vague qu&rsquo;inefficace. Cela suffirait pour la d\u00e9fense de la r\u00e9putation des Etats-Unis dans les instances internationales et ailleurs (le seul argument \u00ab\u00a0rationnel\u00a0\u00bb qu&rsquo;on pourrait avancer pour justifier cette affaire).<\/p>\n<\/p>\n<p><p>&bull; L&rsquo;argument d&rsquo;opposer le State department (auquel appartiennent les n\u00e9gociateurs) au Pentagone, la vertu de l&rsquo;un face \u00e0 la brutalit\u00e9 de l&rsquo;autre, n&rsquo;a aucune valeur. Les \u00ab\u00a0traitements inhumains, conditions de torture physique et psychologique, d&rsquo;humiliation, etc.\u00a0\u00bb sont strictement codifi\u00e9s et r\u00e9glement\u00e9s \u00e0 l&rsquo;int\u00e9rieur de l&rsquo;administration et du syst\u00e8me. On ne torture que dans les r\u00e8gles. Tous les d\u00e9partements sont inform\u00e9s de la chose. Tout au plus peut-on parler d&rsquo;une r\u00e9partition des r\u00f4les : le State department est charg\u00e9 plus pr\u00e9cis\u00e9ment de la mission d&rsquo;exigence de vertu chez les autres.<\/p>\n<\/p>\n<p><p>Face aux incertitudes, aux contradictions sans nombre qui rendent l&rsquo;argument de la duplicit\u00e9 extr\u00eamement al\u00e9atoire, et d&rsquo;ailleurs encore plus affaibli par nombre d&rsquo;autres comportements du m\u00eame genre, nous proposons une hypoth\u00e8se psychologique qui a la vertu de la nettet\u00e9. Elle implique qu&rsquo;il existe des \u00ab\u00a0standards\u00a0\u00bb pour d\u00e9finir une psychologie am\u00e9ricaniste collective, que celle-ci se diffuse quasi-organiquement dans les psychologies individuelles gr\u00e2ce \u00e0 un cadre conformiste de fer, \u00e0 une alimentation par une communication qui se r\u00e9f\u00e8re \u00e0 des informations qui sont des artefacts id\u00e9ologiques constants pr\u00e9sent\u00e9s comme des faits supra-historiques objectifs et incontestables. (Il n&rsquo;y a pas dans la m\u00e9moire am\u00e9ricaniste de faits historiques per\u00e7us comme tels, plus ou moins contest\u00e9s, plus ou moins interpr\u00e9t\u00e9s, etc. Il y a des affirmations id\u00e9ologiques pr\u00e9sent\u00e9es comme des faits.)<\/p>\n<\/p>\n<p><p>Une premi\u00e8re hypoth\u00e8se est que l&rsquo;histoire am\u00e9ricaine selon la d\u00e9finition habituelle de \u00ab\u00a0l&rsquo;histoire\u00a0\u00bb n&rsquo;existe pas pour la psychologie am\u00e9ricaniste. C&rsquo;est l&rsquo;id\u00e9ologie am\u00e9ricaniste qui \u00ab\u00a0fait\u00a0\u00bb l&rsquo;histoire de l&rsquo;Am\u00e9rique, &mdash; n\u00e9cessairement une nouvelle sorte d&rsquo;histoire, d\u00e9cisivement diff\u00e9rente de l&rsquo;Histoire g\u00e9n\u00e9rale. Dans ce cas extraordinaire, l&rsquo;id\u00e9ologie n&rsquo;est plus une opinion, un produit de la propagande, une foi, une passion, une maladie, etc., toutes ces choses qui participent \u00e0 un moment ou l&rsquo;autre au d\u00e9veloppement de l&rsquo;Histoire, voire \u00e0 sa modification d\u00e9cisive ; elle <strong>est<\/strong> l&rsquo;Histoire, et une Histoire objectiv\u00e9e par sa vertu m\u00eame ; par cons\u00e9quent, elle <strong>est<\/strong> la psychologie am\u00e9ricaniste. La diffusion collective de cette psychologie am\u00e9ricaniste s&rsquo;attaque n\u00e9cessairement, dans la psychologie individuelle, au m\u00e9canisme qui permet l&rsquo;\u00e9laboration du jugement et nullement \u00e0 l&rsquo;information qui alimente le jugement. Ce processus n&rsquo;impose pas des pr\u00e9-jugements \u00e0 proprement parler mais impose \u00e0 la psychologie individuelle am\u00e9ricanis\u00e9e de former pour elle-m\u00eame des pr\u00e9-jugements qui influenceront d\u00e9cisivement son jugement dans le sens conforme. Il laisse subsister une r\u00e9elle libert\u00e9, m\u00eame si il en d\u00e9finit par avance un cadre qui ressemble comme deux gouttes d&rsquo;eau au plan d&rsquo;une prison mod\u00e8le.<\/p>\n<\/p>\n<p><p>[En <em>a parte<\/em>, on pourra noter une d\u00e9finition bienvenue de la \u00ab\u00a0libert\u00e9\u00a0\u00bb am\u00e9ricaine. Elle date de 1927 et nous change du cat\u00e9chisme horripilant qui nous tient lieu de pens\u00e9e, depuis bien un demi-si\u00e8cle, d\u00e8s que le mot \u00ab\u00a0libert\u00e9\u00a0\u00bb est prof\u00e9r\u00e9 \u00e0 nos oreilles, &mdash; sans rien dire de la combinaison \u00ab\u00a0libert\u00e9 + Am\u00e9rique\u00a0\u00bb qui, elle, nous plonge dans une sorte d&rsquo;extase. Elle vient de l&rsquo;historien Lucien Romier, extraite de son livre <em>Qui sera le Ma&icirc;tre, Europe ou Am\u00e9rique?<\/em>, &mdash; probl\u00e8me d\u00e9j\u00e0 d&rsquo;actualit\u00e9 en 1927 :<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em;\">\n<p><p>&laquo; <em>En attendant, observons bien. La &lsquo;libert\u00e9&rsquo; am\u00e9ricaine, ce n&rsquo;est rien d&rsquo;autre que l&rsquo;ind\u00e9pendance des activit\u00e9s \u00e9conomiques et sociales \u00e0 l&rsquo;\u00e9gard du &lsquo;jeu&rsquo; politique. De l\u00e0 les t\u00e2tonnements, les incoh\u00e9rentes &lsquo;pu\u00e9rilit\u00e9s&rsquo; ou faiblesses de la politique am\u00e9ricaine. De l\u00e0 encore, l&rsquo;invisible attrait que la soci\u00e9t\u00e9 des Etats-Unis exerce sur tout homme qui a souffert des \u00ab\u00a0exc\u00e8s politiques\u00a0\u00bb de l&rsquo;Europe.<\/em> &raquo;]<\/p>\n<\/p>\n<\/blockquote>\n<p><p>Maintenant, le \u00ab\u00a0mat\u00e9riel\u00a0\u00bb transf\u00e9r\u00e9 par ce processus affectant la psychologie. Sa puissance, ce qui fait que la contrainte du m\u00e9canisme est d&rsquo;autant mieux accept\u00e9e, c&rsquo;est que ce mat\u00e9riel est fondamentalement vertueux. Le point central que v\u00e9hicule la psychologie am\u00e9ricaniste, c&rsquo;est donc l'\u00a0\u00bbinculpabilit\u00e9\u00a0\u00bb de l&rsquo;am\u00e9ricanisme, c&rsquo;est-\u00e0-dire l&rsquo;impossibilit\u00e9 absolue que l&rsquo;am\u00e9ricanisme puisse \u00eatre coupable dans le sens d&rsquo;un acte r\u00e9pondant \u00e0 une intention, une appr\u00e9ciation, un jugement mauvais. M\u00eame des actes fonci\u00e8rement mauvais, in\u00e9luctablement mauvais commis au nom de la politique am\u00e9ricaniste sont pr\u00e9sent\u00e9s dans un contexte tactique qui ne concerne en rien le fond de l&rsquo;attitude am\u00e9ricaniste. Ce qu&rsquo;il y a de mauvais dans l&rsquo;acte tactique est port\u00e9 au d\u00e9bit d&rsquo;un partenaire, d&rsquo;une circonstance ou d&rsquo;un hasard.<\/p>\n<\/p>\n<p><p>L&rsquo;essentiel \u00e0 comprendre est qu&rsquo;il ne s&rsquo;agit pas, pour l&rsquo;am\u00e9ricanisme, d&rsquo;\u00e9carter ou de discuter les critiques et les jugements selon lesquels un acte commis par une nation ou une communaut\u00e9 est mauvais, bl\u00e2mable, condamnable, etc. (cela, c&rsquo;est une recherche de relativisation d&rsquo;une accusation historique: toutes les nations et communaut\u00e9s se livrent \u00e0 cet exercice) ; il s&rsquo;agit d&rsquo;affirmer et de r\u00e9affirmer <em>ad nauseam<\/em> que l&rsquo;Am\u00e9rique est bien absolu et justice pure, et ne conna&icirc;t par cons\u00e9quent pas la notion de culpabilit\u00e9. Il s&rsquo;agit d&rsquo;un caract\u00e8re absolu puisqu&rsquo;il s&rsquo;agit d&rsquo;une conformation formatrice d&rsquo;une psychologie. Ce caract\u00e8re conduit \u00e0 interpr\u00e9ter de fa\u00e7on compl\u00e8tement diff\u00e9rente, en noir et blanc, les m\u00eames actes selon qu&rsquo;ils sont accomplis par l&rsquo;Am\u00e9rique ou par quelque chose qui n&rsquo;est pas am\u00e9ricain. Ce caract\u00e8re est un \u00ab\u00a0outil\u00a0\u00bb pour fabriquer le jugement et nullement un moyen pour influencer le jugement.<\/p>\n<\/p>\n<p><p>Dans le cas qui nous occupe (tortures) : les USA pratiquent ces actes de tortures mais l&rsquo;unique responsabilit\u00e9, la culpabilit\u00e9 de cet acte mauvais retombent enti\u00e8rement sur ceux qui les subissent, parce qu&rsquo;ils sont ce qu&rsquo;ils sont (terroristes) et ce qu&rsquo;ils font (actes de terreur). Cette interpr\u00e9tation absolue bas\u00e9e sur l&rsquo;inculpabilit\u00e9 est absolument r\u00e9serv\u00e9e \u00e0 l&rsquo;Am\u00e9rique. Une autre nation ne peut s&rsquo;en pr\u00e9valoir. Les pays qui recevront les \u00ab\u00a0terroristes\u00a0\u00bb tortur\u00e9s par les Am\u00e9ricains sont avertis qu&rsquo;ils devront se comporter avec eux d&rsquo;une fa\u00e7on vertueuse, c&rsquo;est-\u00e0-dire am\u00e9ricaniste, &mdash; en faisant le contraire de ce que font les Am\u00e9ricanistes.<\/p>\n<\/p>\n<p><p>Cette fonction essentielle de la psychologie am\u00e9ricaniste entra&icirc;ne le reste, qui est par ailleurs confort\u00e9 par une orientation religieuse taill\u00e9e sur mesure : le jugement que la force am\u00e9ricaine est n\u00e9cessairement juste et repr\u00e9sente n\u00e9cessairement le droit ; le jugement que l&rsquo;Am\u00e9rique est, de par son inculpabilit\u00e9, invuln\u00e9rable et ne peut \u00eatre vaincue par cons\u00e9quent ; le jugement que l&rsquo;Am\u00e9rique est, compl\u00e8tement par nature (y compris par la g\u00e9ographie) et nullement par ambition, totalement diff\u00e9rente du reste du monde. Ces jugements inh\u00e9rents \u00e0 la psychologie am\u00e9ricaniste entra&icirc;nent les travers fondamentaux du comportement am\u00e9ricaniste : le d\u00e9sarroi profond et sans rem\u00e8de devant l&rsquo;id\u00e9e inconcevable de d\u00e9faite (Viet-n\u00e2m, Irak aujourd&rsquo;hui) ; l&rsquo;incapacit\u00e9 \u00e9galement sans retour de s&rsquo;adapter aux autres et de conduire victorieusement des conqu\u00eates historiques ; l&rsquo;incapacit\u00e9 \u00e9vidente d&rsquo;influencer les autres cultures (l&rsquo;am\u00e9ricanisation n&rsquo;est pas une influence dans le sens historique, comme fut \u00e9videmment influente la culture romaine : c&rsquo;est une tentative de destruction des autres cultures pour y mettre le fait am\u00e9ricaniste \u00e0 la place) ; et ainsi de suite. Les constats viennent naturellement, \u00e0 la lumi\u00e8re de cette hypoth\u00e8se.<\/p>\n<\/p>\n<p><p>Tous ces caract\u00e8res et ces jugements ont \u00e9videmment leur origine dans la formation du pays, qui est un artefact historique et non pas une n\u00e9cessit\u00e9 historique ; qui se r\u00e9f\u00e8re \u00e0 des principes (ceux des Lumi\u00e8res revus \u00ab\u00a0\u00e0 la lumi\u00e8re\u00a0\u00bb particuli\u00e8re de cet artefact) per\u00e7us comme absolument vertueux et eux-m\u00eames marqu\u00e9s, selon l&rsquo;interpr\u00e9tation am\u00e9ricaniste, d&rsquo;un caract\u00e8re d&rsquo;inculpabilit\u00e9. Les circonstances historiques et g\u00e9ographiques (isolationnisme, puissance naturelle, etc.) n&rsquo;ont fait que renforcer, peut-\u00eatre d\u00e9cisivement, ce trait psychologique. La puissance virtualiste nourrie par la communication et par le conformisme (voir le ph\u00e9nom\u00e8ne de <a class=\"gen\" href=\"http:\/\/www.dedefensa.org\/article.php?art_id=887\">Group Think<\/a>) constitue aujourd&rsquo;hui un ciment d&rsquo;une tr\u00e8s grande force et fait penser que l&rsquo;inculpabilit\u00e9 am\u00e9ricaniste ne pourra que se renforcer. Attendre un changement aujourd&rsquo;hui de l&rsquo;Am\u00e9rique, notamment sous des arguments aussi \u00e9cul\u00e9s que la globalisation et le d\u00e9veloppement des communications, est d&rsquo;une niaiserie compl\u00e8te. C&rsquo;est le contraire qui ne cesse de se renforcer.<\/p>\n<\/p>\n<p><p>Il y a, aujourd&rsquo;hui \u00e9galement, \u00e0 cause des \u00e9v\u00e9nements politiques que nous connaissons, des effets contraires tr\u00e8s d\u00e9stabilisants pour le syst\u00e8me am\u00e9ricaniste et une crise de la psychologie qui ne cesse de s&rsquo;aggraver. Il y a, dans la confrontation de la fiction de l&rsquo;inculpabilit\u00e9 avec la r\u00e9alit\u00e9, une tension inconsciente permanente entre l&rsquo;inculpabilit\u00e9 et les accusations qui sont en permanence jet\u00e9es \u00e0 l&rsquo;Am\u00e9rique \u00e0 cause de l&rsquo;anti-am\u00e9ricanisme que suscite sa politique. Il y a enfin, toujours \u00e0 cause des circonstances politiques qui font croire aux am\u00e9ricanistes \u00e0 l&rsquo;opportunit\u00e9 ultime, une allure de \u00ab\u00a0lutte finale\u00a0\u00bb entre la psychologie am\u00e9ricaniste et la r\u00e9alit\u00e9 historique du monde. Nous sommes arriv\u00e9s \u00e0 la phase paroxystique finale. Comme on dit, \u00ab\u00a0\u00e7a passe ou \u00e7a casse\u00a0\u00bb.<\/p>\n<\/p>\n<p><p>Bien entendu, ce trait psychologique n&rsquo;est pas \u00e9galement r\u00e9parti ni, surtout, absolument impos\u00e9 (au contraire de ce qu&rsquo;il pr\u00e9tend \u00eatre du point de vue du jugement qu&rsquo;il avance). La mati\u00e8re humaine r\u00e9siste ou rechigne. Il existe des \u00ab\u00a0dissidents\u00a0\u00bb en Am\u00e9rique ; et l&rsquo;on doit employer ce mot et non pas celui d'\u00a0\u00bbopposants\u00a0\u00bb parce qu&rsquo;il s&rsquo;agit d&rsquo;individus ayant n\u00e9cessairement rompu avec le syst\u00e8me d&rsquo;une mani\u00e8re radicale, par leur psychologie r\u00e9tive qui fait qu&rsquo;ils ont \u00e9chapp\u00e9 \u00e0 la conformation g\u00e9n\u00e9rale. Il est \u00e0 la fois juste et n\u00e9cessaire de nommer ceux qui appartiennent compl\u00e8tement au syst\u00e8me des \u00ab\u00a0Am\u00e9ricanistes\u00a0\u00bb, pour les diff\u00e9rencier des \u00ab\u00a0Am\u00e9ricains\u00a0\u00bb (terme plus g\u00e9n\u00e9ral et historique qui englobe le tout et qui n&rsquo;implique pas d&rsquo;appr\u00e9ciation id\u00e9ologique). Il est \u00e9galement juste et n\u00e9cessaire d&rsquo;observer que tout individu victime de l&rsquo;am\u00e9ricanisme peut, en th\u00e9orie, en sortir s&rsquo;il se r\u00e9volte contre lui. Il ne nous semble pas qu&rsquo;il y ait, \u00e0 cet \u00e9gard, d&#8217;emprisonnement sans retour.<\/p>\n<\/p>\n<p><p>Il ressort de tout ce qui pr\u00e9c\u00e8de que les \u00ab\u00a0Am\u00e9ricains\u00a0\u00bb en g\u00e9n\u00e9ral sont d&rsquo;abord des victimes d&rsquo;un m\u00e9canisme dont la responsabilit\u00e9 reste \u00e0 \u00e9tablir, et qui d\u00e9passe une nationalit\u00e9, une circonstance particuli\u00e8re, pour se fixer sur ce qui s&rsquo;av\u00e8re \u00eatre une force collective qui met en question le concept de la civilisation qu&rsquo;elle pr\u00e9tend \u00eatre. (Ce projet de civilisation n&rsquo;est-il pas l&rsquo;ultime ambition de la barbarie d\u00e9guis\u00e9e? Des textes, venus d&rsquo;auteurs d&rsquo;une qualit\u00e9 assez moyenne mais bien repr\u00e9sentatifs du syst\u00e8me, nous le font penser. Nous faisons pr\u00e9cis\u00e9ment allusion \u00e0 ce texte du colonel Ralph Peters qu&rsquo;on trouve sur ce site, mis en ligne en <a class=\"gen\" href=\"http:\/\/www.dedefensa.org\/article.php?art_id=140\">2002<\/a> et remis en ligne en <a class=\"gen\" href=\"http:\/\/www.dedefensa.org\/article.php?art_id=662\">2003<\/a>, Peters que nous avions rebaptis\u00e9 \u00ab\u00a0le Barbare jubilant\u00a0\u00bb.)<\/p>\n<\/p>\n<p><p>Bien entendu, l&rsquo;hypoth\u00e8se que nous avan\u00e7ons doit continuer \u00e0 \u00eatre explor\u00e9e. Elle contient d&rsquo;immenses questions, dont la principale, qui est au c&oelig;ur de toute appr\u00e9ciation sur la psychologie, est le rapport entre l&rsquo;organique, la mati\u00e8re, et l&rsquo;artefact immat\u00e9riel de la communication, voire l&rsquo;aspect spirituel. Il s&rsquo;agit de la question de savoir si l&rsquo;action g\u00e9n\u00e9rale de ce qui doit \u00eatre identifi\u00e9 comme un syst\u00e8me socio-politique (cette notion d&rsquo;inculpabilit\u00e9), et qui est d&rsquo;essence psychologique finalement, laisse une trace au niveau organique chez les individus. L&rsquo;extraordinaire puissance de la coh\u00e9sion am\u00e9ricaine observ\u00e9e jusqu&rsquo;ici suscite de telles questions. Aujourd&rsquo;hui, cette extraordinaire puissance devient une extraordinaire faiblesse, \u00e0 mesure des revers que conna&icirc;t le syst\u00e8me dans son imprudente confrontation avec le monde et avec l&rsquo;Histoire par cons\u00e9quent. Cela explique que la plus grande chance de \u00ab\u00a0victoire\u00a0\u00bb contre lui est dans l&rsquo;exploitation contre lui-m\u00eame de sa propre action, devenue auto-destructrice.<\/p>\n<\/p>\n<p><p>Nous nous arr\u00eatons l\u00e0 dans l&rsquo;exploration d&rsquo;une hypoth\u00e8se qui demande des volumes pour \u00eatre pouss\u00e9e dans toutes ses implications. Il est \u00e9vident que cette exploration doit \u00eatre poursuivie par tous les moyens.<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&rsquo;\u00a0\u00bbinculpabilit\u00e9\u00a0\u00bb et la psychologie am\u00e9ricaniste 6 mai 2006 &mdash; A premi\u00e8re lecture, ce devrait \u00eatre un d\u00e9luge d&rsquo;\u00e9pith\u00e8tes d&rsquo;une ironie lasse ou furieuse, d&rsquo;\u00e9coeurements divers, de moqueries et ainsi de suite&hellip; Nous pensons qu&rsquo;il faut tenter d&rsquo;aller au-del\u00e0 avec l&rsquo;effort de penser la psychologie am\u00e9ricaniste comme quelque chose de diff\u00e9rent. D&rsquo;abord la nouvelle. La r\u00e9f\u00e9rence&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[3253,3066,3634,4735,3099,4281,610],"class_list":["post-67531","post","type-post","status-publish","format-standard","hentry","category-faits-et-commentaires","tag-americanisme","tag-americaniste","tag-inculpabilite","tag-indefectibilite","tag-psychologie","tag-torture","tag-virtualisme"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/67531","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=67531"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/67531\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=67531"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=67531"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=67531"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}