{"id":67603,"date":"2006-05-29T00:00:00","date_gmt":"2006-05-29T00:00:00","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2006\/05\/29\/le-pentagone-veut-ses-missiles-strategiques-a-tetes-conventionnelles\/"},"modified":"2006-05-29T00:00:00","modified_gmt":"2006-05-29T00:00:00","slug":"le-pentagone-veut-ses-missiles-strategiques-a-tetes-conventionnelles","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2006\/05\/29\/le-pentagone-veut-ses-missiles-strategiques-a-tetes-conventionnelles\/","title":{"rendered":"Le Pentagone veut ses missiles strat\u00e9giques \u00e0 t\u00eates conventionnelles"},"content":{"rendered":"<p><p>Les textes que nous avons mis en ligne le <a href=\"http:\/\/www.dedefensa.org\/article.php?art_id=2745\" class=\"gen\">27 mai<\/a> et le <a href=\"http:\/\/www.dedefensa.org\/article.php?art_id=2749\" class=\"gen\">28 mai<\/a> sur la probl\u00e9matique des missiles strat\u00e9giques \u00e9quip\u00e9s de t\u00eates conventionnelles arrivent \u00e0 temps pour illustrer un d\u00e9bat qui prend forme \u00e0 Washington. Le Pentagone semble avoir d\u00e9cid\u00e9 de pousser l&rsquo;id\u00e9e de fa\u00e7on d\u00e9cisive devant un Congr\u00e8s qui manque notablement d&rsquo;enthousiasme.<\/p>\n<\/p>\n<p><p>\tUn long article sur le sujet para\u00eet dans l&rsquo;un des habituels journaux de r\u00e9f\u00e9rence. Le New York <em>Times<\/em> nous offre <a href=\"http:\/\/www.nytimes.com\/2006\/05\/29\/washington\/29strike.html?th=&#038;emc=th&#038;pagewanted=print\" class=\"gen\">un article<\/a> de son sp\u00e9cialiste Michael R. Gordon. <\/p>\n<\/p>\n<p><p>\tLe texte de Gordon s&rsquo;appuie notamment sur une audition au Congr\u00e8s du g\u00e9n\u00e9ral Cartwright, chef du U.S. Strategic Command. Un passage int\u00e9ressant de l&rsquo;audition est celui o\u00f9 Cartwright explique qu&rsquo;il s&rsquo;est rendu en Russie pour expliquer au chef d&rsquo;\u00e9tat-major g\u00e9n\u00e9ral le nouveau programme, et pourquoi les Russes n&rsquo;ont rien \u00e0 en craindre.<\/p>\n<\/p>\n<p><p>\t\u00ab <em>The Russians, for their part, seem to have little interest in facilitating Congressional approval of a new American weapons system. During his recent trip to Russia, General Cartwright sought to explain the rationale for program to Gen. Yuri Baluyevski, the chief of the Russian General Staff.<\/em> <\/p>\n<\/p>\n<p><p>\t\u00bb <em>The things that I tried to talk to him about were the common issues that we face  the fact that terrorists and organizations are getting capabilities that are significant and are likely to stay on a trend that could be associated with weapons of mass destruction, General Cartwright said.<\/em> <\/p>\n<\/p>\n<p><p>\t\u00bb <em>After that discussion, General Baluyevski continued to stir up opposition to the plan. As our American colleagues often tell us, these missiles could be used to kill bin Laden, he told reporters earlier this month. This could be a costly move which not only won&rsquo;t guarantee his destruction but could provoke an irreversible response from a nuclear-armed state which can&rsquo;t determine what warhead is fitted on the missile.<\/em> \u00bb<\/p>\n<\/p>\n<p><\/p>\n<p><p>\tMis en ligne le 29 mai 2006 \u00e0  17H17<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Les textes que nous avons mis en ligne le 27 mai et le 28 mai sur la probl\u00e9matique des missiles strat\u00e9giques \u00e9quip\u00e9s de t\u00eates conventionnelles arrivent \u00e0 temps pour illustrer un d\u00e9bat qui prend forme \u00e0 Washington. Le Pentagone semble avoir d\u00e9cid\u00e9 de pousser l&rsquo;id\u00e9e de fa\u00e7on d\u00e9cisive devant un Congr\u00e8s qui manque notablement d&rsquo;enthousiasme.&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[2],"tags":[5442,5443,5435,5147,5434,4775],"class_list":["post-67603","post","type-post","status-publish","format-standard","hentry","category-bloc-notes","tag-balouyevski","tag-cartwright","tag-conventionnelles","tag-gordon","tag-tetes","tag-trident"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/67603","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=67603"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/67603\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=67603"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=67603"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=67603"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}