{"id":67609,"date":"2006-05-31T00:00:00","date_gmt":"2006-05-31T00:00:00","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2006\/05\/31\/le-jsf-et-la-partie-immergee-de-liceberg\/"},"modified":"2006-05-31T00:00:00","modified_gmt":"2006-05-31T00:00:00","slug":"le-jsf-et-la-partie-immergee-de-liceberg","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2006\/05\/31\/le-jsf-et-la-partie-immergee-de-liceberg\/","title":{"rendered":"Le JSF et la partie immerg\u00e9e de l&rsquo;iceberg"},"content":{"rendered":"<p><h2 class=\"common-article\">Le JSF et la partie immerg\u00e9e de l&rsquo;iceberg<\/h2>\n<\/p>\n<p><p>\t31 mai 2006  Il est imp\u00e9ratif de s\u00e9parer de plus en plus nettement le cas britannique (UK-USA) des autres cas des coop\u00e9rants non-US dans le programme JSF. D\u00e9sormais, l&rsquo;affaire sp\u00e9cifique USA-UK\/JSF n&rsquo;a plus rien \u00e0 voir avec le reste. Un <a href=\"http:\/\/news.ft.com\/cms\/s\/37668fb0-ef79-11da-b435-0000779e2340.html\" class=\"gen\">texte<\/a> paru dans le <em>Financial Times<\/em> mercredi prend pour pr\u00e9texte la rencontre Blair-Bush et la <a href=\"http:\/\/www.dedefensa.org\/article.php?art_id=2746\" class=\"gen\">d\u00e9claration commune<\/a> sur le JSF qui a \u00e9t\u00e9 faite, pour donner une appr\u00e9ciation g\u00e9n\u00e9rale du probl\u00e8me. Il s&rsquo;agit bien d&rsquo;une crise majeure qui concerne le JSF et, \u00e0 propos du JSF, les relations sp\u00e9ciales USA-UK sur le plan technologique et militaire,  et, \u00e0 notre sens, bien au-del\u00e0 : les relations sp\u00e9ciales USA-UK dans leur totalit\u00e9.<\/p>\n<\/p>\n<p><p>\tLe texte est de Robin Niblett et Pierre Chao, du CSIS de Georgetown University, un <em>think tank<\/em> pas vraiment r\u00e9publicain et plut\u00f4t d\u00e9mocrate mais remarquablement impliqu\u00e9 dans les affaires de coop\u00e9ration transatlantique, et remarquablement inform\u00e9 l\u00e0-dessus. Le texte (que nous donnons <a href=\"http:\/\/www.dedefensa.org\/choix.php?link_id=6573&#038;comm=1\" class=\"gen\">par ailleurs<\/a> au complet pour la facilit\u00e9 de la compr\u00e9hension) nous donne une appr\u00e9ciation en profondeur et extr\u00eamement juste de la situation.<\/p>\n<\/p>\n<p><p>\tL&rsquo;\u00e9tat de la situation, d&rsquo;abord, et, surtout, le constat du blocage actuel et, par cons\u00e9quent, l&rsquo;impossibilit\u00e9 d&rsquo;accepter que cette situation dure si l&rsquo;on veut sauver les relations sp\u00e9ciales.<\/p>\n<\/p>\n<p><p>\t\u00ab <em>However, the JSF is just the tip of a deeper problem. In the past few years, the US has proved unwilling, in spite of repeated British requests, to overhaul the Kafkaesque maze of restrictions that hampers the exchange of defence technology between the two countries. This situation persists in spite of the long history of sharing information in highly sensitive areas such as nuclear deterrence, classified intelligence and joint military operations.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb <em>British representatives, including Mr Blair, have pointed out this glaring discrepancy to their US counterparts, and asked politely whether the US system could be adapted to reflect the close bilateral security relationship. The responses have sounded positive but little has yet happened. Why?<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb <em>In spite of the many military and economic benefits of a more open Anglo-American technology-sharing relationship, the subject is clouded by the US desire to maintain technological superiority over all adversaries. In this context, the UK is seen by some not as the leading US security ally but as a potential source  like any other country  of leaks of sensitive US technologies to third countries or actors. Combined with a US export-control bureaucracy that has no incentive to change the system, a small clique in the US Congress that believes passionately in further tightening rather than easing the US defence export control regime and a US administration with many other problems on its plate, it is easy to see why the US has turned a deaf ear to British requests.<\/em> \u00bb<\/p>\n<\/p>\n<p><p>\tCette situation n&rsquo;est plus tenable, parce qu&rsquo;elle mine politiquement et \u00e0 tr\u00e8s grande vitesse la confiance britannique \u00e0 l&rsquo;\u00e9gard des USA; parce qu&rsquo;elle emp\u00eache une coop\u00e9ration effective USA-UK au niveau militaire Et surtout, du point de vue de la doctrine fondamentale (ceci compl\u00e9tant la premi\u00e8re raison), parce que les Britanniques ont \u00e9volu\u00e9 (ce qui confirme un de nos r\u00e9cents <a href=\"http:\/\/www.dedefensa.org\/article.php?art_id=2575\" class=\"gen\">F&#038;C<\/a>) : \u00ab <em>Third, the new UK defence industrial strategy requires that the UK government possess \u00a0\u00bboperational sovereignty\u00a0\u00bb over its key defence capabilities. Britain now seeks the capacity to manage its principal weapons platforms, regardless of where they are from, without the need to await an export licence. These UK frustrations have come to a head over the JSF. Without progress, some in the UK have even suggested pulling out of the programme altogether.<\/em> \u00bb<\/p>\n<\/p>\n<p><p>\tAlors, que faire? Niblett-Chao notent que la d\u00e9claration Blair-Bush permet de souffler (argument tr\u00e8s sp\u00e9cieux, fa\u00e7on de rendre poliment gr\u00e2ce aux deux dirigeants, rien de plus,  dans tous les cas nous l&rsquo;esp\u00e9rons, ou bien c&rsquo;est que Niblett-Chao sont bien na\u00effs). Mais il reste deux probl\u00e8mes fondamentaux :<\/p>\n<\/p>\n<p><p>\t\u00ab <em>First, there is still no indication of how to finalise the difficult and sensitive details in time for a year-end decision on funding the next stage of the JSF&rsquo;s development. It is worth remembering that the US government abandoned an effort to ease UK access to unclassified defence technologies last year.<\/em> <\/p>\n<\/p>\n<p><p>\t\u00bb <em>More importantly, if the answer is only JSF-specific, the overall problem will persist, as will its corrosive effect on Anglo-US relations.<\/em> \u00bb<\/p>\n<\/p>\n<p><p>\tEnsuite, Niblett-Chao proposent une solution. Il s&rsquo;agit de <em>wihfull thinking<\/em>, rien de plus ; les deux experts entendent terminer sur une note optimiste et tentent \u00e9videmment d&rsquo;imprimer leur marque sur le probl\u00e8me, pour leur propre promotion. L&rsquo;id\u00e9e pr\u00e9sent\u00e9e, qui pr\u00e9tend r\u00e9soudre le probl\u00e8me, est surtout de la sorte qui tiendrait implicitement le probl\u00e8me pour r\u00e9solu puisqu&rsquo;elle suppose que la bureaucratie aurait accept\u00e9 sa d\u00e9faite en acceptant de transf\u00e9rer certaines de ses pr\u00e9rogatives. Rien, absolument rien ne va dans ce sens, tout va dans le sens contraire. Laissons cela.<\/p>\n<\/p>\n<p><p>\tIl suffit de retenir la parfaite d\u00e9monstration de Niblett-Chao : le syst\u00e8me est radicalis\u00e9, au risque de briser l&rsquo;alliance USA-UK,  mais, d&rsquo;ailleurs, le syst\u00e8me s&rsquo;en fout et certains, \u00e0 Washington, sont pr\u00eats \u00e0 faire leur deuil de cette alliance-l\u00e0 au nom de l&rsquo;omnipotence absolue de la puissance am\u00e9ricaine et de la protection imp\u00e9rative de la puissance technologique qui va avec. Le syst\u00e8me est bloqu\u00e9 et il faudra longtemps pour le rouvrir de force, si cela est seulement possible, bien plus que d&rsquo;ici \u00e0 la fin d\u00e9cembre o\u00f9 les Britanniques veulent des garanties pr\u00e9cises avant de signer pour la commande du JSF. (Pour tout cela, une ni\u00e8me relecture du <a href=\"http:\/\/www.dedefensa.org\/article.php?art_id=201\" class=\"gen\">discours<\/a> de Rumsfeld du 10 septembre 2001 est utile, voire n\u00e9cessaire.)<\/p>\n<\/p>\n<p><p>\tCela signifie-t-il que Niblett-Chao pensent en r\u00e9alit\u00e9 que les Britanniques n&rsquo;auront pas ces garanties ? C&rsquo;est bien ce qui semble \u00eatre non-dit mais bien dit. Simplement, ce sont des choses qu&rsquo;on ne dit pas telles quelles.<\/p>\n<h3>Le JSF rattrapera-t-il Suez ?<\/h3>\n<\/p>\n<p><p>\tNous publions \u00e9galement (dans notre rubrique <a href=\"http:\/\/www.dedefensa.org\/choix.php?link_id=6573&#038;comm=1\" class=\"gen\">Nos choix comment\u00e9s<\/a>), avec l&rsquo;article Niblett-Chao, un article de commentaire de Richard North, sur son <em>blog<\/em> <a href=\"http:\/\/eureferendum.blogspot.com\/2006\/05\/enemy-within.html\" class=\"gen\">Eureferendum<\/a>). Richard North, nos lecteurs le connaissent. Ce sympathique commentateur ultra-atlantiste, plus pro-am\u00e9ricaniste qu&rsquo;un am\u00e9ricaniste, est n\u00e9anmoins un fervent nationaliste britannique. (Pourquoi ce n\u00e9anmoins ?)<\/p>\n<\/p>\n<p><p>\tIl n&rsquo;y a aucune raison de suspecter la bonne foi de North. Ses commentaires nous disent toute sa spontan\u00e9it\u00e9, toute sa passion dans la d\u00e9fense de sa cause. Finalement, sa passion anti-UE et anti-Bruxelles, o\u00f9 parfois il n&rsquo;y a pas que des exc\u00e8s, le conduit \u00e0 \u00e9pouser tout le reste.<\/p>\n<\/p>\n<p><p>\tDans les affaires de la coop\u00e9ration transatlantique, il est \u00e0 la droite de l&rsquo;extr\u00eame droite du Pentagone. Dans l&rsquo;affaire du JSF, il tient Blair pour un vendu \u00e0 l&rsquo;Europe, qui est en train d&rsquo;int\u00e9grer l&rsquo;Angleterre, en douce, dans la construction bureaucratico-fasciste bruxelloise, qui trahit ses engagements pro-am\u00e9ricains m\u00eame quand il les honore \u00e0 l&rsquo;exc\u00e8s. C&rsquo;est dire si le texte Niblett-Chao l&rsquo;a fait bondir.<\/p>\n<\/p>\n<p><p>\tTous les reproches des deux comp\u00e8res du CSIS faits \u00e0 l&rsquo;appareil bureaucratique US sont impitoyablement rejet\u00e9s, comme autant de poudre aux yeux pour mieux pousser les Britanniques vers l&rsquo;Europe. Il y a un axe Niblett-Chao-Blair, et c&rsquo;est <em>The enemy within<\/em> qui complote au nom et dans les int\u00e9r\u00eats du monstre europ\u00e9en. Le verdict est sans appel.<\/p>\n<\/p>\n<p><p>\tQuelques extraits de la conclusion du texte de North, pour go\u00fbter l&rsquo;ambiance : \u00ab <em>Any clinical and honest evaluation of the relationship between the US and Britain would, therefore, advise caution. The two countries may be friends, but the US national interest must prevail. As long as the UK is working with a cast of characters which are potentially hostile to US interests, the US would be mad to open its books completely.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb <em>But then, the CSIS has consistently supported the idea of European defence integration and, no doubt, from its lavish Washington office actively lobbies on the Hill and in the State Department in support of the project. Thus, with Nesbitt and Chao arguing for Bush to give the UK what it wants, without addressing the very real and sensible concerns about technology prevalent in the US, the CSIS is essentially playing the European game.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb <em>Certainly, the CSIS is not supporting the US national interest and, by arguing that the UK should have access to US technology despite its attachment to EU defence interests, it is not really assisting the UK, in helping defer the decision between the US and EU which must soon be made  making out that British attachments to the EU and the US are somehow compatible.<\/em> \u00bb<\/p>\n<\/p>\n<p><p>\tTout cela est excessif, dira-t-on, et tout ce qui est excessif  Mais non, au contraire,  voici ce que William Blake a \u00e9crit : \u00ab <em>La route de l&rsquo;exc\u00e8s m\u00e8ne au palais de la sagesse.<\/em> \u00bb Dans le cas de North, pourquoi pas?<\/p>\n<\/p>\n<p><p>\tLes relations sp\u00e9ciales UK-USA sont si compl\u00e8tement tordues, vici\u00e9es, faites de faux-semblants et de trompe-l&rsquo;il que cette analyse si excessive de North n&rsquo;est pas loin de nous dire le presque-vrai. Elle repr\u00e9sente sans aucun doute un sentiment r\u00e9pandu m\u00eame s&rsquo;il n&rsquo;est pas exprim\u00e9 par les cols cravat\u00e9s-chic type Niblett-Chao. Les Britanniques ont laiss\u00e9 tant de perversion s&rsquo;\u00e9tablir dans leurs rapports avec les Am\u00e9ricains depuis un demi-si\u00e8cle (effectivement, pr\u00e9cis\u00e9ment depuis la catastrophe de Suez et le remplacement de Eden par l&rsquo;homme de Washington MacMillan), que le cabrement britannique actuel para\u00eet compl\u00e8tement hors de saison. Il met en cause des pratiques que les Britanniques ont tant accept\u00e9es qu&rsquo;elles paraissaient \u00eatre devenues la nature de leur fa\u00e7on d&rsquo;\u00eatre avec les Am\u00e9ricains. Se cabrer aujourd&rsquo;hui, c&rsquo;est mettre en cause une situation qui \u00e9tait devenue l\u00e9gitime. Les Britanniques se sont tant soumis qu&rsquo;ils se sont soumis aux int\u00e9r\u00eats US comme s&rsquo;il s&rsquo;agissait des leurs. En r\u00e9futant cet unilat\u00e9ralisme pervers et en proclamant leur unilat\u00e9ralisme (leur int\u00e9r\u00eat national, mais aussi leur souverainet\u00e9 nationale), ils mettent tout l&rsquo;\u00e9difice en cause.<\/p>\n<\/p>\n<p><p>\tLe lecteur sait bien que nous comprenons l&rsquo;attitude britannique, qu&rsquo;elle est de notre parti parce qu&rsquo;elle implique la dignit\u00e9 d&rsquo;une nation et sa souverainet\u00e9. Nous disons simplement qu&rsquo;elle n&rsquo;est pas, dans le cas des Britanniques par rapport aux US, une r\u00e9action naturelle qui d\u00e9coule de ce qui a pr\u00e9c\u00e9d\u00e9 mais une r\u00e9volte soudaine qui rompt avec ce qui a pr\u00e9c\u00e9d\u00e9. Bravo pour la r\u00e9volte,  mais c&rsquo;est bien une r\u00e9volution et il faut accepter qu&rsquo;il y ait des cons\u00e9quences \u00e0 mesure, brutales, bouleversantes. Le tableau que tracent Niblett-Chao est juste ; la r\u00e9paration qu&rsquo;ils proposent est une frime de plus, apr\u00e8s mille autres qui n&rsquo;ont jamais \u00e9t\u00e9 appliqu\u00e9es. North, lui, a la juste plaidoirie du Britannique compl\u00e8tement am\u00e9ricanis\u00e9 par haine absolue du continent europ\u00e9en et qui crie : Au feu ! En l&rsquo;occurrence, il n&rsquo;a pas tort.<\/p>\n<\/p>\n<p><p>\tLa situation d\u00e9crite par Niblett-Chao ne se d\u00e9nouera pas pour les beaux yeux de Tony Blair. Le pauvre GW Bush ne compte plus pour grand&rsquo;chose et il a sans doute d\u00e9j\u00e0 oubli\u00e9 ce que JSF signifie. Si les Britanniques tiennent vraiment \u00e0 leur souverainet\u00e9 op\u00e9rationnelle,  et il semble de plus en plus que cela soit le cas,  t\u00f4t ou tard, dans quelques mois ou dans un ou deux ans, ils devront rompre. L&rsquo;exercice pratique du JSF est le champ id\u00e9al de la rupture de cet \u00e9trange lien de vassalit\u00e9.<\/p>\n<\/p>\n<p><p>\tA notre avis et pour la beaut\u00e9 de la chose, les Britanniques devraient choisir d\u00e9cembre pour clore la p\u00e9riode par la rupture. Cela se passerait exactement cinquante ans apr\u00e8s la fin de tout espoir britannique d&rsquo;ind\u00e9pendance nationale, avec le d\u00e9part de Anthony Eden malade pour les Bermudes, apr\u00e8s la d\u00e9b\u00e2cle britannique de Suez, avant son remplacement, pendant ce repos forc\u00e9, par Harold MacMillan. Cela aurait la couleur de l&rsquo;\u00e9v\u00e9nement historique dont il s&rsquo;agirait effectivement.<\/p>\n<\/p>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le JSF et la partie immerg\u00e9e de l&rsquo;iceberg 31 mai 2006 Il est imp\u00e9ratif de s\u00e9parer de plus en plus nettement le cas britannique (UK-USA) des autres cas des coop\u00e9rants non-US dans le programme JSF. D\u00e9sormais, l&rsquo;affaire sp\u00e9cifique USA-UK\/JSF n&rsquo;a plus rien \u00e0 voir avec le reste. Un texte paru dans le Financial Times mercredi&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[4468,3433,4478,250,5369,3825],"class_list":["post-67609","post","type-post","status-publish","format-standard","hentry","category-faits-et-commentaires","tag-chao","tag-csis","tag-ft","tag-jsf","tag-niblett","tag-north"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/67609","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=67609"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/67609\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=67609"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=67609"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=67609"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}