{"id":67648,"date":"2006-06-12T00:00:00","date_gmt":"2006-06-12T00:00:00","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2006\/06\/12\/un-tournant-psychologique\/"},"modified":"2006-06-12T00:00:00","modified_gmt":"2006-06-12T00:00:00","slug":"un-tournant-psychologique","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2006\/06\/12\/un-tournant-psychologique\/","title":{"rendered":"Un tournant psychologique?"},"content":{"rendered":"<p><h2 class=\"common-article\">Un tournant psychologique?<\/h2>\n<\/p>\n<p><p>\t12 juin 2006  Les trois suicides de Guantanamo vont peut-\u00eatre constituer une date importante dans la perception que l&rsquo;on a du ph\u00e9nom\u00e8ne am\u00e9ricaniste. Plus important que la trag\u00e9die des trois suicides, on l&rsquo;a vu \u00e0 <a href=\"http:\/\/www.dedefensa.org\/article.php?art_id=2794\" class=\"gen\">deux reprises<\/a> dans <a href=\"http:\/\/www.dedefensa.org\/article.php?art_id=2796\" class=\"gen\">nos colonnes<\/a>, nous parlons des r\u00e9actions am\u00e9ricanistes qui les accompagnent, les commentent et en donnent la signification pour Washington.<\/p>\n<\/p>\n<p><p>\tQuelques rappels et indications :<\/p>\n<\/p>\n<p><p>\t&bull; D&rsquo;abord, d\u00e9j\u00e0 abondamment cit\u00e9, le commentaire du commandant de la base de Guantanamo, l&rsquo;amiral Harris, parlant des trois suicid\u00e9s : \u00ab <em>They are smart. They are creative, they are committed. They have no regard for life, either ours or their own. I believe this was not an act of desperation, but an act of asymmetrical warfare waged against us.<\/em> \u00bb<\/p>\n<\/p>\n<p><p>\t&bull; Le commentaire fait \u00e0 la BBC de Colleen Graffy, Deputy Assistant Secretary of State for Public Diplomacy. Premier acte, l&rsquo;antienne m\u00e9canique de toute d\u00e9claration officielle lorsqu&rsquo;il s&rsquo;agit des terroristes islamistes et assimil\u00e9s: \u00ab <em>The three men did not value their lives nor the lives of those around them.<\/em> \u00bb Puis l&rsquo;appr\u00e9ciation de la professionnelle (Mme Graffy est une parmi les nombreux sp\u00e9cialistes de la pub et des RP engag\u00e9s dans l&rsquo;administration GW Bush) : les trois suicides constituent \u00ab <em>a good PR move to draw attention. <\/em>[ it was] <em>part of a strategy and a tactic to further the jihadi cause&#8230;<\/em> \u00bb<\/p>\n<\/p>\n<p><p>\t&bull; Toute la presse officielle et asserment\u00e9e US suit la m\u00eame voie. Les suicides sont consid\u00e9r\u00e9s comme des actes de combat et ceux qui l&rsquo;ont commis pas loin d&rsquo;\u00eatre consid\u00e9r\u00e9s comme d\u00e9loyaux et peu respectueux des lois de la guerre (preuve qu&rsquo;ils m\u00e9ritent d&rsquo;\u00eatre enferm\u00e9s \u00e0 Guantanamo comme ils le sont, sans la protection de la l\u00e9gislation internationale sur les prisonniers de guerre). Un article de David S. Cloud et Neil A. Lewis, dans l&rsquo;<a href=\"http:\/\/www.iht.com\/articles\/2006\/06\/12\/america\/web.0612gitmo.php\" class=\"gen\">International Herald Tribune<\/a> d&rsquo;aujourd&rsquo;hui illustre bien ce climat, qui a d\u00e9finitivement \u00e9cart\u00e9 toute r\u00e9flexion politique, morale ou \u00e9thique sur l&rsquo;acte lui-m\u00eame (le suicide),  et m\u00eame, qui se dispense d&rsquo;identifier l&rsquo;acte pour ce qu&rsquo;il est. Tout l&rsquo;article est construit, dans son langage, ses tournures de phrase, pour montrer le personnel du camp engag\u00e9 dans une bataille sans fin avec les d\u00e9tenus en train de comploter. (Les malheureux gardiens qui doivent en plus respecter le r\u00e8glement lorsqu&rsquo;ils humilient, torturent, surveillent les prisonniers avec un coup d&rsquo;il sur eux toutes les 30 secondes, etc. Harassant.) Si l&rsquo;on n&rsquo;\u00e9tait inform\u00e9, on croirait que les d\u00e9tenus complotent leur \u00e9vasion ou leur r\u00e9volte \u00ab <em>Prisoners&rsquo; ruse is inquiry focus at Guant\u00e1namo<\/em> \u00bb, dit le titre. Ou bien, autre exemple, cet extrait, o\u00f9 l&rsquo;on nous d\u00e9crit les tourments des gardiens pour \u00e9quilibrer leur devoir humaniste de doter les prisonniers du maximum de confort sans leur fournir un instrument,  pour quoi faire? Pour pr\u00e9parer leur \u00e9vasion? Pour pr\u00e9parer une agression? Mais non, toujours la m\u00eame chose : pour se suicider. (Pourtant Comment songer \u00e0 se suicider quand l&rsquo;on est entour\u00e9 de tant de pr\u00e9venances?)<\/p>\n<\/p>\n<p><p>\t\u00ab <em>Guards will now collect bed linens every morning to prevent prisoners from secretly making nooses, Lieutenant Commander Durand said. In addition to possibly revoking permission for detainees to do their own laundry, prison officials are looking at withholding toiletries and other items that might be used in suicide attempts, he added.<\/em> <\/p>\n<\/p>\n<p><p>\t\u00bb <em>We&rsquo;ve got to determine and find the balance between the comfort items that we would like to provide and the point at which comfort items in the possession of a few determined detainees will be turned into something that could contribute to taking their lives, <\/em>[G\u00e9n\u00e9ral] <em>Craddock said.<\/em> \u00bb<\/p>\n<\/p>\n<p><p>\t&bull; &#8230;Le m\u00eame g\u00e9n\u00e9ral Craddock, qui ajoute une hypoth\u00e8se concernant le but poursuivi par les suicid\u00e9s: \u00ab <em>General Craddock speculated that the suicides may have been timed to affect the Supreme Court decision on the Hamdan case. This may be an attempt to influence the judicial proceedings in that perspective, he told reporters, according to a transcript of his comments during a brief visit to Guant\u00e1namo on Sunday.<\/em> \u00bb<\/p>\n<\/p>\n<p><p>\tTous ces exemples montrent combien l&rsquo;\u00e9v\u00e9nement du week-end a \u00e9t\u00e9 model\u00e9 selon une vision compl\u00e8tement relative, selon une fiction relevant d&rsquo;une vision virtualiste am\u00e9ricaniste du monde. Le mot suicide n&rsquo;introduit nulle part, dans les comptes-rendus qui nous sont propos\u00e9s, la dimension d&rsquo;absolu et immens\u00e9ment respectable qu&rsquo;implique n\u00e9cessairement la mort. L&rsquo;id\u00e9e semble compl\u00e8tement accept\u00e9e que le suicide est un concept <strong>comme un autre<\/strong>, un acte <strong>tactique<\/strong> dans une strat\u00e9gie g\u00e9n\u00e9rale du monde des vivants, et, dans ce cas, du monde des vivants-m\u00e9chants. Seule diff\u00e8re la d\u00e9finition qu&rsquo;on peut donner de cet acte tactique : une action de la guerre asym\u00e9trique? Une action de relations publiques? (Mais les relations publiques ne sont-elles pas un des moyens importants de la guerre asym\u00e9trique?)<\/p>\n<\/p>\n<p><p>\tPlus encore que l&rsquo;id\u00e9e est accept\u00e9e, nous dirions qu&rsquo;elle est venue d&rsquo;une fa\u00e7on presque simultan\u00e9e \u00e0 partir d&rsquo;un <em>stimulus<\/em> initial (dans ce cas, la d\u00e9claration de l&rsquo;amiral Harris). Il n&rsquo;y a pas eu d\u00e9lib\u00e9ration, ou suggestion. Les psychologies am\u00e9ricanistes r\u00e9agissent d\u00e9sormais d&rsquo;une fa\u00e7on standard, au quart de tour, \u00e0 la fa\u00e7on pavlovienne revue en post-modernisation \u00e0 propos d&rsquo;id\u00e9es aussi essentielles que de transformer un acte absolu en une action tactique. <\/p>\n<h3>De l&rsquo;incr\u00e9dulit\u00e9 \u00e0 la r\u00e9alit\u00e9<\/h3>\n<\/p>\n<p><p>\tLe reste du monde prend-il sur l&rsquo;instant la mesure de cette sorte d&rsquo;\u00e9v\u00e9nement ? Lorsque <a href=\"http:\/\/news.independent.co.uk\/world\/americas\/article799452.ece\" class=\"gen\">The Independent<\/a> publie ce titre : \u00ab <em>Washington condemns first suicides by Guantanamo inmates as a PR exercise<\/em> \u00bb, ou bien il manifeste une ironie au second degr\u00e9 ou bien il se fait le messager, en en \u00e9tant la dupe, d&rsquo;une pens\u00e9e absurde en plus d&rsquo;\u00eatre perverse. Comment peut-on condamner trois suicides accomplis selon l&rsquo;accusation qu&rsquo;ils sont une manoeuvre de relations publiques? Il y a une incompatibilit\u00e9 d\u00e9finitive, dont l&rsquo;ignorance est l&rsquo;effet d&rsquo;une pens\u00e9e schizophr\u00e9nique, dans l&rsquo;identification d&rsquo;un acte absolu et sans retour (la mort) avec un artefact virtualiste (une manoeuvre de relations publiques) qui est par substance,  parler de substance ici est une figure de style et rien d&rsquo;autre,  un simulacre d&rsquo;acte, un simulacre de r\u00e9alit\u00e9 et un simulacre de v\u00e9rit\u00e9. La mort n&rsquo;est pas un simulacre de la mort, ce n&rsquo;est pas une manoeuvre. Il faut un esprit malade pour \u00e9carter cette \u00e9vidence tragique.<\/p>\n<\/p>\n<p><p>\tMais tr\u00eave de j\u00e9r\u00e9miades. Il est vrai que certains organismes et personnalit\u00e9s en Europe ont r\u00e9agi dans un sens qui indique qu&rsquo;on commence \u00e0 percevoir la port\u00e9e de l&rsquo;\u00e9v\u00e9nement. Jean Asselborn, ministre des affaires \u00e9trang\u00e8res du Luxembourg,  ce pays remarquable par sa petitesse et le courage de ses hommes politiques,  Asselborn observe \u00e0 l&rsquo;intention de journalistes, \u00e0 propos de la remarque sur la manuvre de relations publiques :  \u00ab <em>It&rsquo;s hard to understand why when three people kill themselves, that is an attack on America. Something has to change in the American mentality.<\/em> \u00bb. Le <a href=\"http:\/\/www.guardian.co.uk\/guantanamo\/story\/0,,1795374,00.html\" class=\"gen\">Guardian<\/a> publie un \u00e9ditorial o\u00f9 il emploie certains mots bienvenus (notamment l&rsquo;expression de <em>clinical illegality<\/em>, que nous devrons retenir) m\u00eame s&rsquo;il ne va pas au fond des choses.<\/p>\n<\/p>\n<p><p>\t\u00ab <em>The demented logic of Dr Strangelove hung like a ghost this weekend over the US military&rsquo;s response to the suicide of three prisoners at Guant\u00e1namo Bay. Announcing the news, the first successful suicides since detainees began to arrive in 2002, the camp&rsquo;s commander, Rear-Admiral Harry Harris, said the deaths were not an act of desperation but an act of asymmetric warfare committed against us. That cold and odious language lacked the humanity present even in President Bush&rsquo;s expression of serious concern, but is entirely in keeping with the clinical illegality of America&rsquo;s treatment of terror suspects since 2001.<\/em> \u00bb<\/p>\n<\/p>\n<p><p>\tLe silence observ\u00e9 jusqu&rsquo;ici dans le reste du monde occidental devant les manifestations de la psychologie schizophr\u00e9nique am\u00e9ricaniste semble en train de se rompre devant la manifestation aussi crue et unitaire de cette pens\u00e9e. Ce silence \u00e9tait-il, jusqu&rsquo;ici, celui de l&rsquo;incr\u00e9dulit\u00e9 ? (On pourrait \u00e9galement penser au silence de la sottise ou au silence de la l\u00e2chet\u00e9.) Si l&rsquo;on accepte cette hypoth\u00e8se optimiste (l&rsquo;incr\u00e9dulit\u00e9), cette affaire des r\u00e9actions am\u00e9ricanistes aux trois suicides de Guantanamo devient un pas important, par les r\u00e9actions qu&rsquo;elles provoquent, pour nous faire avancer des r\u00e9actions d&rsquo;incr\u00e9dulit\u00e9 vers l&rsquo;acceptation de la terrifiante r\u00e9alit\u00e9 de la psychologie am\u00e9ricaniste. En tout \u00e9tat de cause, il est \u00e9crit qu&rsquo;il faudra bien que le reste du monde occidental accepte d&rsquo;\u00eatre confront\u00e9 avec cette r\u00e9alit\u00e9 am\u00e9ricaniste parce que cette r\u00e9alit\u00e9 pathologique nous conduira n\u00e9cessairement aux situations les plus folles et les plus graves.<\/p>\n<\/p>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un tournant psychologique? 12 juin 2006 Les trois suicides de Guantanamo vont peut-\u00eatre constituer une date importante dans la perception que l&rsquo;on a du ph\u00e9nom\u00e8ne am\u00e9ricaniste. Plus important que la trag\u00e9die des trois suicides, on l&rsquo;a vu \u00e0 deux reprises dans nos colonnes, nous parlons des r\u00e9actions am\u00e9ricanistes qui les accompagnent, les commentent et en&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[5495,3243,3634,3099,5491],"class_list":["post-67648","post","type-post","status-publish","format-standard","hentry","category-faits-et-commentaires","tag-graffy","tag-guantanamo","tag-inculpabilite","tag-psychologie","tag-suicide"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/67648","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=67648"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/67648\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=67648"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=67648"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=67648"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}