{"id":67651,"date":"2006-06-13T00:00:00","date_gmt":"2006-06-13T00:00:00","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2006\/06\/13\/le-times-lecon-britannique-de-journalisme-objectif\/"},"modified":"2006-06-13T00:00:00","modified_gmt":"2006-06-13T00:00:00","slug":"le-times-lecon-britannique-de-journalisme-objectif","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2006\/06\/13\/le-times-lecon-britannique-de-journalisme-objectif\/","title":{"rendered":"Le <em>Times<\/em>, le\u00e7on britannique de journalisme objectif"},"content":{"rendered":"<p><p>Dans l&rsquo;entrefilet que le <em>Times<\/em> de Londres publie <a href=\"http:\/\/www.timesonline.co.uk\/newspaper\/0,,171-2222439,00.html\" class=\"gen\">aujourd&rsquo;hui<\/a> sur la situation ukrainienne, il attribue le retrait humiliant de l&rsquo;avant-garde de Marines US qui s&rsquo;\u00e9tait install\u00e9e en Crim\u00e9e pour pr\u00e9parer un exercice commun OTAN-Ukraine aux causes et circonstances suivantes :<\/p>\n<\/p>\n<p><p>\t\u00ab <em>Their departure was seen as a victory for Russia as it plots to undermine President Yushchenko and his plans to lead Ukraine into Nato and the European Union.<\/em> <\/p>\n<\/p>\n<p><p>\t\u00bb <em>The reservists arrived on May 27 with material and equipment to build showers and lavatories at a Ukrainian military training facility near Feodosiya. But pro-Russian protesters stopped them from reaching the facility, accusing Mr Yushchenko of inviting Nato to set up a base without parliament&rsquo;s approval.<\/em> \u00bb<\/p>\n<\/p>\n<p><p>\tAlors pourquoi pas certaines pr\u00e9cisions, bien dans le style du grand journalisme objectif anglo-saxon, des pr\u00e9cisions un peu plus pr\u00e9cises que <em>Russia&rsquo;s plot<\/em> et <em>pro-Russian protesters<\/em>? Par exemple :<\/p>\n<\/p>\n<p><p>\t&bull; Le fait que le Parlement de Crim\u00e9e, suivi du conseil municipal de Simf\u00e9ropol, a interdit la pr\u00e9sence de troupes \u00e9trang\u00e8res (i.e. : de l&rsquo;OTAN) sur le sol de la r\u00e9publique autonome. (Voir ce <a href=\"http:\/\/fr.rian.ru\/world\/20060607\/49180066.html\" class=\"gen\">texte<\/a> de Novosti du 7 juin : \u00ab <em>Le conseil municipal de Simf\u00e9ropol, capitale de la r\u00e9publique autonome de Crim\u00e9e, a approuv\u00e9 la d\u00e9cision du Conseil supr\u00eame (parlement) local de proclamer la presqu&rsquo;\u00eele territoire interdit \u00e0 l&rsquo;OTAN. Les d\u00e9put\u00e9s de Simf\u00e9ropol ont approuv\u00e9 la d\u00e9cision du Conseil supr\u00eame de Crim\u00e9e de proclamer la presqu&rsquo;\u00eele territoire interdit \u00e0 l&rsquo;OTAN, et exig\u00e9, \u00e0 l&rsquo;instar de leurs coll\u00e8gues de Crim\u00e9e, d&rsquo;interdire le stationnement de forces arm\u00e9es \u00e9trang\u00e8res dans la r\u00e9publique autonome, a annonc\u00e9 le service de presse du conseil municipal.<\/em> \u00bb) Ces d\u00e9cisions \u00e9minemment d\u00e9mocratiques sont d&rsquo;ailleurs une le\u00e7on de souverainet\u00e9 nationale donn\u00e9e par la r\u00e9publique autonome de Crim\u00e9e \u00e0 la grande d\u00e9mocratie de l&rsquo;Ukraine (et au Royaume-Uni, non?), qui s&rsquo;inspire d&rsquo;une d\u00e9marche gaullienne assez reconnue d&rsquo;utilit\u00e9 publique. <\/p>\n<\/p>\n<p><p>\t&bull; Quant au sentiment g\u00e9n\u00e9ral sur l&rsquo;OTAN en Ukraine, il est para\u00eet-il r\u00e9sum\u00e9 par un adjoint du ministre des affaires \u00e9trang\u00e8res ukrainien de cette fa\u00e7on (<a href=\"http:\/\/en.rian.ru\/world\/20060606\/49132341.html\" class=\"gen\">Novosti<\/a> du 6 juin) : \u00ab <em>But First Deputy Foreign Minister Anton Buteiko dismissed suggestions that anti-NATO sentiments were widespread in the country, saying that only political parties that failed to leave any mark in the March 26 parliamentary elections were fermenting opposition. I can see no opposition to Ukraine&rsquo;s joining NATO.<\/em> \u00bb Plus loin, la m\u00eame d\u00e9p\u00eache pr\u00e9cise:<\/p>\n<\/p>\n<p><p>\t\u00ab <em>Buteiko said the current situation in Ukraine was similar to that in the Baltic States, where 30% of people had supported NATO accession bids before the countries joined the alliance in 2004. Stressing that NATO&rsquo;s accession requirements did not include provisions on holding a referendum on the issue, he said the Ukrainian parliament&rsquo;s ratification of a protocol to the Membership Action Plan, approved at the 1999 Washington Summit, would be enough.<\/em> \u00bb<\/p>\n<\/p>\n<p><p>\t&bull; Tout cela ressemble \u00e0 une superbe le\u00e7on de d\u00e9mocratie (reste \u00e0 voir de qui pour qui? Dans quel sens ? Et ainsi de suite.) Reportons-nous, pour confirmation de la ligne d\u00e9mocratique suivie par les dirigeants ukrainiens, \u00e0 des pr\u00e9cisions datant du mois de mars, lorsqu&rsquo;on se trouvait en pleine campagne \u00e9lectorale. On parle d&rsquo;une d\u00e9p\u00eache de Novosti du <a href=\"http:\/\/fr.rian.ru\/world\/20060322\/44680896.html\" class=\"gen\">22 mars<\/a>, qui nous disait ceci : \u00ab <em>La majorit\u00e9 des Ukrainiens se disent contre l&rsquo;adh\u00e9sion de leur pays \u00e0 l&rsquo;OTAN mais pour l&rsquo;adh\u00e9sion \u00e0 l&rsquo;Union europ\u00e9enne, selon un sondage r\u00e9alis\u00e9 par la Fondation pour la libert\u00e9 ukrainienne. Seulement 14,8% des interrog\u00e9s sont favorables \u00e0 l&rsquo;int\u00e9gration au sein de l&rsquo;Alliance atlantique, contre 63,8% d&rsquo;avis n\u00e9gatifs. Par ailleurs, 42,9% des Ukrainiens voteraient en faveur de l&rsquo;adh\u00e9sion \u00e0 l&rsquo;Union europ\u00e9enne, et 28,3% voteraient contre.<\/em> \u00bb Auparavant, <a href=\"http:\/\/fr.rian.ru\/world\/20060309\/44098949.html\" class=\"gen\">le 9 mars<\/a>, le pr\u00e9sident Iouchtchenko, en campagne orange, nous avait assur\u00e9, parlant de la question d&rsquo;un r\u00e9f\u00e9rendum national en Ukraine pour l&rsquo;entr\u00e9e dans l&rsquo;OTAN : \u00ab <em>Tout le monde sait que sans un r\u00e9f\u00e9rendum personne n&rsquo;acceptera d&rsquo;entrer dans l&rsquo;OTAN, ni dans l&rsquo;Union europ\u00e9enne, ni dans n&rsquo;importe quelle autre institution internationale o\u00f9 l&rsquo;adh\u00e9sion n\u00e9cessite l&rsquo;approbation de la population.<\/em> \u00bb<\/p>\n<\/p>\n<p><p>\tPar cons\u00e9quent, le <em>Times<\/em> de Londres a judicieusement et fort objectivement choisi de s&rsquo;int\u00e9resser \u00e0 l&rsquo;essentiel pour d\u00e9crire objectivement et fort judicieusement la situation ukrainienne : <em>Russia&rsquo;s plot<\/em> et <em>pro-Russian protesters<\/em>, plut\u00f4t que ces assommantes pr\u00e9cisions chiffr\u00e9es et d\u00e9clarations officielles et officiellement pr\u00e9cises.<\/p>\n<\/p>\n<p><\/p>\n<p><p>\tMis en ligne le 13 juin 2006 \u00e0 17H41<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dans l&rsquo;entrefilet que le Times de Londres publie aujourd&rsquo;hui sur la situation ukrainienne, il attribue le retrait humiliant de l&rsquo;avant-garde de Marines US qui s&rsquo;\u00e9tait install\u00e9e en Crim\u00e9e pour pr\u00e9parer un exercice commun OTAN-Ukraine aux causes et circonstances suivantes : \u00ab Their departure was seen as a victory for Russia as it plots to undermine&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[2],"tags":[2684,5498,584,1225,2852,1296],"class_list":["post-67651","post","type-post","status-publish","format-standard","hentry","category-bloc-notes","tag-crimee","tag-iouchtchenko","tag-otan","tag-referendum","tag-times","tag-ukraine"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/67651","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=67651"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/67651\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=67651"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=67651"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=67651"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}