{"id":67670,"date":"2006-06-21T00:00:00","date_gmt":"2006-06-21T00:00:00","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2006\/06\/21\/lencercleur-encercle-fable-postmoderniste\/"},"modified":"2006-06-21T00:00:00","modified_gmt":"2006-06-21T00:00:00","slug":"lencercleur-encercle-fable-postmoderniste","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2006\/06\/21\/lencercleur-encercle-fable-postmoderniste\/","title":{"rendered":"<strong><em>L&rsquo;\u201cencercleur\u201d encercl\u00e9, \u2014 fable postmoderniste<\/em><\/strong>"},"content":{"rendered":"<p><h2 class=\"common-article\">L&rsquo;encercleur encercl\u00e9,  fable postmoderniste<\/h2>\n<\/p>\n<p><\/p>\n<p><p>\t21 juin 2006  Comme l&rsquo;\u00e9crit un lecteur commentant le texte (<em>Guardian<\/em> du <a href=\" http:\/\/www.guardian.co.uk\/iran\/story\/0,,1801570,00.html\" class=\"gen\">20 juin<\/a>) de Simon Tisdall sur la position internationale de l&rsquo;Iran : <\/p>\n<\/p>\n<p><p>\t\u00ab <em>George Bush is right when he says that Iran is getting isolated in the world because for him, and others like him, the world means the US and its two most obedient poodles  UK and Israel.<\/em> \u00bb<\/p>\n<\/p>\n<p><p>\tL&rsquo;autisme am\u00e9ricaniste,  qui touche parfois l&rsquo;Europe et parfois met l&rsquo;Europe au d\u00e9sespoir c&rsquo;est selon,  est plus que jamais actif et efficace. Les derniers b\u00e9n\u00e9ficiaires de cette \u00e9trange attitude : l&rsquo;Iran et son pr\u00e9sident Ahmadinejad. Apr\u00e8s avoir d\u00e9taill\u00e9 le succ\u00e8s de Ahmadinejad \u00e0 Shangha\u00ef, lors du <a href=\"http:\/\/www.dedefensa.org\/article.php?art_id=2810\" class=\"gen\">sommet<\/a> du Pacte de Shangha\u00ef, Tisdall \u00e9crit :<\/p>\n<\/p>\n<p><p>\t\u00ab <em>Iran&rsquo;s diplomatic fightback is taking place on other fronts across the Arab and Islamic spheres. Iran is coming into its own, said Seyed Muhammad Adeli, Iran&rsquo;s former ambassador to Britain and the head of Econotrend, a respected independent thinktank in Tehran. Iran&rsquo;s regional profile has never been higher in modern times. Our neighbours are ever more convinced that Iran is being unfairly treated by the Americans.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb <em>To drive home the point, Tehran is actively building closer links with Azerbaijan, Kazakhstan, Tajikistan and other central Asian countries. Mr Ahmadinejad is planning a Tehran summit of Caspian Sea littoral states to discuss how to stop foreign intervention in the area. Iran also recently wooed a Washington favourite, the Afghan president, Hamid Karzai, in Tehran, and is busily mending fences with Pakistan.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb <em>It has won the support of the Non-Aligned Movement and the Arab League for its nuclear stance. Its envoys have recently visited Iraq, Syria, Saudi Arabia and some north African states. It has reportedly become the biggest single state contributor of funds to Palestine in the wake of the west&rsquo;s ostracism of the Hamas government.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb <em>And in a groundbreaking move earlier this month, Ali Larijani, Iran&rsquo;s chief nuclear negotiator and the second most influential government figure after Mr Ahmadinejad, met Egypt&rsquo;s president, Hosni Mubarak, in Cairo. It was the highest-level contact between the two countries since the 1979 Iranian revolution. Mr Ahmadinejad&rsquo;s outspoken hostility to Israel has won him a big following in the Arab world, Tehran officials say. And that is something Egypt, its notional leader, cannot entirely ignore.<\/em> \u00bb<\/p>\n<\/p>\n<p><p>\tNotez bien ceci : les 3UE (Allemagne, France, UK) n\u00e9gocient avec l&rsquo;Iran depuis l&rsquo;automne 2003. Les choses allaient cahin-caha, mais sans trop provoquer d&rsquo;effets, notamment dans le statut international de chacun des pays concern\u00e9s. Puis l&rsquo;Am\u00e9rique, ayant estim\u00e9 l&rsquo;affaire irakienne r\u00e9gl\u00e9e, est entr\u00e9e dans le jeu, et l&rsquo;on sait comment.<\/p>\n<\/p>\n<p><p>\tEn quelques mois, depuis que l&rsquo;Am\u00e9rique s&rsquo;occupe s\u00e9rieusement de l&rsquo;Iran, ce pays a \u00e9t\u00e9 catapult\u00e9 \u00e0 un niveau tr\u00e8s proche de celui de la puissance \u00e9tablie. \u00c9trange cerise sur le g\u00e2teau, Ahmadinejad lui-m\u00eame profite de la chose, au point o\u00f9 l&rsquo;on se demande s&rsquo;il n&rsquo;a pas secr\u00e8tement engag\u00e9 GW comme conseiller en communication (texte d&rsquo;apr\u00e8s <em>The Guardian<\/em> du <a href=\"http:\/\/www.guardian.co.uk\/iran\/story\/0,,1802280,00.html\" class=\"gen\">21 juin<\/a>): <\/p>\n<\/p>\n<p><p>\t\u00ab <em>The popularity of Iran&rsquo;s controversial leader, Mahmoud Ahmadinejad, is surging almost a year after he unexpectedly won a closely contested presidential election, Iranian officials and western diplomats said yesterday.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb <em>Attributing his success to his populist style and fortnightly meet-the-people tours of the country, the sources said that as matters stood, Mr Ahmadinejad was the clear favourite to win a second term in 2009. The perception that the president was standing up to the US on the nuclear issue was also boosting his standing.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb <em>He&rsquo;s more popular now than a year ago. He&rsquo;s on the rise, said Nasser Hadian-Jazy, a professor of political science at Tehran University. I guess he has a 70% approval rating right now. He portrays himself as a simple man doing an honest job. He&rsquo;s comfortable communicating with ordinary people.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb <em>While there are no reliable national opinion polls in Iran, western diplomats acknowledged that support for Mr Ahmadinejad is growing, defying predictions after last June&rsquo;s election that he would not last more than three months.<\/em> \u00bb<\/p>\n<h3>Autopsie de l&rsquo;anti-politique am\u00e9ricaniste<\/h3>\n<\/p>\n<p><p>\tBravo pour l&rsquo;Iran, dira-t-on si l&rsquo;on veut compter les points,  mais sans nul doute, l&rsquo;essentiel est bien la politique am\u00e9ricaniste et ses effets.<\/p>\n<\/p>\n<p><p>\tD&rsquo;une fa\u00e7on g\u00e9n\u00e9rale (pour l&rsquo;Iran et pour le reste), la politique de l&rsquo;administration GW a soulev\u00e9 ces derni\u00e8res ann\u00e9es col\u00e8re, frustration, d\u00e9sespoir, vindicte, incompr\u00e9hension, etc. Aujourd&rsquo;hui, elle prend une place diff\u00e9rente. Elle devient l&rsquo;objet d&rsquo;une attention presque scientifique, presque attendrie et dans tous les cas tr\u00e8s curieuse, comme devant un \u00e9chantillon rarissime : comment peut-on \u00eatre si parfaitement aveugle, si absolument maladroit, si compl\u00e8tement insensible au r\u00e9el ? Il y a quelque part un secret, comme une pierre philosophale de l&rsquo;anti-politique, de l&rsquo;art tr\u00e8s \u00e9trange de gaspiller tr\u00e8s vite et pour nul profit un capital d&rsquo;influence et de puissance constitu\u00e9 sur une fascination et sur un magist\u00e8re moral (usurp\u00e9 certes mais qu&rsquo;importe du moment que les autres y succombent) sans \u00e9quivalent dans l&rsquo;histoire.<\/p>\n<\/p>\n<p><p>\t(Tout cela valant, cela va sans dire, sauf pour les Europ\u00e9ens qui continuent \u00e0 succomber \u00e0 l&rsquo;influence et \u00e0 la fascination jusqu&rsquo;\u00e0 la naus\u00e9e.)<\/p>\n<\/p>\n<p><p>\tLe sch\u00e9ma est extr\u00eamement r\u00e9v\u00e9lateur. Lors de la p\u00e9riode de n\u00e9gociations avec les seuls 3UE rappel\u00e9s plus haut, l&rsquo;Iran a figur\u00e9 pour ce qu&rsquo;il \u00e9tait (qu&rsquo;on estime juste ou pas son statut). Il s&rsquo;agissait de n\u00e9gociations diplomatiques et le sujet (la question du nucl\u00e9aire) en \u00e9tait effectivement le sujet principal,  cette lapalissade est n\u00e9cessaire pour ce qui va suivre. L&rsquo;intrusion des Am\u00e9ricains a tout chang\u00e9 dans la perception qu&rsquo;ont les autres de la crise. Le sujet (la question du nucl\u00e9aire) n&rsquo;en a plus \u00e9t\u00e9 le sujet principal. On est pass\u00e9 \u00e0 la mise en cause du r\u00e9gime, voire, par radicalisation quasi-automatique, \u00e0 la mise au cause du d\u00e9sir de l&rsquo;Iran en tant que nation d&rsquo;affirmer sa puissance dans le concert r\u00e9gional et mondial. (D&rsquo;ailleurs, il n&rsquo;y a pas de concert, il y a juste un soliste.)<\/p>\n<\/p>\n<p><p>\tCette attaque a \u00e9t\u00e9 mont\u00e9e d&rsquo;une fa\u00e7on \u00e0 la fois syst\u00e9mique et m\u00e9canique, on dirait : en auto-pilote. Les <em>neocons<\/em> poussent leurs beuglements habituels, toujours les m\u00eames. Les slogans sont les m\u00eames, qui servent sans m\u00eame la n\u00e9cessit\u00e9 d&rsquo;un recyclage (une lettre \u00e0 changer : le k de Irak devient le n de Iran). La machine tourne, comme d&rsquo;habitude. Les mises en cause sont les m\u00eames, extr\u00eames, sans r\u00e9mission, apocalyptiques, etc. C&rsquo;est toujours la m\u00eame philosophie qui guide l&rsquo;attaque : la n\u00e9gation de l&rsquo;autre, d&rsquo;autant plus ais\u00e9ment qu&rsquo;on est autiste, aveugle et sourd, et tout le reste. Du coup, na\u00eet la question de l&rsquo;identit\u00e9 et de la souverainet\u00e9 nationales, chez l&rsquo;attaqu\u00e9.<\/p>\n<\/p>\n<p><p>\tCe fut aussit\u00f4t le cas avec l&rsquo;Iran. Le sujet principal (la question du nucl\u00e9aire) qui avait \u00e9t\u00e9 marginalis\u00e9 est redevenu le sujet principal, mais enrichi si l&rsquo;on peut dire, magnifi\u00e9 de la dimension de la souverainet\u00e9 et de l&rsquo;identit\u00e9. La bombe ce n&rsquo;est pas que la bombe, c&rsquo;est aussi l&rsquo;identit\u00e9 et la souverainet\u00e9 nationales. Qui r\u00e9sisterait \u00e0 un tel argument,  d&rsquo;autant plus qu&rsquo;il est fond\u00e9, qu&rsquo;il est juste et qu&rsquo;il est bel et bon? (\u00ab <em>Dans les ann\u00e9es soixante, <\/em>explique un diplomate fran\u00e7ais dubitatif, <em>de Gaulle avait refus\u00e9 de signer le trait\u00e9 de non-prolif\u00e9ration parce qu&rsquo;il le jugeait discriminatoire, injuste et in\u00e9gal. On peut dire qu&rsquo;il n&rsquo;avait pas vraiment tort<\/em> \u00bb)<\/p>\n<\/p>\n<p><p>\t\u00c9tonnante manuvre am\u00e9ricaniste car, vraiment, Ahmadinejad n&rsquo;a eu qu&rsquo;\u00e0 cueillir les fruits qui s&rsquo;offraient \u00e0 lui. Aujourd&rsquo;hui, il n&rsquo;a m\u00eame plus besoin de faire son la\u00efus, il est automatiquement per\u00e7u comme le d\u00e9fenseur en g\u00e9n\u00e9ral de la nation et de l&rsquo;identit\u00e9 iraniennes,  et, au-del\u00e0, du principe m\u00eame de la souverainet\u00e9 et de l&rsquo;exigence de l&rsquo;identit\u00e9. (Ah oui : en Occident, on nomme cela : \u00eatre populiste. C&rsquo;est habile.)<\/p>\n<\/p>\n<p><p>\tCette b\u00eatise-l\u00e0, la n\u00f4tre, avec celle du chef am\u00e9ricaniste au-dessus de tout, en position de leader comme toujours, reconnaissons-lui qu&rsquo;elle a de l&rsquo;allure. Elle \u00e9crase tout sur son passage, elle ne fait pas les choses \u00e0 moiti\u00e9. M\u00eame le bon vieux Moubarak, le corrompu jusqu&rsquo;\u00e0 l&rsquo;os, se croit oblig\u00e9 de f\u00e9liciter Ahmadinejad.<\/p>\n<\/p>\n<p><p>\tVahid Karimin de l&rsquo;Institut des \u00c9tudes Politiques et Internationales, un institut officiel \u00e0 T\u00e9h\u00e9ran, explique non sans satisfaction : \u00ab <em>Shanghai was a big success. All our neighbours support our <\/em>[nuclear] <em>policy, even Mubarak. We are successful in building up relations. That is why the American position is changing &#8230; They thought we were encircled because of Iraq and Afghanistan. But we&rsquo;re not&#8230;<\/em> \u00bb<\/p>\n<\/p>\n<p><p>\tPeut-\u00eatre quelqu&rsquo;un ira-t-il expliquer un jour \u00e0 GW que ce sont l&rsquo;Afghanistan et l&rsquo;Irak qui sont encercl\u00e9s, notamment par l&rsquo;Iran. C&rsquo;est alors que John Bolton hurlera que la meilleure d\u00e9fense c&rsquo;est l&rsquo;attaque et qu&rsquo;il faut taper sur T\u00e9h\u00e9ran. Manoeuvre r\u00e9ussie. (P.S. : On d\u00e9cidera alors de rentrer chez soi et de se replier sur <em>fortress America<\/em>, dos \u00e0 ce reste du monde qui n&rsquo;entend d\u00e9cid\u00e9ment rien.)<\/p>\n<\/p>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&rsquo;encercleur encercl\u00e9, fable postmoderniste 21 juin 2006 Comme l&rsquo;\u00e9crit un lecteur commentant le texte (Guardian du 20 juin) de Simon Tisdall sur la position internationale de l&rsquo;Iran : \u00ab George Bush is right when he says that Iran is getting isolated in the world because for him, and others like him, the world means the&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[5105,5514,5515,3198,2773],"class_list":["post-67670","post","type-post","status-publish","format-standard","hentry","category-faits-et-commentaires","tag-ahmadinejad","tag-autiste","tag-encercle","tag-gw","tag-iran"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/67670","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=67670"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/67670\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=67670"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=67670"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=67670"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}