{"id":67689,"date":"2006-06-26T00:00:00","date_gmt":"2006-06-26T00:00:00","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2006\/06\/26\/la-patte-lourde-de-gordon-brown\/"},"modified":"2006-06-26T00:00:00","modified_gmt":"2006-06-26T00:00:00","slug":"la-patte-lourde-de-gordon-brown","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2006\/06\/26\/la-patte-lourde-de-gordon-brown\/","title":{"rendered":"La patte (lourde) de Gordon Brown"},"content":{"rendered":"<p><p>A la r\u00e9union COREPER de l&rsquo;EU vendredi, qui r\u00e9unissait les ambassadeurs des pays-membres de l&rsquo;UE, les Britanniques ont affirm\u00e9 une nette remise en cause des concessions de Tony Blair faites en d\u00e9cembre dernier sur le ch\u00e8que britannique. Blair avait admis une r\u00e9duction de la r\u00e9duction budg\u00e9taire dont b\u00e9n\u00e9ficie le Royaume-Uni.<\/p>\n<\/p>\n<p><p>\tC&rsquo;est sur instruction directe de Gordon Brown, le Chancelier de l&rsquo;\u00c9chiquier, que l&rsquo;ambassadeur britannique a remis en cause les concessions de d\u00e9cembre 2005, \u00ab <em>d&rsquo;une fa\u00e7on assez brutale, \u00e0 l&rsquo;image de Brown lui-m\u00eame<\/em> \u00bb, selon une source europ\u00e9enne. En cette mati\u00e8re, Brown semble agir sans m\u00eame consulter Blair, en virtuel nouveau Premier ministre.<\/p>\n<\/p>\n<p><p>\tLes r\u00e9actions ont \u00e9t\u00e9 unanimes et tr\u00e8s critiques. Les plus v\u00e9h\u00e9mentes ont \u00e9t\u00e9 celles des pays d&rsquo;Europe de l&rsquo;Est, la Pologne en premier lieu, qui devrait subir les cons\u00e9quences de la d\u00e9cision britannique. Les Fran\u00e7ais ont r\u00e9agi d&rsquo;une fa\u00e7on assez mod\u00e9r\u00e9e, qui a surpris certains.<\/p>\n<\/p>\n<p><\/p>\n<p><p>\tMis en ligne le 26 juin 2006 \u00e0 15H08<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A la r\u00e9union COREPER de l&rsquo;EU vendredi, qui r\u00e9unissait les ambassadeurs des pays-membres de l&rsquo;UE, les Britanniques ont affirm\u00e9 une nette remise en cause des concessions de Tony Blair faites en d\u00e9cembre dernier sur le ch\u00e8que britannique. Blair avait admis une r\u00e9duction de la r\u00e9duction budg\u00e9taire dont b\u00e9n\u00e9ficie le Royaume-Uni. C&rsquo;est sur instruction directe de&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[2],"tags":[4038,4874,5546],"class_list":["post-67689","post","type-post","status-publish","format-standard","hentry","category-bloc-notes","tag-brown","tag-cheque","tag-coreper"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/67689","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=67689"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/67689\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=67689"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=67689"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=67689"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}