{"id":67732,"date":"2006-07-10T00:00:00","date_gmt":"2006-07-10T00:00:00","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2006\/07\/10\/mexico-en-floride\/"},"modified":"2006-07-10T00:00:00","modified_gmt":"2006-07-10T00:00:00","slug":"mexico-en-floride","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2006\/07\/10\/mexico-en-floride\/","title":{"rendered":"Mexico-en-Floride?"},"content":{"rendered":"<p><p>Les commentateurs,  en g\u00e9n\u00e9ral membres de la MSM locale et internationale, et observateurs attentifs \u00e0 la bonne sant\u00e9 des march\u00e9s boursiers,  sont dubitatifs, un peu condescendants mais secr\u00e8tement incertains. Pour eux, les chances d&rsquo;Obrador d&rsquo;obtenir gain de cause aupr\u00e8s de la Cour f\u00e9d\u00e9rale mexicaine sont minces, tr\u00e8s minces. Ce jugement ressemble \u00e9galement \u00e0 un souhait, qui n&rsquo;est pas exempt d&rsquo;une certaine inqui\u00e9tude qu&rsquo;il ne soit pas rencontr\u00e9.<\/p>\n<\/p>\n<p><p>\tIl s&rsquo;agit de la contestation de l&rsquo;\u00e9lection, qu&rsquo;Obrador a officiellement annonc\u00e9e au cours d&rsquo;une manifestation, le 8 juillet, \u00e0 Mexico. Il a appel\u00e9 ses partisans \u00e0 une marche sur Mexico, qui commencera mercredi pour s&rsquo;achever par une grande manifestation \u00e0 Mexico le 16 juillet.<\/p>\n<\/p>\n<p><p>\tLa manifestation du 8 juillet \u00e0 Mexico a \u00e9t\u00e9 diversement comment\u00e9e, avec des estimations tr\u00e8s variables. La presse \u00e9trang\u00e8re a diversement r\u00e9agi, avec le cas du Washington <em>Post<\/em> attentif \u00e0 <a href=\"http:\/\/www.washingtonpost.com\/wp-dyn\/content\/article\/2006\/07\/08\/AR2006070801010_pf.html\" class=\"gen\">suivre<\/a> l&rsquo;\u00e9v\u00e9nement d&rsquo;une fa\u00e7on pr\u00e9cise et document\u00e9e. Le <em>Post<\/em> annonce notamment des chiffres d\u00e9taill\u00e9s pour cette manifestation (\u00ab <em>On Saturday, <\/em>[Obrador] <em>gave a mega-display of street power, drawing an estimated 280,000 people into the city center on a humid, drizzly afternoon, according to a Mexico City government estimate.<\/em> \u00bb). Par contre, un journal comme le <a href=\"http:\/\/www.telegraph.co.uk\/news\/main.jhtml?xml=\/news\/2006\/07\/10\/wmex10.xml&#038;sSheet=\/news\/2006\/07\/10\/ixnews.html\" class=\"gen\">Daily Telegraph<\/a>, qui minimise la manifestation de samedi, s&rsquo;en tient \u00e0 une r\u00e9serve qui semble refl\u00e9ter le souhait que son indiff\u00e9rence annonce effectivement le sort de cette contestation : <\/p>\n<\/p>\n<p><p>\t\u00ab <em>The fiery Left-winger made the claim at a rally of more than 100,000 supporters in the main square of the capital.<\/em> [&#8230;]<\/p>\n<\/p>\n<p><p>\t\u00bb <em>The Left-winger claimed, without offering evidence, that Mr Calderon&rsquo;s National Action Party had fiddled the ballot. Mr Lopez Obrador&rsquo;s appeal to the federal electoral court is regarded by most experts as having little chance of success. But his intransigence and calls for more mass demonstrations are sure to intensify the climate of uncertainty as the nation&rsquo;s financial markets reopen today.<\/em> \u00bb<\/p>\n<\/p>\n<p><p>\tL&rsquo;impression g\u00e9n\u00e9rale subsiste, selon laquelle le Mexique est dans une situation explosive, que la contestation d&rsquo;Obrador et l&rsquo;activisme de ses partisans pourraient effectivement faire basculer. Les partisans de Calderon, tout comme les milieux financiers et industriels qui le soutiennent, esp\u00e8rent essentiellement que leur tactique d&rsquo;apaisement et de minimisation des irr\u00e9gularit\u00e9s \u00e9touffera dans l&rsquo;uf, par manque d&rsquo;effet d&rsquo;entra\u00eenement, la contestation d&rsquo;Obrador. <\/p>\n<\/p>\n<p><\/p>\n<p><p>\tMis en ligne le 10 juillet 2006 \u00e0 08H24<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Les commentateurs, en g\u00e9n\u00e9ral membres de la MSM locale et internationale, et observateurs attentifs \u00e0 la bonne sant\u00e9 des march\u00e9s boursiers, sont dubitatifs, un peu condescendants mais secr\u00e8tement incertains. Pour eux, les chances d&rsquo;Obrador d&rsquo;obtenir gain de cause aupr\u00e8s de la Cour f\u00e9d\u00e9rale mexicaine sont minces, tr\u00e8s minces. Ce jugement ressemble \u00e9galement \u00e0 un souhait,&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[2],"tags":[5561,5592,5593,5591,4604,4134],"class_list":["post-67732","post","type-post","status-publish","format-standard","hentry","category-bloc-notes","tag-calderon","tag-contestation","tag-election","tag-mexico","tag-obrador","tag-presidentielle"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/67732","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=67732"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/67732\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=67732"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=67732"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=67732"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}