{"id":67734,"date":"2006-07-10T00:00:00","date_gmt":"2006-07-10T00:00:00","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2006\/07\/10\/ou-est-la-crise-si-ce-nest-dans-notre-pauvre-tete-malade\/"},"modified":"2006-07-10T00:00:00","modified_gmt":"2006-07-10T00:00:00","slug":"ou-est-la-crise-si-ce-nest-dans-notre-pauvre-tete-malade","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2006\/07\/10\/ou-est-la-crise-si-ce-nest-dans-notre-pauvre-tete-malade\/","title":{"rendered":"<strong><em>O\u00f9 est la crise si ce n&rsquo;est dans notre pauvre t\u00eate malade?<\/em><\/strong>"},"content":{"rendered":"<p><h2 class=\"common-article\">O\u00f9 est la crise si ce n&rsquo;est dans notre pauvre t\u00eate malade?<\/h2>\n<\/p>\n<p><\/p>\n<p><p>\t10 juillet 2006  Avec les abracadabrantesques Europ\u00e9ens dans la roue des washingtoniens en bons porteurs d&rsquo;eau qu&rsquo;ils sont, la folie occidentalo-am\u00e9ricaniste se poursuit. Chaque jour montre notre acharnement \u00e0 construire des crises l\u00e0 o\u00f9 il n&rsquo;y en a pas, \u00e0 abandonner une crise que nous avons fabriqu\u00e9e pour une autre que nous nous empressons de fabriquer, \u00e0 comprendre les crises que nous avons fabriqu\u00e9es selon nos seules obsessions alors qu&rsquo;elles concernent d&rsquo;autres gens que nous-m\u00eames, tout cela appuy\u00e9 sur des fabrications virtualistes lunatiques comme la guerre contre la terreur et sur des conceptions diplomatico-militaires d\u00e9labr\u00e9es qui cumulent aveuglement et obsolescence.<\/p>\n<\/p>\n<p><p>\tExemple : la crise de Cor\u00e9e du Nord. Quelle crise, exactement? Est-ce une vraie crise g\u00e9opolitique ou une crise de plus de nos trouilles s\u00e9curitaires \u00e9rig\u00e9es en philosophie de vie et en sens de la civilisation? R\u00e9ponses des int\u00e9ress\u00e9s.<\/p>\n<\/p>\n<p><p>\tLa Cor\u00e9e du Sud r\u00e9agit vivement. Contre qui? Contre le Japon, rien de moins. Cela confirme l&rsquo;analyse du journaliste Donald Kirk qui juge que la crise va tr\u00e8s rapidement regrouper plusieurs nations d&rsquo;Asie continentale contre les tendances n\u00e9o-militaristes du Japon. Lecture \u00e9difiante (par <a href=\"http:\/\/news.yahoo.com\/s\/afp\/20060709\/wl_asia_afp\/nkoreamissileskoreajapan_060709094910\" class=\"gen\">AFP<\/a>, du 9 juillet), pour une fois qu&rsquo;un communiqu\u00e9 officiel (de la pr\u00e9sidence sud-cor\u00e9enne) a une signification (On notera l&rsquo;accusation \u00e0 peine voil\u00e9e qui devrait contribuer \u00e0 nous faire r\u00e9fl\u00e9chir [nous soulignons ce qui nous para\u00eet essentiel dans la phrase] : \u00ab <em>The possible launch of a Daepodong missile had been widely publicized<\/em> <strong><em>in advance<\/em><\/strong> \u00bb ; si ce n&rsquo;est accuser le Japon et les USA d&rsquo;avoir fabriqu\u00e9 la crise)<\/p>\n<\/p>\n<p><p>\t\u00ab <em>South Korea has called for a calm response to North Korea&rsquo;s missile tests, accusing Japan of heightening tensions through its hawkish remarks. There is no reason to fuss over this from the break of dawn like Japan, but every reason to do the opposite, said a statement from the office of President Roh Moo-Hyun&rsquo;s spokesman. There is nothing good in heightening tensions on the Korean peninsula and worsening inter-Korean relations. This will not help at all to settle the nuclear issue or the missile issue, it said Sunday.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb <em>It is the president&rsquo;s view not to raise a shrill voice but to respond calmly, it said. The possible launch of a Daepodong missile had been widely publicized in advance. It was aimed at nobody and did not lead to a state of emergency in either our country or other countries.<\/em> \u00bb<\/p>\n<\/p>\n<p><p>\tLe pr\u00e9sident sud-cor\u00e9en est-il un imposteur qui prive ses citoyens d&rsquo;une juste trouille? Voici ce que nous disent les Sud-Cor\u00e9ens. Ils sont bien tranquilles, confirme le <a href=\"http:\/\/fairuse.100webcustomers.com\/fairenough\/latimes251.html\" class=\"gen\">Los Angeles Times<\/a>, dans tous les cas pour ce qui concerne les entreprises de Kim. Mais si l&rsquo;on tient absolument \u00e0 ce qu&rsquo;ils craignent quelque chose ce serait le Japon et, \u00e9ventuellement, les USA M\u00e9ditez les remarques de cette m\u00e9nag\u00e8re comme vous et moi, madame Kwong, qui d\u00e9clare simplement qu&rsquo;en cas de guerre men\u00e9e par les USA et le Japon contre la Cor\u00e9e du Nord, \u00ab <em>nous serons bien entendu du c\u00f4t\u00e9 des Cor\u00e9ens du Nord<\/em> \u00bb Nos strat\u00e8ges en s\u00e9minaire mesurent-ils le poids d&rsquo;\u00e9vidence de ce bien entendu? Mesurent-ils l&rsquo;aventure que serait une riposte arm\u00e9e contre Kim?<\/p>\n<\/p>\n<p><p>\t\u00ab <em>The same old story! groaned Bae Min-su, a 41-year-old restaurateur who had woken up early on July 5 to watch the match. The same collective shrug was expressed by millions of other South Koreans. Though the United States and Japan quickly elevated the missile launches to the status of crisis, for South Korea it was just another predictable annoyance among many from a bothersome neighbor. None of the television stations here broke away from the soccer match. The first full reports on the missile launches weren&rsquo;t broadcast until nearly 6 a.m., during a break in the game.<\/em> <\/p>\n<\/p>\n<p><p>\t\u00bb <em>On the surface, it would seem that South Koreans should be more attuned to the developments in North Korea than anyone else. They are the ones who live in the shadow of the demilitarized zone, where North Korea has enough artillery dug into bunkers to rain 25,000 shells on Seoul in an hour.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb <em>Bae&rsquo;s in-laws fled the communists during the Korean War, and many customers at the family&rsquo;s restaurant, specializing in Pyongyang-style cold noodles, have relatives in North Korea. You&rsquo;d be surprised, but nobody is really talking about North Korea and the missiles, Bae said. They don&rsquo;t care. They&rsquo;re more worried about Japan than North Korea.<\/em> <\/p>\n<\/p>\n<p><p>\t\u00bb <em>In fact, the big concern in recent days has been a war of words with Japan over a South Korean ship that conducted an oceanic survey of a disputed cluster of rocks known here as Dokdo, off the east coast. And the big summer blockbuster film here is expected to be Hanbando&rsquo; (Korean Peninsula&rsquo;), opening next weekend. Its futuristic plot pits the two Koreas against Japanese forces who are trying to stop their reunification.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb <em>At Bae&rsquo;s restaurant, customer Kwon Jeong-eon said that North Korea&rsquo;s missile tests would help the two Koreas defend themselves. I&rsquo;d like to see the North Koreans become stronger, especially for when we are united, said Kwon, a homemaker in her 40s who had just polished off a bowl of the slippery buckwheat noodles known as nengmyeon. In the event of a war between North Korea and the United States or Japan, she said, we would of course be on the same side as the North Koreans.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb <em>Among student groups, the views were more extreme. North Korea&rsquo;s missiles are the last fortress of peace to deter a U.S. invasion. We should celebrate, a group called the Citizens Movement for the Withdrawal of U.S. Forces in Korea proclaimed on its website.<\/em> \u00bb<\/p>\n<h3>Kim le clown? Ou Kim notre miroir?<\/h3>\n<\/p>\n<p><p>\tSignalons \u00e9galement, pour poursuivre la discussion, un article vitup\u00e9rant de l&rsquo;analyste Edward N. Luttwak, pour nous entretenir du \u00ab <em> North Korea&rsquo;s clown provocateur<\/em> \u00bb (dans le <a href=\"http:\/\/fairuse.100webcustomers.com\/fairenough\/latimes247.html\" class=\"gen\">Los Angeles Times<\/a>, le 7 juillet). Quelques paragraphes bien sentis pour ridiculiser Kim le clown et ses p\u00e9toires qui ne tiennent pas plus de 42 secondes (ou dix minutes, selon la presse sud-cor\u00e9enne). (Luttwak est un analyste \u00f4 combien respect\u00e9 \u00e0 Washington, un dur de dur de la dialectique pentagonesque, qui fait profession d&rsquo;originalit\u00e9, voire d&rsquo;ind\u00e9pendance d&rsquo;esprit. Voire)<\/p>\n<\/p>\n<p><p>\tQui est le plus ridicule dans cette occurrence apr\u00e8s tant d&rsquo;autres? Qui est le clown provocateur (voir l&rsquo;allusion de la pr\u00e9sidence sud-cor\u00e9enne) de l&rsquo;autre quand l&rsquo;on se tourne vers les Sud-Cor\u00e9ens? Ces remarques du Los Angeles <em>Times<\/em> nous disent tout de notre <strong>autisme<\/strong> occidental, inspir\u00e9 par la schizophr\u00e9nie de Washington : \u00ab <em>On the surface, it would seem that South Koreans should be more attuned to the developments in North Korea than anyone else. They are the ones who live in the shadow of the demilitarized zone, where North Korea has enough artillery dug into bunkers to rain 25,000 shells on Seoul in an hour.<\/em> \u00bb<\/p>\n<\/p>\n<p><p>\tPlut\u00f4t que laisser entendre que l&rsquo;indiff\u00e9rence des Sud-Cor\u00e9ens aux horribles gesticulations de Kim rel\u00e8ve de l&rsquo;inconscience, voire pire (complicit\u00e9 ? trahison ?), ne pourrions-nous pas essayer la conclusion de l&rsquo;\u00e9vidence que c&rsquo;est parce que ces d\u00e9veloppements ne sont pas si horribles que cela? Est-ce parce que les fous du Pentagone ont plusieurs milliers d&rsquo;armes nucl\u00e9aires \u00e0 leur disposition que nous craignons qu&rsquo;ils nous les lancent sur la figure? Est-ce que nous entrons en transes similaires \u00e0 celles du d\u00e9but juillet chaque fois que l&rsquo;USAF tire un <em>Minuteman<\/em> III pour raison de test ? (Quoique A y penser, peut-\u00eatre devrions-nous commencer \u00e0 nous inqui\u00e9ter,  nous voulons dire, avec de plus fortes raisons que dans le cas de Kim.)<\/p>\n<\/p>\n<p><p>\tLa projection syst\u00e9matique de nos obsessions et de nos servilit\u00e9s explique aujourd&rsquo;hui l&rsquo;essentiel des crises du monde. Elle cr\u00e9e leur substance m\u00eame. L&rsquo;obsession du faux-empire washingtonien, qui renvoie \u00e0 la <strong>bonne conscience<\/strong> am\u00e9ricaniste n\u00e9cessaire \u00e0 l&rsquo;auto-absolution de son comportement, est une machine \u00e0 fabriquer les menaces et les crises. L&rsquo;obsession europ\u00e9enne de l&rsquo;alignement sur Washington est une machine \u00e0 fabriquer le conformisme de nos diplomaties de vieilles nations civilis\u00e9es, donnant ainsi <em>quitus<\/em> aux divagations washingtoniennes. L&rsquo;Occident est emport\u00e9 dans un prodigieux exercice d&rsquo;ab\u00eatissement comme s&rsquo;il s&rsquo;agissait d&rsquo;une ultime ivresse. (Le fait est que nous sommes dou\u00e9s.)<\/p>\n<\/p>\n<p><p>\tO\u00f9 voit-on qu&rsquo;il y a l\u00e0-dedans une place quelconque pour la <strong>r\u00e9alit\u00e9<\/strong> de la situation cor\u00e9enne? L&#8217;empire occidental sur le monde n&rsquo;est \u00e9tabli aujourd&rsquo;hui que pour tenter de soigner la pathologie n\u00e9e de la confrontation entre nos utopies et la r\u00e9alit\u00e9 du monde. Tout, depuis 9\/11, doit s&rsquo;analyser selon cette vision m\u00e9dicale. (Avant 9\/11, l&rsquo;illusion pouvait encore faire ; 9\/11 s&rsquo;est av\u00e9r\u00e9 un choc suffisant pour achever le d\u00e9s\u00e9quilibre d&rsquo;une psychologie am\u00e9ricaniste d\u00e9j\u00e0 d\u00e9vor\u00e9e par la maladie.) Toutes les crises du monde sont aujourd&rsquo;hui le produit direct de notre esprit malade. Bien \u00e9videmment, cette pression \u00e9pouvantable engendre des effets qui, eux, sont bien r\u00e9els. Le terrorisme, l&rsquo;Irak, l&rsquo;Iran, la Cor\u00e9e, tout cela a \u00e9t\u00e9 fabriqu\u00e9 par l&rsquo;Occident.<\/p>\n<\/p>\n<p><p>\tRevenons \u00e0 notre antienne : \u00e0 quelque chose malheur est bon. Ce gigantesque mouvement de d\u00e9stabilisation et de d\u00e9structuration qui n&rsquo;a comme but concevable que le n\u00e9ant entropique pr\u00e9cipite les situations potentielles d&rsquo;une r\u00e9alit\u00e9 lib\u00e9r\u00e9e par cette brutalit\u00e9. (Est-ce cela, la destruction cr\u00e9atrice?) La crise actuelle acc\u00e9l\u00e8re en r\u00e9alit\u00e9 le processus de r\u00e9unification des deux Cor\u00e9es, elle accro\u00eet les pouss\u00e9es de d\u00e9sengagements des USA de Cor\u00e9e du Sud et multiplie d&rsquo;autant la confusion \u00e0 Washington, elle met \u00e0 jour les ambitions militaristes d&rsquo;une classe dirigeante japonaise qui s&rsquo;av\u00e8re autant un clone des conceptions du Pentagone que l&rsquo;est la direction isra\u00e9lienne. Il est \u00e9vident que la situation pathologique actuelle \u00e9chappe \u00e0 toute gu\u00e9rison et que la seule chose \u00e0 souhaiter est une acc\u00e9l\u00e9ration de cette maladie engendrant l&rsquo;acc\u00e9l\u00e9ration du d\u00e9s\u00e9quilibre du malade. L&rsquo;important est de faire place nette pour laisser le petit enfant du conte nous crier enfin : le roi est nu. La chose est en bonne voie.<\/p>\n<\/p>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O\u00f9 est la crise si ce n&rsquo;est dans notre pauvre t\u00eate malade? 10 juillet 2006 Avec les abracadabrantesques Europ\u00e9ens dans la roue des washingtoniens en bons porteurs d&rsquo;eau qu&rsquo;ils sont, la folie occidentalo-am\u00e9ricaniste se poursuit. Chaque jour montre notre acharnement \u00e0 construire des crises l\u00e0 o\u00f9 il n&rsquo;y en a pas, \u00e0 abandonner une crise&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[3299,3228,2651,4409,4280,3194,3099,3300,610],"class_list":["post-67734","post","type-post","status-publish","format-standard","hentry","category-faits-et-commentaires","tag-coree","tag-crise","tag-du","tag-luttwak","tag-pathologie","tag-pentagone","tag-psychologie","tag-sud","tag-virtualisme"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/67734","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=67734"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/67734\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=67734"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=67734"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=67734"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}