{"id":67736,"date":"2006-07-11T00:00:00","date_gmt":"2006-07-11T00:00:00","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2006\/07\/11\/le-prix-des-avions-de-combat-occidentaux-a-la-lumiere-de-la-realite-ou-le-roi-est-nu\/"},"modified":"2006-07-11T00:00:00","modified_gmt":"2006-07-11T00:00:00","slug":"le-prix-des-avions-de-combat-occidentaux-a-la-lumiere-de-la-realite-ou-le-roi-est-nu","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2006\/07\/11\/le-prix-des-avions-de-combat-occidentaux-a-la-lumiere-de-la-realite-ou-le-roi-est-nu\/","title":{"rendered":"Le prix des avions de combat occidentaux \u00e0 la lumi\u00e8re de la r\u00e9alit\u00e9, \u2014 ou \u201cle roi est nu\u201d"},"content":{"rendered":"<p><p>Une analyse des prix <strong>r\u00e9els<\/strong> des avions de combat occidentaux, voil\u00e0 une r\u00e9elle surprise. C&rsquo;est le site <a href=\"http:\/\/www.defense-aerospace.com\/cgi-bin\/client\/modele.pl?session=dae.21750931.1152599042.RLNEAsOa9dUAAEOx2zM&#038;modele=jdc_34\" class=\"gen\">defense-aerospace.com<\/a> qui met en ligne cette <a href=\"http:\/\/www.defense-aerospace.com\/dae\/articles\/communiques\/FighterCostFinalJuly06.pdf\" class=\"gen\">\u00e9tude<\/a> (\u00ab <em>Sticker Shock: Estimating the Real Cost of Modern Fighter Aircraft<\/em> \u00bb), le 7 juillet.<\/p>\n<\/p>\n<p><p>\tCette \u00e9tude est et sera consid\u00e9r\u00e9e avec int\u00e9r\u00eat ou inqui\u00e9tude, c&rsquo;est selon, dans les milieux industriels occidentaux. La cause en est simple. Laissant de c\u00f4t\u00e9 les sp\u00e9culations th\u00e9oriques et les arguments de propagande virtualiste des groupes de communication (essentiellement anglo-saxons) qui constituent l&rsquo;essentiel des appr\u00e9ciations actuelles sur les avions de combat et leurs co\u00fbts, l&rsquo;\u00e9tude prend en compte les r\u00e9alit\u00e9s budg\u00e9taires, accessibles \u00e0 tous et v\u00e9rifiables par tous, pour calculer les prix <strong>r\u00e9els<\/strong> des avions de combat occidentaux. Cette incursion de la r\u00e9alit\u00e9 dans un univers enti\u00e8rement conditionn\u00e9 par la communication orient\u00e9e et le virtualisme est r\u00e9volutionnaire. C&rsquo;est une sorte d&rsquo;op\u00e9ration le roi est nu.<\/p>\n<\/p>\n<p><p>\tLes r\u00e9sultats ne sont \u00e9tonnants que pour ceux qui suivent les politiques de communication anglo-saxonnes comme s&rsquo;il s&rsquo;agissait de la r\u00e9alit\u00e9. L&rsquo;avion fran\u00e7ais <em>Rafale<\/em> s&rsquo;impose ais\u00e9ment comme le moins co\u00fbteux avec le JAS 39 <em>Gripen<\/em> (l&rsquo;avantage de l&rsquo;avion fran\u00e7ais \u00e9tant d\u00e9multipli\u00e9 par ses capacit\u00e9s et sa puissance tr\u00e8s sup\u00e9rieures \u00e0 celles de l&rsquo;avion su\u00e9dois),  $62,1 et $68,9 millions respectivement pour le <em>Rafale<\/em> et le <em>Gripen<\/em>. Le reste se situe dans une autre cat\u00e9gorie de prix, on dirait la cat\u00e9gorie anglo-saxonne et assimil\u00e9e : des $78,4 millions du F\/A-18E aux $177 millions du F-22 (avec en interm\u00e9diaire : $108,2 millions pour le F-15E, $115 millions pour le JSF et $118,2 millions pour l&rsquo;Eurofighter <em>Typhoon<\/em>).<\/p>\n<\/p>\n<p><p>\tL&rsquo;\u00e9tude est et devrait \u00eatre largement diffus\u00e9e, quoique, r\u00e9p\u00e9tons-le, sans publicit\u00e9 excessive,  on dirait : sous le manteau, comme un document extraordinaire se r\u00e9f\u00e9rant \u00e0 la r\u00e9alit\u00e9 et nullement \u00e0 la propagande virtualiste. La presse sp\u00e9cialis\u00e9e et MSM anglo-saxonne est et restera discr\u00e8te sur le cas, parce que la <strong>r\u00e9alit\u00e9<\/strong> dans ce domaine s\u00e8me la confusion dans son argumentation habituelle.<\/p>\n<\/p>\n<p><p>\tUne observation, d&rsquo;ores et d\u00e9j\u00e0. Il est r\u00e9v\u00e9lateur que le seul constructeur qui ait refus\u00e9 de donner le moindre commentaire sur les prix de ses avions soit, dans les pays occidentaux, le seul v\u00e9ritable rival \u00e0 long terme du fran\u00e7ais Dassault avec son <em>Rafale<\/em>. Il s&rsquo;agit bien s\u00fbr de l&rsquo;am\u00e9ricain Lockheed Martin, dont on conna\u00eet les ambitions globalisantes. Cette discr\u00e9tion rencontre particuli\u00e8rement la situation du JSF, dont on sait qu&rsquo;elle a commenc\u00e9 \u00e0 \u00eatre d\u00e9licate et ne cessera plus de l&rsquo;\u00eatre, et dont on n&rsquo;ignore pas qu&rsquo;elle a d\u00e9sormais un terrible adversaire : la <strong>r\u00e9alit\u00e9<\/strong>, bien s\u00fbr.<\/p>\n<\/p>\n<p><p>\tNous reviendrons sur cette \u00e9tude qui appelle des commentaires qui peuvent s&rsquo;av\u00e9rer int\u00e9ressants. Elle offre notamment une lumi\u00e8re inattendue et bienvenue sur la r\u00e9alit\u00e9 (encore elle) des processus soi-disant \u00e9conomiques, sur la r\u00e9alit\u00e9 (toujours elle) des processus et des paralysies bureaucratiques, toutes ces choses qui conditionnent la conception et la production des avions de combat aujourd&rsquo;hui.<\/p>\n<\/p>\n<p><\/p>\n<p><p>\tMis en ligne le 11 juillet 2006 \u00e0 08H40<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Une analyse des prix r\u00e9els des avions de combat occidentaux, voil\u00e0 une r\u00e9elle surprise. C&rsquo;est le site defense-aerospace.com qui met en ligne cette \u00e9tude (\u00ab Sticker Shock: Estimating the Real Cost of Modern Fighter Aircraft \u00bb), le 7 juillet. Cette \u00e9tude est et sera consid\u00e9r\u00e9e avec int\u00e9r\u00eat ou inqui\u00e9tude, c&rsquo;est selon, dans les milieux industriels&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[2],"tags":[3734,5596,3735,3767,2631,3302,3713,249,250,3219,3129,610],"class_list":["post-67736","post","type-post","status-publish","format-standard","hentry","category-bloc-notes","tag-avions","tag-brigandi","tag-combat","tag-cout","tag-de","tag-f-15","tag-f-18","tag-f-22","tag-jsf","tag-rafale","tag-typhoon","tag-virtualisme"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/67736","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=67736"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/67736\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=67736"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=67736"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=67736"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}