{"id":67762,"date":"2006-07-18T00:00:00","date_gmt":"2006-07-18T00:00:00","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2006\/07\/18\/poutine-sans-forcer\/"},"modified":"2006-07-18T00:00:00","modified_gmt":"2006-07-18T00:00:00","slug":"poutine-sans-forcer","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2006\/07\/18\/poutine-sans-forcer\/","title":{"rendered":"<strong><em>Poutine, sans forcer<\/em><\/strong>"},"content":{"rendered":"<p><h2 class=\"common-article\">Poutine, sans forcer<\/h2>\n<\/p>\n<p><\/p>\n<p><p>\t18 juillet 2006  Le sommet de Saint-Petersbourg du G8 eut cette vertu de nous donner une image incontestable de justesse de la situation du monde. Les Occidentaux (Japon compris), les riches de l&rsquo;ex-G7, s&rsquo;y montr\u00e8rent tels qu&rsquo;ils sont aujourd&rsquo;hui : d\u00e9sunis, sans coh\u00e9sion ni direction (direction hi\u00e9rarchique et orientation politique, sans imagination, chacun avec ses propres pr\u00e9occupations, sa propre crise,  et les Am\u00e9ricains n&rsquo;\u00e9tant pas les moindres \u00e0 tous ces \u00e9gards). Face \u00e0 eux, Poutine se montra \u00e0 l&rsquo;image de la nouvelle Russie qu&rsquo;il a beaucoup contribu\u00e9 \u00e0 r\u00e9tablir : s\u00fbr de lui-m\u00eame et de sa nouvelle puissance reconnue, ind\u00e9pendant, avec des lignes politiques fermes.<\/p>\n<\/p>\n<p><p>\tC&rsquo;est donc le succ\u00e8s de Poutine qui constitue l&rsquo;\u00e9v\u00e9nement de la chose. <\/p>\n<\/p>\n<p><p>\tNikolas Gvosdev, ce Russe am\u00e9ricanis\u00e9 et devenu \u00e9diteur de <em>The National Interest<\/em>, une prestigieuse revue de l&rsquo;<em>establishment<\/em> washingtonien, a bien pr\u00e9sent\u00e9 cet \u00e9v\u00e9nement. Son texte, dans l&rsquo;International <em>Herald Tribune<\/em> de ce jour, m\u00e9rite une ample citation.<\/p>\n<\/p>\n<p><p>\t\u00ab <em>For many Russians, the lack of concrete results was less important than the image of a vigorous Putin defending Russian national interests and promoting Russia&rsquo;s vision of how global affairs should be structured. A cartoon by the St. Petersburg filmmaker Ivan Sidelnikov, broadcast over the weekend, shows Putin adroitly walking a tightrope strung over the summit meeting room, using oil pipelines to retain his balance while fending off challenges by faceless figures (meant to represent the other G-8 leaders) who try to use human rights, energy security or territorial claims to dislodge him.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb <em>Russian commentators are nearly unanimous in their assessment that the summit marked Russia&rsquo;s full return to the rank of the leading countries of the world. One sentiment expressed to me was that Putin&rsquo;s performance as G-8 host effectively banished the last ghosts of the Yeltsin era, especially the images of the sickly president humbly accepting the diktat of the West in return for the privilege of being seen in the company of then-G-7 leaders.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb <em>Even the failure to reach an agreement with the United States over Russia&rsquo;s entry into the World Trade Organization was spun as a courageous defense of national interests and a sign that Putin, unlike Yeltsin, is not so desperate for approval that he is prepared to acquiesce to all American demands.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb <em>Most Russians also feel that any lingering doubts about the inclusion of Russia in the G-8 have been put to rest. Speaking at a briefing organized at the summit by The National Interest, the television commentator Alexei Pushkov went so far as to say that the three reasons usually advanced as to why Russia did not deserve to be in the G-8 &#8211; Russia is not sufficiently democratic; it is not a rich country; it has problems with its neighbors  were irrelevant.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb <em>Russia should be in the group by virtue of its geopolitical location, the fact that without Russian participation none of the pressing problems facing the international community can be solved, and because of its position as an energy superpower. The English-language St. Petersburg Times cited a poll in which 55 percent of Russian respondents agreed with Pushkov&rsquo;s reasoning: Russia&rsquo;s status is determined by its energy resources and strategic position.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb <em>Putin&rsquo;s ability to insert himself  and Russia  as a balancer was also very much on display here. In contrast to the predictions of some Western pundits that St. Petersburg would be seven industrial democracies versus Russia, Putin&rsquo;s separate meetings precluded any such development. Not only was Russia not isolated at the meeting, it was able to form tactical understandings with other participants (with France, for example, on the statement on the crisis in the Middle East) to ensure that the Russian perspective received a full hearing.<\/em> \u00bb<\/p>\n<h3>La dynamique russe<\/h3>\n<\/p>\n<p><p>\tLa situation est assez \u00e9trange. On croirait que les dirigeants occidentaux font tout pour indirectement renforcer la position de Poutine, notamment \u00e0 l&rsquo;int\u00e9rieur, notamment dans la bureaucratie d&rsquo;Etat russe. Ils engendrent ainsi une dynamique de plus en plus affirm\u00e9e, de plus en plus efficace, qui conduit \u00e0 l&rsquo;affirmation d&rsquo;un triomphalisme russe appuy\u00e9 sur des donn\u00e9es strat\u00e9giques tr\u00e8s concr\u00e8tes (l&rsquo;\u00e9nergie per\u00e7ue comme une donn\u00e9e strat\u00e9gique : 55% des Russes approuvent cette conception nouvelle qu&rsquo;affiche d\u00e9sormais Poutine).<\/p>\n<\/p>\n<p><p>\tIl y a principalement le cas des critiques contre l&rsquo;\u00e9tat de la d\u00e9mocratie en Russie. Il s&rsquo;agit, de la part des Occidentaux, d&rsquo;une sorte d&rsquo;automatisme pavlovien, introduit dans le pipe-line des consignes g\u00e9n\u00e9rales par les services de communication qui r\u00e9pondent, \u00e9galement d&rsquo;une fa\u00e7on pavlovienne, aux excitations des m\u00e9dias et des milieux soi-disant influents (intellectuels, ONG, humanitaires, etc.). Jusqu&rsquo;\u00e0 ces derni\u00e8res ann\u00e9es, les Russes encaissaient sans mot dire les accusations et les le\u00e7ons de vertu que n&rsquo;importe quel ministre, haut fonctionnaire ou commissaire de la Commission se jugeait oblig\u00e9, apr\u00e8s consultation des fiches fournies par son cabinet, de donner publiquement au gouvernement russe. Cette r\u00e9serve faisait beaucoup de tort aux Russes, qui semblaient ent\u00e9riner les accusations. D\u00e9sormais, Poutine annonce qu&rsquo;il n&rsquo;accepte plus les le\u00e7ons et, aux questions des journalistes, r\u00e9pond en citant les cas foisonnants du ridicule et de la corruption des d\u00e9mocraties occidentales. Les rieurs sont de ce c\u00f4t\u00e9. Le cas est tranch\u00e9 (la Russie n&rsquo;accepte plus d&rsquo;ing\u00e9rences des donneurs de le\u00e7ons occidentaux). La popularit\u00e9 de Poutine augmente. Ses paroles ont plus de poids. Et ainsi de suite.<\/p>\n<\/p>\n<p><p>\tLa conjonction est exceptionnelle pour les Russes. Toutes les d\u00e9mocraties occidentales sont en crise. Le r\u00e9sultat de la politique occidentale (am\u00e9ricaniste) est un d\u00e9sastre. Dans toutes les crises qui s&rsquo;allument les unes apr\u00e8s les autres comme cons\u00e9quences de la politique US, les Occidentaux ont besoin, \u00e0 un moment ou l&rsquo;autre, de l&rsquo;aide, voire des bons offices de la Russie. Poutine ne se presse pas, ce qui met \u00e9ventuellement un comble \u00e0 la frustration occidentale, notamment am\u00e9ricaine. (Voir l&rsquo;exclamation de GW Bush aux oreilles empress\u00e9es et consentantes du pauvre Blair, <a href=\"http:\/\/news.independent.co.uk\/world\/politics\/article1183388.ece\" class=\"gen\">entendue<\/a> dans le monde entier gr\u00e2ce \u00e0 un micro malencontreusement ouvert : \u00ab <em> You see, the &#8230; thing is what they need to do is to get Syria, to get Hizbollah to stop doing this shit and it&rsquo;s over.<\/em> \u00bb [le <em>they<\/em> indiquant les Russes, qui ne semblent pas se presser pour faire pression sur les Syriens].)<\/p>\n<\/p>\n<p><p>\tComme le dit Gvosdev, Poutine n&rsquo;a nullement \u00e9t\u00e9 isol\u00e9 \u00e0 Saint-Petersbourg. Ce n&rsquo;est pas qu&rsquo;il ait montr\u00e9 de grandes vertus tactiques pour cela. Il lui a suffi de laisser faire les choses. Les Occidentaux sont tellement d\u00e9cr\u00e9pits et en d\u00e9saccord sur tout  sauf sur la langue de bois officielle  qu&rsquo;il n&rsquo;a eu qu&rsquo;\u00e0 laisser aller les choses. Le triomphe de Poutine est \u00e0 la mesure de la d\u00e9confiture du reste.<\/p>\n<\/p>\n<p><p>\tPoutine n&rsquo;a pas remport\u00e9 un triomphe de substance. La substance de la nouvelle puissance russe existe en dehors du G8 et elle existait <a href=\"http:\/\/www.dedefensa.org\/article.php?art_id=2721\" class=\"gen\">d\u00e9j\u00e0<\/a> avant le G8. Il a remport\u00e9 un triomphe m\u00e9diatique sur la sc\u00e8ne virtualiste que constitue cette sorte de sommets. Poutine a acquis un poids m\u00e9diatique et virtualiste qu&rsquo;il n&rsquo;avait pas avant Saint-Petersbourg. Dans notre univers de faux-semblants et de miroirs d\u00e9formants, cela compte beaucoup puisque c&rsquo;est l&rsquo;essentiel voire l&rsquo;exclusif de l&rsquo;existence politique pour nombre de dirigeants occidentaux.  A Saint-Petersbourg, il a donc boucl\u00e9 l&rsquo;arsenal de la nouvelle puissance russe, en sacrifiant aux murs occidentales et en sauvegardant sans efforts la diff\u00e9rence russe.<\/p>\n<\/p>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Poutine, sans forcer 18 juillet 2006 Le sommet de Saint-Petersbourg du G8 eut cette vertu de nous donner une image incontestable de justesse de la situation du monde. Les Occidentaux (Japon compris), les riches de l&rsquo;ex-G7, s&rsquo;y montr\u00e8rent tels qu&rsquo;ils sont aujourd&rsquo;hui : d\u00e9sunis, sans coh\u00e9sion ni direction (direction hi\u00e9rarchique et orientation politique, sans imagination,&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[4307,5636,916,2859,610],"class_list":["post-67762","post","type-post","status-publish","format-standard","hentry","category-faits-et-commentaires","tag-g8","tag-mediatisme","tag-poutine","tag-saint-petersbourg","tag-virtualisme"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/67762","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=67762"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/67762\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=67762"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=67762"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=67762"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}