{"id":67763,"date":"2006-07-18T00:00:00","date_gmt":"2006-07-18T00:00:00","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2006\/07\/18\/la-pravda-et-le-jsf\/"},"modified":"2006-07-18T00:00:00","modified_gmt":"2006-07-18T00:00:00","slug":"la-pravda-et-le-jsf","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2006\/07\/18\/la-pravda-et-le-jsf\/","title":{"rendered":"<strong><em>La \u201cPravda\u201d et le JSF<\/em><\/strong>"},"content":{"rendered":"<p><h2 class=\"common-article\">La <em>Pravda<\/em> et le JSF<\/h2>\n<\/p>\n<p><p>\t18 juillet 2006  Comme c&rsquo;est la coutume dans un grand \u00e9v\u00e9nement de d\u00e9monstration virtualiste comme l&rsquo;est un Salon A\u00e9ronautique (Farnborough, du 17 au 23 juillet), la guerre de la com&rsquo; bat son plein. Les Am\u00e9ricains sont en premi\u00e8re ligne et le JSF est le principal enjeu de la guerre. Pas de surprises.<\/p>\n<\/p>\n<p><p>\tCe qui ne cesse de surprendre, c&rsquo;est l&rsquo;absence totale de consid\u00e9ration des <em>spin doctors<\/em> pour la r\u00e9alit\u00e9, la logique, la v\u00e9rit\u00e9 et toutes ces sortes de choses. Le mensonge syst\u00e9matique est devenu la marque de fabrique des sp\u00e9cialistes du domaine. Les autres n&rsquo;ont qu&rsquo;\u00e0 faire avec. Certains d&rsquo;entre nous, avec un reste de dignit\u00e9, ont parfois l&rsquo;impression d&rsquo;\u00eatre consid\u00e9r\u00e9s comme des esprits faibles, au bord de la d\u00e9bilit\u00e9, \u00e0 lire ce qu&rsquo;on nous propose ; et puis non, d&rsquo;ailleurs, quant \u00e0 savoir o\u00f9 exactement se trouve la d\u00e9bilit\u00e9, le d\u00e9bat n&rsquo;est pas tranch\u00e9.<\/p>\n<\/p>\n<p><p>\tLes exemples ne manquent pas. La question du JSF est devenue l&rsquo;\u00e9talon universel de l&rsquo;utilisation du mensonge officiel dans l&rsquo;information. Pour autant, les techniques ne se sont pas am\u00e9lior\u00e9es, ce qui est une bonne nouvelle. Au contraire, plus l&rsquo;usage est syst\u00e9matique, plus il est impudent, plus il est primaire. Un exemple tr\u00e8s r\u00e9cent nous rem\u00e9more la r\u00e8gle d&rsquo;or de tous les lecteurs de la <em>Pravda<\/em> du bon temps de la langue de bois communiste : laissez les quatre premiers paragraphes, qui sont l&rsquo;habituel rab\u00e2chage de la langue de bois ; \u00e0 partir du cinqui\u00e8me c&rsquo;est plus int\u00e9ressant car l\u00e0 se trouve le message qu&rsquo;il faut bien faire passer.<\/p>\n<\/p>\n<p><p>\tIl s&rsquo;agit du texte paru <a href=\"http:\/\/www.defensenews.com\/story.php?F=1952624&#038;C=europe\" class=\"gen\">hier<\/a> dans <em>Defense News<\/em>, sous le titre tr\u00e8s aguichant de \u00ab <em>Tanker Agreement Could Ease U.S.-U.K. Strains<\/em> \u00bb. Passons l&rsquo;affaire du <em>tanker<\/em> (FSTA), ni tr\u00e8s lumineuse ni tr\u00e8s convaincante, pour en venir \u00e0 la deuxi\u00e8me partie de l&rsquo;article consacr\u00e9e \u00e0 notre JSF. Nous soulignons en gras les extraits que nous citerons ensuite.<\/p>\n<\/p>\n<p><p>\t\u00ab  <strong><em>JSF Deal in Sight<\/em><\/strong><\/p>\n<\/p>\n<p><p>\t\u00bb <em>FSTA has been among several key British programs affected by technology-release issues with the United States; Raytheon&rsquo;s ASTOR surveillance aircraft is another.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb <em>But the British military&rsquo;s most important problem is how to gain the technology transfer required to operate and upgrade Lockheed Martin&rsquo;s F-35 Joint Strike Fighter independently of the United States.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb <em>At one time, Lord Drayson, defense procurement minister, threatened to pull out of the multinational program if Britain didn&rsquo;t get what it wanted on technology.<\/em> <strong><em>That looked implausible then and unnecessary now, as the two sides are close to reconciling their differences on the JSF.<\/em><\/strong><\/p>\n<\/p>\n<p><p>\t\u00bb <em>The JSF partners<\/em> <strong><em>renamed the aircraft the Lightning II last week, and that appears to be the speed at which the two countries are concluding their technology-release negotiations<\/em><\/strong> <em>in the wake of the surprise announcement by U.S. President George W. Bush and British Prime Minister Tony Blair May 26 that they wanted longstanding technology differences resolved.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb <em>The statement of principles is expected to be sealed following a July 18 meeting between the MoD&rsquo;s top civil servant, Bill Jeffrey, Drayson, Defence Procurement Agency chief Sir Peter Spencer, Pentagon acquisition chief Ken Krieg and John Hillen, U.S. assistant secretary of state for political-military affairs, part of a regular British-American defense cooperation gathering.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb <strong><em>But even with a deal, sources said the two sides will have tough negotiations over the coming months to resolve a central issue  the degree of operational sovereignty Britain will have with its JSFs.<\/em><\/strong> To some, the question is: Just how much operational independence can the cash-strapped British afford?<D><\/p>\n<\/p>\n<p><p>\t\u00bb <em>BAE Systems chief executive Mike Turner said, Whatever the U.K. government asks for in terms of JSF technology, it is possible to get. The question is, how much will the U.K. ask for? There is no doubt the U.S. administration wants to do all it can to help.<\/em> . <strong><em>The issue for me is how much MoD wants operational independence..<\/em><\/strong><\/p>\n<\/p>\n<p><p>\t\u00bb <em>At the end of the day, it comes down to affordability, he said. There is a price to pay for the defense industrial base and sovereignty. Choices have to be made.<\/em> \u00bb<\/p>\n<h3>Explication de texte de la <em>Pravda<\/em><\/h3>\n<\/p>\n<p><p>\tL&rsquo;exercice s&rsquo;impose de lui-m\u00eame, avec les soulign\u00e9s de gras que nous avons impos\u00e9s \u00e0 ce malheureux texte.<\/p>\n<\/p>\n<p><p>\t \u00ab  <strong><em>JSF Deal in Sight<\/em><\/strong> \u00bb, nous annonce-t-on. L&rsquo;\u00e9motion nous \u00e9treint, \u00e0 peu pr\u00e8s comme Christophe Colomb \u00e0 qui son directeur de la communication venait annoncer : L&rsquo;Am\u00e9rique ! L&rsquo;Am\u00e9rique ! (Le bougre,  on parle du DirCom  il avait tout compris.)<\/p>\n<\/p>\n<p><p>\t  \u00ab <strong><em>That looked implausible then and unnecessary now, as the two sides are close to reconciling their differences on the JSF.<\/em><\/strong> \u00bb Non seulement le retrait UK du programme est improbable mais il n&rsquo;est m\u00eame plus n\u00e9cessaire. (Parce que tout est arrang\u00e9.)<\/p>\n<\/p>\n<p><p>\t \u00ab <em>renamed the aircraft the Lightning II last week, and that appears to be the speed at which the two countries are concluding their technology-release negotiations.<\/em> \u00bb Nous sommes entre gens de qualit\u00e9 et l&rsquo;on appr\u00e9ciera \u00e0 la fois l&rsquo;esprit d&rsquo;\u00e0-propos et l&rsquo;esprit tout court,  pour nous confirmer que l&rsquo;accord sera sign\u00e9 avant m\u00eame que l&rsquo;encre noire ait \u00e9t\u00e9 export\u00e9e de Chine.<\/p>\n<\/p>\n<p><p>\t \u00ab <strong><em>But even with a deal, sources said the two sides will have tough negotiations over the coming months to resolve a central issue  the degree of operational sovereignty Britain will have with its JSFs.<\/em><\/strong> \u00bb Ah oui, \u00e0 propos. Tout reste \u00e0 faire n&rsquo;est-ce pas, c&rsquo;est-\u00e0-dire n\u00e9gocier le plus dur,  eh oui. <\/p>\n<\/p>\n<p><p>\t \u00ab <strong><em>The issue for me is how much MoD wants operational independence.<\/em><\/strong> \u00bb Entr\u00e9e en sc\u00e8ne du philosophe de service, Ted Turner de BAE, pour nous expliquer le <strong>vrai<\/strong> probl\u00e8me. Transcrite en langage familial, sa remarque signifierait : Le probl\u00e8me pour moi est de savoir comment cette dame veut \u00eatre enceinte : \u00e0 moiti\u00e9 enceinte, aux deux-tiers, aux trois-quarts ? Ou bien quoi, compl\u00e8tement enceinte ?!.<\/p>\n<\/p>\n<p><p>\t \u00ab  <strong><em>At the end of the day, it comes down to affordability,<\/em><\/strong> [Turner] <strong><em>said. There is a price to pay for the defense industrial base and sovereignty. Choices have to be made.<\/em><\/strong> \u00bb Finalement, le philosophe se laisse aller au parler-vrai : si l&rsquo;on veut la vraie souverainet\u00e9 op\u00e9rationnelle (c&rsquo;est-\u00e0-dire la seule puisqu&rsquo;elle ne saucissonne pas : on est souverain ou on ne l&rsquo;est pas), il faudra payer Par ailleurs, phrase sibylline : cela signifierait-il que Washington ferait payer <strong>tr\u00e8s cher<\/strong> (en plus du prix normal du JSF) les transferts n\u00e9cessaires \u00e0 cette souverainet\u00e9 (le bruit en a couru) ? (Id\u00e9e confirm\u00e9e par une autre phrase de la m\u00eame eau : \u00ab <em>To some, the question is: Just how much operational independence can the cash-strapped British afford?<\/em> \u00bb) Ou bien est-ce que, plus simplement, pour avoir la souverainet\u00e9 il faut quitter le programme et que cela co\u00fbtera cher au Tr\u00e9sor anglais ? Dans tous les cas, ceci est juste quoique un peu Bouvard &#038; P\u00e9cuchet : au bout du compte, <em>at the end of the day<\/em>, il faudra bien choisir. Merci au philosophe.<\/p>\n<h3>Commentaire ? Conclusion ?<\/h3>\n<\/p>\n<p><p>\tCommentaire rapide, toujours le m\u00eame (\u00e0 propos du JSF et du d\u00e9bat UK-USA) : on continue \u00e0 affirmer que tout est r\u00e9solu et l&rsquo;on d\u00e9taille sans le dire comment rien n&rsquo;est r\u00e9solu. Et l&rsquo;on conclut qu&rsquo;au bout, il faudra faire des choix,  assez curieusement puisqu&rsquo;au d\u00e9but on nous annon\u00e7ait que le choix est fait.<\/p>\n<\/p>\n<p><p>\tConclusion : l&rsquo;information est aujourd&rsquo;hui une bataille sans merci o\u00f9 tous les soup\u00e7ons sont permis, et m\u00eame recommand\u00e9s lorsqu&rsquo;il s&rsquo;agit de papier imprim\u00e9 venu de la source la plus respectable possible. Les informations venues des sources les plus proches des sources officielles sont les plus suspectes. Les m\u00e9dias qui s&rsquo;enorgueillissent d&rsquo;une r\u00e9putation d&rsquo;objectivit\u00e9 et de probit\u00e9 sont les premiers sur la liste des suspects.<\/p>\n<\/p>\n<p><p>\tPar bonheur, ils ne sont pas plus habiles pour autant. On dirait m\u00eame que ce statut les aveugle au point de croire que plus la ficelle est grosse, plus on la gobera. Ils se trouvent devant la double n\u00e9cessit\u00e9 : dire que tout va bien et, d&rsquo;autre part, informer les parties en pr\u00e9sence (les Britanniques en l&rsquo;occurrence, pour ce texte) que tout va mal, que rien n&rsquo;est fait et que ceux (les Britanniques) qui esp\u00e8rent l&#8217;emporter contre l&rsquo;\u00e9vidence de la vertu et de la puissance doivent s&rsquo;appr\u00eater \u00e0 de bien terribles sacrifices. Entre les deux, rien, aucune nuance, aucune habilet\u00e9. Ces gens fonctionnent comme des robots.<\/p>\n<\/p>\n<p><p>\tLa <em>Pravda<\/em> ne faisait pas mieux, \u00e0 part qu&rsquo;ils \u00e9taient plus humains. Renata Lesnik, journaliste de la radio sovi\u00e9tique d&rsquo;Etat pass\u00e9e \u00e0 l&rsquo;ouest en 1982 racontait ceci \u00e0 ses amis de l&rsquo;ouest : elle entra un jour, exc\u00e9d\u00e9e et d\u00e9sesp\u00e9r\u00e9e, dans le bureau de son chef hi\u00e9rarchique et lui d\u00e9clara qu&rsquo;elle ne pouvait plus supporter de devoir dire de tels mensonges. L&rsquo;autre, qui l&rsquo;aimait bien et voulait l&#8217;emp\u00eacher de faire des b\u00eatises, ouvrit son tiroir, sortit une bouteille de vodka et lui dit : \u00ab <em>Tiens, fais comme moi. Bois.<\/em> \u00bb Chez nous, l&rsquo;ivresse au travail n&rsquo;est pas <em>politically correct<\/em> et elle est m\u00eame sanctionn\u00e9e. Nom de Dieu, la vertu d\u00e9mocratique n&rsquo;est pas une vaine expression.<\/p>\n<\/p>\n<p><p>\t(Et puis, le journaliste saoul et asserment\u00e9-d\u00e9mocratique pourrait remettre et l&rsquo;on pourrait croire que c&rsquo;est de d\u00e9go\u00fbt pour son travail.)<\/p>\n<\/p>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Pravda et le JSF 18 juillet 2006 Comme c&rsquo;est la coutume dans un grand \u00e9v\u00e9nement de d\u00e9monstration virtualiste comme l&rsquo;est un Salon A\u00e9ronautique (Farnborough, du 17 au 23 juillet), la guerre de la com&rsquo; bat son plein. Les Am\u00e9ricains sont en premi\u00e8re ligne et le JSF est le principal enjeu de la guerre. Pas&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[3507,5638,250,5637,2746,3509,5445],"class_list":["post-67763","post","type-post","status-publish","format-standard","hentry","category-faits-et-commentaires","tag-farnborough","tag-journaliste","tag-jsf","tag-pravda","tag-souverainete","tag-turner","tag-verite"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/67763","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=67763"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/67763\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=67763"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=67763"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=67763"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}