{"id":67786,"date":"2006-07-23T00:00:00","date_gmt":"2006-07-23T00:00:00","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2006\/07\/23\/bienvenue-dans-notre-monde-neocon\/"},"modified":"2006-07-23T00:00:00","modified_gmt":"2006-07-23T00:00:00","slug":"bienvenue-dans-notre-monde-neocon","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2006\/07\/23\/bienvenue-dans-notre-monde-neocon\/","title":{"rendered":"<strong><em>Bienvenue dans notre monde n\u00e9ocon<\/em><\/strong>"},"content":{"rendered":"<p><h2 class=\"common-article\">Bienvenue dans notre monde n\u00e9ocon<\/h2>\n<\/p>\n<p><p>\t23 juillet 2006  Voici une occurrence symbolique, mais op\u00e9rationnelle \u00e9galement, des plus int\u00e9ressantes. Alors que le monde virtualiste et m\u00e9diatique occidental, sous l&rsquo;influence de Washington DC que certains comparent \u00e0 un \u00e9tablissement psychiatrique climatis\u00e9, r\u00e9sonne des glapissements n\u00e9o-conservateurs, la r\u00e9alit\u00e9 de l&rsquo;avenir que nous offrent ces m\u00eames n\u00e9o-conservateurs offre un spectacle tr\u00e8s significatif. D&rsquo;un c\u00f4t\u00e9, le d\u00e9sordre et la fureur, le sang et le feu des situations r\u00e9elles, de l&rsquo;autre, la sottise vaniteuse et arrogante des initiateurs et acteurs principaux du drame.<\/p>\n<\/p>\n<p><p>\tRarement, les situations op\u00e9rationnelles auront co\u00efncid\u00e9 avec tant d&rsquo;harmonie, si l&rsquo;on peut dire, pour nous offrir l&rsquo;enseignement de la politique am\u00e9ricaniste d\u00e9cha\u00een\u00e9e.<\/p>\n<\/p>\n<p><p>\t&bull; Au Liban, malgr\u00e9 des attaques d&rsquo;une brutalit\u00e9 bien caract\u00e9ristique de notre civilisation, <em>Tsahal<\/em> pi\u00e9tine et r\u00e9vise toutes ses ambitions aux aspects les plus modestes possibles. L&rsquo;offensive a\u00e9rienne est un \u00e9chec mais la perspective d&rsquo;une occupation terrestre du Sud Liban fait manifestement peur \u00e0 la deuxi\u00e8me plus puissante arm\u00e9e du monde (apr\u00e8s le patron pentagonesque, cela va de soi). (L&rsquo;article de Steven Erlanger dans le New York <em>Times<\/em> du 23 juillet est <a href=\"http:\/\/fairuse.100webcustomers.com\/sf\/nyt7_23_06.htm \" class=\"gen\">significatif<\/a> \u00e0 cet \u00e9gard.) On envisage donc une occupation du bout des doigts de pied, tandis qu&rsquo;on accentuera autant que faire se peut le pilonnage a\u00e9rien de la zone, qui a donn\u00e9 tant <a href=\"http:\/\/www.dedefensa.org\/article.php?art_id=2930\" class=\"gen\">d&rsquo;excellents<\/a> r\u00e9sultats, pour arriver \u00e0 une sorte de nettoyage ethnique par le vide garantissant la paix et la tranquillit\u00e9 d&rsquo;Isra\u00ebl. Outre la belle le\u00e7on de morale, qu&rsquo;on compare cette situation avec <a href=\"http:\/\/www.dedefensa.org\/article.php?art_id=2904\" class=\"gen\">l&rsquo;ivresse n\u00e9ocon<\/a> annon\u00e7ant l&rsquo;invasion de la Syrie et de l&rsquo;Iran \u00e0 partir de l&rsquo;incursion libanaise. Eh, c&rsquo;est qu&rsquo;il faudrait pouvoir<\/p>\n<\/p>\n<p><p>\t&bull; En <a href=\"http:\/\/www.dedefensa.org\/article.php?art_id=2931\" class=\"gen\">Irak<\/a>, le pire semble chaque jour inventer quelque chose d&rsquo;encore pire, une sorte de transmutation permanente. On se trouve maintenant au bord de n\u00e9gociations s\u00e9rieuses entre les trois composantes du pays pour tenter de trouver un <em>modus vivendi<\/em> qui serait une partition <em>de facto<\/em>, qui puisse apaiser la guerre civile en cours. Tout cela pourrait bien passer, \u00e0 terme, par la rupture avec Washington. Tout est donc d\u00e9sormais possible, de pr\u00e9f\u00e9rence le pire pour les plans US,  si plans il y eut jamais.<\/p>\n<\/p>\n<p><p>\t&bull; En Afghanistan, est-ce tellement mieux ? Depuis que le g\u00e9n\u00e9ral britannique commandant l&rsquo;OTAN l\u00e0-bas a l\u00e2ch\u00e9 le mot, le jugement fleurit : <a href=\"http:\/\/wpherald.com\/articles\/474\/1\/NATO-chief-Anarchy-looms-in-Afghanistan\/Feuding-agencies-compound-problem.html\" class=\"gen\">l&rsquo;anarchie<\/a>. Et notez bien ceci : cette anarchie n&rsquo;est pas due seulement \u00e0 la situation op\u00e9rationnelle engendr\u00e9e par les m\u00e9chants (talibans, chefs de guerre, drogue, etc.), mais aussi,  et dirions-nous : <strong>surtout<\/strong>?  au d\u00e9sordre existant entre Occidentaux, entre agences, entre bureaucraties, entre mercenaires et suppl\u00e9tifs plus ou moins ill\u00e9gaux dans le genre <em>cow boy<\/em>-forces sp\u00e9ciales (Le g\u00e9n\u00e9ral Richard se r\u00e9f\u00e8re \u00ab <em>in particular to what he called the lack of unity between different agencies.<\/em> \u00bb)&#8230;<\/p>\n<\/p>\n<p><p>\t\u00ab <em>Afghanistan is \u00a0\u00bbclose to anarchy\u00a0\u00bb and Western military forces are running out of time, the head of NATO&rsquo;s international security force in that country says. Lt. Gen. David Richards, the British NATO commander who takes over responsibility for southern Afghanistan in 10 days, said Afghan fighting was more severe than NATO expected and feuding foreign agencies were compounding problems caused by local corruption, the Guardian reported Saturday.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb <em>The situation is close to anarchy, he told a conference at Royal United Services Institute think-tank in London Friday. He referred in particular to what he called the lack of unity between different agencies.<\/em> \u00bb<\/p>\n<\/p>\n<p><p>\tIl ne faut attendre aucun ajustement, aucune modification de la Ligne. Plus que jamais, le mot d&rsquo;ordre est ceci : notre politique a amen\u00e9 des catastrophes, c&rsquo;est parce que notre politique n&rsquo;avait pas \u00e9t\u00e9 assez syst\u00e9matiquement appliqu\u00e9e. Les erreurs commises seront donc approfondies et amplifi\u00e9es, et approfondies et amplifi\u00e9es les catastrophes.<\/p>\n<h3>Les comploteurs sans complot<\/h3>\n<\/p>\n<p><p>\tSi nous avons pr\u00e9sent\u00e9 ce spectacle sous le titre aguichant du \u00ab <em>monde n\u00e9ocon<\/em> \u00bb (pour une fois, n\u00e9ocon sans guillemets et avec accent), il ne faut pas s&rsquo;y tromper : c&rsquo;est parce que le terme fait recette. Dans la r\u00e9alit\u00e9, tout le monde est partie prenante dans cette folie (nous sommes tous des <em>neocons<\/em>). Ce n&rsquo;est pas un succ\u00e8s du complot <em>neocon<\/em> (surtout quand l&rsquo;on mesure les effets du complot) ; c&rsquo;est simplement que les <em>neocons<\/em> sont plus ouvertement fous que nous, et qu&rsquo;ils expriment ainsi mieux une folie qui est g\u00e9n\u00e9rale dans l&rsquo;<em>establishment<\/em> occidental. On l&rsquo;a d\u00e9j\u00e0 dit et on le redit, les <em>neocons<\/em> sont les idiots utiles de la pi\u00e8ce. Quand l&rsquo;on envisage un projet et que tout va bien (puisque rien ne s&rsquo;est encore pass\u00e9), on s&rsquo;appuie sur leur rh\u00e9torique exalt\u00e9e. Quand tout va mal (d\u00e8s qu&rsquo;on commence \u00e0 agir), on se retourne vers eux en disant : c&rsquo;est leur faute.<\/p>\n<\/p>\n<p><p>\tSi quelqu&rsquo;un veut voir un complot dans tout cela, libre \u00e0 lui. C&rsquo;est simplement qu&rsquo;aujourd&rsquo;hui, au temps du virtualisme, le terme complot signifie \u00e0 la fois \u00e9chec et d\u00e9sordre incontr\u00f4lable (c&rsquo;est-\u00e0-dire <strong>notre<\/strong> d\u00e9sordre incontr\u00f4lable). Dans ce cas, oui, le complot est une r\u00e9ussite.<\/p>\n<\/p>\n<p><p>\tIl n&rsquo;y a aucune direction concevable, aucun contr\u00f4le sur l&rsquo;\u00e9volution de la situation. On parle bien entendu, dans les salons et dans les r\u00e9dactions, de d\u00e9sordre cr\u00e9ateur, expression favorite et fascinante de notre dialectique politique qui se voudrait lib\u00e9r\u00e9e. Nous ne sommes pas du tout s\u00fbrs qu&rsquo;ils parviennent jamais \u00e0 provoquer le d\u00e9sordre,  c&rsquo;est-\u00e0-dire un <strong>vrai<\/strong> d\u00e9sordre, si complet qu&rsquo;il pourrait engendrer le chaos dont on pourrait attendre qu&rsquo;il enclench\u00e2t \u00e0 son tour des m\u00e9canismes incontr\u00f4lables cr\u00e9ant des opportunit\u00e9s inattendues.<\/p>\n<\/p>\n<p><p>\tLe Liban illustre bien le cas : apr\u00e8s l&rsquo;assassinat d&rsquo;un Premier ministre dont la cause est \u00e0 80% l&rsquo;effet de manigances am\u00e9ricano-isra\u00e9liennes, on aboutit (en f\u00e9vrier-mars 2005) \u00e0 l&rsquo;\u00e9viction de la Syrie et \u00e0 l&rsquo;instauration d&rsquo;une d\u00e9mocratie dont chacun attend sans le moindre doute qu&rsquo;elle sera contr\u00f4l\u00e9e par les ma\u00eetres en manipulation isra\u00e9lo-am\u00e9ricains et qu&rsquo;elle leur servira d&rsquo;instrument. Un an apr\u00e8s, les m\u00eames (les ma\u00eetres en manipulation) attaquent le Liban re-cr\u00e9\u00e9 par le d\u00e9sordre cr\u00e9ateur et vont, dans leur d\u00e9sarroi, jusqu&rsquo;\u00e0 envisager de solliciter \u00e0 nouveau <a href=\"http:\/\/www.dedefensa.org\/article.php?art_id=2933\" class=\"gen\">la Syrie<\/a>. Pourquoi ne pas demander aux troupes syriennes de venir donner un coup de main \u00e0 Isra\u00ebl sur la fronti\u00e8re Sud du Liban, ou de faire partie de la force internationale qui se pr\u00e9pare ? (Qu&rsquo;on ne sourie pas trop : la chose reste une des hypoth\u00e8ses de travail des planificateurs du d\u00e9partement d&rsquo;\u00c9tat. Nous ne sommes pas au bout de nos surprises.)<\/p>\n<\/p>\n<p><p>\tLe probl\u00e8me est que l&rsquo;id\u00e9e du d\u00e9sordre cr\u00e9ateur est paradoxalement une <strong><em>id\u00e9e d&rsquo;ordre<\/em><\/strong>. Celui qui le d\u00e9clenche doit avoir une conception ordonn\u00e9e de ses intentions, de ses moyens, de ses buts, une vision rang\u00e9e de l&rsquo;harmonie qu&rsquo;il esp\u00e8re. Il d\u00e9clenche le d\u00e9sordre parce qu&rsquo;il constate le blocage de la situation pr\u00e9sente et qu&rsquo;il croit \u00e0 une logique <strong>historique<\/strong> op\u00e9rant un reclassement des choses selon des orientations qu&rsquo;il soutient mais sur lesquelles il n&rsquo;a aucune prise directe. C&rsquo;est une sorte de transcendantalisme. En ce sens, l&rsquo;archi-r\u00e9actionnaire (selon le code de pens\u00e9e moderniste) et <a href=\"http:\/\/www.dedefensa.org\/article.php?art_id=1754\" class=\"gen\">anti-moderne<\/a> <a href=\"http:\/\/www.dedefensa.org\/article.php?art_id=1618\" class=\"gen\">Joseph de Maistre<\/a> est un adepte transcendantal du d\u00e9sordre cr\u00e9ateur lorsqu&rsquo;il conseille de laisser aller \u00e0 son terme ultime la R\u00e9volution fran\u00e7aise, dont il d\u00e9nonce le caract\u00e8re n\u00e9faste, pour purger l&rsquo;Histoire de tous les maux manifest\u00e9s par cet \u00e9v\u00e9nement et qui furent, avant lui, cause de cet \u00e9v\u00e9nement,  et que naisse au bout du processus l&rsquo;ordre que lui-m\u00eame appelle de ses vux.<\/p>\n<\/p>\n<p><p>\tPar contre, il appara\u00eet que ce qui est d\u00e9sordre soi-m\u00eame, et qui montre \u00e0 profusion son incapacit\u00e9 \u00e0 se transformer en un ordre harmonieux, f\u00fbt-il celui de l&rsquo;Empire, ne peut enfanter un d\u00e9sordre cr\u00e9ateur,  sinon, paradoxalement, un d\u00e9sordre cr\u00e9ateur contre lui-m\u00eame. Les <em>n\u00e9o-cons<\/em> n&rsquo;ont pas tort sur toute la ligne, mais ils sont irr\u00e9m\u00e9diablement englu\u00e9s dans le d\u00e9sordre du syst\u00e8me qu&rsquo;ils pr\u00e9tendent contr\u00f4ler et qui, en fait, les m\u00e8ne par le bout du nez depuis l&rsquo;origine. C&rsquo;est \u00e9galement le cas de tout le syst\u00e8me washingtonien, dont les <em>n\u00e9o-cons<\/em>, r\u00e9p\u00e9tons-le, sont les idiots utiles, c&rsquo;est-\u00e0-dire les complices inconscients de ce d\u00e9sordre syst\u00e9mique. (Voyez ce que nous dit le g\u00e9n\u00e9ral Richard de l&rsquo;anarchie en Afghanistan, o\u00f9 l&rsquo;on n&rsquo;est pas loin de comprendre que ce sont les agences et diff\u00e9rents pouvoirs occidentaux en place qui l&rsquo;alimentent prioritairement,  notre d\u00e9sordre moderniste et bureaucratique.)<\/p>\n<\/p>\n<p><p>\tLa Russie illustre bien le cas. Le syst\u00e8me du soi-disant d\u00e9sordre cr\u00e9ateur s&rsquo;est pr\u00e9cipit\u00e9 sur la Russie pour la briser encore plus qu&rsquo;elle n&rsquo;\u00e9tait. Ce n&rsquo;\u00e9tait pas pour la briser et la remodeler \u00e0 son image, mais par pure rapacit\u00e9 engendr\u00e9e par son propre d\u00e9sordre, toujours le m\u00eame aveuglement du gain vite fait. On s&rsquo;y est fait quelques fortunes, on a accentu\u00e9 la pauvret\u00e9, la d\u00e9tresse sociale, les troubles psychologiques,   en un mot, on a install\u00e9 un d\u00e9sordre destructeur sans mode d&#8217;emploi pour la suite. Ce d\u00e9sordre-l\u00e0 fut cr\u00e9ateur finalement, peut-\u00eatre selon une logique transcendantale, en enfantant du contraire de ce qu&rsquo;ils avaient esp\u00e9r\u00e9,  en enfantant Poutine et le <a href=\"http:\/\/www.dedefensa.org\/article.php?art_id=2721\" class=\"gen\">destin actuel<\/a> de la Russie. (Les glapissements de rage anti-Poutine des Glucksman &#038; compagnie nous indiquent qu&rsquo;on tient le bon bout.)<\/p>\n<\/p>\n<p><p>\tDu coup, les <em>n\u00e9o-cons<\/em> aid\u00e9s des guerriers de Wall Street ont achev\u00e9 l&rsquo;uvre de Gorbatchev en r\u00e9g\u00e9n\u00e9rant la Russie. Effectivement, comme le fait remarquer de fa\u00e7on lumineuse <a href=\"http:\/\/www.dedefensa.org\/article.php?art_id=2923\" class=\"gen\">James Carroll<\/a> en identifiant le processus dans sa premi\u00e8re partie (le g\u00e9nie intuitif de Gorbatchev), la Russie a r\u00e9ussi sa sortie du syst\u00e8me commun, plut\u00f4t de la prison commune de la Guerre froide :<\/p>\n<\/p>\n<p><p>\t\u00ab <em>And look at the greatest example of that change  it took place in the Soviet Union, which dismantled itself. Instead of blaming everything on the enemy outside, it actually confronted its own corruptions, and took itself apart. That great event of the 20th Century  the non-violent demise of the Soviet Union  is something that we Americans should look much more closely at as a source of hope. Our shallow insistence that we won the Cold War means that we don&rsquo;t actually have to look at what happened on the other side. After the leadership of Mikhail Gorbachev, especially, but not just him, and in response to pressures from below, the Velvet Revolution, the Soviet Union offered us a way to step back from the totalitarian impulse&#8230;<\/em> \u00bb<\/p>\n<\/p>\n<p><p>\tCertes, les fous tiennent le pouvoir. <em>So what<\/em>? C&rsquo;est bien assez pour qu&rsquo;on mesure leurs limites et qu&rsquo;on en rie \u00e0 notre tour, de concert avec le Diable  qui, selon son habitude, en rit encore.<\/p>\n<\/p>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Bienvenue dans notre monde n\u00e9ocon 23 juillet 2006 Voici une occurrence symbolique, mais op\u00e9rationnelle \u00e9galement, des plus int\u00e9ressantes. Alors que le monde virtualiste et m\u00e9diatique occidental, sous l&rsquo;influence de Washington DC que certains comparent \u00e0 un \u00e9tablissement psychiatrique climatis\u00e9, r\u00e9sonne des glapissements n\u00e9o-conservateurs, la r\u00e9alit\u00e9 de l&rsquo;avenir que nous offrent ces m\u00eames n\u00e9o-conservateurs offre un&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[3236,3935,3356,857,2774,5611,3216],"class_list":["post-67786","post","type-post","status-publish","format-standard","hentry","category-faits-et-commentaires","tag-afghanistan","tag-createur","tag-desordre","tag-irak","tag-israel","tag-liban","tag-neocon"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/67786","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=67786"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/67786\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=67786"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=67786"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=67786"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}