{"id":67891,"date":"2006-08-17T00:00:00","date_gmt":"2006-08-17T00:00:00","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2006\/08\/17\/heureusement-reste-les-britts-comme-roue-de-depannage\/"},"modified":"2006-08-17T00:00:00","modified_gmt":"2006-08-17T00:00:00","slug":"heureusement-reste-les-britts-comme-roue-de-depannage","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2006\/08\/17\/heureusement-reste-les-britts-comme-roue-de-depannage\/","title":{"rendered":"Heureusement, reste les Britts comme roue de d\u00e9pannage"},"content":{"rendered":"<p><p>Il y a deux mois, il \u00e9tait absolument hors de question que les Britanniques envisagent d&rsquo;accepter le d\u00e9ploiement sur leur sol d&rsquo;une station de missiles anti-missiles US (pour l&rsquo;instant, baptis\u00e9 GMD). Le gouvernement britannique l&rsquo;avait fait dire aux amis am\u00e9ricains, \u00e0 la Maison-Blanche. Il avait demand\u00e9 qu&rsquo;on \u00e9vite, du c\u00f4t\u00e9 US, de soulever ce probl\u00e8me \u00e0 cause des tensions internes. C\u00f4t\u00e9 Maison-Blanche, on avait promis d&rsquo;en tenir compte, ajoutant que, d&rsquo;apr\u00e8s ce qu&rsquo;on en savait en lisant la presse, le Pentagone n&rsquo;avait pas besoin des Britanniques puisque l&rsquo;affaire \u00e9tait quasiment conclue du c\u00f4t\u00e9 des amis polonais et tch\u00e8ques.<\/p>\n<\/p>\n<p><p>\tMais Londres et la Maison-Blanche d\u00e9couvrent, toujours en feuilletant la presse, qu&rsquo;il n&rsquo;en est rien. La surprise vient des Tch\u00e8ques et des Polonais, qui renaclent et se permettent de juger embarrassante la pr\u00e9sence de bases anti-missiles US sur leurs sols. Le Pentagone commence \u00e0 craindre de ne pas avoir une base assur\u00e9e pour d\u00e9ployer ses superbes missiles. On se tourne donc \u00ac r\u00e9flexe automatique sinon pavlovien, \u00ac \u00e0 nouveau vers Londres, malgr\u00e9 les garanties donn\u00e9e du c\u00f4t\u00e9 politique US. Les Britanniques sont \u00e0 nouveau plac\u00e9s devant la perspective d&rsquo;une crise politique int\u00e9rieure li\u00e9e aux exigences am\u00e9ricanistes (nombre de d\u00e9put\u00e9s travaillistes ne veulent pas entendre de cette base am\u00e9ricaine). Cette remarque, reproduites par une d\u00e9p\u00e8che AFP (sur <a href=\"http:\/\/www.defensenews.com\/story.php?F=2038640&#038;C=europe\" class=\"gen\">Defense News<\/a>) r\u00e9sume assez comiquement le d\u00e9sappointement britannique : \u00ab <em>A few weeks ago it looked like we were out of the woods on this one, an unnamed senior British source was quoted as saying.<\/em> \u00bb<\/p>\n<\/p>\n<p><p>\tBien s\u00fbr, il est bon de signaler que ce r\u00e9seau anti-missiles est destin\u00e9 \u00e0 arr\u00eater les missiles nord-cor\u00e9ens, et, plus tard, les missiles iraniens. Ces extravagantes sp\u00e9cifications n&rsquo;ont strictement aucun int\u00e9r\u00eat militaire mais devraient \u00e9videmment renforcer les entreprises terroristes,  s&rsquo;il y en an, mais Tony Blair et John Reid ont l&rsquo;air de croire qu&rsquo;il y en a,  contre le Royaume-Uni.<\/p>\n<\/p>\n<p><p>\tCette \u00e9volution o\u00f9 la r\u00e9action britannique \u00e9volue alternativement entre le fatalisme, la frustration impuissante et l&rsquo;exasp\u00e9ration contenue, est bien r\u00e9sum\u00e9e par cette autre intervention, d&rsquo;une involontaire ironie \u00e9galement puisqu&rsquo;elle vient d&rsquo;un <em>lobbyist<\/em> favorable du syst\u00e8me GMD. L&rsquo;intervention signifie bien aux Britanniques le r\u00f4le qu&rsquo;ils tiennent dans cette pi\u00e8ce grotesque : \u00ab <em>Speaking to The Times, Riki Ellison, head of the Missile Defense Advocacy Alliance, a pressure group, said: The UK has always been the fall-back option and there is some concern about whether Poland and the Czech Republic will turn out to be stable partners in the same way that you guys have been.<\/em> \u00bb<\/p>\n<\/p>\n<p><\/p>\n<p><p>\tMis en ligne le 17 ao\u00fbt 2006 \u00e0 14H13<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il y a deux mois, il \u00e9tait absolument hors de question que les Britanniques envisagent d&rsquo;accepter le d\u00e9ploiement sur leur sol d&rsquo;une station de missiles anti-missiles US (pour l&rsquo;instant, baptis\u00e9 GMD). Le gouvernement britannique l&rsquo;avait fait dire aux amis am\u00e9ricains, \u00e0 la Maison-Blanche. Il avait demand\u00e9 qu&rsquo;on \u00e9vite, du c\u00f4t\u00e9 US, de soulever ce probl\u00e8me&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[2],"tags":[4056,5550,3194,2827,3575],"class_list":["post-67891","post","type-post","status-publish","format-standard","hentry","category-bloc-notes","tag-antimissiles","tag-gmd","tag-pentagone","tag-pologne","tag-royaume-uni"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/67891","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=67891"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/67891\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=67891"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=67891"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=67891"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}