{"id":68007,"date":"2006-09-20T00:00:00","date_gmt":"2006-09-20T00:00:00","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2006\/09\/20\/rumsfeld-capitule-sans-conditions\/"},"modified":"2006-09-20T00:00:00","modified_gmt":"2006-09-20T00:00:00","slug":"rumsfeld-capitule-sans-conditions","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2006\/09\/20\/rumsfeld-capitule-sans-conditions\/","title":{"rendered":"<strong><em> Rumsfeld capitule sans conditions<\/em><\/strong>"},"content":{"rendered":"<p><h2 class=\"common-article\">Rumsfeld capitule sans conditions<\/h2>\n<\/p>\n<p><\/p>\n<p><p>\t20 septembre 2006  Le monstre, le Mordor de <a href=\"http:\/\/www.dedefensa.org\/article.php?art_id=2923\" class=\"gen\">James Carroll<\/a>, est-il en train de d\u00e9vorer ses enfants? La d\u00e9cision prise par Donald Rumsfeld d&rsquo;autoriser les services \u00e0 n\u00e9gocier directement leurs budgets avec OMB est sans pr\u00e9c\u00e9dent. Elle nous ram\u00e8ne,  budg\u00e9tairement parlant, ce qui est l&rsquo;essentiel aujourd&rsquo;hui,  \u00e0 la situation d&rsquo;avant 1947, lorsque les grands services des forces arm\u00e9es \u00e9taient directement repr\u00e9sent\u00e9s dans le Cabinet. <\/p>\n<\/p>\n<p><p>\t(Il y avait alors un War Department, repr\u00e9sentant l&rsquo;U.S. Army et, \u00e0 l&rsquo;int\u00e9rieur de celle-ci, l&rsquo;USAAF, anciennement USAAC,  respectivement U.S. Army Air Force et Air Corps,  incorpor\u00e9e dans l&rsquo;Army. Le Navy Department repr\u00e9sentait la marine de guerre et ses d\u00e9pendances, le Marine Corps et la Coast Guard. En 1947, le National Security Act d\u00e9cida la fusion des deux d\u00e9partements en un, le DoD ou Department of Defense. L&rsquo;USAAF devint une arme  ind\u00e9pendante  sous le sigle USAF. Trois sous-minist\u00e8res, sans r\u00e9el pouvoir, repr\u00e9sent\u00e8rent les trois armes aupr\u00e8s du secr\u00e9taire \u00e0 la d\u00e9fense : Departments of Air Force, Army et Navy.)<\/p>\n<\/p>\n<p><p>\tRumsfeld s&rsquo;en lave les mains. Il ne veut plus arbitrer entre des demandes budg\u00e9taires qui d\u00e9passent de toutes les fa\u00e7ons les moyens qui lui sont allou\u00e9s. Le corps budg\u00e9taire monstrueux des forces arm\u00e9es US va donc \u00eatre expos\u00e9 \u00e0 nu, \u00e0 deux chirurgiens principalement : le OMB (Office of Management and Budget), qui pr\u00e9pare le budget de la nation pour le pr\u00e9sident et d\u00e9pend directement de lui \u00e0 la Maison-Blanche, et le Congr\u00e8s qui l&rsquo;examine, qui l&rsquo;amende \u00e9ventuellement, qui d\u00e9cide finalement (\u00e0 moins d&rsquo;un veto victorieux du pr\u00e9sident).<\/p>\n<\/p>\n<p><p>\tVoici quelques extraits de ce que <em>Defense News<\/em>  nous dit de la chose, dans un article du 18 septembre que nous publions <a href=\"http:\/\/www.dedefensa.org\/choix.php?link_id=6806&#038;comm=1\" class=\"gen\">par ailleurs<\/a>:<\/p>\n<\/p>\n<p><p>\t\u00ab<em>Defense Secretary Donald Rumsfeld has allowed the military services to press their case for larger budgets directly with the White House&rsquo;s Office of Management and Budget (OMB), which according to sources has balked at increasing future year defense spending to meet the services&rsquo; projected needs.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>The move is particularly critical for the U.S. Army that wants $141 billion in 2008 alone, $30 billion more than the $111.8 billion requested last year, sources said.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>The direct discussions between the uniformed services and OMB are unprecedented, according to sources. Usually, the individual military services have to negotiate their annual budgets with the senior civilian leaders of the Pentagon, including the defense secretary and the comptroller.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>An Army spokesman said the service is in continuing discussions with Pentagon officials about its budget, but declined to say if it was in direct talks with the White House.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tLes positions des diff\u00e9rents acteurs du d\u00e9bat budg\u00e9taire dans ce cas varient selon leurs int\u00e9r\u00eats respectifs, comme on le lit dans le texte. (Le m\u00eame <a href=\"http:\/\/www.dedefensa.org\/choix.php?link_id=6806&#038;comm=1\" class=\"gen\">texte<\/a> donne des pr\u00e9cisions chiffr\u00e9es impressionnantes qui permettent de mesurer l&rsquo;importance budg\u00e9taire du d\u00e9bat.)<\/p>\n<\/p>\n<p><p>\t Les services eux-m\u00eames sont peu enthousiastes pour cette pratique, qui les expose particuli\u00e8rement du point de vue politique. Par contre, ils ne veulent pas que les augmentations qu&rsquo;ils demandent se fassent aux d\u00e9pens des autres. Ils pr\u00e9f\u00e9reraient la proc\u00e9dure normale : un budget en augmentation obtenu par le secr\u00e9taire \u00e0 la d\u00e9fense (OSD) et une r\u00e9partition satisfaisant toutes leurs demandes. Tant pis, ils devront assumer leurs responsabilit\u00e9s.<\/p>\n<\/p>\n<p><p>\t  Le Congr\u00e8s pr\u00e9f\u00e8re que les services n\u00e9gocient directement avec OMB, ce qui lui donne plus de puissance et de capacit\u00e9s d&rsquo;intervention en divisant la puissance du DoD en autant de services. De ce point de vue, la d\u00e9cision de Rumsfeld est un succ\u00e8s pour lui.<\/p>\n<\/p>\n<p><p>\tMais tout cela reste accessoire. On comprend qu&rsquo;il y a d&rsquo;abord une dimension politique de tr\u00e8s grande importance dans cette d\u00e9cision. Elle concerne Rumsfeld lui-m\u00eame, et les ambitions qu&rsquo;il affichait lorsqu&rsquo;il arriva \u00e0 la t\u00eate du d\u00e9partement.<\/p>\n<h3>La d\u00e9faite de 9\/10<\/h3>\n<\/p>\n<p><p>\tBien s\u00fbr, nous ne cessons de revenir \u00e0 la r\u00e9f\u00e9rence essentielle du discours de Rumsfeld, le <a href=\"http:\/\/www.dedefensa.org\/article.php?art_id=201\" class=\"gen\">10 septembre 2001<\/a> (9\/10). Il s&rsquo;agissait d&rsquo;une d\u00e9claration de guerre de Rumsfeld \u00e0 la bureaucratie du Pentagone, d\u00e9nonc\u00e9e comme l&rsquo;ennemi le plus dangereux des Etats-Unis (pas question du terrorisme la veille du 11 septembre) :<\/p>\n<\/p>\n<p><p>\t\u00ab<em>The topic today is an adversary that poses a threat, a serious threat, to the security of the United States of America. This adversary is one of the world&rsquo;s last bastions of central planning. It governs by dictating five-year plans. From a single capital, it attempts to impose its demands across time zones, continents, oceans and beyond. With brutal consistency, it stifles free thought and crushes new ideas. It disrupts the defense of the United States and places the lives of men and women in uniform at risk.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>Perhaps this adversary sounds like the former Soviet Union, but that enemy is gone: our foes are more subtle and implacable today. You may think I&rsquo;m describing one of the last decrepit dictators of the world. But their day, too, is almost past, and they cannot match the strength and size of this adversary.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>The adversary&rsquo;s closer to home. It&rsquo;s the Pentagon bureaucracy. Not the people, but the processes. Not the civilians, but the systems. Not the men and women in uniform, but the uniformity of thought and action that we too often impose on them.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tL&rsquo;attaque 9\/11 n&rsquo;a pas, paradoxalement, donn\u00e9 \u00e0 Rumsfeld les moyens de cette lutte qu&rsquo;il annon\u00e7ait la veille,  alors qu&rsquo;elle lui donnait pourtant un pouvoir sans pr\u00e9c\u00e9dent, une puissance inconnue pour un secr\u00e9taire \u00e0 la d\u00e9fense. Au contraire, elle a pr\u00e9cipit\u00e9 le DoD dans une spirale sans fin d&rsquo;augmentations massives de budget pour le simple entretien logistique et mat\u00e9riel de conflits qu&rsquo;on attendait rapides et victorieux et qui se sont r\u00e9v\u00e9l\u00e9s comme d&rsquo;\u00e9pouvantables bourbiers o\u00f9 les forces arm\u00e9es US s&rsquo;av\u00e8rent compl\u00e8tement inadapt\u00e9es. Le r\u00e9sultat est une course en avant budg\u00e9taire forc\u00e9e par les besoins de ces conflits qui noie toute possibilit\u00e9 de contr\u00f4le rationnel, et donc bat en br\u00e8che les espoirs de Rumsfeld de contr\u00f4ler la bureaucratie et de la r\u00e9former.<\/p>\n<\/p>\n<p><p>\tLa d\u00e9cision de laisser aux forces le soin d&rsquo;aller demander \u00e0 OMB l&rsquo;argent dont elles ont besoin est une capitulation de Rumsfeld. (Si l&rsquo;on veut, il tend \u00e0 dire \u00e0 propos des budgets: Je m&rsquo;en lave les mains, ce qui est effectivement abdiquer un pouvoir essentiel.) La d\u00e9cision revient \u00e0 renoncer \u00e0 assurer le contr\u00f4le budg\u00e9taire des forces, donc leur \u00e9volution structurelle, \u00e0 terme leur \u00e9quipement, voire leur strat\u00e9gie. Elle porte en germe un \u00e9clatement des orientations strat\u00e9giques des services par absence de coordination,  l&rsquo;absence de contr\u00f4le du budget pr\u00e9c\u00e9dant la perte de contr\u00f4le de ces domaines.<\/p>\n<\/p>\n<p><p>\tCette d\u00e9cision repr\u00e9sente l&rsquo;amorce d&rsquo;un \u00e9v\u00e9nement historique. L&rsquo;on peut d&rsquo;ores et d\u00e9j\u00e0 tenir ce fait historique pour acquis car il n&rsquo;y a plus rien qui puisse stopper la dynamique lanc\u00e9e par cette d\u00e9cision initiale. La d\u00e9cision ent\u00e9rine un fait primordial et fondamental, et aux cons\u00e9quences globales : l&rsquo;abandon de tout espoir de ma\u00eetriser et de contr\u00f4ler la b\u00eate d\u00e9cha\u00een\u00e9e qu&rsquo;est devenu le Pentagone.<\/p>\n<\/p>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Rumsfeld capitule sans conditions 20 septembre 2006 Le monstre, le Mordor de James Carroll, est-il en train de d\u00e9vorer ses enfants? La d\u00e9cision prise par Donald Rumsfeld d&rsquo;autoriser les services \u00e0 n\u00e9gocier directement leurs budgets avec OMB est sans pr\u00e9c\u00e9dent. Elle nous ram\u00e8ne, budg\u00e9tairement parlant, ce qui est l&rsquo;essentiel aujourd&rsquo;hui, \u00e0 la situation d&rsquo;avant 1947,&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[3127,5906,3194,569],"class_list":["post-68007","post","type-post","status-publish","format-standard","hentry","category-faits-et-commentaires","tag-budget","tag-capitulation","tag-pentagone","tag-rumsfeld"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/68007","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=68007"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/68007\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=68007"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=68007"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=68007"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}