{"id":68018,"date":"2006-09-22T00:00:00","date_gmt":"2006-09-22T00:00:00","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2006\/09\/22\/les-doutes-concernant-911-et-5-nouveaux-livres-des-editions-demi-lune-sur-le-sujet\/"},"modified":"2006-09-22T00:00:00","modified_gmt":"2006-09-22T00:00:00","slug":"les-doutes-concernant-911-et-5-nouveaux-livres-des-editions-demi-lune-sur-le-sujet","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2006\/09\/22\/les-doutes-concernant-911-et-5-nouveaux-livres-des-editions-demi-lune-sur-le-sujet\/","title":{"rendered":"Les doutes concernant 9\/11 et 5 nouveaux livres des \u00e9ditions Demi-Lune sur le sujet"},"content":{"rendered":"<p><p>Nous avons re\u00e7u dans notre courrier un message des \u00e9ditions Demi-Lune concernant la question de la validit\u00e9 de la version officielle sur l&rsquo;attaque 9\/11. Ces m\u00eames \u00e9ditions annoncent la sortie de cinq livres sur cette question.<\/p>\n<\/p>\n<p><p>\tL&rsquo;int\u00e9r\u00eat du d\u00e9bat sur cette question autant que l&rsquo;int\u00e9r\u00eat de ce que nous annoncent les \u00e9ditions Demi-Lune nous conduisent \u00e0 publier quelques extraits du message qu&rsquo;elles nous ont fait parvenir dans cette rubrique <em>Bloc-Notes<\/em>.<\/p>\n<\/p>\n<p><p>\t\u00ab<em>Les angles \u00e9ditoriaux des articles ou reportages sur le 11 Septembre 2001<\/p>\n<\/p>\n<p><p>\t\u00e9voluent lentement dans la presse et les m\u00e9dias align\u00e9s. Nous nous en<\/p>\n<\/p>\n<p><p>\tr\u00e9jouissons, m\u00eame si nous sommes encore bien s\u00fbr, tr\u00e8s loin du compte !<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>Il est notable qu&rsquo;ici, en France, le sujet n&rsquo;est plus compl\u00e8tement tabou dans<\/p>\n<\/p>\n<p><p>\tles m\u00e9dias: il devient presque acceptable d&rsquo;exprimer des doutes quant \u00e0 la<\/p>\n<\/p>\n<p><p>\tversion officielle et de (se) poser des questions. En revanche, pour ce qui est<\/p>\n<\/p>\n<p><p>\td&rsquo;obtenir des r\u00e9ponses&#8230; eh bien, soyons optimistes et esp\u00e9rons que ce temps<\/p>\n<\/p>\n<p><p>\taussi arrive, bient\u00f4t !<\/em><\/p>\n<\/p>\n<p><p>\t<a href=\"http:\/\/www.liberation.fr\/transversales\/grandsangles\/203107.FR.php\" class=\"gen\">http:\/\/www.liberation.fr\/transversales\/grandsangles\/203107.FR.php<\/a><\/p>\n<\/p>\n<p><p>\t<a href=\"http:\/\/www.liberation.fr\/culture\/television\/202595.FR.php\" class=\"gen\">http:\/\/www.liberation.fr\/culture\/television\/202595.FR.php<\/a><\/p>\n<\/p>\n<p><p>\t\u00bb<em>Il semble ainsi que Lib\u00e9ration (par exemple) soit maintenant un peu plus en<\/p>\n<\/p>\n<p><p>\tphase avec son lectorat (voir les r\u00e9ponses dans le forum) qu&rsquo;il y a, disons<\/p>\n<\/p>\n<p><p>\tencore quelques mois&#8230;<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\t\u00bb<em>Cinq livres qui font r\u00e9f\u00e9rence dans le monde anglo-saxon (ainsi<\/p>\n<\/p>\n<p><p>\tqu&rsquo;en Italie et en Allemagne), sont enfin disponibles en fran\u00e7ais sur le sujet.<\/p>\n<\/p>\n<p><p>\tIls fondent la contestation \u00e0 la th\u00e8se officielle en asseyant inexorablement sa<\/p>\n<\/p>\n<p><p>\tcr\u00e9dibilit\u00e9. Nous vous invitons \u00e0 en d\u00e9couvrir la pr\u00e9sentation compl\u00e8te et des<\/p>\n<\/p>\n<p><p>\textraits sur notre site<\/em> (<a href=\"http:\/\/www.editionsdemilune.com.\" class=\"gen\"><\/p>\n<\/p>\n<p><p>\thttp:\/\/www.editionsdemilune.com.<\/a>)<\/p>\n<\/p>\n<p><p>\tLes cinq nouveaux livres que proposent les \u00e9ditions Demi-Lune sont les suivants :<\/p>\n<\/p>\n<p><p>\t  <em>Le Nouveau Pearl Harbor<\/em>, de David Ray Griffin ;<\/p>\n<\/p>\n<p><p>\t  <em>Omissions et manipulations de la Commission d&rsquo;enqu\u00eate<\/em>, de David Ray Griffin ;<\/p>\n<\/p>\n<p><p>\t  <em>La Terreur Fabriqu\u00e9e, Made in USA<\/em> de Webster G. Tarpley ;<\/p>\n<\/p>\n<p><p>\t  <em>Le Proc\u00e8s du 11 Septembre<\/em>, de Victor Thorn<\/p>\n<\/p>\n<p><p>\t  <em>La Guerre contre la v\u00e9rit\u00e9<\/em>, de Nafeez Mosaddeq Ahmed.<\/p>\n<\/p>\n<p><p>\tToutes les indications et informations sur ces publications (qui font partie de la collection R\u00e9sistances de l&rsquo;\u00e9diteur) se trouvent sur le site des \u00e9ditions <a href=\"http:\/\/www.editionsdemilune.com\" class=\"gen\">Demi-Lune<\/a>. A signaler que l&rsquo;un des auteurs, Tarpley, \u00e0 Paris depuis le 19 septembre, y sera encore jusqu&rsquo;\u00e0 demain.<\/p>\n<\/p>\n<p><p>\tIl s&rsquo;agit \u00e9videmment d&rsquo;un notable effort d&rsquo;\u00e9dition sur le sujet de l&rsquo;attaque 9\/11 et de la pol\u00e9mique qui entoure les circonstances o\u00f9 s&rsquo;est faite cette attaque. Nous y voyons la confirmation, pour notre part, de ce ph\u00e9nom\u00e8ne <a href=\"http:\/\/www.dedefensa.org\/article.php?art_id=3140\" class=\"gen\">d\u00e9j\u00e0<\/a> signal\u00e9 de l&rsquo;extension dans le domaine public de la mise en question de la version officielle. Importe moins ici, dans tous les cas pour l&rsquo;instant, la manifestation de la v\u00e9rit\u00e9 que la mise en cause du Mensonge g\u00e9n\u00e9ral qu&rsquo;organise le syst\u00e8me lorsqu&rsquo;il pr\u00e9tend imposer, par ses moyens de communication, sa version officielle comme V\u00e9rit\u00e9 du monde. La mise en sc\u00e8ne de 9\/11,  que l&rsquo;attaque soit vraie ou pas  fait partie du Mensonge g\u00e9n\u00e9ral, aujourd&rsquo;hui \u00e9lev\u00e9 au rang d&rsquo;une doctrine pr\u00e9tendant organiser la perception du monde. Cette bataille contre le virtualisme est, comme disait l&rsquo;autre, la m\u00e8re de toutes les batailles.<\/p>\n<\/p>\n<p><\/p>\n<p><p>\tMis en ligne le 22 septembre 2006 \u00e0 06H37<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nous avons re\u00e7u dans notre courrier un message des \u00e9ditions Demi-Lune concernant la question de la validit\u00e9 de la version officielle sur l&rsquo;attaque 9\/11. Ces m\u00eames \u00e9ditions annoncent la sortie de cinq livres sur cette question. L&rsquo;int\u00e9r\u00eat du d\u00e9bat sur cette question autant que l&rsquo;int\u00e9r\u00eat de ce que nous annoncent les \u00e9ditions Demi-Lune nous conduisent&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[2],"tags":[354,370,4926,5918,5921,5919,5446,5920,610],"class_list":["post-68018","post","type-post","status-publish","format-standard","hentry","category-bloc-notes","tag-354","tag-370","tag-complot","tag-demi","tag-livres","tag-lune","tag-officielle","tag-version","tag-virtualisme"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/68018","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=68018"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/68018\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=68018"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=68018"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=68018"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}