{"id":68027,"date":"2006-09-25T00:00:00","date_gmt":"2006-09-25T00:00:00","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2006\/09\/25\/ineluctabilite-et-impossibilite-de-lattaque-us-contre-liran\/"},"modified":"2006-09-25T00:00:00","modified_gmt":"2006-09-25T00:00:00","slug":"ineluctabilite-et-impossibilite-de-lattaque-us-contre-liran","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2006\/09\/25\/ineluctabilite-et-impossibilite-de-lattaque-us-contre-liran\/","title":{"rendered":"In\u00e9luctabilit\u00e9 et impossibilit\u00e9 de l&rsquo;attaque US contre l&rsquo;Iran"},"content":{"rendered":"<p><h2 class=\"common-article\">In\u00e9luctabilit\u00e9 et impossibilit\u00e9 de l&rsquo;attaque US contre l&rsquo;Iran<\/h2>\n<\/p>\n<p><p>\t25 septembre 2006  On a lu Jim Lobe, il y a trois jours, expliquer l&rsquo;\u00e9trange dualit\u00e9 contradictoire entre la diplomatie US d&rsquo;une part, de plus en plus inclin\u00e9e, ou forc\u00e9e \u00e0 \u00eatre inclin\u00e9e \u00e0 l&rsquo;accommodement dans la crise iranienne, et la ligne dure plus que jamais partisane d&rsquo;une attaque de l&rsquo;Iran. <\/p>\n<\/p>\n<p><p>\t<a href=\"http:\/\/www.antiwar.com\/lobe\/?articleid=9725\" class=\"gen\">Lobe<\/a>: \u00ab<em>If you&rsquo;re feeling increasingly confused about whether the administration of President George W. Bush is determined to go to war with Iran or whether it is instead truly committed to a diplomatic process with its European allies to reach some kind of modus vivendi, you&rsquo;re not alone.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>On the one hand, a growing number of informed voices are arguing that the administration is simply going through the diplomatic motions in order to persuade domestic and international opinion that it had acted in good faith before it pulls the plug and launches attacks on Iran&rsquo;s suspected nuclear facilities and related targets some time before the end of Bush&rsquo;s term.<\/em> ()<\/p>\n<\/p>\n<p><p>\t\u00bb<em>On the other hand, a second group of analysts, also increasing in number, believes that the administration has effectively discarded the military option on Iran and has instead resigned itself to a protracted diplomatic process that will likely end in Washington&rsquo;s adoption of a containment strategy designed to curb Tehran&rsquo;s regional influence and delay as long as possible its acquisition of a nuclear-weapons capacity.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\t<a href=\"http:\/\/www.antiwar.com\/hadar\/?articleid=9738\" class=\"gen\">Samedi<\/a>, sur le m\u00eame site <em>Antiwar.com<\/em>, Leon Hadar revient sur le probl\u00e8me et d\u00e9veloppe d&rsquo;abord l&rsquo;argument g\u00e9n\u00e9ral tr\u00e8s solide pour que l&rsquo;attaque US n&rsquo;ait pas lieu : de moins en moins de moyens de le faire, un environnement international de plus en plus hostile \u00e0 cette attaque, etc. Il y ajoute le statut de plus en plus affirm\u00e9 de l&rsquo;Iran dans la r\u00e9gion, son influence grandissante,  essentiellement, bien s\u00fbr, gr\u00e2ce \u00e0 l&rsquo;absurde politique am\u00e9ricaniste, avec ses menaces, ses accusations infond\u00e9es, la brutalit\u00e9 de mani\u00e8re et la m\u00e9diocrit\u00e9 de pens\u00e9e de ceux qui d\u00e9fendent la cause US au niveau international (Bolton, arch\u00e9type du cas), mettant en \u00e9vidence par contraste la finesse et l&rsquo;habilet\u00e9 iraniennes.<\/p>\n<\/p>\n<p><p>\tDu c\u00f4t\u00e9 des partisans de la guerre, quoi? L&rsquo;hyst\u00e9rie belliciste des n\u00e9o-conservateurs, qui est loin d&rsquo;\u00eatre un cas-clinique isol\u00e9, qui serait plut\u00f4t un cas un peu plus affirm\u00e9 d&rsquo;un sentiment g\u00e9n\u00e9ral qui continue \u00e0 pr\u00e9dominer \u00e0 Washington, et qui ne cesse m\u00eame de se renforcer. C&rsquo;est une sorte d&rsquo;affirmation d&rsquo;une lourdeur martiale incroyable, qui n&rsquo;a aucune n\u00e9cessit\u00e9 d&rsquo;\u00eatre d\u00e9montr\u00e9e. Contre toutes les \u00e9vidences accumul\u00e9es ci-dessus, il y a le sentiment irrationnel toujours grandissant qu&rsquo;il est <strong>impensable<\/strong> que Washington n&rsquo;impose pas sa loi et que cette loi ne peut \u00eatre faite que de l&rsquo;airain et du tonnerre de la guerre. Litt\u00e9ralement, la pens\u00e9e washingtonienne est dans une sorte d&rsquo;autisme : elle ne peut penser autrement que dans le sens de la surench\u00e8re.<\/p>\n<\/p>\n<p><p>\tHadar termine son analyse par quelques observations qui nous disent, d&rsquo;une certaine fa\u00e7on en tout illogisme : alors que tout nous dit que l&rsquo;attaque n&rsquo;aura pas lieu, elle aura lieu.<\/p>\n<\/p>\n<p><p>\t\u00ab<em>Instead,<\/em> [Bush-Cheney] <em>are now in the process of writing their historical legacy which will center on their policies in the Middle East. Leaving office with Iraq in ruins and Iran emerging as the military hegemon in the Persian Gulf  equipped with nuclear military power!  would damage whatever remains of the Bush-Cheney legacy.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>While the possibility of the Democrats taking over the House of Representatives and even the Senate could make it difficult for the administration to deploy more troops in Iraq, it will not face major opposition from the mostly pro-Israeli Democrats on Capitol Hill if and when it decides to take military action against Iran.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>Of course, there is another way for Mr. Bush and Mr. Cheney to deal with the challenges they are facing in the Middle East: a diplomatic dialogue with Iran (and Syria) combined with an effort to revive the Israeli-Palestinian peace process. But for an administration that has portrayed the Iranian regime as a member of the axis of evil and has placed itself squarely behind Israel, such a move would be out of character.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tIl y a d&rsquo;autres indications allant dans le sens d&rsquo;une interpr\u00e9tation belliciste pour nous dire : oui, malgr\u00e9 toutes les apparences vertueuses de la diplomatie, malgr\u00e9 toutes les perspectives de n\u00e9gociations, Washington tapera sur T\u00e9h\u00e9ran.<\/p>\n<\/p>\n<p><p>\t  Un article du 21 septembre de Larisa Alexandrovna, sur le site <a href=\"http:\/\/www.rawstory.com\/news\/2006\/Pentagon_moves_to_secondstage_planning_for_0921.html\" class=\"gen\">RAW Story<\/a>, est l&rsquo;une de ces indications : <\/p>\n<\/p>\n<p><p>\t\u00ab<em>The Pentagon&rsquo;s top brass has moved into second-stage contingency planning for a potential military strike on Iran, one senior intelligence official familiar with the plans tells RAW STORY.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>The official, who is close to the Joint Chiefs of Staff, the highest ranking officials of each branch of the US military, says the Chiefs have started what is called branches and sequels contingency planning.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>The JCS has accepted the inevitable, the intelligence official said, and is engaged in serious contingency planning to deal with the worst case scenarios that the intelligence community has been painting.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\t  Il est fait grand cas des avis du colonel (\u00e0 la retraite) Gardiner, qu&rsquo;on dit fort proche du Pentagone. D&rsquo;o\u00f9 l&rsquo;int\u00e9r\u00eat de la publication de son rapport \u00ab<em>The end of the summer diplomacy  Assessing U.S. Military options on Iran<\/em>\u00bb, disponible sur le site de <a href=\"http:\/\/www.tcf.org\/publications\/internationalaffairs\/gardiner_summer_diplomacy.pdf\" class=\"gen\">The Century Foundation<\/a>. On y trouve les d\u00e9tails de l&rsquo;attaque telle qu&rsquo;elle aura lieu <strong>de toutes les fa\u00e7ons<\/strong>. Pour un peu, on disposerait m\u00eame des r\u00e9sultats<\/p>\n<h3>\u00ab<em>As crazy as it sounds&#8230;<\/em>\u00bb<\/h3>\n<\/p>\n<p><p>\tQue conclure de ces attitudes et appr\u00e9ciations contradictoires ? On peut faire comme Jim Lobe, les constater et tenter d&rsquo;\u00e9tablir une comparaison, pour voir quelle partie progresse et quelle partie recule. C&rsquo;est faire un travail d&rsquo;analyse rationnelle qui a sa raison d&rsquo;\u00eatre mais qui semble si peu correspondre \u00e0 la r\u00e9alit\u00e9 de la situation \u00e0 Washington. Une autre possibilit\u00e9 existe, correspondant mieux \u00e0 la psychologie am\u00e9ricaniste qui domine aujourd&rsquo;hui dans cette capitale. Elle fait la part belle, essentielle voire exclusive \u00e0 l&rsquo;irrationnel, et c&rsquo;est elle que nous privil\u00e9gions.<\/p>\n<\/p>\n<p><p>\tLorsqu&rsquo;on envisage la possibilit\u00e9 d&rsquo;une attaque contre l&rsquo;Iran, tout le monde pense au pr\u00e9c\u00e9dent de l&rsquo;attaque contre l&rsquo;Irak. Les m\u00eames proc\u00e9d\u00e9s sont d\u00e9velopp\u00e9s, comme les pressions faites <a href=\"http:\/\/www.dedefensa.org\/article.php?art_id=3080\" class=\"gen\">sur la CIA<\/a> pour obtenir un renseignement sur mesure pour justifier la guerre.<\/p>\n<\/p>\n<p><p>\tLe grand fait, la grande diff\u00e9rence par rapport \u00e0 la situation pr\u00e9-irakienne \u00e0 laquelle tout le monde pense, c&rsquo;est \u00e9videmment l&rsquo;\u00e9tat de la puissance US. Cette puissance est consid\u00e9rablement diminu\u00e9e et, par cons\u00e9quent, elle r\u00e9duit tout aussi consid\u00e9rablement les options. Elle constitue un fardeau psychologique d&rsquo;un poids incroyable.<\/p>\n<\/p>\n<p><p>\tDans le cas iranien, \u00e0 part l&rsquo;option a\u00e9rienne, rien de bien s\u00e9rieux ne peut \u00eatre envisag\u00e9 (m\u00eame si l&rsquo;on signale des activit\u00e9s de forces sp\u00e9ciales US en Iran, ce qui n&rsquo;est pourtant pas confirm\u00e9). Cette situation est un fait op\u00e9rationnel qui est pris en consid\u00e9ration dans la comptabilit\u00e9 des attaques possibles, mais sans qu&rsquo;une conclusion plus large ne soit tir\u00e9e. Personne n&rsquo;ose \u00e9crire que le roi est nu.<\/p>\n<\/p>\n<p><p>\tCette situation de la faiblesse militaire US est surtout un frein psychologique, certainement inconscient pour l&rsquo;essentiel, qui n&rsquo;est nulle part pr\u00e9sent\u00e9 \u00e0 hauteur de son importance r\u00e9elle (sauf dans le chef de quelques dissidents). Ce frein psychologique joue pourtant, \u00e0 notre sens, un r\u00f4le consid\u00e9rable.<\/p>\n<\/p>\n<p><p>\tLes affirmations d&rsquo;attaques n\u00e9cessaires et in\u00e9vitables surgissent de fa\u00e7on \u00e9pisodique, comme des spasmes, mais sans la moindre continuit\u00e9 et sans une progression  notable qui soit continue et r\u00e9ponde \u00e0 une v\u00e9ritable mont\u00e9e en puissance, comme dans le cas irakien en 2002-2003. Le rapport <em>authoritative<\/em> du colonel Gardiner n&rsquo;est pas le premier du genre, dans l&rsquo;esprit dans tous les cas. On en voit d\u00e9filer de semblables depuis plusieurs mois, qui alimentent l&rsquo;affirmation d&rsquo;une attaque in\u00e9luctable. Aucun ne r\u00e8gle pourtant le cas.<\/p>\n<\/p>\n<p><p>\tLa position des chefs militaires est du m\u00eame type. Elle est r\u00e9guli\u00e8rement pr\u00e9sent\u00e9e comme acquise apr\u00e8s un d\u00e9bat douloureux, les militaires acceptant finalement la perspective de l&rsquo;attaque. Puis de nouvelles informations viennent d\u00e9mentir cette acceptation pr\u00e9sent\u00e9e comme finale, pour nous informer d&rsquo;une nouvelle remise en cause de l&rsquo;attaque. Il y a le cas de Seymour Hersh, annon\u00e7ant (le 9 avril) que le principe de l&rsquo;attaque est <a href=\"http:\/\/www.dedefensa.org\/article.php?art_id=2589\" class=\"gen\">acquis<\/a>, \u00e9ventuellement avec du nucl\u00e9aire, puis montrant (le 3 juillet) comment le cas a \u00e9t\u00e9 revu, notamment avec <a href=\"http:\/\/www.dedefensa.org\/article.php?art_id=2862\" class=\"gen\">l&rsquo;abandon<\/a> de l&rsquo;option nucl\u00e9aire. Hersh fait-il du sensationnalisme? Toute sa carri\u00e8re nous montre que non. Il rapporte les soubresauts, les spasmes de la direction washingtonienne sur laquelle p\u00e8se cette terrible pression inconsciente de la puissance militaire dans un d\u00e9clin acc\u00e9l\u00e9r\u00e9, proche d&rsquo;\u00eatre rendue impuissante par rapport aux ambitions politiques.<\/p>\n<\/p>\n<p><p>\tLe tableau qui surgit est contrast\u00e9. Tant\u00f4t, l&rsquo;attaque para\u00eet \u00e9vidente, tant\u00f4t c&rsquo;est tout juste si on y pense encore. M\u00eame les n\u00e9o-conservateurs sont parfois \u00e0 court de souffle. Partout \u00e0 Washington r\u00e8gne une atmosph\u00e8re, un conformisme de fer qui emprisonne la pens\u00e9e am\u00e9ricaniste avec sa psychologie malade dans ce caract\u00e8re d&rsquo;in\u00e9luctabilit\u00e9 de l&rsquo;attaque. Il s&rsquo;agit d&rsquo;une sc\u00e8ne compl\u00e8tement virtualiste, qui d\u00e9crit beaucoup plus une impuissance compl\u00e8te avec les tourments psychologiques qui l&rsquo;accompagnent, les erreurs d&rsquo;\u00e9valuation qui la ponctuent, les fausses appr\u00e9ciations qui s&rsquo;en d\u00e9duisent. La conclusion peut \u00eatre emprunt\u00e9e \u00e0 Charlie Reese le 23 septembre sur <a href=\"http:\/\/www.antiwar.com\/reese\/?articleid=9736\" class=\"gen\">Antiwar.com<\/a> : \u00ab<em>As crazy as it sounds, President George Bush might be planning to bomb Iran&rsquo;s nuclear facilities.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\t<em>Crazy<\/em> (traduction facile) est le mot qui convient. Ce n&rsquo;est pas la premi\u00e8re ni derni\u00e8re analyse sur l&rsquo;in\u00e9luctabilit\u00e9 d&rsquo;une attaque qui est pourtant impossible que nous offrons \u00e0 nos lecteurs. Parfois, cela para\u00eet \u00eatre une r\u00e9p\u00e9tition sans but et sans fin. D&rsquo;une certaine fa\u00e7on, c&rsquo;est le cas : une sorte de balbutiement convulsif qui n&rsquo;est pas loin du d\u00e9s\u00e9quilibre mental.<\/p>\n<\/p>\n<p><p>\tIl y a un prix \u00e0 payer dans la r\u00e9alit\u00e9. Il sera de plus en plus fort. On en voit une indication dans notre Bloc-Notes&rsquo; d&rsquo;<a href=\"http:\/\/www.dedefensa.org\/article.php?art_id=3188\" class=\"gen\">hier<\/a>. La situation irrationnelle de Washington, entre n\u00e9cessit\u00e9 d&rsquo;agir et impossibilit\u00e9 d&rsquo;agir, entre affirmation belliqueuse et impuissance des moyens, produit l&rsquo;effet de l&rsquo;affaiblissement constant de la perception qu&rsquo;on a de la puissance am\u00e9ricaniste. Cela n&rsquo;est pas une nouvelle qui se proclame au jour le jour, sauf dans l&rsquo;une ou l&rsquo;autre occasion ; c&rsquo;est une tendance de fond, puissante et irr\u00e9sistible, qui s&rsquo;impose dans les esprits par le biais de la perception de la psychologie.<\/p>\n<\/p>\n<p><p>\tIl ne faut pas se bercer d&rsquo;espoirs fallacieux. C&rsquo;est un paradoxe incroyable mais bien r\u00e9el, parce que l&rsquo;Iran est effectivement un cas plus s\u00e9rieux (du point de vue de la puissance) que le montage pitoyable fait autour de la puissance irakienne en 2002-2003 : l&rsquo;accord est bien plus g\u00e9n\u00e9ral \u00e0 Washington sur la n\u00e9cessit\u00e9 d&rsquo;\u00e9liminer la puissance iranienne qu&rsquo;il n&rsquo;\u00e9tait dans le cas de l&rsquo;Irak. En quelque sorte, la folle tromperie du cas en faveur de l&rsquo;attaque de l&rsquo;Irak impose de prendre bien plus au s\u00e9rieux encore le cas iranien,  sorte d&rsquo;encha\u00eenement g\u00e9n\u00e9ral du virtualisme <a href=\" http:\/\/www.dedefensa.org\/article.php?art_id=3080\" class=\"gen\">au second degr\u00e9<\/a>, comme on a d\u00e9j\u00e0 vu dans le cas sp\u00e9cifique de la CIA&#8230; <\/p>\n<\/p>\n<p><p>\tL&rsquo;analyse faite ici d\u00e9passe compl\u00e8tement le cas GW Bush, qui para\u00eet en l&rsquo;occurrence plus un bouchon sur une mer d\u00e9cha\u00een\u00e9e qu&rsquo;un pseudo-chef de guerre d\u00e9cid\u00e9 \u00e0 en d\u00e9coudre. La description que nous faisons de Washington d\u00e9passe l&rsquo;administration Bush et ses manigances et la situation qu&rsquo;elle restitue est destin\u00e9e \u00e0 durer et durer, au-del\u00e0 de 2008 s&rsquo;il le faut. C&rsquo;est la description de la d\u00e9cadence finale de la puissance am\u00e9ricaniste.<\/p>\n<\/p>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>In\u00e9luctabilit\u00e9 et impossibilit\u00e9 de l&rsquo;attaque US contre l&rsquo;Iran 25 septembre 2006 On a lu Jim Lobe, il y a trois jours, expliquer l&rsquo;\u00e9trange dualit\u00e9 contradictoire entre la diplomatie US d&rsquo;une part, de plus en plus inclin\u00e9e, ou forc\u00e9e \u00e0 \u00eatre inclin\u00e9e \u00e0 l&rsquo;accommodement dans la crise iranienne, et la ligne dure plus que jamais partisane&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[5680,5616,857,2773,610],"class_list":["post-68027","post","type-post","status-publish","format-standard","hentry","category-faits-et-commentaires","tag-consensus","tag-impuissance","tag-irak","tag-iran","tag-virtualisme"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/68027","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=68027"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/68027\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=68027"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=68027"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=68027"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}