{"id":68165,"date":"2006-11-04T00:00:00","date_gmt":"2006-11-04T00:00:00","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2006\/11\/04\/le-civil-cest-aussi-lennemmi\/"},"modified":"2006-11-04T00:00:00","modified_gmt":"2006-11-04T00:00:00","slug":"le-civil-cest-aussi-lennemmi","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2006\/11\/04\/le-civil-cest-aussi-lennemmi\/","title":{"rendered":"Le civil, c&rsquo;est aussi l&rsquo;ennemmi"},"content":{"rendered":"<p><h2>Le civil, c&rsquo;est aussi l&rsquo;ennemmi<\/h2>\n<\/p>\n<blockquote>\n<p><p>Pour l&rsquo;am\u00e9ricanisme, le civil de la nation ennemie est-il un ennemi ? &mdash; La question de l&rsquo;individualisme<\/p>\n<\/p>\n<\/blockquote>\n<p><p>Les consid\u00e9rables pertes civiles caus\u00e9es par le conflit irakien &mdash; le chiffre de <a class=\"gen\" href=\"http:\/\/www.dedefensa.org\/article.php?art_id=3258\">655.000 morts<\/a> depuis 2003 est d\u00e9sormais assur\u00e9 d&rsquo;\u00eatre une r\u00e9f\u00e9rence &mdash; conduisent \u00e0 s&rsquo;interroger sur la question des pertes civiles caus\u00e9es par la guerre dans l&rsquo;esprit am\u00e9ricaniste. Ces 655.000 victimes ne sont pas \u00e0 mettre sous la seule responsabilit\u00e9 de l&rsquo;action am\u00e9ricaniste mais elles indiquent bien la tendance des conflits d\u00e9clench\u00e9s par les USA aujourd&rsquo;hui, et inspir\u00e9s par leurs m\u00e9thodes sans aucun doute ; elles l&rsquo;indiquent d&rsquo;autant plus lorsqu&rsquo;on compare ces pertes civiles aux pertes militaires US en Irak de pr\u00e8s de 3.000 morts depuis 2003.<\/p>\n<\/p>\n<p><p>(Le terrorisme et la gu\u00e9rilla, qui sont \u00e9galement impliqu\u00e9s dans ces conflits, frappent \u00e9galement les civils, ce qui alourdit \u00e9videmment les pertes. Mais leurs intentions sont diff\u00e9rentes. Nous analysons ici une attitude am\u00e9ricaniste \u00e9ventuelle, d\u00e9barrass\u00e9e de toute contrainte technique et op\u00e9rationnelle \u00e0 l&rsquo;\u00e9gard du probl\u00e8me consid\u00e9r\u00e9.)<\/p>\n<\/p>\n<p><h3 class=\"subtitleset_b.deepblue\" style=\"color:#0f3955; font-size:1.65em; font-variant:small-caps\">Une doctrine a\u00e9rienne pour les psychologies<\/h3>\n<\/p>\n<p><p>On sait par ailleurs que l&rsquo;action <strong>sur<\/strong> (et non \u00ab\u00a0contre\u00a0\u00bb) les civils joue un r\u00f4le important dans les plans strat\u00e9giques US. L&rsquo;id\u00e9e est \u00e0 la base de la violence des offensives a\u00e9riennes que privil\u00e9gient les Am\u00e9ricains, selon une doctrine qui vise autant les psychologies que les objectifs mat\u00e9riels.<\/p>\n<\/p>\n<p><p>On cite ici le journaliste du <em>New Yorker<\/em> Seymour Hersh, dont nous signalions la d\u00e9claration dans un r\u00e9cent (<a class=\"gen\" href=\"http:\/\/www.dedefensa.org\/article.php?art_id=3040\">15 ao&ucirc;t<\/a>) &lsquo;Bloc-Notes&rsquo; (Hersh parle des Isra\u00e9liens mais, en l&rsquo;occurrence, nous consid\u00e9rons les Isra\u00e9liens comme totalement <a class=\"gen\" href=\"http:\/\/www.dedefensa.org\/article.php?art_id=3128\">\u00ab\u00a0am\u00e9ricanis\u00e9s\u00a0\u00bb<\/a> dans leur fa\u00e7on de faire la guerre) :<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em\">\n<p><p>&laquo; <em>Il y avait un autre \u00e9l\u00e9ment, et vous l&rsquo;avez mentionn\u00e9 dans votre introduction et \u00e9galement dans votre reportage. Une des choses qui m&rsquo;a tout de suite frapp\u00e9, d\u00e8s que j&rsquo;ai vu comment Isra\u00ebl bombardait, et mon instinct m&rsquo;a dit qu&rsquo;il y avait quelque chose l\u00e0-dedans, parce que dans l&rsquo;un des plans de l&rsquo;USAF que je connaissais mais sur lequel je n&rsquo;ai pas \u00e9crit, l&rsquo;une des options de l&rsquo;USAF pour \u00e9liminer l&rsquo;Iran a \u00e9t\u00e9, bien s&ucirc;r, la doctrine &lsquo;<a href=\"https:\/\/www.dedefensa.org\/article\/le-cur-du-sujet\">Schock &#038; Awe<\/a>&lsquo;, un bombardement massif, massif, bien au-del\u00e0 de toutes les installations nucl\u00e9aires. Allez frapper durement le pays pendant 36 heures, conduisez les gens dans des bunkers souterrains. Ne ciblez pas n\u00e9cessairement les civils, mais frappez leurs infrastructures, frappez les routes, frappez les centrales \u00e9lectriques, frappez les installations d&rsquo;approvisionnement en eau<\/em>.<\/p>\n<\/p>\n<p><p>&raquo; <em>Alors, quand ils sortent de leurs bunkers apr\u00e8s 36 heures, ils regardent autour d&rsquo;eux. Dans la vision n\u00e9o-conservatrice am\u00e9ricaine, ils allaient se dire : \u00ab\u00a0Oh, mon Dieu, ce sont les mollahs qui nous ont fait \u00e7a, les mollahs religieux qui dirigent le pays. Nous allons les renverser et installer un gouvernement la\u00efc\u00a0\u00bb. C&rsquo;\u00e9tait la r\u00e9flexion de l&rsquo;ann\u00e9e derni\u00e8re. C&rsquo;est la r\u00e9flexion men\u00e9e l&rsquo;ann\u00e9e derni\u00e8re au sein de certains \u00e9l\u00e9ments du Pentagone, du c\u00f4t\u00e9 civil, ainsi que dans l&rsquo;\u00e9quipe Cheney<\/em>. &raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><h3 class=\"subtitleset_b.deepblue\" style=\"color:#0f3955; font-size:1.65em; font-variant:small-caps\">La le\u00e7on de Curtiss LeMay<\/h3>\n<\/p>\n<p><p>Dans la description que fait Hersh, le civil n&rsquo;est pas consid\u00e9r\u00e9 comme un \u00ab\u00a0ennemi\u00a0\u00bb mais comme un \u00ab\u00a0individu dans l&rsquo;erreur\u00a0\u00bb (volontairement ou pas, peu importe) qu&rsquo;il s&rsquo;agit de \u00ab\u00a0convaincre\u00a0\u00bb, par le choc de la violence, de rectifier son erreur. On peut penser qu&rsquo;il s&rsquo;agit d&rsquo;une nuance et rien d&rsquo;autre.<\/p>\n<\/p>\n<p><p>Dans la conception implicite de l&rsquo;am\u00e9ricanisme, l'\u00a0\u00bbennemi\u00a0\u00bb est un \u00ab\u00a0individu dans l&rsquo;erreur\u00a0\u00bb puisqu&rsquo;il n&rsquo;est pas am\u00e9ricanis\u00e9. Le sort qui lui est r\u00e9serv\u00e9 d\u00e9pend de la fortune des armes, et aussi de leur sophistication. Aujourd&rsquo;hui, on est inclin\u00e9 \u00e0 pr\u00e9tendre le convaincre de son erreur sans avoir \u00e0 le tuer puisqu&rsquo;on dispose en principe d&rsquo;armes suffisamment pr\u00e9cises pour lui faire subir une violence qui le convaincra, sans devoir le tuer &mdash; tout cela en th\u00e9orie, selon la pr\u00e9cision sophistiqu\u00e9e des armes. (Il est \u00e9vident, pour la suite, qu&rsquo;ayant renvers\u00e9 le pouvoir usurpateur, l&rsquo;individu ainsi \u00ab\u00a0converti\u00a0\u00bb en installera un autre dont la mission sera de coordonner l&rsquo;am\u00e9ricanisation g\u00e9n\u00e9rale &mdash; la sienne propre et celle de son cadre de vie.)<\/p>\n<\/p>\n<p><p>L&rsquo;id\u00e9e n&rsquo;est donc pas du tout diff\u00e9rente de celle qui pr\u00e9sidait aux bombardements strat\u00e9giques de la Deuxi\u00e8me Guerre mondiale, lorsqu&rsquo;on en confie l&rsquo;expos\u00e9 \u00e0 celui qui fut l&rsquo;architecte de cette sorte d&rsquo;action militaire. Il s&rsquo;agit du g\u00e9n\u00e9ral Curtiss LeMay.<\/p>\n<\/p>\n<p><p>Dans son <em>House of War<\/em>, James Carroll cite LeMay, d\u00e9clarant (d&rsquo;apr\u00e8s Sherry, <em>The Rise of American Air Power<\/em>) \u00e0 propos des campagnes de bombardement strat\u00e9gique &mdash; au Japon dans ce cas mais il est \u00e9vident que chaque cible fait l&rsquo;affaire :<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em\">\n<p><p>&laquo;<em>Nous avions l&rsquo;intention de rechercher et de d\u00e9truire l&rsquo;ennemui o&ugrave; qu&rsquo;il ou qu&rsquo;elle se trouve dans le plus grand nombre possible, dans le temps le plus court possible. Pour nous, il n&rsquo;y avait pas de civils au Japon, mais que des ennemis qu&rsquo;il fallait d\u00e9truire jusqu&rsquo;au dernier.. .<\/em>&raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>Ou, dit en d&rsquo;autres termes : le \u00ab\u00a0civil\u00a0\u00bb n&rsquo;est pas moins un \u00ab\u00a0ennemi\u00a0\u00bb que le soldat. L\u00e0 encore, on nuancera le mot \u00ab\u00a0ennemi\u00a0\u00bb en fonction de ce qui a \u00e9t\u00e9 dit plus haut : \u00ab\u00a0celui qui est en attente d&rsquo;\u00eatre am\u00e9ricanis\u00e9\u00a0\u00bb. Avec LeMay, pas de chance &mdash; \u00ab\u00a0l&rsquo;ennemi\u00a0\u00bb \u00e9tait en g\u00e9n\u00e9ral tu\u00e9 avant d&rsquo;\u00eatre am\u00e9ricanis\u00e9. (A moins que &mdash; hypoth\u00e8se gratuite &mdash; le tuer revient \u00e0 l&rsquo;am\u00e9ricaniser ?)<\/p>\n<\/p>\n<p><h3 class=\"subtitleset_b.deepblue\" style=\"color:#0f3955; font-size:1.65em; font-variant:small-caps\">L&rsquo;hypoth\u00e8se du \u00ab\u00a0fondamentalisme individualiste\u00a0\u00bb<\/h3>\n<\/p>\n<p><p>Pourquoi l&rsquo;individu civil est-il englob\u00e9 sans restriction dans la vindicte guerri\u00e8re de l&rsquo;Am\u00e9rique? La dur\u00e9e et la constance de cette perception nous assurent qu&rsquo;il y a bien autre chose que les sentiments n\u00e9s des exc\u00e8s de tel ou tel conflit.<\/p>\n<\/p>\n<p><p>(M\u00eame le conflit central de l&rsquo;histoire am\u00e9ricaniste a montr\u00e9 cette m\u00eame vindicte : la destruction du Sud par le Nord dans la derni\u00e8re partie de la Guerre de S\u00e9cession impliquait express\u00e9ment, selon les ordres de Lincoln et de Grant \u00e0 leurs g\u00e9n\u00e9raux, une attaque directe contre les civils sudistes. Il y a toujours eu des pertes civiles dans les conflits, par vengeance, col\u00e8re, volont\u00e9 d&rsquo;\u00e9limination syst\u00e9matique, etc. Dans le cas de Lincoln-Grant, comme en t\u00e9moignent leurs consignes, il y a une consigne syst\u00e9matique qui ne comporte aucune vindicte mais un projet constructif : d\u00e9truire une culture pour permettre une nouvelle culture qui sera am\u00e9ricaniste. Une \u00ab\u00a0<em>creative destruction<\/em>\u00a0\u00bb avant l&rsquo;heure. Peut-on rapprocher cette consigne du \u00ab\u00a0<em>Tuez-les tous, Dieu reconna&icirc;tra les siens<\/em>\u00a0\u00bb de Simon de Montfort ? Peut-\u00eatre, sauf que Montfort parlait en fonction de l&rsquo;accession au Royaume de Dieu et que dans le cadre de cette logique la mort n&rsquo;est pas vraiment destructrice.)<\/p>\n<\/p>\n<p><p>On propose l&rsquo;hypoth\u00e8se qu&rsquo;il existe dans cette d\u00e9marche une logique r\u00e9pondant \u00e0 la psychologie am\u00e9ricaniste et aux conceptions qu&rsquo;elle engendre &mdash; une sorte de \u00ab\u00a0raison am\u00e9ricaniste\u00a0\u00bb si l&rsquo;on veut, n\u00e9e d&rsquo;une psychologie compl\u00e8tement sp\u00e9cifique. Nous proposons une explication dans la notion fondamentale d&rsquo;individualisme qui caract\u00e9rise le syst\u00e8me ; une notion si radicale, si extr\u00eame que nous aurions tendance \u00e0 l&rsquo;habiller d&rsquo;un atour id\u00e9ologique en la qualifiant de \u00ab\u00a0fondamentalisme individualiste\u00a0\u00bb.<\/p>\n<\/p>\n<p><h3 class=\"subtitleset_b.deepblue\" style=\"color:#0f3955; font-size:1.65em; font-variant:small-caps\">Le refus de toute substance de nation<\/h3>\n<\/p>\n<p><p>L&rsquo;individualisme am\u00e9ricain est une notion identifiable non par rapport \u00e0 l&rsquo;individu seul, sa culture, sa psychologie, etc., &mdash; comme cela est fait d&rsquo;habitude &mdash; mais en fonction essentiellement des rapports ou\/et des liens entre l&rsquo;individu et les structures o&ugrave; il vit, et notamment la structure soi-disant politique du gouvernement. L&rsquo;individu est d\u00e9clar\u00e9 enti\u00e8rement responsable dans la mesure contraire o&ugrave; le gouvernement et les autres structures o&ugrave; il \u00e9volue n&rsquo;existent qu&rsquo;au regard de son attribution et sa fonction, et n&rsquo;ont aucune existence substantielle.<\/p>\n<\/p>\n<p><p>Cette id\u00e9e s&rsquo;appuie sur l&rsquo;absence compl\u00e8te, dans l&rsquo;esprit am\u00e9ricaniste conform\u00e9 par sa psychologie, de l&rsquo;id\u00e9e du bien public, de la fonction r\u00e9galienne, de la transcendance qui caract\u00e9riserait une nation dans sa d\u00e9finition historique, qui donneraient aux repr\u00e9sentations de l&rsquo;autorit\u00e9, par la l\u00e9gitimit\u00e9 repr\u00e9sentant la souverainet\u00e9 de l&rsquo;ensemble, une capacit\u00e9 de transcender une vocation collective qui serait en substance diff\u00e9rente (et sans doute sup\u00e9rieure) de l&rsquo;addition des vocations des individus formant la collectivit\u00e9. L&rsquo;id\u00e9e am\u00e9ricaniste est que la \u00ab\u00a0nation\u00a0\u00bb n&rsquo;a pas de substance, d&rsquo;\u00eatre propre.<\/p>\n<\/p>\n<p><p>Cette responsabilit\u00e9 exclusive et fondamentale de l&rsquo;individu s&rsquo;entend d&rsquo;abord dans son r\u00f4le dans le cadre du respect des termes du contrat qui le lie aux structures o&ugrave; il \u00e9volue. Le conformisme am\u00e9ricaniste a un aspect utilitariste compl\u00e8tement fondamental : tout le monde a <strong>int\u00e9r\u00eat<\/strong> \u00e0 ce que le syst\u00e8me subsiste dans sa forme. Tout le monde agit dans ce sens. Les plus riches sont capables de donner une partie de leurs avoirs pour susciter des organisations collectives (fondations) qui formeront des individus pour devenir des \u00ab\u00a0cadres\u00a0\u00bb du syst\u00e8me. La fameuse charit\u00e9 am\u00e9ricaine est la fonction de l&rsquo;individu substituant, dans les \u00e9tats de crise, aux fonctions r\u00e9galiennes de protection des citoyens qui n&rsquo;existent pas aux USA une fonction d&rsquo;aide temporaire \u00e0 l&rsquo;individu d\u00e9muni pour l&rsquo;aider \u00e0 redevenir un individu conforme \u00e0 l&rsquo;am\u00e9ricanisme.<\/p>\n<\/p>\n<p><p>Cette position de responsabilit\u00e9 individuelle contractuelle confirme par ailleurs la tradition protestante comme son extension moderniste \u00e9largie aux domaines divers de la vie publique. Elle se nourrit \u00e0 cette tradition et la nourrit en retour (le \u00ab\u00a0contrat\u00a0\u00bb est rempli, l\u00e0 aussi). On retrouve dans la d\u00e9marche d\u00e9crite ici le rejet protestant de toute autorit\u00e9 et de toute hi\u00e9rarchie par o&ugrave; transiteraient les rapports de l&rsquo;individu-croyant avec Dieu. Dans ce cas \u00e9galement, la responsabilit\u00e9 individuelle est enti\u00e8re.<\/p>\n<\/p>\n<p><h3 class=\"subtitleset_b.deepblue\" style=\"color:#0f3955; font-size:1.65em; font-variant:small-caps\">Les individus sont cr\u00e9ateurs de la nation<\/h3>\n<\/p>\n<p><p>Poussant cette logique, on est conduit \u00e0 constater qu&rsquo;il n&rsquo;y a pas de \u00ab\u00a0citoyen d&rsquo;une nation\u00a0\u00bb pour l&rsquo;am\u00e9ricaniste. Il n&rsquo;y a pas de citoyens ou\/et de patriotes en tant qu&rsquo;individus transform\u00e9s par l&rsquo;appartenance \u00e0 une nation, qui sont ce qu&rsquo;ils sont devenus, notamment mais puissamment, parce que leur psychologie les attache \u00e0 la nation pr\u00e9existante \u00e0 eux, du point de vue spirituel, par transcendance. Ils ne sauraient \u00eatre parties d&rsquo;un Grand Tout terrestre (la nation au sens r\u00e9galien) qui aurait une existence spirituelle propre. Il n&rsquo;y a que des individus, dont chacun d&rsquo;eux est unique par lui-m\u00eame. Ces individus acceptent par contrat de se regrouper en une nation. Ils sont cr\u00e9ateurs de la nation, laquelle n&rsquo;est faite que de l&rsquo;addition des individus et n&rsquo;est rien sans eux.<\/p>\n<\/p>\n<p><p>La conception que chaque individu est totalement responsable se retrouve fortement et naturellement au travers de ces constats. Les individus assument \u00e9galement les engagements de la partie \u00e0 laquelle ils sont contractuellement rattach\u00e9s, la nation en l&rsquo;occurrence. (Le syst\u00e8me am\u00e9ricaniste ne peut \u00eatre \u00e0 cet \u00e9gard que d\u00e9mocratique, d&rsquo;un point de vue technique plus que vertueux.)<\/p>\n<\/p>\n<p><p>L&rsquo;am\u00e9ricaniste projette cette id\u00e9e chez l'\u00a0\u00bbautre\u00a0\u00bb (le soi-disant et pas pour longtemps non-am\u00e9ricaniste) parce qu&rsquo;il est incapable d&rsquo;en concevoir une autre (principalement l&rsquo;id\u00e9e du citoyen comme partie d&rsquo;un tout transcend\u00e9) ; parce que les conditions de formation de l&rsquo;Am\u00e9rique sont exceptionnelles et assurent que le contrat sign\u00e9 est lui-m\u00eame exceptionnel et le seul d\u00e9sirable et acceptable.<\/p>\n<\/p>\n<p><p>L&rsquo;am\u00e9ricaniste d\u00e9duit de ces conceptions :<\/p>\n<\/p>\n<p><p>&bull; que le civil d&rsquo;une autre nation qui s&rsquo;est r\u00e9v\u00e9l\u00e9e \u00eatre une ennemie (toutes le sont potentiellement puisque l&rsquo;Am\u00e9rique est le seul contrat \u00ab\u00a0d\u00e9sirable et acceptable\u00a0\u00bb) est autant ennemi que le contractant principal, et contractant exclusif de la guerre, sa nation. L&rsquo;am\u00e9ricaniste ne fait pas de diff\u00e9rence entre la nation et ses outils de guerre (le gouvernement, l&rsquo;arm\u00e9e, l&rsquo;armement) d&rsquo;une part, et les citoyens civils qui sont d&rsquo;habitude consid\u00e9r\u00e9s comme en dehors des fatalit\u00e9s de la guerre d&rsquo;autre part ;<\/p>\n<\/p>\n<p><p>&bull; que ce civil est d&rsquo;autant plus responsable et donc justement soumis aux pressions de l&rsquo;am\u00e9ricaniste qu&rsquo;il est manifeste qu&rsquo;il ne peut d\u00e9sirer longtemps rester dans un contrat si peu int\u00e9ressant par rapport \u00e0 celui que lui offre l&rsquo;am\u00e9ricanisation ;<\/p>\n<\/p>\n<p><p>&bull; que le sort du civil devra donc \u00eatre d&rsquo;accepter l&rsquo;am\u00e9ricanisation avec empressement ou de subir le sort de la nation \u00ab\u00a0ennemie\u00a0\u00bb (quand elle s&rsquo;est r\u00e9v\u00e9l\u00e9e telle) ;<\/p>\n<\/p>\n<p><p>&bull; que la guerre contre une nation \u00ab\u00a0ennemie\u00a0\u00bb devra \u00eatre dans un premier temps l&rsquo;\u00e9limination maximale, avec tous les moyens de la puissance aveugle, de tout ce qui fait partie de cet \u00ab\u00a0ennemi\u00a0\u00bb, et, dans un deuxi\u00e8me temps, la soumission \u00e9ducatrice et vertueuse \u00e0 un processus d&rsquo;am\u00e9ricanisation de ce qui aura \u00e9chapp\u00e9 \u00e0 la destruction.<\/p>\n<\/p>\n<p><h3 class=\"subtitleset_b.deepblue\" style=\"color:#0f3955; font-size:1.65em; font-variant:small-caps\">Diff\u00e9rence avec la \u00ab\u00a0responsabilit\u00e9 collective\u00a0\u00bb<\/h3>\n<\/p>\n<p><p>Pour autant, il n&rsquo;y a pas n\u00e9cessairement de \u00ab\u00a0responsabilit\u00e9 collective\u00a0\u00bb, comme certains forment l&rsquo;accusation de \u00ab\u00a0responsabilit\u00e9 collective\u00a0\u00bb dans le cas de l&rsquo;Holocauste des juifs, \u00e0 l&rsquo;encontre du peuple allemand. Dans la perception US, l&rsquo;individu est responsable de tout ce qui est fait au nom de sa communaut\u00e9 mais cette communaut\u00e9 qui n&rsquo;a pas d&rsquo;\u00eatre propre n&rsquo;est pas capable de produire un ph\u00e9nom\u00e8ne collectif et, par cons\u00e9quent, une \u00ab\u00a0responsabilit\u00e9 collective\u00a0\u00bb.<\/p>\n<\/p>\n<p><p>Une fois la communaut\u00e9 punie au maximum et soumise sans condition (cette rengaine de la \u00ab\u00a0capitulation sans conditions\u00a0\u00bb qui caract\u00e9rise toutes les guerres am\u00e9ricanistes), vient le temps de la r\u00e9demption, qui n&rsquo;est rien d&rsquo;autre que l&rsquo;am\u00e9ricanisation. C&rsquo;est la raison du retournement extraordinaire des Am\u00e9ricains vis-\u00e0-vis des Allemands. Avant la victoire, ils envisageaient les pires ch\u00e2timents (le \u00ab\u00a0plan Morgenthau\u00a0\u00bb de transformation de l&rsquo;Allemagne en un pays uniquement agricole, avec liquidation de toute son industrie qui aurait entra&icirc;n\u00e9 des millions de morts par famine). Aussit\u00f4t apr\u00e8s la victoire, l&rsquo;am\u00e9ricanisation commen\u00e7a (y compris chez nombre de fonctionnaires nazis), qui pouvait s&rsquo;appeler aussi bien \u00ab\u00a0d\u00e9nazification\u00a0\u00bb que \u00ab\u00a0d\u00e9mocratisation\u00a0\u00bb. L&rsquo;Allemagne fut transform\u00e9e en alli\u00e9e-vassale la plus s&ucirc;re de l&rsquo;Am\u00e9rique en Europe.<\/p>\n<\/p>\n<p><p>Dans ce nouveau contexte, on n&rsquo;accorda gu\u00e8re de cr\u00e9dit \u00e0 l&rsquo;accusation de \u00ab\u00a0responsabilit\u00e9 collective\u00a0\u00bb contre les Allemands. Cette accusation fut reprise plus tard par intermittence, lorsque l&rsquo;Allemagne, redevenue puissante, s&rsquo;av\u00e9ra un concurrent \u00e9conomique, voire politique (Schr\u00f6der sur l&rsquo;Irak). En un sens, tout parut alors avoir \u00e9volu\u00e9 comme si l&rsquo;Allemagne s&rsquo;\u00e9tait \u00e9mancip\u00e9e en partie de l&rsquo;am\u00e9ricanisation initiale, qu&rsquo;elle l&rsquo;avait trahie, au moins en partie.<\/p>\n<\/p>\n<p><h3 class=\"subtitleset_b.deepblue\" style=\"color:#0f3955; font-size:1.65em; font-variant:small-caps\">Nation ou pays sous contrat ?<\/h3>\n<\/p>\n<p><p>Il va de soi que tout cela implique une mise en cause radicale du concept de \u00ab\u00a0nation\u00a0\u00bb. Il faut songer \u00e0 \u00e9carter pour d\u00e9finir l&rsquo;Am\u00e9rique le mot \u00ab\u00a0nation\u00a0\u00bb selon la d\u00e9signation classique qu&rsquo;en donnent les Fran\u00e7ais au profit d&rsquo;un autre mot tel que \u00ab\u00a0pays\u00a0\u00bb, &mdash; ou\u00a0\u00bbnation par contrat\u00a0\u00bb.<\/p>\n<\/p>\n<p><p>Cette id\u00e9e, autant que celle de l&rsquo;individu seul responsable, explique l&rsquo;in\u00e9luctable antagonisme entre Am\u00e9rique et France, la France repr\u00e9sentant l&rsquo;arch\u00e9type de la nation (la \u00ab\u00a0Grande nation\u00a0\u00bb disent les Allemands avec une ironie furieuse) qui appuie l&rsquo;id\u00e9e d&rsquo;un destin collectif sur la transcendance.<\/p>\n<\/p>\n<p><p>Dans ce contexte, on comprend que l&rsquo;individualisme appara&icirc;t comme une notion centrale de l&rsquo;am\u00e9ricanisme. Cette notion explique, dans la logique qu&rsquo;elle implique, l&rsquo;absence de diff\u00e9rence entre civils et militaires chez l&rsquo;ennemi. Elle explique le comportement am\u00e9ricaniste vis-\u00e0-vis des civils, qui ne varie dans l&rsquo;Histoire qu&rsquo;au fil des capacit\u00e9s technologiques. Les conceptions de LeMay sont nuanc\u00e9es aujourd&rsquo;hui par l&rsquo;affirmation que la technologie (pr\u00e9cision des armes) permet de soumettre les civils \u00e0 des pressions d\u00e9cisives sans devoir n\u00e9cessairement les tuer &mdash; ce qui n&rsquo;est pas contradictoire puisque le but est d&rsquo;am\u00e9ricaniser et non de tuer.<\/p>\n<\/p>\n<p><p>Bien entendu, on conna&icirc;t les limites de cette th\u00e9orie, \u00e0 la mesure des illusions qu&rsquo;on se fait concernant les armes de haute pr\u00e9cision. La sophistication et la technologie \u00e9tant ce qu&rsquo;elles sont, la tentative d&rsquo;am\u00e9ricanisation continue \u00e0 aboutir souvent \u00e0 tuer. Dans tous les cas, c&rsquo;est toujours la m\u00eame conception fondamentale : les civils sont d&rsquo;abord des individus, au m\u00eame titre que les soldats, et ont, durant le conflit in\u00e9vitable et n\u00e9cessaire, une part \u00e9gale de responsabilit\u00e9 individuelle dans l&rsquo;action ou la posture hostiles contre l&rsquo;am\u00e9ricanisme.<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le civil, c&rsquo;est aussi l&rsquo;ennemmi Pour l&rsquo;am\u00e9ricanisme, le civil de la nation ennemie est-il un ennemi ? &mdash; La question de l&rsquo;individualisme Les consid\u00e9rables pertes civiles caus\u00e9es par le conflit irakien &mdash; le chiffre de 655.000 morts depuis 2003 est d\u00e9sormais assur\u00e9 d&rsquo;\u00eatre une r\u00e9f\u00e9rence &mdash; conduisent \u00e0 s&rsquo;interroger sur la question des pertes civiles&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[3],"tags":[3376,5916,6083,6084,3879,3153,4194],"class_list":["post-68165","post","type-post","status-publish","format-standard","hentry","category-analyse","tag-americanisation","tag-bombarder","tag-citoyen","tag-individu","tag-individualisme","tag-lemay","tag-nation"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/68165","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=68165"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/68165\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=68165"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=68165"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=68165"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}