{"id":68219,"date":"2006-11-21T00:00:00","date_gmt":"2006-11-21T00:00:00","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2006\/11\/21\/le-choix-de-segolene\/"},"modified":"2006-11-21T00:00:00","modified_gmt":"2006-11-21T00:00:00","slug":"le-choix-de-segolene","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2006\/11\/21\/le-choix-de-segolene\/","title":{"rendered":"<strong><em>Le choix de S\u00e9gol\u00e8ne<\/em><\/strong>"},"content":{"rendered":"<p><h2 class=\"common-article\">Le choix de S\u00e9gol\u00e8ne<\/h2>\n<\/p>\n<p><\/p>\n<p><p>\t21 novembre 2006  Le premier pas en avant de la candidate S\u00e9gol\u00e8ne Royal est int\u00e9ressant. Il porte sur l&rsquo;Europe (relay\u00e9 par le <a href=\"http:\/\/www.telegraph.co.uk\/news\/main.jhtml?xml=\/news\/2006\/11\/20\/wsego20.xml\" class=\"gen\">Daily Telegraph<\/a> du 21 novembre, que nous signale un lecteur dans notre <a href=\"http:\/\/www.dedefensa.org\/forum.php\" class=\"gen\">Forum<\/a>, au 20 novembre 2006, avec reproduction du texte de l&rsquo;article auquel on se reportera). Il nous indique une direction fran\u00e7aise naturelle, qui devrait s&rsquo;imposer au centre de la campagne pr\u00e9sidentielle, en m\u00eame temps que d&rsquo;autres th\u00e8mes de politique ext\u00e9rieure.<\/p>\n<\/p>\n<p><p>\tIl est curieux, ou bien r\u00e9v\u00e9lateur de la tendance \u00e0 faire des apparences le fond des choses, que les Britanniques aient d&rsquo;abord accueilli Royal avec chaleur, comme une admiratrice de Tony Blair, une Tony Blair \u00e0 la fran\u00e7aise. Pour la m\u00e9thode  m\u00e9diatique, peut-\u00eatre ; pour l&rsquo;orientation politique, c&rsquo;est une autre affaire. Les grandes lignes de la politique europ\u00e9enne de S\u00e9gol\u00e8ne Royal telles qu&rsquo;expos\u00e9es dans l&rsquo;article sont claires et s&rsquo;inscrivent directement contre la politique ext\u00e9rieure blairiste :<\/p>\n<\/p>\n<p><p>\t  Une Europe politique ind\u00e9pendante r\u00e9duite d&rsquo;abord aux pays qui acceptent ce projet. Les quatre pays <a href=\"http:\/\/www.dedefensa.org\/article.php?art_id=3372\" class=\"gen\">d\u00e9j\u00e0 nomm\u00e9s<\/a> sont cit\u00e9s : Allemagne, Espagne, France, Italie. C&rsquo;est la formule du noyau dur dans toutes ses conditions et ses cons\u00e9quences.<\/p>\n<\/p>\n<p><p>\t  Cette Europe politique r\u00e9duite au noyau dur est d\u00e9finie d&rsquo;abord par le choix fondamental de politique ext\u00e9rieure, au travers du choix exig\u00e9 de l&rsquo;Angleterre : l&rsquo;ind\u00e9pendance ou la vassalit\u00e9 am\u00e9ricaniste. (Le reste va avec : une Europe renforc\u00e9e, protectionniste \u00e0 l&rsquo;instar des USA, etc.)<\/p>\n<\/p>\n<p><p>\tLes d\u00e9clarations faites au <em>Telegraph<\/em> viennent du d\u00e9put\u00e9 Gilles Savary, porte-parole de S\u00e9gol\u00e8ne pour la politique ext\u00e9rieure. Elles ont la marque d&rsquo;une orientation fondamentale d&rsquo;un programme \u00e9lectoral con\u00e7u comme une politique coh\u00e9rente, appuy\u00e9e sur l&rsquo;exigence d&rsquo;un nouveau trait\u00e9 europ\u00e9en proposant une orientation souveraine, radicalement diff\u00e9rente de celle qui est suivie aujourd&rsquo;hui. C&rsquo;est du super-Chirac (le Chirac non-dit, lorsqu&rsquo;il se d\u00e9barrasse de la gangue du conformisme), revu \u00e0 la sauce gaullienne originelle et accord\u00e9 aux conceptions souverainistes. <\/p>\n<\/p>\n<p><p>\t\u00ab<em>Britain would be asked to sign up to the new treaty, but if it rejected calls for increased protectionism, an EU foreign minister, convergence on tax rates and moves to create a European army, then France and her allies would agree a treaty among themselves,<\/em> [Savary] <em>said.<\/em><\/p>\n<\/p>\n<p><p>\t()<\/p>\n<\/p>\n<p><p>\t\u00bb<em>Nicolas Sarkozy, the centre-Right favourite for the presidency, recently set out his own plans for reviving Europe after the failed constitution, involving a mini-treaty, extracting elements from the defunct text. Miss Royal, who has no foreign policy experience and has only ever held junior ministerial posts, will seek the immediate support of Angela Merkel, the German chancellor, for her plans, and believes Spain and Italy can also be signed up.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>Although Miss Royal does not want a two-speed Europe, Mr Savary said, he admitted her plans could lead to a quartet of nations leading the way, with others scrambling to catch up. He complained that Britain currently led an ultra-Atlanticist bloc within the EU.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>Great Britain is absolutely indispensable to the European Union. It is great nation, a global power. But the question the English have to answer is  do the English consider the English Channel to be wider than the Atlantic? We on the continent have the right to deplore the fact that Great Britain appears to consider the Channel is wider, he said.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>Miss Royal was confident that Europe can be relaunched with Germany, Italy and Spain. It is perfectly possible to have treaties within the treaty, among four nations, he said. If other nations want to sign up, that&rsquo;s good. But we cannot have a Europe where one part goes to war in Iraq, another part does not, and we all end up paying the bill.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>He demanded efforts to integrate foreign policy and cast that struggle in searingly anti-American tones. Mr Savary said: The question that needs to be asked is  do we want to be vassals of the United States, do we want to be a 51st state?<\/em>\u00bb<\/p>\n<h3>Est-ce une voie royale vers l&rsquo;\u00e9lection?<\/h3>\n<\/p>\n<p><p>\tIl est int\u00e9ressant de noter que Royal et son \u00e9quipe ont choisi :<\/p>\n<\/p>\n<p><p>\t  L&rsquo;Europe comme premier acte de d\u00e9claration de programme de la campagne \u00e9lectorale de la candidate socialiste.<\/p>\n<\/p>\n<p><p>\t  L&rsquo;Europe prise dans son acceptation la plus politique et la plus volontariste, c&rsquo;est-\u00e0-dire l&rsquo;Europe consid\u00e9r\u00e9e comme un th\u00e8me de politique ext\u00e9rieure fondamental impliquant une affirmation souveraine.<\/p>\n<\/p>\n<p><p>\t  Un journal britannique pour relayer ce premier acte de la campagne, \u00e9largissant par l\u00e0 le d\u00e9bat europ\u00e9en vers ses choix fondamentaux au travers du choix demand\u00e9 \u00e0 l&rsquo;Angleterre : une Europe politique, ind\u00e9pendante (essentiellement des USA), si n\u00e9cessaire r\u00e9duite \u00e0 des acteurs actifs, comme choix fondamental et n\u00e9cessaire ; et c&rsquo;est, implicitement, cette Europe-l\u00e0 ou rien.<\/p>\n<\/p>\n<p><p>\tL&rsquo;approche est int\u00e9ressante parce qu&rsquo;elle \u00e9l\u00e8ve le d\u00e9bat, l&rsquo;\u00e9largit et transcende en un coup les fronti\u00e8res politiques. Avec ce projet europ\u00e9en, Royal, appuy\u00e9e sur son \u00e9lectorat socialiste, lance un appel \u00e0 l&rsquo;\u00e9lectorat souverainiste fran\u00e7ais (de gauche comme de droite, de Chev\u00e9nement \u00e0 de Villiers et d\u00e9passant largement les rassemblements des deux hommes) tout en satisfaisant une partie des revendications des altermondialistes. Elle d\u00e9nonce aussit\u00f4t, de fa\u00e7on implicite mais assur\u00e9e, la grande faiblesse (ou l&rsquo;incertitude) du programme de Sarkozy et de la droite lib\u00e9rale : l&rsquo;Europe lib\u00e9rale de Sarkozy peut-elle \u00eatre \u00e9galement politique et souveraine? (Critique valable si Sarkozy confirme son choix lib\u00e9ral, alors qu&rsquo;il a tendance \u00e0 \u00e9voluer ces derniers temps. Mais la prise de position tr\u00e8s rapide de S\u00e9gol\u00e8ne tend \u00e0 l&rsquo;enfermer dans ce choix par antagonisme \u00e9lectoral, ce qui est d&rsquo;une bonne habilet\u00e9.) Enfin, cette approche tend \u00e0 poursuivre le 29 mai 2005 en allant au-devant du vu implicite des partisans du non (adversaires de la forme actuelle de l&rsquo;Europe plus que de l&rsquo;Europe <em>per se<\/em>.)<\/p>\n<\/p>\n<p><p>\tStrat\u00e9giquement, le choix se justifie. Il est \u00e9videmment radical sur un point fondamental de politique ext\u00e9rieure qui entra\u00eene tout le reste, cr\u00e9ant une coh\u00e9rence bienvenue. (Une telle Europe ne peut \u00eatre qu&rsquo;anti-am\u00e9ricaniste dans toutes les manifestations essentielles des relations internationales aujourd&rsquo;hui ; elle a la vertu de l&rsquo;affirmation europ\u00e9enne forte, par cons\u00e9quent pose l&rsquo;Europe comme acteur fondamental de la vie internationale, n\u00e9cessairement contre la politique am\u00e9ricaniste ; elle pose l&rsquo;Europe comme adversaire de la d\u00e9structuration de la globalisation, par cons\u00e9quent comme p\u00f4le de rassemblement contre la politique am\u00e9ricaniste. C&rsquo;est la d\u00e9finition de l&rsquo;Europe-puissance.)<\/p>\n<\/p>\n<p><p>\tTactiquement, le choix de Royal et de son \u00e9quipe est \u00e9galement justifi\u00e9. On peut m\u00eame dire qu&rsquo;il s&rsquo;agit, le jeu de mots est tentant, d&rsquo;une voie royale vers une possible \u00e9lection et le seul choix possible pour une campagne de rupture d\u00e9barrassant la candidate socialiste de sa gangue m\u00e9diatique (candidate peu s\u00e9rieuse, inexp\u00e9riment\u00e9e, etc.) qui est son principal handicap.<\/p>\n<\/p>\n<p><p>\t  Ce choix tend \u00e0 faire monter les ench\u00e8res de l&rsquo;\u00e9lection vers un paroxysme, \u00e0 maintenir la mobilisation de l&rsquo;\u00e9lectorat (socialiste et bien au-del\u00e0 des socialistes, vers les souverainistes de droite et de gauche, vers les altermondialistes) sur le th\u00e8me de l&rsquo;identit\u00e9 europ\u00e9enne prot\u00e9geant l&rsquo;identit\u00e9 fran\u00e7aise. On retrouve le <em>tempo<\/em> du r\u00e9f\u00e9rendum de mai 2005.<\/p>\n<\/p>\n<p><p>\t  Il tend \u00e0 contenir la mont\u00e9e aux extr\u00eames (Le Pen) en mobilisant l&rsquo;\u00e9lectorat (droite et gauche) sur le seul th\u00e8me capable de combattre l&rsquo;effet mobilisateur extr\u00e9miste des th\u00e8mes s\u00e9curitaires et autres.<\/p>\n<\/p>\n<p><p>\t  Il tend \u00e0 susciter la mise \u00e0 nu des contradictions (entre volontarisme et lib\u00e9ralisme) de son probable adversaire principal.<\/p>\n<\/p>\n<p><p>\tD&rsquo;une certaine fa\u00e7on, ces choix radicaux rendent plus probable le sch\u00e9ma envisag\u00e9 actuellement (Royal <em>versus<\/em> Sarkozy) parce qu&rsquo;ils renforcent radicalement la substance de la candidature Royal. Si ces conditions de d\u00e9part pr\u00e9vues (Royal <em>versus<\/em> Sarkozy) sont r\u00e9alis\u00e9es au deuxi\u00e8me tour et les choix radicaux de S\u00e9gol\u00e8ne Royal confirm\u00e9s, on pourrait se retrouver avec une situation in\u00e9dite, rappelant celle de 1995 et de la complicit\u00e9 Mitterrand-Chirac. Chirac pourrait se d\u00e9couvrir plut\u00f4t favorable \u00e0 Royal, par choix politique autant que par hostilit\u00e9 fondamentale \u00e0 Sarkozy. On pourrait m\u00eame imaginer que Chirac aide objectivement S\u00e9gol\u00e8ne contre Sarko en mettant en place, dans les six mois qui viennent, les premiers \u00e9l\u00e9ments de la politique de la candidate socialiste. (Encore un peu d&rsquo;audace et de haine anti-sarkozyste et l&rsquo;on peut aller jusqu&rsquo;\u00e0 l&rsquo;hypoth\u00e8se d&rsquo;\u00e9v\u00e9nements de rupture, de surprises in\u00e9dites, comme une proclamation chiraquienne au terme de la campagne dans le sens des propositions europ\u00e9ennes de S\u00e9gol\u00e8ne, au nom de l&rsquo;int\u00e9r\u00eat national et de l&rsquo;int\u00e9r\u00eat europ\u00e9en. C&rsquo;est l&rsquo;hypoth\u00e8se de la rupture sarkozyste retourn\u00e9e contre Sarkozy.)<\/p>\n<\/p>\n<p><p>\tSi cette voie royale est poursuivie loyalement et fid\u00e8lement, si les obstacles et les pressions en sens inverse ne l&#8217;emportent pas (le parti de l&rsquo;\u00e9tranger est puissant en France), si le d\u00e9bat fran\u00e7ais se fixe sur la question europ\u00e9enne et la politique ext\u00e9rieure qui en d\u00e9coule,  et il faut mesurer le poids restrictif des si  on peut aller \u00e0 un  bouleversement int\u00e9rieur fran\u00e7ais impliquant une recomposition de la droite (avec l&rsquo;opposition implicite entre lib\u00e9raux et souverainistes mise \u00e0 jour), encha\u00eenant sur un bouleversement europ\u00e9en. Mai 2007 deviendrait une vraie rupture et cette rupture serait la digne continuatrice et l&rsquo;accomplissement de la premi\u00e8re rupture de mai 2005.<\/p>\n<\/p>\n<p><p>\t(Mais c&rsquo;est un tout ou rien, \u00e0 notre sens. Si, au contraire, Royal abandonne cette voie radicale et compromet cette annonce de d\u00e9part dans des concessions, voire des changements importants d&rsquo;orientation, sa candidature risque de voler en \u00e9clats. C&rsquo;est l&rsquo;enjeu des candidatures in\u00e9dites. Pour se justifier d&rsquo;exister, elles doivent n\u00e9cessairement \u00eatre radicales et affirmer avec fermet\u00e9 cette radicalit\u00e9 jusqu&rsquo;\u00e0 imposer leur propre continuit\u00e9. Il faut du souffle.)<\/p>\n<\/p>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le choix de S\u00e9gol\u00e8ne 21 novembre 2006 Le premier pas en avant de la candidate S\u00e9gol\u00e8ne Royal est int\u00e9ressant. Il porte sur l&rsquo;Europe (relay\u00e9 par le Daily Telegraph du 21 novembre, que nous signale un lecteur dans notre Forum, au 20 novembre 2006, avec reproduction du texte de l&rsquo;article auquel on se reportera). Il nous&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[398,4345,4214,2789,6147,2746,6148],"class_list":["post-68219","post","type-post","status-publish","format-standard","hentry","category-faits-et-commentaires","tag-europe","tag-independance","tag-royal","tag-rupture","tag-segolene","tag-souverainete","tag-souverainiste"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/68219","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=68219"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/68219\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=68219"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=68219"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=68219"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}