{"id":68236,"date":"2006-11-26T00:00:00","date_gmt":"2006-11-26T00:00:00","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2006\/11\/26\/la-grande-guerre-avant-la-parenthese-monstrueuse\/"},"modified":"2006-11-26T00:00:00","modified_gmt":"2006-11-26T00:00:00","slug":"la-grande-guerre-avant-la-parenthese-monstrueuse","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2006\/11\/26\/la-grande-guerre-avant-la-parenthese-monstrueuse\/","title":{"rendered":"La Grande Guerre avant la <em>parenth\u00e8se monstrueuse<\/em>"},"content":{"rendered":"<p><h3>La Grande Guerre avant la parenth\u00e8se monstrueuse<\/h3>\n<\/p>\n<p><p>\tVoici un extrait d&rsquo;un livre auquel travaille actuellement Philippe Grasset. Ce livre, dont le titre provisoire est <em>La parenth\u00e8se monstrueuse  1934-1989<\/em>, tente de donner un \u00e9clairage nouveau de l&rsquo;histoire du XX\u00e8me si\u00e8cle, prolong\u00e9e naturellement jusqu&rsquo;\u00e0 2001 et aujourd&rsquo;hui. Nous comptons naturellement offrir \u00e0 nos lecteurs ce livre en vente en ligne, sur notre site d&rsquo;\u00e9dition <em>edde.eu<\/em>, lorsqu&rsquo;il sera termin\u00e9.<\/p>\n<\/p>\n<p><p>\tL&rsquo;extrait ci-dessous concerne la Grande Guerre. Dans le livre, il fait partie du deuxi\u00e8me chapitre de la Deuxi\u00e8me Partie, chapitre pr\u00e9sent\u00e9 par le chapeau suivant :<\/p>\n<\/p>\n<p><p>\t\u00ab<em>Le cas de la France par rapport \u00e0 l&rsquo;Am\u00e9rique, jusqu&rsquo;\u00e0 l&rsquo;ouverture des ann\u00e9es 1919-1934. *  France-Am\u00e9rique au XIX\u00e8me si\u00e8cle, jusqu&rsquo;au tournant de la Grande Guerre. *  La bataille de Verdun poursuivie par l&rsquo;attaque de l&rsquo;Am\u00e9rique par la France entreprise en 1919.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tBien entendu, il est bon que le lecteur lise cet extrait \u00e0 la lumi\u00e8re de notre texte rapport\u00e9 d&rsquo;une <a href=\"http:\/\/www.dedefensa.org\/article.php?art_id=3396\" class=\"gen\">visite \u00e0 Verdun<\/a>. Toutes ces choses participent d&rsquo;une m\u00eame d\u00e9marche.<\/p>\n<\/p>\n<p><\/p>\n<h2 class=\"common-article\">La Grande Guerre de 1914-1918<\/h2>\n<\/p>\n<p><p>\tJ&rsquo;ai acquis \u00e0 mesure des ann\u00e9es pass\u00e9es une perception de plus en plus vive, et aussi de plus en plus chaleureuse et tragique de la Grande Guerre ; une perception gouvern\u00e9e par une empathie de l&rsquo;\u00e2me qui va jusqu&rsquo;\u00e0 l&rsquo;irr\u00e9sistible et au sublime ; une perception mesur\u00e9e par le temps, comme si, en m&rsquo;\u00e9loignant de l&rsquo;\u00e9v\u00e9nement terrestre, le temps qui passe me rapprochait de sa substance spirituelle. L&rsquo;intuition, l&rsquo;\u00e9motion, la compassion extraordinaire que j&rsquo;\u00e9prouve devant tant d&rsquo;horribles souffrances tiennent une place consid\u00e9rable dans cette perception, que la raison ne d\u00e9ment pas une seule seconde. Chaque fois que je regarde la fin de ce documentaire sur les restes pr\u00e9serv\u00e9s de Verdun (la campagne encore martyris\u00e9e malgr\u00e9 la repousse de la nature, telle croix pos\u00e9e ici, une marque comm\u00e9morative, des restes d&rsquo;une position d&rsquo;une pi\u00e8ce d&rsquo;artillerie, un <em>blockhaus<\/em> rouill\u00e9, des galeries de repos, la trace d&rsquo;une tranch\u00e9e, etc.),  la fin avec ce long plan en mouvement lent qui dure pr\u00e8s d&rsquo;une minute, filmant les alignement des tombes de Verdun vers l&rsquo;Ossuaire entre les rang\u00e9es d&rsquo;arbres \u00e9lanc\u00e9s et espac\u00e9s, qu&rsquo;une musique lente, fun\u00e8bre mais non d\u00e9nu\u00e9e d&rsquo;apaisement accompagne avec une solennit\u00e9 poignante, qu&rsquo;une voix grave et contenue d&rsquo;\u00e9motion dit le quatrain de P\u00e9guy :<\/p>\n<\/p>\n<p><p>\t\u00ab<em>M\u00e8re, voici vos fils qui se sont tant battus,<\/em> <\/p>\n<\/p>\n<p><p>\t\u00bb<em>Qu&rsquo;ils ne soient pas jug\u00e9s sur leur seule mis\u00e8re.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>Que Dieu mette avec eux un peu de cette terre<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>Qui les a tant perdus et qu&rsquo;ils ont tant aim\u00e9e.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\t Chaque fois avec la m\u00eame \u00e9motion, chaque fois je pleure \u00e0 nouveau. Ces larmes, je ne les r\u00e9serve \u00e0 l&rsquo;\u00e9vocation d&rsquo;aucun autre \u00e9v\u00e9nement de notre histoire r\u00e9cente. Je crois \u00e9galement avec force que la Grande Guerre tient une place centrale et unique dans son genre dans notre Histoire,  que l&rsquo;on parle de l&rsquo;histoire de la France et de l&rsquo;histoire du monde. L&rsquo;\u00e9v\u00e9nement est semblable en intensit\u00e9 et en signification spirituelle \u00e0 l&rsquo;\u00e9pop\u00e9e de Jeanne d&rsquo;Arc, dans la puissance tragique qu&rsquo;il exprime. Il faut qu&rsquo;une telle catastrophe, qu&rsquo;une telle somme de souffrances au-del\u00e0 du concevable de l&rsquo;esprit bien s\u00fbr, soit justifiable par quelque chose d&rsquo;au-del\u00e0 du terrestre, et que l&rsquo;\u00e2me qui \u00e9largit et grandit l&rsquo;esprit puisse en avoir la connaissance intuitive. Puisque la terre, en cette occurrence, s&rsquo;est compromise jusqu&rsquo;\u00e0 \u00eatre le linceul sanglant et boueux de nations enti\u00e8res, et de quelle fa\u00e7on, puisqu&rsquo;elle n&rsquo;a pas encore connu le rachat de l&rsquo;\u00e9vocation qu&rsquo;en fait Charles P\u00e9guy, inutile d&rsquo;en chercher la justification en elle. (C&rsquo;est qu&rsquo;en effet la terre qu&rsquo;\u00e9voque P\u00e9guy, elle, est pass\u00e9e par le rachat de l&rsquo;\u00e2me. Elle est sanctifi\u00e9e. Elle est au-del\u00e0 de la bataille qui nous occupe pour l&rsquo;instant.) L&rsquo;explication sera spirituelle [].<\/p>\n<\/p>\n<p><p>\tPour emprunter plus s\u00fbrement cette voie spirituelle, pour l&rsquo;assurer sur des bases qui n&rsquo;aient pas elles-m\u00eames l&rsquo;incertitude initiale des \u00e9motions et des intuitions, pour s&rsquo;assurer sur le sol ferme avant d&rsquo;en venir \u00e0 l&rsquo;\u00e9vocation de l&rsquo;\u00e2me, il faut rassembler les indices terrestres. Je partirai d&rsquo;une question en apparence grossi\u00e8re : que se serait-il pass\u00e9 si n&rsquo;avaient exist\u00e9 ni le canon ni la mitrailleuse? Les historiens et experts militaires s&rsquo;entendent \u00e0 conclure que la disposition de ces deux armes terribles, sans la riposte possible d&rsquo;instruments m\u00e9caniques de mouvement, interdit effectivement le mouvement et fixa cette guerre dans une longue agonie sanglante. Apr\u00e8s la guerre de mouvement initiale, qui fut marqu\u00e9e par des pertes \u00e9lev\u00e9es justement \u00e0 cause de la pr\u00e9sence de ces armes nouvelles dont on d\u00e9couvrait l&rsquo;effet terrifiant, apr\u00e8s la bataille inspir\u00e9e (La Marne) qui brisa l&rsquo;\u00e9lan initial de l&rsquo;invasion et renversa le cours de la guerre, l&rsquo;\u00e9puisement, la fatigue, la r\u00e9duction des forces forc\u00e8rent au choix de la position statique. La m\u00e9canique qui compromet le mouvement avait emp\u00each\u00e9 l&rsquo;ultime phase de la bataille de mouvement renvers\u00e9e, de la bataille d\u00e9bouchant sur l&rsquo;issue du sublime,  l&rsquo;exploitation de sa victoire strat\u00e9gique ultime par le vaincu tactique de la campagne.<\/p>\n<\/p>\n<p><p>\tLa victoire strat\u00e9gique fran\u00e7aise (La Marne) avait \u00e9t\u00e9 la r\u00e9action supr\u00eame de la volont\u00e9 contre l&#8217;empire de la puissance m\u00e9canique. L&rsquo;interdiction d&rsquo;exploiter cette victoire strat\u00e9gique jusqu&rsquo;\u00e0 son terme indiquait que la logique de la guerre dans ce qu&rsquo;elle peut avoir de sublime,  lorsque la science militaire fait volte-face pour devenir art militaire et rejoint la justice transcendante,  cette logique \u00e9tait pervertie, bafou\u00e9e, bris\u00e9e et r\u00e9duite. La guerre fut profond\u00e9ment diff\u00e9rente. Le monde changea, ou plut\u00f4t il bascula. Des arm\u00e9es enti\u00e8res furent paralys\u00e9es, leurs soldats subirent la mitraille sans pouvoir rien sinon que subir le pire, jusqu&rsquo;au sort d&rsquo;une mort terrible et paralys\u00e9e. Lorsqu&rsquo;un g\u00e9n\u00e9ral voulait briser cet infernal enfermement, il provoquait une tuerie monstrueuse. On reprocha souvent et l&rsquo;on reproche toujours \u00e0 ces g\u00e9n\u00e9raux d&rsquo;\u00eatre des bouchers. L&rsquo;argument est facile et vous pare \u00e0 bon compte d&rsquo;une bonne conscience d&rsquo;humaniste ; il vous donne les atours de l&rsquo;esprit libre et vous permet de p\u00e9rorer ; vous \u00eates pacifiste sans vous engager ; vous \u00eates anti-militariste sans vous brouiller avec l&rsquo;H\u00f4tel des Invalides et la rue Saint-Dominique. En un mot, vous \u00eates irresponsable.<\/p>\n<\/p>\n<p><p>\tOn trouve l&rsquo;explication technique qui fait le cas qu&rsquo;elle m\u00e9rite de cette brillante plaidoirie dans le travail r\u00e9cent d&rsquo;un historien militaire, Sir John Keegan et sa <em>Premi\u00e8re Guerre Mondiale<\/em> (1998 et 2003). Le livre n&rsquo;apporte rien sur l&rsquo;essentiel en plus de pr\u00e9senter une vision extraordinairement britannique de la guerre (la guerre comme un grand affrontement Angleterre-Allemagne, la France comme compl\u00e9ment utile ici et l\u00e0). Certains d\u00e9tails sont utiles, comme celui que je cite ici. L&rsquo;argument s&rsquo;appuie sur la conjonction de deux facteurs, l\u00e0 aussi avec le d\u00e9s\u00e9quilibre des progr\u00e8s compl\u00e9mentaires : d&rsquo;une part, l&rsquo;extension du champ de bataille au-del\u00e0 du champ visuel, for\u00e7ant les chefs \u00e0 se reposer sur les communications pour avoir une vision de la bataille qui leur permettrait de la conduire et d&rsquo;offrir les d\u00e9cisions qui importent au moment qui importe ; d&rsquo;autre part, la vuln\u00e9rabilit\u00e9 de ces communications (par fils), qui conduisait dans la plupart des cas \u00e0 leur destruction au d\u00e9but de la bataille (l&rsquo;artillerie \u00e9crasant et coupant les fils) et rendait les chefs aveugles et sourds. Les erreurs sont in\u00e9vitables sinon in\u00e9luctables et elles sont multipli\u00e9es par l&rsquo;\u00e9norme puissance de feu du facteur d\u00e9fenseur statique (artillerie et mitrailleuses). Le feu devient affreusement meurtrier lorsque l&rsquo;attaque se d\u00e9veloppe en aveugle et sans coordination. \u00ab<em>Le rideau de fer de la guerre est descendu entre les commandants, quel que soit leur grade, et leurs hommes,<\/em> \u00e9crit Sir John, <em>les coupant les uns des autres comme s&rsquo;ils se trouvaient sur des continents diff\u00e9rents.<\/em> [] <em>Tant que les ressources n\u00e9cessaires \u00e0 la modification d&rsquo;une bataille (v\u00e9hicules blind\u00e9s tout-terrain fiable, \u00e9metteurs-r\u00e9cepteurs portables) font d\u00e9faut (et elles continueront cruellement \u00e0 le faire le temps de se d\u00e9velopper, ce qui prendra plusieurs ann\u00e9es), les g\u00e9n\u00e9raux sont entrav\u00e9s par une technologie \u00f4 combien apte \u00e0 la destruction massive de la vie, mais tout \u00e0 fait inapte \u00e0 leur donner la flexibilit\u00e9 de contr\u00f4le qui pourrait maintenir ces massacres dans les limites du supportable.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\t(La chose n&rsquo;est pas nouvelle parce qu&rsquo;elle n&rsquo;est que simple bon sens. Le 31 janvier 1931, Paul Val\u00e9ry accueille le mar\u00e9chal P\u00e9tain \u00e0 l&rsquo;Acad\u00e9mie Fran\u00e7aise. On lit notamment ceci dans son discours: \u00ab<em>C&rsquo;\u00e9tait donc peu de dire que le feu tue. Le feu moderne fauche ; il supprime ; il interdit le mouvement et la vie dans toute zone qu&rsquo;il bat. Quatre hommes r\u00e9solus tiennent mille hommes en respect, couchent morts ou vifs tous ceux qui se montrent. On arrive \u00e0 cette conclusion surprenante que la puissance de l&rsquo;arme, son<\/em> <strong><em>rendement<\/em><\/strong>, <em>augmente comme le nombre m\u00eame de ses adversaires. Plus il y en a, plus elle tue. C&rsquo;est par quoi elle a eu raison du mouvement, elle a enterr\u00e9 le combat, embarrass\u00e9 la manuvre, paralys\u00e9 en quelque sorte, toute strat\u00e9gie.<\/em>\u00bb)<\/p>\n<\/p>\n<p><p>\tIl ne m&rsquo;importe pas tant de redresser ici quelques torts, de tenter de montrer que l&rsquo;\u00e9poque 1890-1914 n&rsquo;\u00e9tait pas n\u00e9cessairement propice \u00e0 la floraison d&rsquo;une g\u00e9n\u00e9ration enti\u00e8re et universelle d&rsquo;officiers g\u00e9n\u00e9raux au front bas, cruels, se frottant les mains au constat des souffrances de leurs hommes. Ces clich\u00e9s stupides,  expression sugg\u00e9rant d&rsquo;ajouter une stupidit\u00e9 conjoncturelle \u00e0 la stupidit\u00e9 ontologique du clich\u00e9,  ont servi en g\u00e9n\u00e9ral de base de travail \u00e0 plusieurs g\u00e9n\u00e9rations de commentateurs de la Grande Guerre. Je les soup\u00e7onne d&rsquo;arri\u00e8re-pens\u00e9es id\u00e9ologiques, et le mot est bien l\u00e9ger. Passons outre, une fois la chose bien entendue. Il n&#8217;emp\u00eache qu&rsquo;elle est l\u00e0 pour introduire l&rsquo;argument principal, dans la mesure o\u00f9 l&rsquo;interpr\u00e9tation trompeuse et fallacieuse de cet aspect du conflit consiste finalement \u00e0 prendre des vessies pour des lanternes, et la puissance de feu massacreuse pour la b\u00eatise du g\u00e9n\u00e9ral. C&rsquo;est en arriver \u00e0 l&rsquo;argument de la m\u00e9canisation d\u00e9j\u00e0 sugg\u00e9r\u00e9.<\/p>\n<\/p>\n<p><p>\tIl m&rsquo;importe de renforcer l&rsquo;argument de la m\u00e9canisation de la guerre comme cause essentielle de sa cruaut\u00e9, de son caract\u00e8re de catastrophe effroyable, de sa dur\u00e9e par cons\u00e9quent ; la cause est ainsi transcend\u00e9e ; l&rsquo;argument de la m\u00e9canisation de la guerre devient la cause fondamentale et exclusive du choc que les \u00e9v\u00e9nements inflig\u00e8rent aux psychologies collectives en m\u00eame temps qu&rsquo;aux corps individuels, et au-del\u00e0 d&rsquo;eux, car en cette occurrence les vivants (les suvivants) doivent souffrir <strong>autant<\/strong> que les morts. Pour r\u00e9duire la d\u00e9monstration \u00e0 une image, je propose celle-ci qui d\u00e9montre <em>a contrario<\/em>: si les mitrailleuses et l&rsquo;artillerie dans leur puissance d&rsquo;arr\u00eat et de fixation sanglante n&rsquo;avaient pas exist\u00e9, la guerre n&rsquo;aurait jamais eu le caract\u00e8re sanglant de la tuerie qui a perdu le sens qu&rsquo;elle eut, elle n&rsquo;aurait pas dur\u00e9 le temps tr\u00e8s long qu&rsquo;elle dura, elle n&rsquo;aurait pas provoqu\u00e9 directement ou indirectement les \u00e9v\u00e9nements politiques et sociaux d\u00e9stabilisateurs et d\u00e9structurants qu&rsquo;elle provoqua \u00e0 cause du temps qu&rsquo;elle dura et de la tuerie qu&rsquo;elle provoqua Le si\u00e8cle e\u00fbt \u00e9t\u00e9 diff\u00e9rent, et diff\u00e9rentes les situations en Russie \u00e0 la fin du conflit, en Europe m\u00eame, dans la structure, la nature et la psychologie des nations et des r\u00e9gions, dans le champ transatlantique avec l&rsquo;intervention des Etats-Unis en position de puissance dominatrice, dans les champs d\u00e9mographique et psychologique avec l&rsquo;ampleur et la cruaut\u00e9 des pertes et leurs effets collectifs sans nombre et d&rsquo;une profondeur consid\u00e9rable, et ainsi de suite si cela ne suffisait pas. Qui sait, dans cette hypoth\u00e8se d&rsquo;une guerre r\u00e9duite en cruaut\u00e9s et en dur\u00e9e, et en cons\u00e9quences psychologiques sur la conscience puis la m\u00e9moire collectives des gens, si Paul Val\u00e9ry e\u00fbt \u00e9t\u00e9 encore conduit \u00e0 \u00e9crire, en avril 1919 : \u00ab<em>Nous autres, civilisations, nous savons maintenant que nous sommes mortelles<\/em>\u00bb C&rsquo;est l&rsquo;hypoth\u00e8se d&rsquo;une relativisation extr\u00eame de la valeur et de l&rsquo;identification de l&rsquo;\u00e9v\u00e9nement \u00e0 cause d&rsquo;un ph\u00e9nom\u00e8ne purement m\u00e9canique.<\/p>\n<\/p>\n<p><p>\tComment sauver cette guerre ? Comment expliquer qu&rsquo;ainsi r\u00e9duite \u00e0 la cons\u00e9quence triviale et mal\u00e9fique d&rsquo;un progr\u00e8s \u00e9pouvantable, cette guerre provoque par le biais de la psychologie si fortement boulevers\u00e9e des effets d&rsquo;ordre spirituel si grands que nous e\u00fbmes un si\u00e8cle d\u00e9vast\u00e9 au point o\u00f9 il fut, au point d&rsquo;entra\u00eener une crise de civilisation qui est la crise de l&rsquo;esprit par essence, qui est le sujet de cette uvre? Pour en venir \u00e0 mon propre cas que j&rsquo;ai expos\u00e9 plus haut,  comment expliquer que cette guerre r\u00e9duite aux effets de la m\u00e9canisation provoque en moi une \u00e9motion si grande que je la compare, dans ma perception, aux plus grands moments spirituels de l&rsquo;histoire de la France?  Une fois per\u00e7ue par intuition, la r\u00e9ponse ne fait pas de doute : parce que cette guerre, prolong\u00e9e artificiellement dans la boue et le sang par la m\u00e9canisation ne se grandit que dans la mesure o\u00f9 elle est aussi, et m\u00eame <strong>plus que tout<\/strong>, une guerre contre la m\u00e9canisation. Ceux qui la subissent dans leurs chairs et dans leurs \u00e2mes sont conduits \u00e0 se battre, d&rsquo;une fa\u00e7on inconsciente et dans le champ spirituel aussi bien, contre le mal\u00e9fice qui est la cause de ce prolongement monstrueux. L&rsquo;on dira alors, et l&rsquo;on verra cela prolong\u00e9 plus loin, que cette perception habille la m\u00e9canisation de la guerre d&rsquo;une orientation et d&rsquo;une dynamique mal\u00e9fiques. Les deux aspects qui s&rsquo;opposent sont enlev\u00e9s vers les hauteurs qui justifient qu&rsquo;on en fasse si grand cas. Le grand cas est bien entendu cette appr\u00e9ciation spirituelle de la Grande Guerre, qui semblerait \u00e0 premi\u00e8re vue ne l&rsquo;\u00eatre pas du tout.<\/p>\n<\/p>\n<p><p>\tComme naturellement, comme se vivent et se per\u00e7oivent les intuitions fondamentales, je reviens \u00e0 la France puisque j&rsquo;en viens \u00e0 Verdun. (Un aspect important de la Grande Guerre, qui explique l&rsquo;approche de Sir John Keegan, est qu&rsquo;\u00e0 bien l&#8217;embrasser il semblerait qu&rsquo;il y ait eu <strong>deux guerres<\/strong> dans cette guerre: la guerre g\u00e9opolitique, qui semblerait principalement avoir \u00e9t\u00e9 livr\u00e9e entre Allemands et Anglais, pour la pr\u00e9pond\u00e9rance industrielle et, indirectement, pour la ma\u00eetrise des mers. [Les Anglais craignaient l&rsquo;effet des ambitions allemandes dans ce domaine.] Cette guerre-l\u00e0 est d\u00e9crite, par les Britanniques, et plus pr\u00e9cis\u00e9ment par la g\u00e9n\u00e9ration actuelle des historiens [Keegan, Ferguson, etc.] comme domin\u00e9e du c\u00f4t\u00e9 alli\u00e9 par les Britanniques, jusqu&rsquo;\u00e0 oublier compl\u00e8tement les Fran\u00e7ais,  en plus, cela ne d\u00e9pla\u00eet pas aux Britanniques aujourd&rsquo;hui. L&rsquo;autre guerre est celle de la France contre la m\u00e9canisation repr\u00e9sent\u00e9e pour ce cas par la puissance m\u00e9canique allemande,  et je veux dire en disant pour ce cas que l&rsquo;Allemagne n&rsquo;est dans ce cas qu&rsquo;un pr\u00eate-nom. C&rsquo;est cette guerre-l\u00e0 qui m&rsquo;int\u00e9resse parce que c&rsquo;est elle qui interpr\u00e8te et nous restitue les grandes tendances de l&rsquo;Histoire, parce qu&rsquo;elle est d&rsquo;abord psychologie pure transcend\u00e9e.)<\/p>\n<\/p>\n<p><p>\tLa bataille de Verdun est la pire des stupidit\u00e9s et des cruaut\u00e9s humaines si elle n&rsquo;est \u00e9lev\u00e9e par une dimension spirituelle ; sans elle, la bataille n&rsquo;est que boue, souffrances et morts. Les Fran\u00e7ais ont nomm\u00e9 Voie sacr\u00e9e la route qui ravitaillait Verdun. Ce qui est per\u00e7u comme un artefact de propagande par les historiens asserment\u00e9s, acquiert \u00e0 la lumi\u00e8re du temps et de la profondeur des choses  une dimension sans \u00e9gale. Il y a bien entendu une inspiration dans cette expression.<\/p>\n<\/p>\n<p><p>\tLorsque d\u00e9bute la bataille le 21 f\u00e9vrier 1916, les Fran\u00e7ais disposent de 175-180 canons sur le front de Verdun, les Allemands de plus de 1.200. Les intentions du <em>Kronprinz<\/em>, qui commande la V\u00e8me Arm\u00e9e, sont connues ; elles sont directement inspir\u00e9es par le chef d&rsquo;\u00e9tat-major, le g\u00e9n\u00e9ral Falkenhayn, qui en informa directement le <em>Kaizer<\/em> Guillaume par lettre du 25 d\u00e9cembre 1915, lettre surnomm\u00e9e le m\u00e9mo de No\u00ebl. C&rsquo;est la litanie des gens s\u00e9rieux qui revient, sur le fond de la reconnaissance que l&rsquo;Allemagne ne pourra tenir longtemps dans la guerre d&rsquo;usure qui s&rsquo;est install\u00e9e depuis l&rsquo;automne 1914, et dont il faut briser le carcan; seule la puissance anglaise importe, disent-ils, mais nous ne pouvons en \u00eatre quitte, alors liquidons la France; c&rsquo;est la litanie allemande, voire la litanie des peuplades nordiques et anglo-saxonnes: la France est quantit\u00e9 n\u00e9gligeable (puisque latine dans ses origines) mais c&rsquo;est pourtant elle qu&rsquo;il faut liquider \u00e0 tout prix. Falkenhayn emploie tous les arguments possibles pour convaincre Guillaume, et se convaincre lui-m\u00eame, que la France doit \u00eatre la cible privil\u00e9gi\u00e9e : \u00ab<em>La pression exerc\u00e9e sur la France atteint la derni\u00e8re limite m\u00eame si elle est sans aucun doute support\u00e9e avec la derni\u00e8re des d\u00e9votions. Si nous parvenons \u00e0<\/em> [faire] <em>ouvrir les yeux \u00e0 son peuple sur le fait que, dans le domaine militaire, tout est d\u00e9sormais vain, cette limite sera atteinte et le meilleur atout de l&rsquo;Angleterre lui sera enlev\u00e9 des mains.<\/em>\u00bb La conclusion de l&rsquo;Allemand est celle-ci : presser les Fran\u00e7ais, les attaquer massivement, les menacer en un point, si fortement qu&rsquo;ils seraient oblig\u00e9s \u00ab<em>\u00e0 engager tous les hommes \u00e0 leur disposition. S&rsquo;ils le font, les forces fran\u00e7aises seront saign\u00e9es \u00e0 blanc<\/em>\u00bb. Le but explicite est la destruction de l&rsquo;arm\u00e9e fran\u00e7aise et, \u00e0 peine implicite, la destruction de la race fran\u00e7aise. C&rsquo;est le cas. Keegan note encore que les Allemands ne pr\u00e9tendirent pas, dans la pouss\u00e9e initiale, submerger les lignes fran\u00e7aises en lan\u00e7ant toutes leurs forces comme ils eussent pu le faire, et percer pour l&#8217;emporter par la manuvre d&rsquo;enveloppement. Ils veulent fixer et massacrer. C&rsquo;est une guerre d&rsquo;attrition pure.<\/p>\n<\/p>\n<p><p>\t(Il y a une autre version. Certains [par exemple, le professeur Gerd Krumeich, de D\u00fcsseldorf, dans sa communication au colloque du 23-24 f\u00e9vrier 2006 \u00e0 Verdun : <em>1916-2006, Verdun sous le regard du monde<\/em>] mettent en doute l&rsquo;existence, \u00e0 la date indiqu\u00e9e du m\u00e9mo de Noel. Falkenhayn l&rsquo;aurait r\u00e9dig\u00e9 apr\u00e8s coup, simplement gliss\u00e9 dans ses m\u00e9moires pour se justifier d&rsquo;une offensive rat\u00e9e, d&rsquo;une tactique d\u00e9nonc\u00e9e comme pusillanime, etc. Possible ? Qu&rsquo;importe. Cette tactique pusillanime, justement, correspond bien aux intentions affich\u00e9es dans le m\u00e9mo qui n&rsquo;existait peut-\u00eatre pas. D\u00e8s la mi-mars 1916, devant l&rsquo;insucc\u00e8s initial, la justificatin allemande de la bataille devient effectivement de saigner les Fran\u00e7ais. Il suffit d&rsquo;avancer le fameux tout se passe comme si,  car c&rsquo;est bien le cas : tout se passe comme si l\u00e0 \u00e9tait bien lintention de Falkenhayn. Le m\u00e9mo Falkenhayn? <em>Si non \u00e8 vero, \u00e8 ben trovato<\/em> Ou encore, l&rsquo;explication de Val\u00e9ry, qui suppose un tel vide dans la guerre fig\u00e9e par la tuerie qu&rsquo;effectivement, la dimension supr\u00eame de Verdun pourrait bien s&rsquo;y \u00eatre gliss\u00e9e Valery, toujours en 1931: \u00ab <em>C&rsquo;est pourquoi il n&rsquo;a pas \u00e0 rechercher trop profond\u00e9ment les raisons de la grande attaque de Verdun. Celles que les Allemands en ont donn\u00e9es ne sont pas invincibles,  n&rsquo;\u00e9tant pas d&rsquo;ailleurs concordantes. La v\u00e9rit\u00e9 semble fort simple. Il suffit de se mettre un instant \u00e0 la place des hommes. On ne sait que faire, et il faut faire quelque chose. Grande et irr\u00e9sistible raison. Rien ne s&rsquo;impose. La strat\u00e9gie est ligot\u00e9e dans les r\u00e9seaux. Jusqu&rsquo;ici, toutes les offensives ont \u00e9chou\u00e9. L&rsquo;imagination d\u00e9faillante ne sait plus sugg\u00e9rer que ce qu&rsquo;elle a d\u00e9j\u00e0 con\u00e7u ; mais cette fois, on frappera beaucoup plus fort. C&rsquo;est \u00e0 une \u00e9chelle d\u00e9mesur\u00e9e que l&rsquo;on va monter cette attaque. 400 000 hommes ; une artillerie incroyable, accumul\u00e9e sur un point du front ; l&rsquo;h\u00e9ritier de la couronne, pour chef ; une place forte de premier ordre, d\u00e9j\u00e0 illustre dans l&rsquo;histoire, pour objectif,  et c&rsquo;est la bataille de Verdun.<\/em>\u00bb  Ainsi le myst\u00e8re enveloppe cette bataille: pourquoi eut-elle lieu ? C&rsquo;est alors que les hypoth\u00e8ses audacieuses s&rsquo;imposent.)<\/p>\n<\/p>\n<p><p>\tLa bataille de Verdun dura dix mois, ou 300 jours. Ce fut une bataille d&rsquo;acier, de sang et de boue. Tr\u00e8s vite, plus personne n&rsquo;y reconnut plus rien. Il restait l&rsquo;\u00e9lan initial, qui avait donn\u00e9 sa marque \u00e0 cette bataille, qui fait qu&rsquo;aujourd&rsquo;hui nombre d&rsquo;entre nous ne peuvent \u00e9voquer Verdun, en voir un alignement de tombes ou les fant\u00f4mes de ses restes dans la for\u00eat revenue, sans \u00eatre submerg\u00e9s par l&rsquo;\u00e9motion. Seul le sens spirituel justifie une telle r\u00e9action. \u00c9clair\u00e9e par cette intuition, l&rsquo;interpr\u00e9tation spirituelle de Verdun qui revient ici et l\u00e0, qui en fait un affrontement de la nation fran\u00e7aise contre la puissance m\u00e9canique, prend son sens historique et sa place dans l&rsquo;Histoire,  comme un <strong>fait<\/strong> historique \u00e0 part enti\u00e8re, avec une importance tr\u00e8s grande dans l&rsquo;interpr\u00e9tation que je veux donner de cette p\u00e9riode de l&rsquo;Histoire menant jusqu&rsquo;\u00e0 nous. Verdun rejoint les grands courants souterrains qui donnent sa substance \u00e0 l&rsquo;Histoire, en-dessous de la surface des choses laiss\u00e9es \u00e0 l&rsquo;investigation pointilleuse des historiens asserment\u00e9s.<\/p>\n<\/p>\n<p><p>\tVal\u00e9ry donna plus tard l&rsquo;explication plus large, et mise en perspective, du texte dont j&rsquo;ai cit\u00e9 plus haut une phrase, laquelle est si souvent cit\u00e9e, et cet extrait de Val\u00e9ry concernant cette phrase elle-m\u00eame:<\/p>\n<\/p>\n<p><p>\t\u00ab<em>Enfin, quant \u00e0 ma phrase m\u00eame, elle exprime une impression de 1919 et annonce le d\u00e9veloppement qui la suit et est charg\u00e9 de lui donner un sens. Je la consid\u00e8re comme une sorte de photographie. Le titre m\u00eame de l&rsquo;\u00e9tude (La crise de l&rsquo;Esprit&rsquo;) et l&rsquo;ensemble des id\u00e9es qu&rsquo;elle contient me semble montrer assez clairement que j&rsquo;entends d\u00e9crire une phase critique, un \u00e9tat de choses oppos\u00e9 fortement \u00e0 celui que l&rsquo;on repr\u00e9sente par les noms de r\u00e9gime et de d\u00e9veloppement r\u00e9gulier. Le probl\u00e8me de la IIe d\u00e9cade me para\u00eet donc se pr\u00e9ciser ainsi : Sommes-nous vraiment dans une phase critique? A quoi le conna\u00eet-on? Cette maladie peut-elle \u00eatre mortelle? Pouvons-nous, oui ou non, imaginer de telles destructions mat\u00e9rielles et spirituelles, ou de telles substitutions, non fantastiques mais r\u00e9alisables, que l&rsquo;ensemble de nos \u00e9valuations d&rsquo;ordre intellectuel et esth\u00e9tique n&rsquo;ait plus de sens actuel?<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tCette id\u00e9e d&rsquo;un moment historique fondamental qui r\u00e9sume tout mon propos se r\u00e9sume bien \u00e0 cette question de Valery : \u00ab<em>Sommes-nous vraiment dans une phase critique?<\/em>\u00bb Elle me donne le biais d&rsquo;un encha\u00eenement par r\u00e9f\u00e9rence qui a tout d&rsquo;un encha\u00eenement naturel, qui a la force de la logique de la grande Histoire dissimul\u00e9e, \u00e0 partir de l&rsquo;interpr\u00e9tation de la Grande Guerre et du r\u00f4le de la Grande Nation dans cette guerre.<\/p>\n<\/p>\n<p><p>\tIl y a eu effectivement deux guerres dans la Grande Guerre. D&rsquo;un c\u00f4t\u00e9, la guerre classique, opposant les puissances terrestres, qui n&rsquo;a aucun int\u00e9r\u00eat pour le pr\u00e9sent propos. Dans un champ compl\u00e8tement diff\u00e9rent, la Grande Guerre s&rsquo;est av\u00e9r\u00e9e \u00eatre, pour la France, un affrontement brutal avec le processus de m\u00e9canisation du monde dont elle est naturellement l&rsquo;adversaire. L&rsquo;Allemagne repr\u00e9sentait ce processus de m\u00e9canisation ; si ce n&rsquo;est un accident de l&rsquo;Histoire, c&rsquo;en est plus un d\u00e9tail que sa substance. On a aussit\u00f4t la preuve de cette circonstance, dans ce moment pr\u00e9cis o\u00f9 l&rsquo;identit\u00e9 des autres nations a moins d&rsquo;importance que le processus qu&rsquo;elles se passent de main en main. Les subtilit\u00e9s insondables de l&rsquo;Histoire mettent, en m\u00eame temps que la guerre approche de sa fin, la France dans un contact \u00e0 nouveau intime avec l&rsquo;Am\u00e9rique, qui semble renouer le fil avec 1776-1783 sans qu&rsquo;on prenne encore garde que c&rsquo;est peut-\u00eatre pour donner \u00e0 l&rsquo;ensemble un \u00e9clairage nouveau. (Pr\u00e9par\u00e9 comme un bon coup de relations publiques, comme une formule pour journalistes, le mot de Pershing arrivant en France prend une dimension tr\u00e8s particuli\u00e8re \u00e0 cette lumi\u00e8re. Il a une <strong>v\u00e9rit\u00e9<\/strong> inattendue : \u00ab<em>La Fayette, nous voici.<\/em>\u00bb)<\/p>\n<\/p>\n<p><p>\tLes Am\u00e9ricains sont venus en Europe prendre, sur la fin du conflit, un r\u00f4le important dans la coalition. Le poids de cette puissance, soudain affirm\u00e9 bien plus vite et d&rsquo;une fa\u00e7on plus pressante que son poids effectif dans la guerre, lui donne un r\u00f4le inattendu dans les n\u00e9gociations de paix. Wilson s&rsquo;y tient, au moins \u00e0 l&rsquo;\u00e9gal de Cl\u00e9menceau et de Llyod George. La paix est presque une paix am\u00e9ricaine d&rsquo;une guerre qui ne le fut pas. L&rsquo;alliance des d\u00e9mocraties occidentales pr\u00e9sente un front uni d\u00e9couvrant assez vite des nuances significatives qui deviennent des fractures. <em>Grosso modo<\/em>, l&rsquo;accueil que fait la France aux Am\u00e9ricains et \u00e0 l&rsquo;Am\u00e9rique en 1917-18, est affectueux et sentimental pour les premiers, plus circonspect pour la seconde. La France d\u00e9couvre le changement extraordinaire qui s&rsquo;est op\u00e9r\u00e9 entre l&rsquo;image qu&rsquo;elle conserva de l&rsquo;Am\u00e9rique tout au long du XIX\u00e8me si\u00e8cle, et l&rsquo;Am\u00e9rique qu&rsquo;elle d\u00e9couvre en 1917-18, puis en 1919. Tr\u00e8s vite, le malaise le dispute victorieusement \u00e0 l&rsquo;affection. Cela va \u00eatre affirm\u00e9 avec force, tout au long des ann\u00e9es 1920, par la voix puissante d&rsquo;une litt\u00e9rature d&rsquo;analyse, de r\u00e9flexion et de pol\u00e9mique. La mise en question de l&rsquo;am\u00e9ricanisme dans la d\u00e9cennie des ann\u00e9es 1920 est le legs direct bien que dissimul\u00e9 de la bataille de Verdun et de l&rsquo;esprit qui anima la France dans la bataille qu&rsquo;elle mena tout au long de la Grande Guerre.<\/p>\n<\/p>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Grande Guerre avant la parenth\u00e8se monstrueuse Voici un extrait d&rsquo;un livre auquel travaille actuellement Philippe Grasset. Ce livre, dont le titre provisoire est La parenth\u00e8se monstrueuse 1934-1989, tente de donner un \u00e9clairage nouveau de l&rsquo;histoire du XX\u00e8me si\u00e8cle, prolong\u00e9e naturellement jusqu&rsquo;\u00e0 2001 et aujourd&rsquo;hui. Nous comptons naturellement offrir \u00e0 nos lecteurs ce livre en&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[18],"tags":[2891,3125,2645,6165,5120,5119,3997,3928,6161],"class_list":["post-68236","post","type-post","status-publish","format-standard","hentry","category-archivesphg","tag-grande","tag-grasset","tag-guerre","tag-mecanisation","tag-monstrueuse","tag-parenthese","tag-philippe","tag-valery","tag-verdun"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/68236","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=68236"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/68236\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=68236"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=68236"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=68236"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}