{"id":68289,"date":"2006-12-10T00:00:00","date_gmt":"2006-12-10T00:00:00","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2006\/12\/10\/est-il-donc-si-difficile-de-dire-nous-avons-perdu\/"},"modified":"2006-12-10T00:00:00","modified_gmt":"2006-12-10T00:00:00","slug":"est-il-donc-si-difficile-de-dire-nous-avons-perdu","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2006\/12\/10\/est-il-donc-si-difficile-de-dire-nous-avons-perdu\/","title":{"rendered":"Est-il donc si difficile de dire : \u201cnous avons perdu\u201d ?"},"content":{"rendered":"<p><p>Habitu\u00e9s \u00e0 l&rsquo;hypocrisie structurelle de la politique anglo-saxonne (y compris la branche am\u00e9ricaniste, cela va de soi), souvent relay\u00e9e par la presse officielle, saluons avec d&rsquo;autant plus de respect le commentaire de Matthew Parris dans le <em>Times<\/em> de Londres du <a href=\"http:\/\/www.timesonline.co.uk\/article\/0,,1065-2494860_2,00.html\" class=\"gen\">9 d\u00e9cembre<\/a>. Le titre illustre l&rsquo;\u00e9tat d&rsquo;esprit de l&rsquo;auteur, que nous essayons pour une fois de rendre en bon fran\u00e7ais : \u00ab<em>Je devrais applaudir le rapport Baker. Alors, pourquoi est-ce qu&rsquo;il me rend malade?<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tCette chronique ne dissimule rien des formidables hypocrisies de la politique US-UK en Irak. Elle ne dissimule rien de la formidable hypocrisie du rapport Baker qui pr\u00e9tend rejeter la responsabilit\u00e9 de la fin de la guerre, qui devrait \u00eatre \u00e9videmment heureuse, sur la cr\u00e9ature enfant\u00e9e par cette m\u00eame politique,  le gouvernement-marionnette mis en place \u00e0 Bagdad,  sous peine de vouer aux g\u00e9monies la marionnette si elle ne parvient finalement pas \u00e0 cette fin heureuse.<\/p>\n<\/p>\n<p><p>\tParris d\u00e9monte le processus formidable mis en place par la commission Baker pour tenter de camoufler une formidable d\u00e9faite avec son cort\u00e8ge d&rsquo;erreurs et de malheurs, dont la responsabilit\u00e9 \u00e9choit aux seuls anglo-saxons, en une op\u00e9ration r\u00e9aliste et pleine d&rsquo;habilet\u00e9s mesur\u00e9es \u00e0 l&rsquo;aune d&rsquo;une pr\u00e9tendue raison.<\/p>\n<\/p>\n<p><p>\t\u00ab<em>Tony Blair will like the Baker report. It is shallow and dishonest. It shows how to weasel a way out of trouble and leave former friends to fall, undefended, by the wayside. It suggests how blame may be shifted onto hapless Iraqi ministers, and fatuous milestones and timetables confected with a view to their being demonstrably missed. It explains how international conferences may be set up in order that they should fail. For Britain and the United States, Baker is now, with no shadow of doubt, the only way out. So is Forward with James Baker III! to be my banner?<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>Well it should be. But something rises in my gorge at the moral and intellectual shabbiness of the exercise. If we have lost this war, and with it the likely capacity to forestall the vacuum that our defeat will surely leave behind, shouldn&rsquo;t we just say so?<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tVoil\u00e0 bien l&rsquo;antienne du propos. Comment ne parviennent-ils pas \u00e0 affronter la r\u00e9alit\u00e9?  Comment ne parviennent-ils pas \u00e0 ce qui serait finalement une lib\u00e9ration,  d&rsquo;enfin confronter les cons\u00e9quences de leurs actes et d&rsquo;assumer les effets de leurs responsabilit\u00e9s?<\/p>\n<\/p>\n<p><p>\tGraves questions. Matthew Parris n&rsquo;a pas beaucoup d&rsquo;espoir. Il lui reste \u00e0 supporter son estomac nou\u00e9, avec la naus\u00e9e qui va avec. Certes, il continuera \u00e0 faire son travail au <em>Times<\/em> de Londres. Il faut bien vivre. Au moins, il aura \u00e9crit ce qu&rsquo;il a \u00e9crit ce jour-l\u00e0, et certes tout le monde ne peut en dire autant.<\/p>\n<\/p>\n<p><p>\t\u00ab<em>But Mr Baker has, and furious neocons realise it too. The term realpolitik has become a clich\u00e9 in media treatment of the ISG report this week but the irony is this: Baker&rsquo;s conclusions are anything but realistic: they represent unrealism of the most fanciful kind. His route map is to La-la Land. He knows it. His report is the sugar. The pill is Defeat.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>Forgive me but I am finding the sheer cynicism of all this difficult to stomach. Is we lost so very hard to say? Now that he has limbered up with a range of moving apologies for things done by dead people who are not him, perhaps, on one of his increasingly fleeting visits to this country, Tony Blair might try his hand at the big one.<\/em>\u00bb<\/p>\n<\/p>\n<p><\/p>\n<p><p>\tMis en ligne le 10 d\u00e9cembre 2006 \u00e0 10H23<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Habitu\u00e9s \u00e0 l&rsquo;hypocrisie structurelle de la politique anglo-saxonne (y compris la branche am\u00e9ricaniste, cela va de soi), souvent relay\u00e9e par la presse officielle, saluons avec d&rsquo;autant plus de respect le commentaire de Matthew Parris dans le Times de Londres du 9 d\u00e9cembre. Le titre illustre l&rsquo;\u00e9tat d&rsquo;esprit de l&rsquo;auteur, que nous essayons pour une fois&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[2],"tags":[4094,4255,857,6014,4907,2852],"class_list":["post-68289","post","type-post","status-publish","format-standard","hentry","category-bloc-notes","tag-baker","tag-defaite","tag-irak","tag-isg","tag-parris","tag-times"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/68289","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=68289"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/68289\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=68289"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=68289"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=68289"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}