{"id":68312,"date":"2006-12-16T00:00:00","date_gmt":"2006-12-16T00:00:00","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2006\/12\/16\/une-action-legale-contre-la-decision-darreter-lenquete-sur-yamamah-en-plus-de-la-crainte-et-de-lhonneur-des-saoudiens\/"},"modified":"2006-12-16T00:00:00","modified_gmt":"2006-12-16T00:00:00","slug":"une-action-legale-contre-la-decision-darreter-lenquete-sur-yamamah-en-plus-de-la-crainte-et-de-lhonneur-des-saoudiens","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2006\/12\/16\/une-action-legale-contre-la-decision-darreter-lenquete-sur-yamamah-en-plus-de-la-crainte-et-de-lhonneur-des-saoudiens\/","title":{"rendered":"Une action l\u00e9gale contre la d\u00e9cision d&rsquo;arr\u00eater  l&rsquo;enqu\u00eate sur <em>Yamamah<\/em>? \u2014 En plus de la crainte et de l&rsquo;\u201chonneur\u201d des Saoudiens"},"content":{"rendered":"<p><p>En restera-t-on \u00e0 la d\u00e9cision abrupte d&rsquo;abandonner l&rsquo;enqu\u00eate du SFO sur le scandale <em>Yamamah<\/em>? Le <em>Guardian<\/em>, qui est toujours le relais privil\u00e9gi\u00e9 de groupes oppos\u00e9s aux ventes d&rsquo;armes, donne <a href=\"http:\/\/www.guardian.co.uk\/armstrade\/story\/0,,1973356,00.html\" class=\"gen\">aujourd&rsquo;hui<\/a> des indications selon lesquelles des actions juridiques ont \u00e9t\u00e9 d\u00e9cid\u00e9es.<\/p>\n<\/p>\n<p><p>\t\u00ab<em>The government&rsquo;s controversial decision to drop a Serious Fraud Office investigation into allegations that Saudi officials were bribed to win a lucrative order for a British arms firm could be challenged in the high court, it emerged last night.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>Anti-arms trade campaigners yesterday instructed lawyers to consider a legal action against Lord Goldsmith, the attorney general, after he halted the SFO inquiry into allegations of corruption by officials from BAE Systems when sealing the Al-Yamamah deal in the 1980s.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>The Campaign against the Arms Trade and the Corner House, a social and environmental justice group, believe the grounds for the decision  made after the prime minister warned it was against Britain&rsquo;s security and foreign policy interests &#8211; could be subject to judicial review. David Pannick QC has been hired.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>The Organisation for Economic Cooperation and Development also signalled that it would launch its own investigation. Britain is a signatory to the 30-nation grouping&rsquo;s anti-bribery convention.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tPour l&rsquo;instant, il s&rsquo;agit moins de savoir o\u00f9 peuvent \u00e9ventuellement mener ces actions, si elles sont effectivement conduites, que de voir leurs effets sur les n\u00e9gociations entre Britanniques et Saoudiens concernant l&rsquo;achat de 72 <em>Typhoon<\/em> selon le sch\u00e9ma <em>Yamamah<\/em>. Les dirigeants saoudiens sont d\u00e9crits comme absolument d\u00e9cha\u00een\u00e9s dans cette affaire et, \u00e9galement, tr\u00e8s inquiets de ne risquer aucune inculpation. La question se pose de savoir s&rsquo;ils ne vont pas craindre d&rsquo;une fa\u00e7on disproportionn\u00e9e la possibilit\u00e9 d&rsquo;actions l\u00e9gales contre la d\u00e9cision d&rsquo;arr\u00eater l&rsquo;enqu\u00eate du SFO. Les projets d&rsquo;action juridique signal\u00e9s par le <em>Guardian<\/em> sont d&rsquo;ailleurs aussi bien per\u00e7us comme tactiques, pour interf\u00e9rer sur les n\u00e9gociations du contrat <em>Typhoon<\/em> dans ce sens.<\/p>\n<\/p>\n<p><p>\tConcernant ces n\u00e9gociations, il reste par ailleurs la grande inconnue de savoir comment l&rsquo;on pourrait n\u00e9gocier sans risques consid\u00e9rables  risques qui effraient les Saoudiens  un nouveau contrat type <em>Yamamah<\/em> avec les habituelles clauses secr\u00e8tes de commission. La v\u00e9ritable question qui se pose aux Britanniques est la suivante : n&rsquo;ont-ils pas, dans cette affaire, perdu la confiance des Saoudiens pour ce type de transactions? Et il n&rsquo;est pas question, pour les m\u00eames Saoudiens, d&rsquo;abandonner les commissions. C&rsquo;est encore plus,  on pourra juger paradoxal dans ce cas l&#8217;emploi de certains mots,  une question d&rsquo;honneur et de ne pas perdre la face que la question de l&rsquo;argent lui-m\u00eame.<\/p>\n<\/p>\n<p><\/p>\n<p><p>\tMis en ligne le 16 d\u00e9cembre 2006 \u00e0 06H12<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>En restera-t-on \u00e0 la d\u00e9cision abrupte d&rsquo;abandonner l&rsquo;enqu\u00eate du SFO sur le scandale Yamamah? Le Guardian, qui est toujours le relais privil\u00e9gi\u00e9 de groupes oppos\u00e9s aux ventes d&rsquo;armes, donne aujourd&rsquo;hui des indications selon lesquelles des actions juridiques ont \u00e9t\u00e9 d\u00e9cid\u00e9es. \u00abThe government&rsquo;s controversial decision to drop a Serious Fraud Office investigation into allegations that Saudi&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[2],"tags":[2756,3621,3858,6221,6178,6219,4364],"class_list":["post-68312","post","type-post","status-publish","format-standard","hentry","category-bloc-notes","tag-action","tag-confiance","tag-corruption","tag-legale","tag-saoudiens","tag-sfo","tag-yamamah"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/68312","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=68312"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/68312\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=68312"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=68312"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=68312"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}